{"id":841,"date":"2007-09-19T18:10:45","date_gmt":"2007-09-19T18:10:45","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2007\/09\/19\/ambiente-il-trattato-sullozono-potrebbe-rallentare-il-cambiamento-climatico\/"},"modified":"2007-09-19T18:10:45","modified_gmt":"2007-09-19T18:10:45","slug":"ambiente-il-trattato-sullozono-potrebbe-rallentare-il-cambiamento-climatico","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2007\/09\/19\/ambiente-il-trattato-sullozono-potrebbe-rallentare-il-cambiamento-climatico\/","title":{"rendered":"AMBIENTE: Il trattato sull&#8217;ozono potrebbe rallentare il cambiamento climatico"},"content":{"rendered":"<p>MONTREAL, 19 settembre 2007 (IPS) &#8211; I delegati di 191 nazioni sono riuniti questa settimana a Montreal, in Canada, per celebrare ed ampliare il trattato sull&rsquo;ambiente pi&ugrave; conosciuto al mondo: il Protocollo di Montreal, per proteggere la cappa di ozono.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1006\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1006\" class=\"size-full wp-image-1006\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/ozone_layer_final.jpg\" alt=\"L'area blu rappresenta lo strato di ozono antartico nel 2006 NASA\" width=\"200\"\/><p id=\"caption-attachment-1006\" class=\"wp-caption-text\">L&#8217;area blu rappresenta lo strato di ozono antartico nel 2006<br \/>NASA<\/p><\/div><\/div>\n<p>Dopo aver raggiunto l&rsquo;obiettivo di eliminare il 95 per cento dei composti chimici, c&rsquo;&egrave; adesso un forte consenso per accelerare il ritiro graduale dei nuovi composti responsabili dell&rsquo;assottigliamento dell&rsquo;ozono, che sono anche potenti gas serra.<\/p>\n<p>Molti esperti ritengono infatti che questo incontro potr&agrave; contribuire alla riduzione delle emissioni di gas serra molto pi&ugrave; del tanto propagandato Protocollo di Kyoto.<\/p>\n<p>Le sfide restano, visto che gli Stati Uniti continuano a fare ampio uso di bromuro di metile, una sostanza implicata nella degradazione dell&rsquo;ozono (ODS), e il boom economico di Cina e India ha prodotto un rapido aumento del numero di condizionatori che utilizzano sostanze chimiche sostitutive. <\/p>\n<p>I delegati presenti al ventesimo anniversario del Protocollo di Montreal e alla XIX Conferenza delle Parti si autodefiniscono la &ldquo;famiglia dell&rsquo;ozono&rdquo;. Hanno cominciato a met&agrave; degli anni &rsquo;80 ad occuparsi della recente scoperta dei buchi e dell&rsquo;assottigliamento della cappa di ozono, che protegge ogni essere biologico dai danni causati dall&rsquo;esposizione alle radiazioni ultraviolette (UV) emesse dal sole. Gli accresciuti livelli di raggi UV negli ultimi decenni sono stati collegati alle accresciute incidenze di tumori, malattie degli occhi e altri problemi di salute negli umani e in molte altre specie.<\/p>\n<p>&ldquo;La scienza che spiega le cause dell&rsquo;impoverimento dell&rsquo;ozono non era molto sviluppata all&rsquo;epoca&rdquo;, ha osservato Tom McElroy, esperto di ozono presso Environment Canada.<\/p>\n<p>&ldquo;Ma la comunit&agrave; internazionale ha continuato ad occuparsi del problema, a causa dei rischi potenziali&rdquo;, ha detto McElroy in un&rsquo;intervista. <\/p>\n<p>Dalle ricerche dello scienziato statunitense Sherwood Rowland e del messicano Mario Molina, avviate nel 1974, &egrave; gradualmente emerso che due famiglie di composti chimici &#8211; i clorofuorocarburi, o CFC (contenuti negli impianti di refrigerazione, condizionatori e propellenti di aerosol), e i gas halon (usati negli estintori) &#8211; stavano riducendo la quantit&agrave; di ozono presente nella stratosfera. Grazie al loro lavoro, i due studiosi, insieme allo scienziato olandese Paul Crutzen, hanno ottenuto il Premio Nobel per la chimica nel 1995. <\/p>\n<p>Rowland e Molina, rivolgendosi ai delegati domenica scorsa, hanno raccontato di aver dovuto sviluppare un nuovo tipo di chimica dell&rsquo;atmosfera; ma i crescenti riscontri della diminuzione dei livelli di ozono di oltre il 30 per cento sull&rsquo;Antartico hanno allarmato alcune nazioni, in particolare l&rsquo;Argentina.    &rdquo;Nella zona meridionale dell&rsquo;Argentina, i bambini non potevano pi&ugrave; giocare all&#039;aperto in primavera, a causa del buco dell&rsquo;ozono&rdquo;, ha spiegato Romina Picolotti, ministra argentina dell&rsquo;ambiente.<\/p>\n<p>&rdquo;C&rsquo;erano abbastanza prove scientifiche per agire. Non c&rsquo;&egrave; bisogno di essere sicuri al 100 per cento&rdquo;, ha detto Picolotti all&rsquo;IPS. <\/p>\n<p>L&rsquo;Argentina, insieme a Stati Uniti, Canada e ad altri pochi paesi, ha cominciato a fare pressioni per un trattato internazionale teso ad eliminare le sostanze che causano l&rsquo;assottigliamento dell&rsquo;ozono, come i CFC.<\/p>\n<p>&rdquo;L&rsquo;accordo &egrave; stato raggiunto in nove mesi, un periodo di tempo incredibilmente breve&rdquo;, ha commentato Richard Benedick, negoziatore statunitense ed ex ambasciatore. <\/p>\n<p>Nel 1987, 24 paesi hanno firmato il Protocollo di Montreal sulle sostanze che impoveriscono lo strato d&rsquo;ozono, e oggi sono 191 i paesi che hanno aderito al trattato.<\/p>\n<p>Secondo Benedick, il rapido accordo &egrave; stato possibile grazie alla flessibilit&agrave; del trattato, che poteva essere adattato di pari passo con i progressi della scienza, e che ha ricevuto la piena collaborazione dell&rsquo;industria chimica. Per lo scarso numero di paesi aderenti &egrave; stato anche pi&ugrave; facile negoziare &#8211; al contrario dei titanici incontri come la Convenzione quadro delle Nazioni Unite sul cambiamento climatico e il Protocollo di Kyoto.<\/p>\n<p>&ldquo;I negoziati del 1987 sono stati difficili, ma abbiamo raggiunto un equilibrio seppure fragile&rdquo;, ha ricordato Victor Buxton, ingegnere chimico e tra i rappresentanti del Canada. Dove invece non sono stati raggiunti accordi formali, i paesi hanno optato per intese informali sulle questioni chiave come il trasferimento di tecnologie, i crediti di emissione, e gli aiuti finanziari.<\/p>\n<p>Il Protocollo di Montreal prevedeva degli incentivi per incoraggiare i paesi non aderenti ad unirsi il pi&ugrave; presto possibile, e anche sanzioni commerciali per eliminare le importazioni da altri paesi.<\/p>\n<p>Un fattore chiave fu la creazione nel 1990 del Fondo multilaterale per l&rsquo;attuazione del Protocollo di Montreal, un fondo di milioni di dollari per aiutare i paesi in via di sviluppo a ritirare gradualmente la produzione e l&rsquo;uso dei composti chimici responsabili dell&rsquo;impoverimento dell&rsquo;ozono. 49 paesi industrializzati hanno contribuito fino ad oggi con oltre 2,2 miliardi di dollari, e 146 nazioni hanno ricevuto denaro dal fondo.<\/p>\n<p>&ldquo;Il Fondo multilaterale &egrave; stato fondamentale per il successo del Protocollo di Montreal&rdquo;, ha detto l&rsquo;ambasciatore del Messico Juan Antonio Mateos, aggiungendo: &ldquo;Non siamo riusciti a crearne un altro analogo per il Protocollo di Kyoto&rdquo;. <\/p>\n<p>Per di pi&ugrave;, c&rsquo;&egrave; stata una spinta contraria agli accordi internazionali multilaterali, con molti paesi pi&ugrave; favorevoli ad un approccio unilaterale o bilaterale, ha osservato.<\/p>\n<p>&ldquo;Dovremmo tornare al multilateralismo, se vogliamo avere un trattato forte sul clima&rdquo;, ha detto Mateos all&rsquo;IPS.<\/p>\n<p>Bench&eacute; il problema dell&rsquo;assottigliamento dell&rsquo;ozono non sia completamente risolto, e il buco dell&rsquo;ozono non sar&agrave; recuperato fino al 2060 o 2070, il cambiamento climatico resta il principale tema in discussione qui a Montreal. E questo per due motivi: quasi tutti gli ODS sono anche gas responsabili del riscaldamento globale, e si spera che il Protocollo di Montreal possa servire da modello per un trattato climatico forte ed efficace. <\/p>\n<p>Tra il 1990 e il 2000, l&rsquo;eliminazione degli ODS produsse una netta riduzione dei 25 miliardi di tonnellate di gas responsabili del riscaldamento globale.   &rdquo;La scienza attuale mostra che una accelerazione del graduale ritiro di ODS, grazie al Protocollo di Montreal, pu&ograve; aiutarci ad avere un futuro con poco carbonio&rdquo;, ha detto in conferenza stampa Achim Steiner, sottosegretario generale dell&#039;Onu e direttore esecutivo del Programma Onu per l&rsquo;ambiente (UNEP).<\/p>\n<p>Gli idroclorofluorocarburi, i sostituti meno dannosi dei vecchi CFC, si sono ormai diffusi nei prodotti come sistemi di refrigerazione, impianti di condizionamento e schiume. Ma gli HCFC sono anche gas serra molto potenti. Secondo il Protocollo di Montreal, l&rsquo;uso di HCFC dovrebbe essere completamente sospeso nei paesi sviluppati nel 2030, e nel 2040 nei paesi in via di sviluppo. <\/p>\n<p>Una sospensione pi&ugrave; rapida dell&rsquo;utilizzo e della produzione di HCFC, e un loro ritiro definitivo entro i prossimi 10 anni, porterebbe nei prossimi decenni ad una riduzione cumulativa delle emissioni fino a 38 miliardi di tonnellate metriche di anidride carbonica, secondo l&rsquo;UNEP.<\/p>\n<p>Il Protocollo di Kyoto punta invece ad eliminare appena due miliardi di tonnellate metriche in una prima fase 2008-12. Annualmente, questo potrebbe rappresentare un taglio di oltre il 3,5 per cento di tutte le attuali emissioni di gas serra nel mondo.    Invece, il Protocollo di Kyoto, il principale trattato per la riduzione dei gas serra, &egrave; stato concordato con l&rsquo;obiettivo di ridurre i livelli di emissioni nei paesi sviluppati nel 1990 appena sopra il cinque per cento entro il 2012. <\/p>\n<p>I paesi presenti all&rsquo;incontro si dicono favorevoli a un ritiro graduale pi&ugrave; rapido, ma i dettagli devono ancora essere negoziati.    &rdquo;Se riusciremo a usare il Protocollo per accelerare il ritiro graduale, ci&ograve; sar&agrave; di enorme beneficio per la cappa d&rsquo;ozono, e dar&agrave; un contributo significativo alla riduzione dei gas serra&rdquo;, ha detto Steiner.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTREAL, 19 settembre 2007 (IPS) &#8211; I delegati di 191 nazioni sono riuniti questa settimana a Montreal, in Canada, per celebrare ed ampliare il trattato sull&rsquo;ambiente pi&ugrave; conosciuto al mondo: il Protocollo di Montreal, per proteggere la cappa di ozono.<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[38,4,11,1,27,30,25],"tags":[],"class_list":["post-841","post","type-post","status-publish","format-standard","hentry","category-sviluppo","category-ambiente","category-columnas","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-nord-america","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=841"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/841\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}