{"id":741,"date":"2007-03-27T11:37:01","date_gmt":"2007-03-27T11:37:01","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2007\/03\/27\/pena-di-morte-cina-lettere-dal-braccio-della-morte\/"},"modified":"2007-03-27T11:37:01","modified_gmt":"2007-03-27T11:37:01","slug":"pena-di-morte-cina-lettere-dal-braccio-della-morte","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2007\/03\/27\/pena-di-morte-cina-lettere-dal-braccio-della-morte\/","title":{"rendered":"PENA DI MORTE-CINA: Lettere dal braccio della morte"},"content":{"rendered":"<p>PECHINO, 27 marzo 2007 (IPS) &#8211; Il loro numero &egrave; tab&ugrave;. Le loro storie, condannate all&rsquo;oblio. Il mondo dei detenuti nel braccio della morte in Cina &egrave; troppo spaventoso, e le ragioni delle esecuzioni troppo sordide, perch&eacute; se ne possa scrivere senza sfuggire al controllo dei censori di stato comunisti.<\/p>\n<p><!--more--><\/p>\n<p>Ma proprio in virt&ugrave; della sua semplicit&agrave;, &ldquo;Lettere dal braccio della morte&rdquo;, di recente pubblicazione, ha avuto successo, laddove altri lavori pi&ugrave; ambiziosi avrebbero probabilmente fallito. Il volume narra la storia di 22 prigionieri cinesi nel braccio della morte, uomini e donne. Raccontati direttamente dalle celle delle loro prigioni. La storia &egrave; avvincente perch&eacute; lascia trapelare la rara onest&agrave; dei condannati, a poche ore dalla loro morte.<\/p>\n<p>Il libro non aspira a diventare ci&ograve; che fu il resoconto romanzato di Truman Capote di un omicidio sensazionale negli Stati Uniti degli anni &rsquo;60, &ldquo;A sangue freddo&rdquo;. Huan Jingting, l&rsquo;autore, ha dichiarato che il suo intento non era discutere del valore della pena di morte; e nemmeno scrivere un&rsquo;analisi sulle divisioni sociali.<\/p>\n<p>&ldquo;Questo libro &egrave; stato scritto come un tributo alla vita umana&rdquo;, ha detto. &ldquo;A mio parere, non c&rsquo;&egrave; niente di pi&ugrave; umile della vita umana&rdquo;.<\/p>\n<p>Ci&ograve; che suggerisce parallelismi con il lavoro di Capote, tuttavia, sono le osservazioni comprensive di Huan sulla mente criminale. Le sue pagine sono popolate di criminali comuni &#8211; rapinatori e contrabbandieri, la cui lotta per la vita finisce, per qualche motivo inspiegabile e crudele, nella camera d&rsquo;esecuzione.<\/p>\n<p>Cos&igrave; &egrave; la storia di Wen Shou, un ingenuo ragazzo di 19 anni di Chongqing, nella Cina centrale, che viene usato da spacciatori senza scrupoli come intermediario in una catena di consegne, e poco a poco trasformato in un tossicodipendente. Quando gli viene offerta la prima costosa sigaretta &ldquo;straniera&rdquo;, con una indulgente pacca sulla spalla, Wen non sa che questo sar&agrave; l&rsquo;inizio di una spirale verso il basso, destinata a trascinarlo fino nel braccio della morte. <\/p>\n<p>&ldquo;Mentre inalava quell&rsquo;odore pungente, pensava: che differenza, tra questa roba straniera e le sigarette cinesi economiche che vendono nei chioschi per strada&rdquo;.<\/p>\n<p>Oppure la storia del ragazzo di campagna Liu Yuan, che a vent&#039;anni era stato arrestato e rieducato nei campi di lavoro per piccoli furti cos&igrave; tante volte, che non riuscir&agrave; pi&ugrave; a trovare un lavoro nel suo villaggio. Lascer&agrave; la campagna per la fiorente citt&agrave; di Shenzhen, nel sud della Cina, dove milioni di migranti lavorano in fabbriche che sfruttano la manodopera.<\/p>\n<p>Il suo carattere rude di teppista di campagna piace al delicato boss di un&rsquo;agenzia di casting di Shenzhen, e invece di lavorare come trasportatore, Liu diventa un &ldquo;modello che interpreta il ruolo di gangster&rdquo;. Per mantenere il profilo &ldquo;cool&rdquo; di questa sua nuova immagine, Liu si ritrova alla fine costretto a diventare un vero gangster.<\/p>\n<p>A Huan Jingting non &egrave; stato permesso registrare le ultime parole di funzionari di alto livello condannati a morte per corruzione, poich&eacute; costoro, ha detto, vengono tenuti in un carcere speciale. Il suo libro &egrave; quindi uno studio sulla morte nella vita delle persone svantaggiate. Anche gli assassini di cui traccia il profilo vengono rappresentati in una luce compassionevole, quasi tutti perpetratori involontari dei crimini di cui sono imputati.<\/p>\n<p>&ldquo;Mamma, mia cara mamma, spero che non ti affliggerai troppo a lungo, e che potrai presto perdonare questo tuo figlio ignorante&rdquo;, si legge nella lettera di addio di Ai Qiang, un ragazzo di appena 20 anni che aspetta la morte per aver derubato e ucciso uno straniero per strada. &ldquo;&Egrave; a causa dell&rsquo;ignoranza che ho rovinato la mia vita. &Egrave; a causa dell&rsquo;ignoranza che lascer&ograve; questo mondo. Spero di essere un figlio migliore nell&rsquo;aldil&agrave;. Addio. Il tuo figlio indegno&rdquo;.<\/p>\n<p>&ldquo;Oserei dire che &egrave; il primo libro in Cina che ritrae il lato umano delle persone che siamo abituati a considerare irrimediabilmente cattive&rdquo;, ha detto Huan, intervistato dall&rsquo;IPS. &ldquo;Esistono pile e pile di reportage di crimini, ma l&rsquo;ottica dello scrittore &egrave; sempre che i criminali sono nati tali&rdquo;. <\/p>\n<p>In Cina, pi&ugrave; di 60 tipi di crimini &#8211; tra cui delitti non violenti come la corruzione e l&rsquo;evasione  fiscale &#8211; sono punibili con la morte. Gli attivisti per i diritti umani condannano il fatto che le sentenze di morte vengano emesse con troppa leggerezza, portando a terribili errori giudiziari.<\/p>\n<p>Le autorit&agrave; cinesi non rivelano il numero delle esecuzioni ordinate dai tribunali. Nel 2005, Amnesty International ha registrato 1.770 esecuzioni in Cina, o pi&ugrave; dell&rsquo;80 per cento di tutte le sentenze di morte eseguite nel mondo. Ma secondo gli esperti il numero effettivo di pene capitali raggiunge addirittura  le 10.000 esecuzioni l&rsquo;anno.<\/p>\n<p>Anche se negli ultimi anni sembra essersi intensificato il dibattito pubblico sulla necessit&agrave; di limitare una cos&igrave; ampia applicazione della pena di morte, la maggioranza della popolazione, secondo gli esperti, sarebbe in sostanza favorevole alla pena capitale come l&rsquo;unico modo per assicurare che i grandi criminali abbiano ci&ograve; che meritano. <\/p>\n<p>Il progetto di un libro incentrato su un tema cos&igrave; delicato come la pena di morte non era qualcosa in cui Huan Jingting aveva mai pensato di imbarcarsi di sua spontanea volont&agrave;. Ma alla fine degli anni &rsquo;90 fu condannato per frode, e fu detenuto, con una pena di un anno e mezzo da scontare in una prigione di Chongqing. Proprio perch&eacute; sapeva leggere e scrivere, gli fu chiesto di scrivere le ultime volont&agrave; dei prigionieri condannati a morte, alla scadenza della sua pena. <\/p>\n<p>E cos&igrave; ha riportato le storie dei carcerati nel braccio della morte. &ldquo;&Egrave; stata un&rsquo;esperienza che ha cambiato irrevocabilmente la mia vita&rdquo;, ricorda Huan. &ldquo;Mi ha reso pi&ugrave; tollerante&rdquo;.<\/p>\n<p>Ha imparato a portare con s&eacute; un pacchetto di sigarette ogni volta che entrava nelle celle dei prigionieri nel braccio della morte, nelle ore precedenti le esecuzioni. I detenuti pensano che fumando una sigaretta nelle ultime ore di vita, la loro morte sar&agrave; meno dolorosa, e gli sar&agrave; garantita la rinascita in una buona famiglia. <\/p>\n<p>Huan trascrive solo i fatti principali, passando pi&ugrave; tempo ad ascoltare le loro storie. In vero stile Capote, i suoi resoconti fondono con successo il reportage giornalistico dei fatti con lo stile narrativo del romanzo.<\/p>\n<p>Ha cambiato i nomi di tutti i prigionieri, riportando meticolosamente la topografia e i veri nomi dei luoghi. Le prime dodici storie sono state pubblicate nel 2001, ma la raccolta completa &egrave; uscita solo nell&rsquo;autunno dello scorso anno.<\/p>\n<p>Pur rifiutando intenti di critica sociale, il volume di Huan &egrave; un potente ritratto del sottoproletariato cinese, che dovr&agrave; sostenere il peso delle riforme economiche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PECHINO, 27 marzo 2007 (IPS) &#8211; Il loro numero &egrave; tab&ugrave;. Le loro storie, condannate all&rsquo;oblio. Il mondo dei detenuti nel braccio della morte in Cina &egrave; troppo spaventoso, e le ragioni delle esecuzioni troppo sordide, perch&eacute; se ne possa&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2007\/03\/27\/pena-di-morte-cina-lettere-dal-braccio-della-morte\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":66,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[8,11,14,15,1,27,25,31],"tags":[],"class_list":["post-741","post","type-post","status-publish","format-standard","hentry","category-asia-e-oceania","category-columnas","category-cultura","category-diritti-umani","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile","category-pena-capitale"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=741"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/741\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}