{"id":683,"date":"2006-12-21T18:04:54","date_gmt":"2006-12-21T18:04:54","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/12\/21\/sfide-2006-2007-un-popolo-sotto-assedio\/"},"modified":"2006-12-21T18:04:54","modified_gmt":"2006-12-21T18:04:54","slug":"sfide-2006-2007-un-popolo-sotto-assedio","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/12\/21\/sfide-2006-2007-un-popolo-sotto-assedio\/","title":{"rendered":"SFIDE 2006-2007: Un popolo sotto assedio"},"content":{"rendered":"<p>NEW YORK, 21 dicembre 2006 (IPS) &#8211; Cinque anni dopo gli attacchi terroristici dell&rsquo;11 settembre 2001, l&rsquo;&ldquo;islamofobia&rdquo; &#8211; intensificatasi con la guerra in Iraq e le iniziative dei governi &#8211; ha reso milioni di musulmani qui e in altri paesi occidentali timorosi di molestie, discriminazioni e dubbie persecuzioni, e confusi sul loro ruolo nella societ&agrave;.<\/p>\n<p><!--more--><\/p>\n<p>Recenti sondaggi indicano che quasi la met&agrave; dei cittadini americani ha una percezione negativa dell&rsquo;Islam, e che una persona su quattro ha una visione &ldquo;estremamente&rdquo; anti-musulmana. In un&rsquo;inchiesta condotta dal Consiglio per le relazioni americano-islamiche (CAIR) &egrave; emerso che un quarto degli abitanti degli Usa crede a stereotipi come: &ldquo;I musulmani danno un valore diverso alla vita rispetto ad altri popoli&rdquo;, e &ldquo;la religione musulmana insegna la violenza e l&rsquo;odio&rdquo;.<\/p>\n<p>Nel 2005, CAIR ha ricevuto 1.972 reclami sui diritti civili, rispetto ai 1.522 del 2004. E cio&egrave; il 29,6 per cento in pi&ugrave; rispetto ai ricorsi nel 2004 per molestie, violenze e comportamenti discriminatori contro i musulmani. &Egrave; il maggior numero di reclami per i diritti civili dei musulmani mai presentati a CAIR.<\/p>\n<p>Qual &egrave; l&rsquo;impatto sui musulmani e sugli altri americani di origine araba? Una persona, che ha preferito rimanere anonima, ha detto all&rsquo;IPS: &ldquo;Talvolta ci si sente soffocare a vivere negli Usa oggi. Non possiamo accendere la televisione per vedere la CNN o la MSNBC, o altri canali di notizie, a causa di persone come Glenn Beck, o altri che sputano continuamente odio, fandonie e mala informazione sull&rsquo;Islam e sugli arabi, in prima serata&rdquo;.<\/p>\n<p>&ldquo;E se vogliamo vedere uno spettacolo qualsiasi in televisione, veniamo bombardati da programmi sul terrorismo mediorientale\/arabo e islamico; trasmissioni come &ldquo;24&rdquo;, &ldquo;Sleeper Cell&rdquo;, &ldquo;The Agency&rdquo;, ecc. &Egrave; molto difficile essere un americano arabo\/musulmano al giorno d&rsquo;oggi&rdquo;.<\/p>\n<p>Dopo l&rsquo;11 settembre, il Dipartimento di giustizia Usa (DOJ) ha cominciato a non fare pi&ugrave; distinzione tra gli arabi e gli altri musulmani e, erroneamente, chiunque avesse un aspetto &ldquo;mediorientale&rdquo;, compresi i Sikh dell&rsquo;Asia meridionale. Nei mesi immediatamente successivi agli attacchi, 5.000 uomini sono stati trattenuti senza accuse formali, la maggior parte di essi senza poter contattare un avvocato o i propri familiari. Come conferma un&rsquo;inchiesta dell&rsquo;ispettore generale del DOJ, molti sono stati incarcerati e tenuti in isolamento e hanno subito abusi fisici.<\/p>\n<p>Nessuna di queste persone ha subito procedimenti legali o condanne. Alcuni, che si trovavano negli Usa con un visto scaduto o avevano commesso altre trasgressioni relative all&rsquo;immigrazione, sono stati espulsi dal paese.<\/p>\n<p>Da allora, l&rsquo;elenco apparentemente infinito di molestie e abusi dei diritti civili dei cittadini Usa &egrave; andato inesorabilmente infoltendosi. Alcuni esempi:<\/p>\n<p>Ahmad Al Halabi si &egrave; diplomato all&rsquo;istituto superiore di Dearborn, Michigan, nucleo della comunit&agrave; musulmana del paese. Si &egrave; poi arruolato nell&rsquo;aviazione ed &egrave; stato mandato come traduttore dei sospetti membri di al Qaeda presso il centro di detenzione di Guantanamo, Cuba. Ma &egrave; stato accusato di spionaggio e ha dovuto trascorrere 10 mesi in isolamento, prima che fossero ritirate le accuse contro di lui. <\/p>\n<p>Osama Abulhassan e Ali Houssaiky, entrambi 20enni di Dearborn, sono stati accusati lo scorso agosto di sostegno al terrorismo a Marietta, Ohio, dopo aver acquistato una grossa quantit&agrave; di carte telefoniche prepagate a basso costo in magazzini discount. Le accuse sono cadute dopo una settimana.<\/p>\n<p>Farooq Al-Fatlawi, che stava viaggiando in autobus verso Chicago, &egrave; stato fatto scendere dal mezzo con i propri bagagli a Toledo, Ohio, dopo aver detto all&rsquo;autista di essere iracheno.<\/p>\n<p>A San Francisco Bay, Raed Jarrar, un attivista per i diritti civili, non ha potuto imbarcarsi su un aereo perch&eacute; indossava una maglietta con la scritta: &ldquo;Non resteremo in silenzio&rdquo;, in arabo e in inglese.<\/p>\n<p>Sei imam che erano stati visti pregare in un aeroporto di Minneapolis sono stati fatti scendere da un aereo della US Airways, dopo che un passeggero ha dichiarato all&rsquo;assistente di volo di aver visto gli uomini comportarsi in modo sospetto. Gli imam sono stati portati fuori dall&rsquo;aereo in manette. Sono stati interrogati e poi rilasciati, ma la compagnia aerea ha dichiarato che l&rsquo;equipaggio aveva agito bene nel respingere gli imam, e ha rifiutato di emettere nuovi biglietti per il giorno successivo. Gli imam hanno fatto causa alla compagnia.<\/p>\n<p>In un altro caso spesso citato come esempio di islamofobia, il musulmano canadese\/siriano Maher Arar &egrave; stato sequestrato da alcuni funzionari Usa all&rsquo;aeroporto Kennedy di New York nel 2002, e poi deportato in un carcere in Siria, dove &egrave; rimasto prigioniero per pi&ugrave; di 10 mesi in una cella in condizioni disumane. &Egrave; stato picchiato, torturato, e costretto ad una falsa confessione sui suoi presunti legami con al Qaeda. Una commissione d&rsquo;inchiesta canadese ha sentenziato, dopo una investigazione durata due anni, che tutte le accuse erano infondate. Ma ad Arar &egrave; stato impedito di sporgere denuncia contro il governo Usa, il quale ha spiegato che con un processo si sarebbero divulgati &ldquo;segreti di stato&rdquo;.<\/p>\n<p>Il Dipartimento del tesoro Usa, nell&rsquo;intento di tagliare i finanziamenti alle organizzazioni islamiche radicali, ha utilizzato un provvedimento del Patriot Act per definire organizzazioni terroristiche gli enti di beneficenza che sostengano la causa musulmana. Quando una di queste organizzazioni di volontariato viene definita sostenitrice del terrorismo, tutto il suo materiale e le sue propriet&agrave; vengono requisite, e i suoi beni congelati.<\/p>\n<p>Fino ad oggi, questo intento ha portato alla chiusura da parte del governo di cinque istituti di beneficenza. Ma &egrave; stata formulata solo un&rsquo;accusa; nessun processo, e nessuna condanna. &Egrave; stata sporta solo un&rsquo;accusa penale ufficiale contro un&rsquo;organizzazione musulmana per appoggio al terrorismo, ma il caso non &egrave; ancora passato in giudizio. Tre mesi fa, alcuni agenti federali hanno fatto irruzione in uno dei maggiori istituti di beneficenza islamici del paese, Life for Relief and Development. Gli agenti hanno sequestrato i computer e i registri dei donatori. Ma non &egrave; stata formulata nessuna accusa, e l&rsquo;organizzazione &egrave; ancora operativa.<\/p>\n<p>Molti americani musulmani sono impiegati nelle forze armate Usa, mentre hanno meno fortuna se cercano un lavoro presso agenzie civili incaricate della sicurezza nazionale. Quando l&rsquo;FBI, la CIA e il DHS (Dipartimento per la sicurezza nazionale) hanno avuto un forte bisogno di reperire ed assumere nuovi analisti e traduttori, molti arabo-americani e altri musulmani americani hanno fatto domanda. Ma non hanno avuto molto successo, poich&eacute; spesso vengono negate loro le autorizzazioni di sicurezza, sulla base del fatto che hanno amici e familiari in Medio Oriente.<\/p>\n<p>Ma questa isteria post 11 settembre non si limita ai soli Stati Uniti. In Gran Bretagna, anch&rsquo;essa vittima di attacchi terroristici, il parlamentare ed ex ministro degli esteri Jack Straw ha suggerito che le sue elettrici musulmane si togliessero il velo con cui coprono il proprio viso, cos&igrave; che lui potesse interagire meglio con loro. <\/p>\n<p>E i tentativi del governo britannico di impegnarsi con la comunit&agrave; musulmana dopo le bombe a Londra dello scorso anno, sembra gli si siano rivoltati contro, e non sono in grado di ostacolare la diffusione del fondamentalismo. Un rapporto del think tank Demos riferisce che &ldquo;invece di isolare gli elementi estremisti, le iniziative del governo hanno portato ad &lsquo;ampliare la distanza&rsquo; tra la popolazione musulmana e il resto della comunit&agrave;&rdquo;.<\/p>\n<p>In Olanda, un tempo considerata la societ&agrave; pi&ugrave; aperta e tollerante in Europa, il governo di centro-destra ha promesso di introdurre una legislazione per proibire l&rsquo;uso del burqa e di altri veli sul viso in quasi tutti i luoghi pubblici, tra cui tribunali, scuole, treni e persino in strada.<\/p>\n<p>La Francia, sconvolta la scorsa estate dai tumulti nelle periferie povere di Parigi, abitate in gran parte da immigrati nordafricani e mediorientali, ha gi&agrave; vietato agli studenti nelle scuole pubbliche di indossare veli che coprano il capo. Nicolas Sarkozy, un ministro del governo e tra i candidati favoriti per la presidenza del paese, ha adottato la linea dura sia verso l&rsquo;immigrazione che nei confronti della vasta popolazione musulmana della Francia. Sostiene di non volere l&rsquo;Islam &ldquo;in Francia&rdquo;, ma di sostenere &ldquo;un Islam francese&rdquo;.<\/p>\n<p>Negli Usa, il governo riconosce le proteste degli arabi e musulmani americani. Daniel Sutherland, a capo della divisione diritti civili del Dipartimento della sicurezza nazionale, dice che combattere il terrorismo rispettando al tempo stesso i diritti civili, implica &ldquo;sfide difficili&rdquo;.<\/p>\n<p>Ma secondo Sutherland, il governo ha bisogno dell&rsquo;aiuto di questi gruppi nella lotta contro il terrorismo nel paese: &ldquo;La sicurezza nazionale non verr&agrave; conquistata da persone sedute in un palazzo nella Beltway&rdquo;, ha affermato.<\/p>\n<p>La maggior parte dei membri di questa comunit&agrave; pensa che il governo stia &#8211; forse inavvertitamente &#8211; alimentando il fuoco del bigottismo, con l&rsquo;uso di frasi come &ldquo;islamico-fascisti&rdquo;, prese dal vocabolario che ha coniato per la &ldquo;guerra globale al terrore&rdquo;, e con iniziative come conferenze stampa di alto profilo annunciando persecuzioni che spesso falliscono. <\/p>\n<p>Samer Shehata, professore di politica araba presso la Georgetown University, parla probabilmente a nome della maggior parte della comunit&agrave; musulmana negli Usa: &ldquo;Semplicemente&rdquo;, ha detto all&rsquo;IPS, l&rsquo;islamofobia &ldquo;produce un ambiente che &egrave; fondamentalmente in conflitto con il modello che si presume rappresenti gli stessi Stati Uniti, con i nostri valori di un comportamento giusto e uguale per tutti, senza discriminazioni in base al colore della pelle, alla razza, religione, genere, ecc.&rdquo;   &rdquo;Questo sta certamente danneggiando tutti gli americani, e danneggia anche la reputazione degli Usa all&rsquo;estero&rdquo;, ha sostenuto. &ldquo;Uno degli interrogativi che sento pi&ugrave; spesso mentre sono in Egitto o in altre parti del Medio Oriente &egrave;: Com&rsquo;&egrave; adesso la situazione per gli arabi negli Usa? Siete vittime di discriminazioni, di bigottismo, di abusi?&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NEW YORK, 21 dicembre 2006 (IPS) &#8211; Cinque anni dopo gli attacchi terroristici dell&rsquo;11 settembre 2001, l&rsquo;&ldquo;islamofobia&rdquo; &#8211; intensificatasi con la guerra in Iraq e le iniziative dei governi &#8211; ha reso milioni di musulmani qui e in altri paesi&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/12\/21\/sfide-2006-2007-un-popolo-sotto-assedio\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":139,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[11,15,1,27,28,30,25,32,33],"tags":[],"class_list":["post-683","post","type-post","status-publish","format-standard","hentry","category-columnas","category-diritti-umani","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-medioriente","category-nord-america","category-obiettivi-di-sviluppo-sostenibile","category-politica","category-popolazione"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}