{"id":603,"date":"2006-08-16T11:05:28","date_gmt":"2006-08-16T11:05:28","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/08\/16\/ambiente-italia-la-valle-amica-dellambiente-un-modello-per-leuropa\/"},"modified":"2006-08-16T11:05:28","modified_gmt":"2006-08-16T11:05:28","slug":"ambiente-italia-la-valle-amica-dellambiente-un-modello-per-leuropa","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/08\/16\/ambiente-italia-la-valle-amica-dellambiente-un-modello-per-leuropa\/","title":{"rendered":"AMBIENTE-ITALIA: La valle &#8216;amica dell&#8217;ambiente&#8217; &egrave; un modello per l&#8217;Europa"},"content":{"rendered":"<p>MILANO, 16 agosto 2006 (IPS) &#8211; Esempio di convivenza tra economia salutare, cura ambientale e benessere sociale, Varese Ligure, nell&rsquo;entroterra ligure della Val di Vara, provincia di La Spezia, &egrave; forse la comunit&agrave; pi&ugrave; pulita &egrave; pi&ugrave; &ldquo;amica dell&rsquo;ambiente&rdquo; in Europa.<\/p>\n<p><!--more--><\/p>\n<p>Dall&rsquo;agricoltura all&rsquo;allevamento, dall&rsquo;energia rinnovabile al riciclaggio dei rifiuti, dal turismo sostenibile ai programmi sociali: ogni cosa in questa cittadina &#8211; che si estende per oltre 1.600 ettari tra le montagne della provincia ligure &#8211; viene realizzato nel pi&ugrave; rigoroso rispetto per la natura.<\/p>\n<p>Questo comune, dove vivono appena 2.350 persone, era destinato a rimanere escluso dagli itinerari turistici. La popolazione stava invecchiando, e i pi&ugrave; giovani preferivano le grandi citt&agrave; per cercare lavoro.<\/p>\n<p>Il declino ha spinto le autorit&agrave; locali a cambiare il tradizionale modello di sviluppo verso un approccio sostenibile, che negli ultimi 14 anni ha trasformato Varese Ligure in un esempio da seguire sia in Italia che in Europa.<\/p>\n<p>&Egrave; la prima comunit&agrave; ad aver ricevuto le certificazioni europee per l&rsquo;ambiente (ISO-14001 nel 1999, e EMAS II nel 2002), oltre al premio come &ldquo;migliore comunit&agrave; rurale del vecchio continente&rdquo;, nel 2004.<\/p>\n<p>&ldquo;I servizi funzionano bene e nel rispetto per l&rsquo;ecologia, e la pulizia &egrave; la conseguenza di questa politica. L&rsquo;ambiente era l&rsquo;unica risorsa che avevamo a disposizione, e l&rsquo;unica cosa che potevamo sfruttare. Perci&ograve; i benefici sono di tutti&rdquo;, ha spiegato a Tierram&eacute;rica il sindaco di Varese Ligure, Michela Marcone.<\/p>\n<p>Il novanta per cento del territorio &egrave; coltivato biologicamente: frutta e verdura non vengono trattate con pesticidi n&eacute; altri prodotti chimici; e anche gli animali, in particolare capre e bovini, vengono allevati secondo il &#039;credo&#039; eco-sostenibile.<\/p>\n<p>Uno degli esempi &egrave; la cooperativa Cibele. &ldquo;Non &egrave; facile seguire le regole, perch&eacute; sono molto rigide, e vengono eseguiti controlli durante tutto l&rsquo;anno&rdquo;, ha detto a Tierram&eacute;rica il proprietario, Percy Wochiecivich.<\/p>\n<p>La conversione dalle normali pratiche commerciali alle tecniche agricole sostenibili ha beneficiato 50 cooperative rurali dell&rsquo;area, che riforniscono le mense scolastiche locali e vendono i loro prodotti ai supermercati e ai centri vicini. Quasi tutte hanno aumentato la loro forza lavoro e le entrate, come la cooperativa Pietro Vara (750.000 euro all&rsquo;anno) e la Casearia (1,3 milioni di euro).<\/p>\n<p>Varese Ligure &egrave; pioniera nella cura per la qualit&agrave; dell&rsquo;ambiente. La cittadina ha quattro turbine eoliche, alte 46 metri e con una media di velocit&agrave; del vento di 7,2 metri al secondo; permette un risparmio nei costi energetici di 30.000 euro all&rsquo;anno, oltre ad evitare l&rsquo;emissione di 8.000 tonnellate di anidride carbonica. <\/p>\n<p>La citt&agrave; possiede anche dei pannelli solari che producono energia secondo le dimensioni e la quantit&agrave; di luce solare che ricevono le celle, producendo circa 23.000 kilowatt in pi&ugrave;, e consentendo un risparmio di 9.600 kg di emissioni di anidride carbonica (principale causa dell&rsquo;effetto serra). Una diga idroelettrica fornisce energia alle case di 3.000 persone.<\/p>\n<p>La produzione di rifiuti in questa &ldquo;eco-valle&rdquo; &egrave; precipitata a 350 kg per persona, comparata ad una media provinciale di 530 kg a persona.<\/p>\n<p>&ldquo;&Egrave; una delle comunit&agrave; pi&ugrave; avanzate in Europa in termini di ambiente, e un esempio di come amministrare un territorio particolare, praticamente in montagna, e con molti problemi&rdquo;, ha fatto notare a Tierram&eacute;rica Stefano Sarti, presidente regionale dell&rsquo;organizzazione non governativa italiana Legambiente.<\/p>\n<p>Il turismo sostenibile &egrave; in crescita a Varese Ligure, attirando i viaggiatori in cerca di pace e tranquillit&agrave;, che amano la natura, e che riescono ad adattarsi alle norme ambientali. Gran parte dei visitatori provengono da Germania e Gran Bretagna, e apprezzano gli sforzi di questa ordinata comunit&agrave; italiana.<\/p>\n<p>&ldquo;I giovani sono in parte tornati, perch&eacute; sono stati creati 140 nuovi posti di lavoro, e turismo e commercio sono aumentati. Oggi gli abitanti si sentono orgogliosi: sono i protagonisti di questi cambiamenti, e sono motivati a rimanere&rdquo;, ha osservato il presidente dell&rsquo;associazione Qualitambiente, Maurizio Caranza, in una conversazione con Tierram&eacute;rica.<\/p>\n<p>(* Francesca Colombo &egrave; collaboratrice di Tierram&eacute;rica. L&rsquo;articolo &egrave; stato pubblicato per la prima volta il 5 agosto dai quotidiani latinoamericani che fanno parte della rete di Tierram&eacute;rica, un servizio speciale di notizie prodotto dall&rsquo;IPS con il supporto del Programma di sviluppo delle Nazioni Unite).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MILANO, 16 agosto 2006 (IPS) &#8211; Esempio di convivenza tra economia salutare, cura ambientale e benessere sociale, Varese Ligure, nell&rsquo;entroterra ligure della Val di Vara, provincia di La Spezia, &egrave; forse la comunit&agrave; pi&ugrave; pulita &egrave; pi&ugrave; &ldquo;amica dell&rsquo;ambiente&rdquo; in&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/08\/16\/ambiente-italia-la-valle-amica-dellambiente-un-modello-per-leuropa\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[4,38,11,22,1,27,25,32,33],"tags":[],"class_list":["post-603","post","type-post","status-publish","format-standard","hentry","category-ambiente","category-sviluppo","category-columnas","category-europa","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile","category-politica","category-popolazione"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=603"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/603\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}