{"id":601,"date":"2006-08-10T12:39:23","date_gmt":"2006-08-10T12:39:23","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/08\/10\/energia-nigeria-lenergia-solare-in-aiuto-dei-villaggi\/"},"modified":"2006-08-10T12:39:23","modified_gmt":"2006-08-10T12:39:23","slug":"energia-nigeria-lenergia-solare-in-aiuto-dei-villaggi","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/08\/10\/energia-nigeria-lenergia-solare-in-aiuto-dei-villaggi\/","title":{"rendered":"ENERGIA-NIGERIA: L&#8217;energia solare in aiuto dei villaggi"},"content":{"rendered":"<p>LAGOS, 10 agosto 2006 (IPS) &#8211; Bishop Kodji, una piccola isola di pescatori e intagliatori di canoe nell&rsquo;Oceano Atlantico, di fronte al vasto snodo commerciale nigeriano di Lagos, &egrave; il primo villaggio collegato alla rete elettrica grazie al progetto pilota di energia solare realizzato dall&rsquo;amministrazione dello stato di Lagos.<\/p>\n<p><!--more--><\/p>\n<p>Prima dell&rsquo;attuazione del progetto, il villaggio, che ha una popolazione di 5.000 abitanti, non conosceva l&rsquo;energia elettrica. <\/p>\n<p>Per portare i servizi sull&rsquo;isola, che poteva essere raggiunta solo via mare, l&rsquo;amministrazione dello stato aveva deciso di introdurre il progetto di energia solare lo scorso maggio. <\/p>\n<p>Secondo i funzionari di governo, altri diciannove villaggi remoti avrebbero beneficiato del progetto entro la fine dell&rsquo;anno. <\/p>\n<p>&rdquo;Con il clima tropicale, l&rsquo;energia solare &egrave; la forma di energia rinnovabile alternativa pi&ugrave; accessibile in Nigeria. Sfruttare l&rsquo;energia del sole per produrre corrente elettrica &egrave; un imperativo per le aree rurali, dove la  speranza di essere collegati alla rete nazionale &egrave; molto remota ed estremamente costosa&rdquo;, ha dichiarato in giugno a Ikeja, capitale del Lagos, Kadiri Hamzat, Commissario dello Stato di Lagos per le scienze e la tecnologia, informando i giornalisti sulle attivit&agrave; del suo ministero nell&rsquo;ultimo anno. <\/p>\n<p>Hamzat ha dichiarato che la tecnologia dell&rsquo;energia solare &egrave; meno cara dell&rsquo;elettricit&agrave; generata dalla nuova compagnia elettrica, la Power Holding Company of Nigeria (PHCN), che ha sostituito la National Electric Power Authority (NEPA); ma la fornitura del servizio &egrave; peggiorata dopo il suo insediamento. In teoria, &egrave; cambiato soltanto il nome, ma &egrave; ancora il gruppo NEPA a gestire la nuova societ&agrave;. <\/p>\n<p>Hamza ha riferito: &ldquo;Collegare ogni villaggio alla rete nazionale costa circa 150 milioni di naira (quasi 1,2 milioni di dollari), mentre il progetto per l&rsquo;energia solare richiede appena 10 milioni di naira (circa 83.000 dollari) per villaggio&rdquo;. <\/p>\n<p>Un progetto analogo realizzato nel 2002 dal governo nigeriano, con l&rsquo;assistenza del governo giapponese, aveva illuminato 200 comunit&agrave; rurali negli stati di Imo, Ondo e Jigawa, e ad Abuja, capitale della nazione. <\/p>\n<p>Durante una visita nel settembre 2001 a Tokyo, in Giappone, il presidente Olusegun Obasanjo aveva chiesto al governo giapponese di aiutare la Nigeria con energia solare a basso costo, per migliorare la fornitura di elettricit&agrave; nel paese. <\/p>\n<p>In Nigeria, l&rsquo;energia solare &egrave; utilizzata per molte applicazioni, come l&rsquo;illuminazione dei villaggi, gli impianti idrici e l&rsquo;irrigazione per scopi agricoli. <\/p>\n<p>Nel villaggio di Bishop Kodji, che vive principalmente di pesca e costruzione di barche, oggi gli abitanti fanno seccare il pesce con apparecchiature alimentate ad energia solare, e guardano la televisione nell&rsquo;unica sala della comunit&agrave;; anche chiese e moschee, cos&igrave; come la strada principale, sono state illuminate. <\/p>\n<p>&rdquo;Il progetto ci ha procurato una grande allegria e ci ha aiutato molto. Il governo ora &egrave; pi&ugrave; vicino e abbiamo un maggiore accesso all&rsquo;informazione rispetto a prima, quando dipendevamo dalle radio a batteria. Adesso possiamo guardare la televisione e ricaricare i nostri telefoni cellulari&rdquo;, ha spiegato all&rsquo;IPS Solomon Hennu, segretario dell&rsquo;Associazione per lo sviluppo della comunit&agrave; di Kodji, durante una visita sull&rsquo;isola lo scorso giugno. <\/p>\n<p>Ezekiel Huehunmey, responsabile dell&rsquo;unica scuola elementare del villaggio di Bishop Kodji, &egrave; ottimista circa l&rsquo;aumento delle iscrizioni e della frequenza scolastica. <\/p>\n<p>&rdquo;Data l&rsquo;inadeguatezza delle aule, la maggior parte dei nostri figli viaggia in mare aperto per andare a scuola in citt&agrave;. Con l&rsquo;elettricit&agrave; e un maggior numero di aule, per loro si ridurr&agrave; il rischio legato al ribaltamento delle canoe. Il numero di iscritti potr&agrave; aumentare e sar&agrave; possibile organizzare due turni &ndash; mattina e pomeriggio&rdquo;, ha dichiarato. <\/p>\n<p>Eppure il sistema solare non &egrave; infallibile. <\/p>\n<p>Recentemente, l&rsquo;impianto sull&rsquo;isola &egrave; rimasto bloccato per due giorni. &ldquo;Quando sono venuti a ripararlo, i funzionari  di governo hanno detto che il guasto era dovuto a un sovraccarico del sistema. Hanno riavviato l&rsquo;impianto, raccomandando alla popolazione di non sovraccaricarlo&rdquo;, ha dichiarato Huehunmey. <\/p>\n<p>Oggi gli abitanti del villaggio sfruttano quasi completamente l&rsquo;elettricit&agrave; del sistema solare, mentre la popolazione di Orile, un sobborgo di Lagos, &egrave; collegata alla rete PHCN, e continua a subire frequenti interruzioni dell&rsquo;alimentazione. <\/p>\n<p>&rdquo;Da gennaio, non abbiamo mai avuto nella zona elettricit&agrave; funzionante per un&rsquo;intera giornata. Adesso tutti usano un generatore&rdquo;, ha dichiarato Sunday Onyema, abitante di Orile. Ogni generatore costa circa 66 dollari. <\/p>\n<p>Ma anche i generatori hanno un prezzo: il fuoco. Onyema, proprietario di un negozio, ha raccontato all&rsquo;IPS che a giugno uno dei residenti ha incendiato un edificio a un piano, dopo aver lasciato acceso un generatore portatile a tarda notte, che ha provocato un incendio distruggendo l&rsquo;intero fabbricato. Anche Ilebrick, un sobborgo povero di Lagos, il 9 luglio &egrave; stato colpito da un incendio nel cuore della notte, mentre uno degli abitanti cercava di ricaricare un generatore portatile. <\/p>\n<p>In Nigeria, negli ultimi 20 anni, l&rsquo;elettricit&agrave; &egrave; sempre stata inaffidabile, soprattutto a causa dell&rsquo;incuria nel settore energetico da parte dei regimi militari che hanno guidato il paese per quasi tutti gli anni &lsquo;80 e &lsquo;90. La democrazia in Nigeria &egrave; arrivata solo nel 1999, dopo il fallimento del secondo tentativo democratico (1979-1983), stroncato dall&rsquo;esercito che nel 1966 aveva rovesciato la prima repubblica con un colpo di stato. <\/p>\n<p>Secondo l&rsquo;Organizzazione dei paesi esportatori di petrolio (OPEC) con sede a Vienna, la Nigeria, sesto esportatore di petrolio grezzo nel mondo, dipende ancora dai prodotti raffinati di importazione. Le quattro raffinerie della Nigeria, con una capacit&agrave; totale di 445.000 barili al giorno, operano al di sotto della loro capacit&agrave;, a causa della strumentazione obsoleta. <\/p>\n<p>Secondo il Dipartimento per le risorse petrolifere, organo governativo dell&rsquo;industria del petrolio, la Nigeria consuma ogni giorno 30 milioni di litri di petrolio raffinato, mentre le sue quattro raffinerie ne producono in totale circa 18 milioni di litri al giorno, lasciando un disavanzo di 12 milioni di litri per l&rsquo;importazione. <\/p>\n<p>Una ricerca diffusa a maggio dall&rsquo;Associazione nigeriana manifatturieri (MAN), sostiene che in Nigeria pi&ugrave; del 60 per cento delle industrie dipende dai generatori per le principali fonti di energia, e questo, secondo lo studio, avrebbe prodotto un rincaro dei prodotti manifatturieri, che grava sui consumatori. Il fenomeno ha avuto un impatto negativo sulla competitivit&agrave; dei prodotti locali, denuncia il MAN. <\/p>\n<p>Bashir Borodo, nuovo presidente del MAN, ha rivelato ai giornalisti all&rsquo;inizio di luglio a Lagos l&rsquo;intenzione di realizzare un impianto elettrico autonomo per fornire elettricit&agrave; alle industrie. <\/p>\n<p>&rdquo;L&rsquo;esperienza dei membri dell&rsquo;associazione con il servizio di fornitura elettrica dello stato ha raggiunto livelli scoraggianti. Il peggioramento della situazione ha portato il settore manifatturiero del paese sull&rsquo;orlo del collasso&ldquo;, ha denunciato Borodo. L&rsquo;impianto dovrebbe cominciare a decollare il prossimo anno. <\/p>\n<p>Borodo ha dichiarato all&rsquo;IPS: &ldquo;Gestire il sistema solare &egrave; troppo costoso per le aziende manifatturiere, quindi non pensiamo che l&rsquo;energia solare sia una alternativa possibile per fornire elettricit&agrave; alle industrie. L&rsquo;impianto autonomo che abbiamo in programma utilizzer&agrave; il gas di cui la Nigeria &egrave; ricca per alimentare le turbine e generare elettricit&agrave;&rdquo;. <\/p>\n<p>Secondo il Bureau for Public Enterprises (BPE), istituito dal governo per liquidare beni pubblici in perdita, i danni economici dovuti all&rsquo;inaffidabilit&agrave; della rete elettrica nazionale sono di circa un miliardo di dollari all&rsquo;anno. Meno del 36 per cento dei nigeriani ha accesso all&rsquo;elettricit&agrave;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAGOS, 10 agosto 2006 (IPS) &#8211; Bishop Kodji, una piccola isola di pescatori e intagliatori di canoe nell&rsquo;Oceano Atlantico, di fronte al vasto snodo commerciale nigeriano di Lagos, &egrave; il primo villaggio collegato alla rete elettrica grazie al progetto pilota&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/08\/10\/energia-nigeria-lenergia-solare-in-aiuto-dei-villaggi\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":184,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,4,11,1,27,25],"tags":[],"class_list":["post-601","post","type-post","status-publish","format-standard","hentry","category-africa","category-ambiente","category-columnas","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/184"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=601"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/601\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}