{"id":596,"date":"2006-08-03T11:22:14","date_gmt":"2006-08-03T11:22:14","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/08\/03\/politica-iraq-e-afghanistan-tra-i-primi-dieci-stati-falliti\/"},"modified":"2006-08-03T11:22:14","modified_gmt":"2006-08-03T11:22:14","slug":"politica-iraq-e-afghanistan-tra-i-primi-dieci-stati-falliti","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/08\/03\/politica-iraq-e-afghanistan-tra-i-primi-dieci-stati-falliti\/","title":{"rendered":"POLITICA: Iraq e Afghanistan tra i primi dieci stati &#8216;falliti&#8217;"},"content":{"rendered":"<p>WASHINGTON, 3 agosto 2006 (IPS) &#8211; Nonostante abbiano ricevuto circa otto miliardi di dollari al mese in aiuti economici e militari nell&rsquo;ultimo anno, Iraq e Afghanistan sono classificati tra i 10 stati pi&ugrave; deboli del mondo, insieme a buona parte dell&rsquo;Africa<br \/>\ncentrale, stando al &#8220;Failed States Index&#8221; del  2006, la classifica degli stati falliti pubblicata di recente.<\/p>\n<p><!--more--><\/p>\n<p>Secondo il nuovo indice, diffuso da Fund for Peace e dalla rivista Foreign Policy, con sede a Washington, l&rsquo;Iraq si trova al quarto posto &shy;- lo stesso del 2005 &shy;- dopo il Sudan, in prima posizione, la Repubblica democratica del Congo (RDC), e la Costa d&rsquo;Avorio.<\/p>\n<p>Tuttavia, lo studio &egrave; stato chiuso prima dell&rsquo;ultima escalation di violenza settaria seguita al bombardamento della Moschea d&rsquo;oro di Samarra, che molti osservatori considerano la causa scatenante della guerra civile.<\/p>\n<p>L&rsquo;Afghanistan, che l&rsquo;anno scorso era all&rsquo;undicesimo posto, &egrave; passato quest&rsquo;anno in decima posizione, subito dopo il vicino Pakistan sostenuto dagli Stati Uniti, e Haiti, il terzo paese occupato dalle forze Usa, e destinatario, negli ultimi due anni, di ingenti aiuti americani.<\/p>\n<p>Tra Iraq e Haiti si posizionano tre stati sub-sahariani: lo Zimbabwe, che l&rsquo;anno scorso era al quindicesimo posto; il Ciad, il cui governo &egrave; attualmente minacciato da una rivolta militare e da incursioni delle milizie arabe sostenute dal Sudan; e la Somalia, dove, a circa 12 anni dal ritiro delle forze di pace dell&rsquo;Onu, non esiste ancora un governo centrale funzionante.<\/p>\n<p>Sei dei 10 stati pi&ugrave; vulnerabili e 11 dei primi 20 paesi definiti &ldquo;critici&rdquo; si trovano in Africa sub-sahariana. Ad eccezione di Haiti, gli altri sono sparsi intorno alla periferia dell&rsquo;Eurasia &#8212; Iraq e Yemen in Medio Oriente; Afghanistan, Pakistan, Nepal, Bangladesh, e Birmania in Asia meridionale; e Corea del Nord in Asia orientale.<\/p>\n<p>L&rsquo;indice, la cui analisi poggia su una decina di indicatori sociali,economici e politici, &egrave; in parte concepito come strumento per assicurare un preavviso alla comunit&agrave; internazionale sui possibili stati a rischio di fallimento, qualora la situazione non fosse gi&agrave; degenerata, come nel caso della Somalia.<\/p>\n<p>Per ciascun indicatore, ai paesi viene assegnato un punteggio da uno (miglior rendimento) a 10 (peggior rendimento). Il Sudan, ad esempio, ha ottenuto 7,5 sulla sua crescita economica, e pi&ugrave; di 9 sugli altri indicatori, per un totale di 112,3.<\/p>\n<p>Lo studio di quest&rsquo;anno riguarda 148 stati. Le 40 nazioni pi&ugrave; vulnerabili sono state divise in due categorie: &ldquo;critiche&rdquo; e &ldquo;in pericolo&rdquo;. Il gruppo singolo pi&ugrave; esteso, che copre la maggior parte del Terzo Mondo, oltre a Russia e Cina, &egrave; stato giudicato come &ldquo;borderline&rdquo;, mentre la parte restante &egrave; suddivisa in &ldquo;stabile&rdquo; e &ldquo;pi&ugrave; stabile&rdquo;.<\/p>\n<p>La conclusione forse inaspettata &egrave; che Stati Uniti e buona parte dell&rsquo;Europa sono stati classificati come &ldquo;stabili&rdquo;, al pari di Costa Rica, Panama,Argentina, Cile, Uruguay, Sud Africa, Oman, Corea del Sud e Mongolia.<\/p>\n<p>Il rendimento relativamente scarso degli Stati Uniti e dell&rsquo;Europa si basa fondamentalmente sull&rsquo;esistenza di &ldquo;sacche di fallimento&rdquo; nel loro territorio, come dimostrano le conseguenze dell&rsquo;Uragano Katrina, durante il quale la &ldquo;superpotenza mondiale ha abbandonato per giorni migliaia di suoi cittadini&rdquo;, e i disordini delle comunit&agrave; di immigrati esplosi in Francia l&rsquo;anno scorso, come riferisce un&rsquo;analisi dell&rsquo;indice pubblicata su Foreign Policy.<\/p>\n<p>Tra le nazioni &rdquo;pi&ugrave; sicure&rdquo;, figurano Canada, Giappone, Australia, Svizzera, Austria, Irlanda, Olanda, Belgio e i quattro paesi scandinavi.<\/p>\n<p>L&rsquo;indice ha definito come &ldquo;stato fallito&rdquo; quello in cui &ldquo;il governo non ha effettivo controllo sul proprio territorio, non &egrave; percepito come legittimo da una parte significativa della sua popolazione, non garantisce sicurezza nazionale o servizi pubblici di base ai propri abitanti, e manca dell&rsquo;esclusiva sull&rsquo;uso della forza&rdquo;.<\/p>\n<p>Lo studio &egrave; pensato per valutare il rischio di conflitti violenti o di altre forme di debolezza dello stato, piuttosto che di fallimento reale.<\/p>\n<p>L&rsquo;ultimo indice sembra sollevare seri dubbi sui principi fondanti della politica estera del presidente Bush e sul fatto che le elezioni democratiche abbiano necessariamente rafforzato la stabilit&agrave; dello stato. Malgrado il &ldquo;successo&rdquo; delle elezioni sia in Iraq che Afghanistan, la stabilit&agrave; sembra diminuita in entrambi i paesi, secondo l&rsquo;analisi di Foreign Policy.<\/p>\n<p>Come era accaduto lo scorso novembre in Sri Lanka, le elezioni in Iraq sembrano aver acuito le tensioni settarie, puntualizza l&rsquo;analisi, malgrado le ragioni fondamentali dello scarso rendimento dello scorso anno potrebbero essere dovute al declino della classe dirigente del paese, e all&rsquo;intensificazione del conflitto settario. In totale, quest&rsquo;anno l&rsquo;Iraq ha ottenuto un punteggio di 109,0, superando il 103,2 dello scorso anno.   I paesi che registrano differenze numeriche pi&ugrave; significative da un anno all&rsquo;altro sono lo Zimbabwe, il cui rendimento &egrave; peggiorato di 14 punti, passando dalla quindicesima alla quinta posizione, e il Pakistan, che &egrave; passato dal trentaquattresimo al quindicesimo posto, soprattutto a causa dell&rsquo;impatto del terremoto dello scorso novembre, delle &ldquo;crescenti tensioni etniche in Baluchistan e dell&rsquo;incapacit&agrave; del governo di controllare le zone tribali lungo il confine afgano&rdquo;.<\/p>\n<p>Tra i paesi pi&ugrave; stabili, l&rsquo;intensificarsi della guerra civile in Nigeria e Cina spiega l&rsquo;aumento di 10 punti che ha fatto avanzare entrambi. La Nigeria, che l&rsquo;anno scorso era al inquantaquattresimo posto, &egrave; passata in ventiduesima posizione e si trova quasi in cima alla categoria &ldquo;in pericolo&rdquo; di quest&rsquo;anno. La Cina, che l&rsquo;anno scorso al settantacinquesimo posto su un totale di 76, &egrave; salita al cinquantasettesimo posto, soprattutto per il crescente gap tra ricchi e poveri e le conseguenti tensioni.<\/p>\n<p>Nella sfera pi&ugrave; &lsquo;positiva&rsquo; di questa equazione, i maggiori progressi verso la stabilit&agrave; si attribuiscono al Venezuela, che &egrave; passato dal ventiduesimo posto e dalla categoria &ldquo;in pericolo&rdquo; del 2005, alla classe &ldquo;borderline&rdquo;.<\/p>\n<p>&rdquo;Nonostante la politica economica del presidente Hugo Chavez non abbia probabilmente giovato alla maggioranza dei venezuelani, la sua ardente retorica anti-americana e i prezzi elevati del petrolio lo hanno aiutato a consolidare il potere e a dare stabilit&agrave; al paese, almeno a breve termine&rdquo;, riferisce l&rsquo;analisi di Foreign Policy, curata per lo pi&ugrave; da Moises Naim, ex ministro venezuelano del commercio e dell&rsquo;industria e critico dichiarato di Chavez.<\/p>\n<p>Tra gli altri paesi che hanno visibilmente migliorato le loro performance nell&rsquo;ultimo anno figurano Repubblica Dominicana, Guatemala e Bosnia.<\/p>\n<p>Mentre Haiti &egrave; caduta nell&rsquo;area &ldquo;critica&rdquo;, la Colombia &egrave; l&rsquo;unico paese latinoamericano considerato &ldquo;in pericolo&rdquo;, pur avendo migliorato la sua posizione: l&rsquo;anno scorso occupava il quattordicesimo posto, salendo quest&rsquo;anno al ventisettesimo.<\/p>\n<p>Oltre a Colombia, Bosnia e Nigeria, tra i paesi &ldquo;in pericolo&rdquo;, figurano Uzbekistan e Tajikistan nell&rsquo;Asia centrale, Laos, Sri Lanka e Indonesia nel Sud e Sud-est asiatico; Egitto e Siria nel mondo arabo; Angola, Camerun e Burkina Faso nell&rsquo;Africa occidentale; Etiopia, Kenya e Uganda in Africa orientale.<\/p>\n<p>Diversi gli indicatori sociali utilizzati dallo studio, fra cui statistiche sulla densit&agrave; di popolazione in relazione alle risorse per la sostenibilit&agrave;; migrazioni forzate o fuga di ampie porzioni della popolazione; e l&rsquo;esistenza, intensit&agrave;, ed eredit&agrave; di divisioni all&rsquo;interno delle comunit&agrave;.<\/p>\n<p>Gli indicatori economici comprendono la percentuale di crescita (o di de-crescita) pro capite e la distribuzione non equa dei vantaggi portati dalla crescita fra i diversi gruppi.<\/p>\n<p>Gli indicatori politici comprendono i criteri del buon governo, come l&rsquo;esistenza e la portata della corruzione; l&rsquo;efficienza dei servizi pubblici; lo stato di diritto; la frammentazione delle elite al potere in gruppi minori; il controllo dei civili sulle forze di sicurezza; e l&rsquo;intervento degli stati esteri o di altre forze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, 3 agosto 2006 (IPS) &#8211; Nonostante abbiano ricevuto circa otto miliardi di dollari al mese in aiuti economici e militari nell&rsquo;ultimo anno, Iraq e Afghanistan sono classificati tra i 10 stati pi&ugrave; deboli del mondo, insieme a buona parte&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/08\/03\/politica-iraq-e-afghanistan-tra-i-primi-dieci-stati-falliti\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,5,8,18,22,1,26,28,30,25,32],"tags":[],"class_list":["post-596","post","type-post","status-publish","format-standard","hentry","category-africa","category-america-latina","category-asia-e-oceania","category-economia","category-europa","category-headlines","category-iraq-e-asia-centrale","category-medioriente","category-nord-america","category-obiettivi-di-sviluppo-sostenibile","category-politica"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=596"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/596\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}