{"id":577,"date":"2006-07-04T18:00:42","date_gmt":"2006-07-04T18:00:42","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/07\/04\/sviluppo-mega-citt-e-sensibilit-di-genere\/"},"modified":"2006-07-04T18:00:42","modified_gmt":"2006-07-04T18:00:42","slug":"sviluppo-mega-citt-e-sensibilit-di-genere","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/07\/04\/sviluppo-mega-citt-e-sensibilit-di-genere\/","title":{"rendered":"SVILUPPO: Mega-citt&agrave; e sensibilit&agrave; di genere"},"content":{"rendered":"<p>VANCOUVER, 3 Luglio 2006 (IPS) &#8211; Mentre il World Urban Forum di Vancouver si concludeva con la promessa di &ldquo;lavorare di pi&ugrave;&rdquo; per risolvere la crisi globale della casa, alcune donne presenti al meeting sottolineavano che la sensibilit&agrave; di genere dovrebbe essere inclusa tra le politiche per il miglioramento delle terribili condizioni di vita in cui versano milioni di esseri umani.<\/p>\n<p><!--more--><\/p>\n<p>La conferenza, che ha riunito circa 10.000 persone provenienti da 100 paesi, &egrave; stata organizzata per cercare soluzioni alternative alla cos&igrave; rapida urbanizzazione e al problema degli alloggi. <\/p>\n<p>Si prevede che, nei prossimi trent&#039;anni, la popolazione urbana dei paesi in via di sviluppo raddoppi, salendo da due a quattro miliardi. La concentrazione nelle mega-citt&agrave; sar&agrave; elevata; entro il 2015, saranno all&rsquo;incirca 23 le citt&agrave; con una popolazione superiore ai 10 milioni, di cui 19 nei paesi in via di sviluppo. <\/p>\n<p>Marni Kellison, di Power Camp National\/Filles D&#039;Action, organizzazione non governativa con sede a Montreal, sostiene che le vittime della rapida urbanizzazione sono per lo pi&ugrave; donne e bambini, e che &ldquo;le donne devono essere riconosciute come le principali garanti della sostenibilit&agrave; urbana&rdquo;.<\/p>\n<p>Il ruolo femminile &egrave; quasi sempre fondamentale nell&rsquo;educazione dei bambini, e garantisce spesso le risorse necessarie per soddisfare i bisogni dei piccoli in fatto di nutrizione, sanit&agrave; e scuola. Inoltre, le donne che vivono negli slum rischiano maggiormente di contrarre l&rsquo;Hiv\/Aids, rispetto alle loro controparti rurali. <\/p>\n<p>Secondo gli esperti, le donne che partecipano alle migrazioni dalle aree rurali a quelle urbane sono spesso pi&ugrave; vulnerabili allo sfruttamento economico e sessuale, ma possono anche usufruire di nuove opportunit&agrave; in termini di diritti per l&rsquo;istruzione e la procreazione. <\/p>\n<p>Tuttavia, per chi abita negli slum, inquinamento, acqua sporca e sovraffollamento rendono la vita quotidiana una mera lotta per la sopravvivenza. <\/p>\n<p>L&rsquo;inadeguatezza degli alloggi e delle principali infrastrutture, come acqua ed elettricit&agrave;, e l&rsquo;insufficiente risposta del governo, rappresentano le preoccupazioni fondamentali di Iyabo Ogunyannwo, funzionaria per lo sviluppo urbano di Abuja, Nigeria. <\/p>\n<p>Dopo aver chiesto ai governi di rendere la vita nelle citt&agrave; &ldquo;meno estenuante&rdquo;, Ogunyannwo ha dichiarato che il suo paese, come molti altri del mondo in via di sviluppo, sta ancora lottando per le sfide dell&rsquo;urbanizzazione e i relativi sforzi legati ai servizi municipali.<\/p>\n<p>&rdquo;Si parla di popolazione e di risorse come se fossero questi i problemi, ma non sono d&rsquo;accordo. Credo che le risorse ci siano&rdquo;, ha detto all&rsquo;IPS. &ldquo;Il problema &egrave; che i politici non capiscono che le citt&agrave; sono il motore di ogni nazione. Abbiamo bisogno di investire nelle nostre citt&agrave; e di renderle pi&ugrave; interessanti per gli investitori stranieri, migliorando cos&igrave; la vita degli abitanti&rdquo;.<\/p>\n<p>Amministratrice del governo federale nigeriano, Ogunyannwo &egrave; irritata perch&eacute; i progettisti delle citt&agrave; non stanno ottenendo l&rsquo;aiuto necessario da parte dei politici del paese. <\/p>\n<p>&rdquo;Prima di utilizzare qualunque spazio bisogna fare dei progetti, in modo da massimizzare i benefici&rdquo;, ha fatto notare, aggiungendo che donne e bambini restano i pi&ugrave; vulnerabili di fronte alle malattie e all&rsquo;insicurezza che domina in questi ambienti ostili. &ldquo;&Egrave; il motivo per cui siamo preoccupati, il ritmo al quale si forniscono le case ai pi&ugrave; bisognosi &egrave; troppo lento&rdquo;. <\/p>\n<p>Ogunyannwo ha dichiarato che secondo un piano nazionale presentato di recente, il governo sta provvedendo a fornire 500 unit&agrave; abitative per lavoratori a basso reddito in tutte le capitali di stato. <\/p>\n<p>Tuttavia, la funzionaria &egrave; preoccupata: la popolazione del paese &egrave; di circa 130 milioni, e questo non baster&agrave;  a risolvere il problema, &ldquo;a meno che l&rsquo;operazione non venga ripetuta pi&ugrave; volte e non sia estesa oltre le capitali di stato&rdquo;. La Nigeria ha 36 capitali, ma i centri urbani sono migliaia. <\/p>\n<p>Maryanne Kimuyi del Kenya ha raccontato una storia simile. Il lavoratore medio non pu&ograve; permettersi le case costruite dai privati, e le abitazioni a basso reddito offerte dal governo costano circa 1.300 scellini keniani, mentre in media un lavoratore a basso reddito guadagna appena 21.000 scellini l&rsquo;anno. <\/p>\n<p>&rdquo;La situazione migliorerebbe un po&rsquo; se i lavoratori avessero delle agevolazioni sui mutui&rdquo;, ha proseguito Kimuyi. &ldquo;Purtroppo, si sa che nelle economie pseudo-capitaliste, quando si va in banca a chiedere un prestito, &egrave; difficile che venga dato del denaro a chi non dispone gi&agrave; di un certo capitale&rdquo;.<\/p>\n<p>Kimuyi ritiene che il governo possa e debba fare di pi&ugrave; per rendere possibile ai poveri, soprattutto a donne con figli, di ottenere mutui per l&rsquo;acquisto di una casa. <\/p>\n<p>Winifred David, che lavora per la Port of Spain Corporation di Trinidad e Tobago, ha detto che il suo paese, insieme a tre stati vicini dei Caraibi, ha appena costituito un ente che lavora per rendere accessibile su larga scala l&rsquo;acquisto di un&rsquo;abitazione. Secondo lei, le donne saranno particolarmente favorite. <\/p>\n<p>Jennifer Pepall, del Centro ricerche per lo sviluppo internazionale (IDRC) con sede in Canada, sostiene che il suo gruppo considera prioritaria l&rsquo;assistenza alle donne nei progetti. L&rsquo;IDRC sta attualmente lavorando in cinque citt&agrave; del mondo, con l&rsquo;obiettivo di accelerare lo sviluppo urbano. <\/p>\n<p>Tra le citt&agrave;, Dakar in Senegal; Kampala in Uganda; Colombo in Sri Lanka e Giakarta in Indonesia; e Moreno in Argentina. Prima della fine dell&rsquo;anno saranno scelte altre quattro citt&agrave; in Medio Oriente, Nord Africa, America Latina e Caraibi. <\/p>\n<p>La portata di questi problemi aumenta, mentre funzionari e attivisti per lo sviluppo valutano i progressi compiuti in direzione degli Obiettivi di sviluppo del millennio (MDG), approvati nel settembre 2000 al vertice delle Nazioni Unite da 189 leader mondiali, e che includono l&rsquo;uguaglianza di genere e &ldquo;il miglioramento delle condizioni di vita di almeno 100 milioni di abitanti urbani entro il 2020&rdquo;. <\/p>\n<p>Sisa Njikelana, membro del parlamento sudafricano, ha concluso che le soluzioni &ldquo;non si dovrebbero limitare all&#039;offerta di infrastrutture e servizi, malgrado anche questi siano importanti. Piuttosto, lo stile di &#8220;vita urbana&#8221; sana del quale stiamo parlando &egrave; quello pi&ugrave; vicino all&rsquo;uomo, quello in cui il denaro non viene prima della nostra umanit&agrave;&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VANCOUVER, 3 Luglio 2006 (IPS) &#8211; Mentre il World Urban Forum di Vancouver si concludeva con la promessa di &ldquo;lavorare di pi&ugrave;&rdquo; per risolvere la crisi globale della casa, alcune donne presenti al meeting sottolineavano che la sensibilit&agrave; di genere&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/07\/04\/sviluppo-mega-citt-e-sensibilit-di-genere\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,38,11,13,15,16,1,27,30,25,33],"tags":[],"class_list":["post-577","post","type-post","status-publish","format-standard","hentry","category-africa","category-sviluppo","category-columnas","category-cooperazione","category-diritti-umani","category-donne-e-sviluppo","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-nord-america","category-obiettivi-di-sviluppo-sostenibile","category-popolazione"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=577"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/577\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}