{"id":524,"date":"2006-03-23T10:40:53","date_gmt":"2006-03-23T10:40:53","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/03\/23\/kenya-costruzioni-ovunque-e-neanche-una-goccia-dacqua-da-bere\/"},"modified":"2006-03-23T10:40:53","modified_gmt":"2006-03-23T10:40:53","slug":"kenya-costruzioni-ovunque-e-neanche-una-goccia-dacqua-da-bere","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/03\/23\/kenya-costruzioni-ovunque-e-neanche-una-goccia-dacqua-da-bere\/","title":{"rendered":"KENYA: Costruzioni ovunque e neanche una goccia d&#8217;acqua da bere"},"content":{"rendered":"<p>NAIROBI, 23 marzo 2006 (IPS) &#8211; Quando si parla della situazione degli alloggi nella capitale del Kenya,<br \/>\nNairobi, spesso si sottolinea la mancanza di luoghi puliti in cui<br \/>\nvivere, in particolare nel caso della vastissima baraccopoli di Kibera,<br \/>\ndove decine di migliaia di persone vivono in condizioni terribili.<\/p>\n<p><!--more--><\/p>\n<p>In altre zone della citt&agrave;, invece, si continuano a costruire anche  troppi complessi residenziali, o comunque si costruiscono troppo  velocemente.<\/p>\n<p>Qui, lo sviluppo corre pi&ugrave; veloce delle forniture di acqua, elettricit&agrave;  e sistema fognario. E il risultato, ossia grandi numeri di persone che  contano su un&rsquo;infrastruttura limitata, viene visto come la ricetta per  il disastro.<\/p>\n<p>John Gakuo, segretario comunale di Nairobi, ha lanciato l&rsquo;allarme al  riguardo alla fine dello scorso anno, quando ha fermato le costruzioni  di nuovi appartamenti in edifici a pi&ugrave; piani nei quartieri alti di  Kileleshwa, Kilimani e Westlands.<\/p>\n<p>Prima che vi si cominciasse a costruire, queste tre zone nella parte  ovest di Nairobi erano aree spaziose disseminate di bungalow, abitate in  modo sparso; adesso, i grandi edifici residenziali sono diventati il  loro segno distintivo. <\/p>\n<p>Gakuo ha evidenziato che le infrastrutture dei servizi per i complessi  residenziali non erano destinate ad alloggiare il numero sempre maggiore  di abitanti prodotti dal passaggio dai bungalow ai nuovi edifici.<\/p>\n<p>In altri quartieri alla periferia di Nairobi, come Syokimau, Mlolongo e  Ruai, &egrave; ancora peggio.<\/p>\n<p>Chi ha portato lo sviluppo in queste aree ha costruito gli edifici prima  che le autorit&agrave; imponessero determinate infrastrutture basilari. Oltre  all&rsquo;assenza di acqua ed elettricit&agrave; canalizzate, non ci sono strade di  accesso. I costruttori ne hanno create delle loro, trovando delle  soluzioni per procurarsi acqua ed elettricit&agrave; a chilometri di distanza.<\/p>\n<p>&ldquo;Lo sviluppo sul campo &egrave; molto lontano dalla pianificazione; &egrave; lontano  da qualsiasi infrastruttura&rdquo;, ha detto all&rsquo;Erastus Abonyo,  vicepresidente dell&rsquo;Architectural Association of Kenya (AAK).<\/p>\n<p>Ma Abonyo rimprovera il governo per come vanno le cose, non i  costruttori: &ldquo;Il problema non sono i costruttori: &egrave; che le istituzioni  responsabili di gestire lo sviluppo locale e la pianificazione non lo  stanno facendo&rdquo;.<\/p>\n<p>Secondo Abonyo, neanche il Consiglio comunale di Nairobi (NCC) ha un  piano generale dei servizi che definisca una soluzione al problema della  carenza di infrastrutture.<\/p>\n<p>Ma John Koyier Barreh, funzionario del dipartimento comunale per la  pianificazione dell&rsquo;NCC, non &egrave; d&rsquo;accordo.<\/p>\n<p>Sono state messe in piedi iniziative di pianificazione, ha riferito  all&rsquo;IPS, menzionando la &ldquo;Strategia di crescita metropolitana di  Nairobi&rdquo;, preparata per il consiglio nel 1973.<\/p>\n<p>Bench&eacute; il progetto stabilisca delle modalit&agrave; per allestire le  infrastrutture a Nairobi e dintorni, la sua attuazione &egrave; stata  frammentaria, e questo per la mancanza di fondi, ha osservato Barreh.<\/p>\n<p>&ldquo;Il governo non ha mai stanziato fondi per la totale attuazione del  progetto&rdquo;, ha aggiunto.<\/p>\n<p>&ldquo;Non si pu&ograve; biasimare l&rsquo;NCC, che ha un budget di quattro miliardi di  scellini kenioti (circa 56 milioni di dollari) all&rsquo;anno per costruire  infrastrutture come le strade in citt&agrave;. Di questo &egrave; responsabile il  governo centrale&rdquo;.<\/p>\n<p>Barreh sostiene che le autorit&agrave; avrebbero garantito dei fondi per l&rsquo;NCC  della Banca mondiale, che si &egrave; detta anch&rsquo;essa preoccupata per la  carenza di infrastrutture, osservando che la crescita della popolazione  a Nairobi ha seriamente indebolito i servizi esistenti.<\/p>\n<p>Tuttavia, ha aggiunto l&rsquo;esperto, questi fondi non sono sufficienti per  realizzare in pieno la Strategia di crescita metropolitana.<\/p>\n<p>Al momento &egrave; stato avviato un terzo progetto di sviluppo delle  infrastrutture urbane.<\/p>\n<p>Ma alcuni ritengono che per avere forniture adeguate di acqua,  fognature, ecc., la chiave non sia nei progetti, bens&igrave; nella  costituzione di un ente nazionale e indipendente che impedisca  all&rsquo;industria delle costruzioni di edificare prima che siano realizzate  le necessarie infrastrutture.<\/p>\n<p>Un comitato ufficiale, costituito nel 1998 per esaminare la situazione  degli alloggi a Nairobi, ha raccomandato di costituire un ente di questo  tipo, e da allora l&rsquo;AAK ha fatto pressioni al governo perch&eacute; si muova in  tal senso.<\/p>\n<p>Ad oggi, i suoi sforzi non hanno prodotto nessun risultato.<\/p>\n<p>&ldquo;Abbiamo continuato a organizzare diversi incontri con l&rsquo;NCC e altre  autorit&agrave; locali, come anche con il governo centrale, avvertendo  dell&rsquo;urgenza di un ente per le costruzioni. Fino ad ora, nessuna  risposta, ma continuiamo ad aspettare&rdquo;, ha concluso Abonyo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAIROBI, 23 marzo 2006 (IPS) &#8211; Quando si parla della situazione degli alloggi nella capitale del Kenya, Nairobi, spesso si sottolinea la mancanza di luoghi puliti in cui vivere, in particolare nel caso della vastissima baraccopoli di Kibera, dove decine&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/03\/23\/kenya-costruzioni-ovunque-e-neanche-una-goccia-dacqua-da-bere\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,38,11,13,1,27,25,33],"tags":[],"class_list":["post-524","post","type-post","status-publish","format-standard","hentry","category-africa","category-sviluppo","category-columnas","category-cooperazione","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile","category-popolazione"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=524"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/524\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}