{"id":486,"date":"2006-02-01T10:42:20","date_gmt":"2006-02-01T10:42:20","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/02\/01\/forum-economico-mondiale-i-lavoratori-si-attivano-per-la-crisi-delloccupazione\/"},"modified":"2006-02-01T10:42:20","modified_gmt":"2006-02-01T10:42:20","slug":"forum-economico-mondiale-i-lavoratori-si-attivano-per-la-crisi-delloccupazione","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/02\/01\/forum-economico-mondiale-i-lavoratori-si-attivano-per-la-crisi-delloccupazione\/","title":{"rendered":"FORUM ECONOMICO MONDIALE: I lavoratori si attivano per la crisi dell&#8217;occupazione"},"content":{"rendered":"<p>DAVOS, Svizzera, 1 febbraio 2006 (IPS) &#8211; Mentre uomini d&rsquo;affari e leader mondiali si spremevano le meningi per trovare soluzione alla crisi globale dell&rsquo;occupazione, al Forum Economico Mondiale (WEF, World Economic Forum) nel centro sciistico di Davos, un piccolo sindacato messicano risolveva il problema usando una vecchia formula: l&rsquo;attivismo dei lavoratori.<\/p>\n<p><!--more--><\/p>\n<p>La settimana scorsa, il Sindicato Nacional Revolucionario de Trabajadores de Euzkadi (SNRTE) ha celebrato il suo primo anniversario per il recupero dell&rsquo;occupazione nella fabbrica di pneumatici Euzkadi di El Salto, nello stato messicano di Jalisco. La fabbrica era stata chiusa tre anni prima dalla propriet&agrave;, la compagnia tedesca Continental AG. <\/p>\n<p>Il capo dello SNRTE, Jes&uacute;s Torres Nu&ntilde;o, ha raccontato all&rsquo;IPS di essere contento dei successi ottenuti dal sindacato, e di voler fare sapere alla gente che &ldquo;&egrave; possibile combattere, e vincere&rdquo;.<\/p>\n<p>Il conflitto di El Salto &egrave; iniziato quando la Continental ha cercato di imporre misure per incrementare la produttivit&agrave; dei lavoratori. <\/p>\n<p>Dibattiti e discussioni alla riunione di quest&rsquo;anno del WEF, che si &egrave; svolto dal 25 al 29 gennaio, hanno riconosciuto uno stretto legame tra l&rsquo;adozione degli standard internazionali di produttivit&agrave; e il calo dell&rsquo;occupazione. <\/p>\n<p>Juan Somav&iacute;a, direttore generale dell&rsquo;Organizzazione internazionale del lavoro (OIL), ha confermato all&rsquo;IPS l&rsquo;esistenza del rapporto che esiste tra l&rsquo;aumento della produttivit&agrave; e la riduzione dell&rsquo;impiego. <\/p>\n<p>Somav&iacute;a ha evidenziato che &ldquo;malgrado la robusta crescita economica del 4,3 per cento nel 2005, l&rsquo;economia globale non riesce a garantire nuovi impieghi a chi entra nel mercato del lavoro&rdquo;.<\/p>\n<p>La crisi dell&rsquo;occupazione ha assunto &ldquo;dimensioni mastodontiche&rdquo;, avverte il funzionario dell&rsquo;OIL. <\/p>\n<p>Nel mondo, quasi 1,4 miliardi di poveri lavoratori sopravvivono con meno di due dollari al giorno; secondo fonti ufficiali, la disoccupazione &egrave; cresciuta pi&ugrave; del 25 per cento e oggi colpisce circa 192 milioni di persone, ovvero il sei per cento della forza lavoro globale. <\/p>\n<p>Somav&iacute;a ha elogiato la decisione del WEF di inserire il problema dell&rsquo;occupazione nella sua agenda di quest&rsquo;anno, sollecitando l&rsquo;incontro di Davos tra il mondo degli affari e i leader di governo sui &ldquo;passi da intraprendere per fermare l&rsquo;aggravarsi della situazione globale&rdquo;.<\/p>\n<p>I quasi mille lavoratori rappresentati dallo SNRTE si sono tempestivamente attivati quando la Continental ha deciso di chiudere gli stabilimenti di El Salto il 16 settembre 2001, dopo che i sindacati avevano rifiutato di rendere operativi i nuovi standard di produttivit&agrave;. <\/p>\n<p>La fabbrica, fondata nel 1935 da uno spagnolo del Paese Basco, &egrave; stata per anni leader nell&rsquo;industria dei pneumatici in Messico. Nel 1992, &egrave; stata acquistata dal miliardario messicano Carlos Slim e nel 1998, quando produceva 4,5 milioni di gomme all&rsquo;anno, &egrave; stata acquistata dalla Continental. <\/p>\n<p>Non appena la Continental ha deciso di chiudere lo stabilimento messicano, i sindacati hanno indetto uno sciopero, chiedendo la riapertura della fabbrica. <\/p>\n<p>Torres Nu&ntilde;o ha spiegato che, sebbene sembri strano che i lavoratori di una fabbrica chiusa si mettano in sciopero, secondo la legislazione messicana, per i dipendenti &egrave; l&rsquo;unico modo di mantenere il controllo sul loro posto di lavoro e far s&igrave; che i proprietari non rimuovano macchinari e attrezzature. <\/p>\n<p>&rdquo;Per tre anni siamo andati avanti e indietro dalla Germania, dove abbiamo partecipato ai meeting annuali degli azionisti della Continental, con l&rsquo;appoggio di due organizzazioni indipendenti non governative, la Food First Information and Action Network (FIAN) e Germanwatch&rdquo;, ha raccontato Torres Nu&ntilde;o all&rsquo;IPS. <\/p>\n<p>&rdquo;Purtroppo, i sindacati tedeschi non hanno sostenuto la nostra lotta&rdquo;, ha rimarcato l&rsquo;attivista. <\/p>\n<p>Cornelia Heydenreich di Germanwatch e Martin Wolpold-Bosien di FIAN hanno ottenuto la collaborazione dei comitati di solidariet&agrave; internazionale del Sindacato dei metalmeccanici e della Fondazione Friedrich-Ebert, che sono tra le organizzazioni cui si deve il successo del sindacato messicano.<\/p>\n<p>Alla fine, lo SNRTE ha raggiunto un accordo con la Continental che garantiva ai 600 lavoratori coinvolti nella lotta un totale di circa 12 milioni di dollari di compensazione. <\/p>\n<p>Inoltre, ai dipendeni &egrave; stata concessa la propriet&agrave; di met&agrave; della fabbrica, valutata in circa 40 milioni di dollari. L&rsquo;altra met&agrave; &egrave; stata venduta dalla Continental a un&rsquo;industria messicana di pneumatici, la Llanti Systems. <\/p>\n<p>&rdquo;Dopo i tre anni di chiusura, gli impianti erano piuttosto deboli, ma li abbiamo riattivati e a dicembre &egrave; stata prodotta la centomillesima ruota&rdquo;, ha riferito Torres Nu&ntilde;o. <\/p>\n<p>Attualmente, gli stabilimenti producono circa 3000 gomme al giorno, risultato piuttosto modesto considerata la capacit&agrave; dell&rsquo;impianto. &ldquo;Siamo lontani dalla produzione quotidiana di 12.000-14.000 pneumatici, quando la fabbrica era al rendimento massimo&rdquo;, ha aggiunto. <\/p>\n<p>Come riconoscimento del loro successo nella campagna contro la Continental, lo SNRTE e le due Ong tedesche che hanno sostenuto questa lotta, FIAN e Germanwatch, hanno ricevuto il primo &ldquo;Premio positivo&rdquo; assegnato dal Public Eye a Davos. <\/p>\n<p>I Public Eye Awards, un&rsquo;iniziativa delle Ong svizzere Pro Natura, Friends of the Earth e la Dichiarazione di Berna, sono un&rsquo;onorificenza ironica che premia l&rsquo;irresponsabilit&agrave; delle compagnie.<\/p>\n<p>I &ldquo;vincitori&rdquo; di quest&rsquo;anno dei Public Eye Awards, annunciati la scorsa settimana a Davos, sono stati: Citigroup, per aver consentito l&rsquo;evasione fiscale e il riciclaggio di denaro; il gigante del petrolio Chevron, per l&rsquo;inquinamento delle foreste in Ecuador; e la Walt Disney, per aver violato i diritti umani e dei lavoratori nei suoi stabilimenti della Cina meridionale. <\/p>\n<p>&rdquo;Il Premio positivo &egrave; estremamente motivante e siamo felici che sia stato finalmente concesso un riconoscimento adeguato a una vittoria dei lavoratori&rdquo;, ha dichiarato Torres Nu&ntilde;o. <\/p>\n<p>La vittoria sulla Continental &egrave; stata particolarmente significativa &ldquo;perch&eacute; il governo messicano era contro di noi&rdquo;, ha fatto notare il sindacalista. <\/p>\n<p>&rdquo;In Messico, il governo &egrave; assolutamente servile nei confronti delle societ&agrave; transnazionali, soprattutto di quelle tedesche. La fonte di investimento numero uno del paese sono gli Stati Uniti, seguiti dalla Germania&rdquo;, ha spiegato. <\/p>\n<p>Durante la lotta, avevano minacciato che se lo sciopero non si fosse risolto in favore della Continental, anche altre compagnie tedesche, come Volkswagen e Boge, produttore di ricambi automobilistici, avrebbero chiuso i loro stabilimenti in Messico, ha commentato Torres Nu&ntilde;o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DAVOS, Svizzera, 1 febbraio 2006 (IPS) &#8211; Mentre uomini d&rsquo;affari e leader mondiali si spremevano le meningi per trovare soluzione alla crisi globale dell&rsquo;occupazione, al Forum Economico Mondiale (WEF, World Economic Forum) nel centro sciistico di Davos, un piccolo sindacato&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/02\/01\/forum-economico-mondiale-i-lavoratori-si-attivano-per-la-crisi-delloccupazione\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[38,5,11,18,22,1,27,25],"tags":[],"class_list":["post-486","post","type-post","status-publish","format-standard","hentry","category-sviluppo","category-america-latina","category-columnas","category-economia","category-europa","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/486\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}