{"id":1721,"date":"2011-03-24T18:58:24","date_gmt":"2011-03-24T18:58:24","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2011\/03\/24\/libia-gli-insorti-formano-governo-ad-interim\/"},"modified":"2011-03-24T18:58:24","modified_gmt":"2011-03-24T18:58:24","slug":"libia-gli-insorti-formano-governo-ad-interim","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2011\/03\/24\/libia-gli-insorti-formano-governo-ad-interim\/","title":{"rendered":"Libia, gli insorti formano governo ad interim"},"content":{"rendered":"<p>TRIPOLI\/BENGASI, 23 marzo 2011 (Al Jazeera) (IPS) &#8211; I ribelli libici hanno formato un governo ad interim, mentre continuano gli attacchi delle forze fedeli al regime di Muammar Gheddafi.<\/p>\n<p><!--more--><\/p>\n<p>Il primo ministro del nuovo governo sar&agrave; Mahmoud Jibril, fino ad ora rappresentante dei ribelli nelle relazioni esterne, meglio noto sulla scena internazionale per il suo incontro con il presidente francese Nicolas Sarkozy che ha riconosciuto il consiglio ribelle come unico rappresentante del popolo libico. <\/p>\n<p>&ldquo;Il consiglio nazionale provvisorio &egrave; un organo legislativo, ma abbiamo bisogno di un esecutivo per assumere il controllo e avere un&rsquo;amministrazione&rdquo;, ha dichiarato ad Al Jazeera il portavoce dei ribelli, Nisan Gouriani. <\/p>\n<p>&ldquo;La posizione degli insorti &egrave; stata molto chiara sin dal principio: la Libia &egrave; indivisibile&rdquo;, ha detto. <\/p>\n<p>&ldquo;La nostra capitale &egrave; Tripoli, e sar&agrave; per sempre Tripoli&#8230; Stiamo lottando per liberare la parte occidentale del paese e Tripoli, per mantenere il paese unito. Vogliamo che sia chiaro&rdquo;. <\/p>\n<p>I ribelli ci hanno tenuto a sottolineare che la nascente amministrazione nella loro roccaforte di Bengasi sar&agrave; solo provvisoria, per evitare che la loro azione venga vista come un&rsquo;intenzione di dividere il paese. <\/p>\n<p>&ldquo;Vogliono che il popolo libico resti unito, ma senza Gheddafi&rdquo;, ha detto il corrispondente di Al Jazeera a Bengasi James Bays. <\/p>\n<p>Intanto, proseguono gli scontri. Le forze fedeli al regime hanno attaccato le postazioni degli insorti in tutto il paese. <\/p>\n<p>Imperterrite di fronte ai bombardamenti della coalizione internazionale, per creare una no-fly zone, le forze di Gheddafi hanno continuato ad attaccare le citt&agrave; di Misurata, Ajdabiya y Zintan. <\/p>\n<p>Per gli insorti, la situazione &egrave; ancora difficile. In pochi hanno le armi e sono privi di strutture di comando. La loro unica tattica &egrave; compiere attacchi a sorpresa contro le forze di Gheddafi per poi ripiegare di immediato. <\/p>\n<p>Ma uno dei ribelli ha assicurato che le loro unit&agrave; sono formate da &ldquo;veri eroi&rdquo;. &ldquo;Sono talmente coraggiosi che sono disposti a morire&rdquo;, ha detto Mohamed Hariri a Al Jazeera. <\/p>\n<p>Durante i combattimenti, Gheddafi ha ribadito di &ldquo;essere pronto alla battaglia, breve o lunga che sia&rdquo;.<\/p>\n<p>&ldquo;Vinceremo la battaglia&rdquo;, aveva detto durante un&rsquo;apparizione pubblica nel suo bunker di Bab Al Aziziyah a Tripoli. &ldquo;Questo attacco.. &egrave; stato perpetrato da un branco di fascisti che finir&agrave; nella spazzatura della storia&rdquo;.<\/p>\n<p>&ldquo;Le forze di Gheddafi hanno occupato l&rsquo;ospedale della citt&agrave; appostando dei cecchini sul tetto e nei carri armati stazionati all&rsquo;esterno&rdquo;, ha riferito il corrispondente. <\/p>\n<p>Gli insorti chiedono di mandare una nave ospedale, e assicurano di controllare ancora il porto. In questo modo, sperano di riuscire a salvare diverse vite, visto che adesso non hanno un posto dove mettere i feriti&rdquo;, ha aggiunto. <\/p>\n<p>&ldquo;Si sono registrati altri morti tra i civili ad Ajdabiya e in altre localit&agrave;, e (i ribelli) stanno chiedendo alle forze internazionali di dare un&rsquo;interpretare pi&ugrave; ampia alla risoluzione dell&rsquo;Onu per poter garantire un maggiore sostegno e realizzare pi&ugrave; attacchi contro le forze di Gheddafi&rdquo;, ha detto. <\/p>\n<p>Da parte sua, la corrispondente Anita McNaught, da Tripoli, ha parlato del fuoco antiaereo che per diverse notti consecutive ha continuato a colpire la capitale del paese. <\/p>\n<p>&ldquo;Abbiamo sentito forti rumori&rdquo;, ha raccontato. &ldquo;Non abbiamo visto fumo all&rsquo;orizzonte. La gente spara con le armi che ha come forma di resistenza. Siamo nel cuore dei sostenitori del regime, dove le persone sfidano apertamente le forze internazionali che vogliono costringere Gheddafi ad arrendersi&rdquo;. <\/p>\n<p>La no-fly zone &egrave; intesa a proteggere i civili dagli attacchi delle forze fedeli a Gheddafi. Gli Stati Uniti hanno annunciato marted&igrave; scorso l&rsquo;intenzione di estendere la no-fly zone alla zona nord del paese africano. &copy; IPS <\/p>\n<p>* Pubblicato in accordo con Al Jazeera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRIPOLI\/BENGASI, 23 marzo 2011 (Al Jazeera) (IPS) &#8211; I ribelli libici hanno formato un governo ad interim, mentre continuano gli attacchi delle forze fedeli al regime di Muammar Gheddafi.<\/p>\n","protected":false},"author":170,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[1,28,25,32],"tags":[],"class_list":["post-1721","post","type-post","status-publish","format-standard","hentry","category-headlines","category-medioriente","category-obiettivi-di-sviluppo-sostenibile","category-politica"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/170"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}