{"id":1635,"date":"2009-06-12T18:24:42","date_gmt":"2009-06-12T18:24:42","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/06\/12\/sviluppo-africa-trovare-alloggi-per-i-poveri-urbani\/"},"modified":"2009-06-12T18:24:42","modified_gmt":"2009-06-12T18:24:42","slug":"sviluppo-africa-trovare-alloggi-per-i-poveri-urbani","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2009\/06\/12\/sviluppo-africa-trovare-alloggi-per-i-poveri-urbani\/","title":{"rendered":"SVILUPPO-AFRICA: Trovare alloggi per i poveri urbani"},"content":{"rendered":"<p> NAIROBI, 12 giugno 2009 (IPS) &#8211; Milioni di persone si spostano ogni anno verso le citt&agrave; africane, andando ad ingrossare le fila dei poveri urbani. &ldquo;Non possiamo cacciare la gente dalle baraccopoli&rdquo;, dice Kelvin Mmangisa, direttore generale della Lilongwe City Assembly. &ldquo;Ma possiamo migliorare le condizioni degli slum per rendere migliore la vita di chi ci abita&rdquo;.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1458\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1458\" class=\"size-full wp-image-1458\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/200906_UrbanStuff_Edited.jpg\" alt=\"UN-HABITAT UN-HABITAT\" width=\"200\" \/><p id=\"caption-attachment-1458\" class=\"wp-caption-text\">UN-HABITAT<br \/>UN-HABITAT<\/p><\/div><\/div>\n<p>Mmangisa ha lanciato un appello per alloggi pi&ugrave; accessibili per i poveri in un&rsquo;intervista concessa il 10 giugno a Nairobi, dove ha partecipato insieme a 200 delegati in una conferenza sulle sfide dell&rsquo;urbanizzazione e la riduzione della povert&agrave; per gli abitanti degli slum nei paesi in via di sviluppo. Il meeting &egrave; stato organizzato dal gruppo dei paesi di Africa, Caraibi e Pacifico (ACP), Commissione Europea e UN-Habitat, l&rsquo;agenzia delle Nazioni Unite per gli insediamenti umani.<\/p>\n<p>Il suo discorso &egrave; stato accolto tra i punti chiave dell&rsquo;incontro dell&rsquo;8-10 giugno: finanziare il miglioramento degli insediamenti informali provvedendo ai servizi di base fondamentali. <\/p>\n<p>Un miliardo di persone vivono nella povert&agrave;, nelle baraccopoli e negli insediamenti abusivi di tutto il mondo; nell&rsquo;ottica di un aumento della popolazione degli slum a due miliardi entro il 2025, il miglioramento delle condizioni degli alloggi dei poveri urbani diventa una questione urgente. &ldquo;Se non verranno stanziate risorse adeguate per lo sviluppo di alloggi migliori e servizi necessari, la popolazione sempre pi&ugrave; numerosa rester&agrave; intrappolata nella povert&agrave; urbana, con scarse condizioni igieniche e sanitarie, continuando ad aggravare l&rsquo;enorme sfida degli slum di oggi&rdquo;, ha dichiarato Anna Tibaijuka, sottosegretario generale dell&rsquo;Onu e direttrice esecutiva di UN-Habitat. <\/p>\n<p>Il sessantadue per cento della popolazione delle aree urbane nell&rsquo;Africa sub-sahariana vive negli slum, dove i servizi di base sono scarsi o inesistenti. L&rsquo;accesso all&rsquo;acqua potabile sicura &egrave; un problema serio, e la situazione dell&rsquo;igiene &egrave; ancora pi&ugrave; grave. <\/p>\n<p>Trovare le risorse per costruire case e infrastrutture per l&rsquo;acqua e le strutture igienico-sanitarie &egrave; una enorme sfida. Uno degli approcci adottati da diversi governi riguarda le risorse degli stessi abitanti degli slum. <\/p>\n<p>Tra questi progetti, il Moratuwa Slum Upgrading Project nello Sri Lanka, un&rsquo;iniziativa congiunta di UN-Habitat e governo del paese, che punta a costruire nuove unit&agrave; abitative per gli abitanti delle baraccopoli nella capitale Colombo. Circa il 60 per cento dei 2,3 milioni di abitanti del paese vive negli slum, secondo UN-Habitat. Il progetto gestisce un fondo sostenuto dalla Women Development Bank Federation, una rete nazionale di oltre mille gruppi di credito e di risparmio che operano in Sri Lanka. Anche il governo e UN-Habitat contribuiscono al fondo, che funziona da garanzia per permettere ai gruppi di abitanti degli slum di accedere al credito delle istituzioni finanziarie, e poter in questo modo pagare nuovi alloggi. &Egrave; stata poi messa in luce una iniziativa analoga realizzata in Malawi, per il suo successo non solo nel fornire alloggi decenti ai poveri, e in particolare alle donne, ma per avergli permesso di dedicarsi ad altre attivit&agrave; generatrici di reddito e di riduzione della povert&agrave;. <\/p>\n<p>Il programma, del Centre for Community Organisation and Development, ha utilizzato i programmi di credito e di risparmio gestiti dalla comunit&agrave; per fornire prestiti alle donne per alloggi decenti. I progetti generatori di reddito le hanno aiutate a rimborsare i prestiti. <\/p>\n<p>&ldquo;Grazie all&rsquo;aiuto del governo e dei donatori, molte persone povere hanno potuto costruire alloggi migliori, con attrezzature come l&rsquo;acqua, gabinetti e in generale condizioni igieniche adeguate. Gli alloggi si trovano alla periferia della citt&agrave; &#8211; Lilongwe &#8211; e non hanno l&rsquo;aspetto di slum. Sono ben organizzati e oggi sono insediamenti pianificati&rdquo;, spiega Mmangisa. Il successo dell&rsquo;iniziativa viene attribuito soprattutto alla sua capacit&agrave; di promuovere la partecipazione della popolazione povera nella risoluzione dei problemi specifici legati agli alloggi. <\/p>\n<p>La sostenibilit&agrave; dei progetti abitativi per i poveri emerge come una preoccupazione fondamentale, laddove alcuni ritengono il governo responsabile di non aver dato priorit&agrave; al problema dell&rsquo;urbanizzazione. <\/p>\n<p>&ldquo;Nei piani di strategie per lo sviluppo regionale abbiamo visto tante volte che non compare il tema dell&rsquo;urbanizzazione. Dobbiamo fare pressione &#8211; per assicurare che l&rsquo;urbanizzazione sia al centro di questi piani, perch&eacute; solo cos&igrave; potranno essere stanziati fondi in questo settore&rdquo;, ha dichiarato all&rsquo;incontro il vicesegretario generale del gruppo ACP Andrew Bradley. Il Burundi pu&ograve; essere preso ad esempio. Qui, il governo stanzia appena il quattro per cento del suo budget negli alloggi, e &ldquo;non c&rsquo;&egrave; da stupirsi&rdquo;, sostiene indignato Sebastian Ntirampeba, consulente del dipartimento della pianificazione urbana del ministero risorse idriche, ambiente e urbanizzazione. <\/p>\n<p>&ldquo;&Egrave; una cifra insignificante. Come possiamo impedire la presenza degli slum se non investiamo negli alloggi&rdquo;, ha detto in un&rsquo;intervista. &ldquo;La maggioranza della popolazione &egrave; povera&rdquo;.<\/p>\n<p>Secondo Jose Maria Veiga, ministro per lo sviluppo rurale e le risorse marine di Capo Verde, un passo cruciale sarebbe prima di tutto impedire alle persone di emigrare verso i centri urbani.<\/p>\n<p>&ldquo;E questo &egrave; possibile decentralizzando i servizi nelle aree rurali, per garantire l&rsquo;accesso della gente ai servizi sul posto, oltre a creare infrastrutture in queste zone. Per esempio l&rsquo;elettricit&agrave;, le strade, i mercati, le telecomunicazioni, ecc.&rdquo;, dice Vega. <\/p>\n<p>Inoltre, uniformare l&rsquo;accesso alle opportunit&agrave; di lavoro e ai servizi tra aree rurali e urbane rallenterebbe la crescita esplosiva dell&rsquo;Africa urbana. <\/p>\n<p>Un rapporto dell&rsquo;Onu 2008 incentrato sulla distribuzione della popolazione e l&rsquo;urbanizzazione, ammette che la crescita della popolazione urbana &egrave; alimentata dalla migrazione campagne-citt&agrave;, ma rivela che, ad eccezione di Cina e Indonesia, due terzi della crescita urbana sono rappresentati dalla crescita naturale &#8211; le nascite tra i residenti urbani.&copy;IPS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAIROBI, 12 giugno 2009 (IPS) &#8211; Milioni di persone si spostano ogni anno verso le citt&agrave; africane, andando ad ingrossare le fila dei poveri urbani. &ldquo;Non possiamo cacciare la gente dalle baraccopoli&rdquo;, dice Kelvin Mmangisa, direttore generale della Lilongwe City&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2009\/06\/12\/sviluppo-africa-trovare-alloggi-per-i-poveri-urbani\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,38,11,1,27,25,33],"tags":[],"class_list":["post-1635","post","type-post","status-publish","format-standard","hentry","category-africa","category-sviluppo","category-columnas","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile","category-popolazione"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1635"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1635\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}