{"id":1472,"date":"2006-09-26T11:21:10","date_gmt":"2006-09-26T11:21:10","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/09\/26\/sviluppo-dai-margini-della-societ-al-centro-del-campo\/"},"modified":"2006-09-26T11:21:10","modified_gmt":"2006-09-26T11:21:10","slug":"sviluppo-dai-margini-della-societ-al-centro-del-campo","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2006\/09\/26\/sviluppo-dai-margini-della-societ-al-centro-del-campo\/","title":{"rendered":"SVILUPPO: Dai margini della societ&agrave; al centro del campo"},"content":{"rendered":"<p>CITT&Agrave; DEL CAPO, 26 settembre 2006 (IPS) &#8211; Nelson Mandela vi fece il primo discorso dopo la liberazione, ma la piazza fu anche palcoscenico di proteste anti-apartheid e parate militari. Questa settimana per&ograve;, la Grand Parade di Citt&agrave; del Capo ospiter&agrave; un evento assolutamente diverso: partite di calcio da strada disputate per la Coppa del mondo dei senzatetto 2006 (HWC).<\/p>\n<p><!--more--><\/p>\n<p>Iniziate domenica, si concluderanno il 30 settembre, e circa 500 persone da tutto il mondo prenderanno parte al torneo, il quarto di questo tipo. La Coppa ha per&ograve; l&rsquo;obiettivo di offrire molto pi&ugrave; che un gioco emozionante o una vetrina per talenti del calcio. Gli organizzatori sperano che si trasformi anche in uno stimolo per i partecipanti ad abbandonare le loro vite precarie sulla strada, da cui lo slogan del torneo: &ldquo;48 nazioni, un goal&rdquo;.<\/p>\n<p>L&rsquo;idea dell&rsquo;HWC &egrave; arrivata nel 2001 durante la conferenza annuale della Rete internazionale della stampa di strada con sede a Glasgow. (I giornali di strada sono pubblicazioni realizzate per assistere i senzatetto che ricevono parte dei profitti ricavati dalla loro vendita).<\/p>\n<p>Harald Schmied, redattore della pubblicazione austriaca &ldquo;Megaphon&rdquo;, e Mel Young, co-fondatore di &ldquo;The Big Issue Scotland&rdquo;, stavano cercando un modo per riunire i senzatetto provenienti dai diversi paesi, e altre persone che vivono ai margini della societ&agrave;. Lo hanno trovato nel calcio.<\/p>\n<p>&rdquo;&Egrave; un linguaggio universale&rdquo;, sostiene Richard Ishmail, direttore amministrativo di &ldquo;The Big Issue South Africa&rdquo;, il giornale di strada che ospita l&rsquo;HWC di quest&rsquo;anno. &ldquo;Il calcio mobilita la gente. Combattere il problema dei senzatetto&#8230;significa relazionarsi con le societ&agrave;, formare delle squadre, lavorare insieme. &Egrave; questo che fa il calcio&rdquo;.<\/p>\n<p>Il calcio ha certamente mobilitato Ataka Jansen, stella della squadra del Namibia durante la Coppa del 2005 a Edimburgo, in Scozia.<\/p>\n<p>Dopo aver abbandonato la scuola, si era ritrovato sulle strade di Swakopmund, citt&agrave; costiera, a bere, e a vivere di furti e aggressioni. Jansen ha poi incontrato un venditore ambulante della versione del Namibia di &ldquo;The Big Issue&rdquo; e ha deciso di vendere anche lui il giornale; successivamente si &egrave; qualificato per un posto nell&rsquo;ultima HWC.<\/p>\n<p>&rdquo;Non molti hanno l&rsquo;opportunit&agrave; di rappresentare il proprio paese&rdquo;, ha dichiarato. &ldquo;Mi sono sentito incredibilmente fiero&rdquo;.<\/p>\n<p>L&rsquo;esperienza di Jansen a Edimburgo l&#039;ha aiutato ad essere pi&ugrave; determinato nel voler migliorare la propria condizione: &ldquo;Volevo davvero risollevare la mia vita, non volevo pi&ugrave; essere lo stesso Ataka&rdquo;.<\/p>\n<p>Cos&igrave;, quando &egrave; tornato a casa dalla Scozia, ha detto addio al crimine una volta per tutte, e ha trovato un lavoro come apprendista meccanico attraverso &ldquo;The Big Issue&rdquo;. &ldquo;La Coppa mi ha dato uno spirito nuovo per cambiare&rdquo;, ha detto Jansen all&rsquo;IPS.<\/p>\n<p>Questa esperienza non &egrave; isolata. La ricerca condotta un anno dopo il campionato del 2005 ha dimostrato che il 77 per cento dei giocatori ha cambiato la propria vita in meglio, dopo la partecipazione al torneo. I miglioramenti comprendono il conseguimento di un lavoro, l&rsquo;abbandono di droga e alcolismo, la ripresa degli studi, e il far fronte ai problemi di alloggio.<\/p>\n<p>&rdquo;Gli allenamenti regolari aiutano i giocatori a sviluppare uno stile di vita pi&ugrave; sano. Inoltre, facendo parte di una squadra, si apprendono responsabilit&agrave; e disciplina&rdquo;, secondo Mattieu Rukoro, coordinatore per lo sviluppo sociale di &ldquo;The Big Issue Namibia&rdquo;.<\/p>\n<p>Anche il &ldquo;fattore divertimento&rdquo; &egrave; importante, ha aggiunto: &ldquo;Viaggiare all&rsquo;estero, fare nuove amicizie ed essere applauditi da migliaia di persone aumenta l&rsquo;autostima dei giocatori. Questi ragazzi sono sempre stati invisibili. Improvvisamente sono stati visti&rdquo;. <\/p>\n<p>Angus Okanume racconta un&rsquo;altra storia sul successo dell&rsquo;HWC. Nato in Nigeria, era fuggito in Austria da adolescente per il timore della persecuzione religiosa, ed era rimasto da allora alla ricerca di un rifugio. La sua vita &egrave; giunta a una svolta solo quando ha ottenuto un posto nella squadra austriaca dei senzatetto, che ha vinto la Coppa del 2003.<\/p>\n<p>La copertura dei media che hanno seguito la vittoria della squadra ha portato delle opportunit&agrave; ai giocatori coinvolti. Nel caso di Okanume, gli &egrave; stato permesso di iniziare dei corsi di lingua tedesca, e di tornare a scuola. Inoltre, gli &egrave; stato assegnato un posto in un campionato di calcio semi-professionale in una delle leghe regionali austriache, e poi alla FC Graz.<\/p>\n<p>&rdquo;La Coppa mi ha dato grande motivazione, volevo davvero andare avanti nella vita&rdquo;, dichiara Okanume sul sito web dell&rsquo;HWC.<\/p>\n<p>Oggi dodici partecipanti alla Coppa del 2005 traggono parte del loro sostentamento dal calcio, come allenatori o giocatori in squadre professionali e semi-professionali.<\/p>\n<p>Jansen, nel 2006 capitano della squadra del Namibia, potrebbe essere il prossimo. Poco prima di partire per il Sud Africa gli hanno comunicato che Civics, la squadra che ha vinto la Namibia Premier League dello scorso anno, vorrebbe offrirgli un contratto.<\/p>\n<p>&rdquo;La Coppa del mondo dei senzatetto ha dimostrato che lo sport, e nel nostro caso il calcio, ha un enorme potere nel concretizzare cambiamenti reali e duraturi&rdquo;, ha detto Young, attuale presidente dell&rsquo;HWC. &ldquo;La Coppa mondiale dei senzatetto di Citt&agrave; del Capo promette di essere la migliore, con il doppio dei paesi rappresentati rispetto ai tornei precedenti&rdquo;.<\/p>\n<p>Le 48 squadre nazionali che competeranno in questa citt&agrave; costiera del Sud Africa rappresentano paesi molto diversi, come Afghanistan, Zimbabwe, Brasile, Italia, Ucraina, Stati Uniti e Australia. In totale, sono presenti 13 nazioni africane.<\/p>\n<p>Pi&ugrave; di 10.000 senzatetto sono stati coinvolti nella preparazione al torneo, nelle prove nazionali preagonistiche e in societ&agrave; di calcio da strada.<\/p>\n<p>E anche per coloro che non approdano sul campo potrebbe arrivare il cambiamento.<\/p>\n<p>&rdquo;La Coppa tocca le vite di molti volontari e spettatori, che inizieranno a guardare ai senzatetto in maniera diversa, anche quando questo torneo sar&agrave; finito&rdquo;, ha detto Ishmail.<\/p>\n<p>Tuttavia, non manca una sua nota di prudenza circa l&rsquo;effetto dell&rsquo;HWC sulle vite dei giocatori. Non esistono soluzioni rapide alla condizione di senzatetto e ai relativi problemi: &ldquo;Uscire dalla povert&agrave; e dallo status di senzatetto &egrave; un processo che richiede tempo&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CITT&Agrave; DEL CAPO, 26 settembre 2006 (IPS) &#8211; Nelson Mandela vi fece il primo discorso dopo la liberazione, ma la piazza fu anche palcoscenico di proteste anti-apartheid e parate militari. Questa settimana per&ograve;, la Grand Parade di Citt&agrave; del Capo&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2006\/09\/26\/sviluppo-dai-margini-della-societ-al-centro-del-campo\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":194,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,38,11,1,27,25,33],"tags":[],"class_list":["post-1472","post","type-post","status-publish","format-standard","hentry","category-africa","category-sviluppo","category-columnas","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile","category-popolazione"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/194"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1472"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1472\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}