{"id":1205,"date":"2010-04-19T19:12:14","date_gmt":"2010-04-19T19:12:14","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2010\/04\/19\/donne-maltrattate-e-senza-risorse\/"},"modified":"2010-04-19T19:12:14","modified_gmt":"2010-04-19T19:12:14","slug":"donne-maltrattate-e-senza-risorse","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2010\/04\/19\/donne-maltrattate-e-senza-risorse\/","title":{"rendered":"DONNE: Maltrattate, e senza risorse"},"content":{"rendered":"<p>NEW YORK, 19 aprile 2010 (IPS) &#8211; Intervistata nella sua casa di Glen Oaks, nel Queens, Anna Mollah piange senza sosta ricordando le percosse subite dal marito.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1571\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1571\" class=\"size-full wp-image-1571\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/51060-20100415.jpg\" alt=\"Anna Mollah, una musulmana di origine indonesiana, ha subito abusi dal marito per vent'anni senza avere nessuno a cui rivolgersi Elizabeth Wagner\" width=\"200\"\/><p id=\"caption-attachment-1571\" class=\"wp-caption-text\">Anna Mollah, una musulmana di origine indonesiana, ha subito abusi dal marito per vent&#8217;anni senza avere nessuno a cui rivolgersi<br \/>Elizabeth Wagner<\/p><\/div><\/div>\n<p>Mentre era incinta del loro primo figlio, la colpiva con pugni nello stomaco, la prendeva a calci mentre aspettava la seconda figlia, e ancora durante la terza gravidanza. La picchiava quando discutevano della bolletta della luce, quando lui aveva mal di testa, o se disapprovava i libri di scuola che lei comprava per i bambini.<\/p>\n<p>La insultava ripetutamente, chiamandola &#8220;donna inutile&#8221;, &#8220;spazzatura&#8221; e &#8220;buona a nulla&#8221;, e alla fine glielo faceva credere. <\/p>\n<p>Un giorno Anna prese l&#039;auto di famiglia per fare alcune commissioni senza il suo permesso e lui si infuri&ograve;. Ebbero una discussione, lui era fuori di s&eacute;. Poi scoppi&ograve;, le avvolse le mani intorno al collo e strinse forte. Lei cerc&ograve; di urlare per chiedere aiuto mentre lui la strangolava. Riusc&igrave; solo a dire: &#8220;Chiamo la polizia&#8221;. Poi lui la spinse a terra con violenza. <\/p>\n<p>Anna nasconde il viso tra le sue piccole mani e comincia a singhiozzare, mentre ricorda la paura e l&rsquo;orrore che vide negli occhi dei suoi figli mentre assistevano alla scena.<\/p>\n<p>Anna Mollah, come lei stessa racconta, &egrave; stata vittima di violenze domestiche per vent&rsquo;anni. Sapeva che a New York nessuno avrebbe aiutato una come lei, un&rsquo;immigrata musulmana proveniente dall&rsquo;Indonesia.<\/p>\n<p>&#8220;Perdi ogni speranza&#8221;, ha detto. &ldquo;Non sai pi&ugrave; che fare&#8221;.<\/p>\n<p>Cos&igrave; Mollah rimase in silenzio per 20 anni, condividendo il suo segreto solo con Dio.<\/p>\n<p> <b>Non vogliono parlarne<\/b><\/p>\n<p>Per Mollah e per migliaia di altre donne immigrate che come lei hanno subito maltrattamenti, rompere il silenzio &egrave; estremamente difficile. Le donne straniere faticano a denunciare gli abusi molto pi&ugrave; delle donne statunitensi, per una serie di ragioni: barriere linguistiche, la paura di essere rimandate nel loro paese e i tab&ugrave; culturali sulla possibilit&agrave; di parlare dei problemi coniugali, secondo l&rsquo;ufficio municipale di New York responsabile della lotta alla violenza domestica.<\/p>\n<p>Anna Mollah ha nascosto per anni tutti gli abusi subiti, era troppo imbarazzata per confidarli persino alla madre e alla sorella, quando anche loro si trasferirono nel Queens.<\/p>\n<p>&#8220;Mi vergognavo, mi sentivo molto imbarazzata&#8221;, ha spiegato. &#8220;Siamo noi che scegliamo con chi stare. Ero d&rsquo;accordo di sposarlo ma poi ho fallito. Per questo non potevo dirlo a nessuno. Non l&rsquo;ho mai raccontato a nessuno&#8221;. <\/p>\n<p>Centinaia di organizzazioni no-profit di New York City danno sostegno alle donne maltrattate. Gli enti comunali che combattono la violenza domestica hanno strutture che dirigono le vittime verso gruppi di supporto, rifugi e aiuti legali. Il personale parla pi&ugrave; di 20 lingue, ed &egrave; in grado di comunicare in 150 lingue.<\/p>\n<p>&#8220;I servizi esistono e sono gratuiti&#8221;, ha detto la portavoce di OCDV , Ruth Villalonga.<\/p>\n<p>Ma secondo alcuni, molte organizzazioni non riescono a soddisfare le esigenze dei nuovi gruppi di immigrati; spesso le vittime preferirebbero cercare aiuto tra le persone della loro stessa etnia o religione.<\/p>\n<p>Secondo Robina Niaz, direttrice del centro &ldquo;Turning Point for women and families&rdquo;, gli immigrati pi&ugrave; recenti, soprattutto sud-asiatici e musulmani, stanno ancora lottando per farcela da soli. Niaz fond&ograve; nel 2004 questa organizzazione per le donne musulmane a Flushing, nel Queens.<\/p>\n<p>Attualmente in citt&agrave; la sua &egrave; l&#039;unica organizzazione di sostegno agli abusi per le donne musulmane, ha detto. <\/p>\n<p>&#8220;Se provi un senso di appartenenza, allora puoi gi&agrave; superare alcune paure&#8221;, ha detto Niaz, un&rsquo;immigrata musulmana venuta dal Pakistan. &#8220;Gli abusi ti isolano. Come si rompe l&#039;isolamento? Creando organizzazioni. Il senso di sicurezza &egrave; fondamentale&#8221;. <\/p>\n<p><b>Wanted: Zona di sicurezza<\/b><\/p>\n<p> Niaz ritiene che molte associazioni non possono soddisfare le esigenze delle donne musulmane e di conseguenza non riescono a trasmettere un senso di sicurezza. Per esempio, Niaz dice che sono pochi i rifugi che hanno uno spazio apposito in cui i musulmani possano pregare, o che tengono conto delle loro esigenze alimentari; i musulmani non mangiano carne di maiale, per esempio.<\/p>\n<p>Le donne musulmane sono tradizionalmente reticenti nel discutere le proprie difficolt&agrave; personali,  ha aggiunto Niaz, ammettendo che lei stessa aveva tenuto nascosti gli abusi verbali del marito.<\/p>\n<p>&#8220;Le nostre donne spesso provengono da culture in cui di norma aspettano che qualcuno chieda loro se qualcosa non va&raquo;, dice. &#8220;Spetta alle famiglie interessarsi e capire se qualcuno ha bisogno di aiuto. Qui in America la gente chiede: &#039;Come facevo a sapere che avevi bisogno di aiuto se non mi hai detto niente?&#039; E le donne musulmane rispondono: &#8220;Beh, non me l&rsquo;hai mai chiesto&#039;&#8221;.<\/p>\n<p>Niaz crede che se le organizzazioni musulmane fossero pi&ugrave; presenti, la violenza domestica sarebbe meno uno stigma. New York ospita la seconda pi&ugrave; grande comunit&agrave; musulmana degli Stati Uniti, e Niaz pensa che il numero delle vittime musulmane in cerca di aiuto aumenter&agrave;.<\/p>\n<p>Turning Point ha assistito pi&ugrave; di 250 donne dalla sua fondazione, ma Niaz crede che potrebbe fornire ancora pi&ugrave; aiuto con pi&ugrave; dipendenti e pi&ugrave; denaro (oggi il suo staff conta cinque persone). Lo spazio per gli uffici &egrave; composto da una sola stanza di piccole dimensioni, destinata all&rsquo;assistenza legale. E un grosso contributo le arriver&agrave; dal suo principale finanziatore alla fine di giugno 2010.<\/p>\n<p>Oggi i gruppi musulmani o le organizzazioni islamiche, fra cui Turning Point, non ricevono molti fondi: dopo l&rsquo;11 settembre c&rsquo;&egrave; molto scetticismo e ostilit&agrave; nei loro confronti.<\/p>\n<p>&#8220;I sentimenti anti-musulmani si stanno facendo pi&ugrave; forti&#8221;, ha detto Carroll Adem, presidente del Muslim Consultative Network New York. Carroll sostiene che gli americani sono sempre pi&ugrave; prudenti nell&rsquo;associare il loro nome a quello di organizzazioni musulmane, e possono rifiutarsi di fare donazioni agli enti di beneficenza islamici. <\/p>\n<p> Niaz riconosce che la citt&agrave;, lo stato e le agenzie federali sanno che le organizzazioni contro gli abusi per gli immigrati hanno bisogno di soldi. Ma &egrave; anche scoraggiata dal fatto che il governo non stia considerando l&rsquo;assistenza come una priorit&agrave;.<\/p>\n<p>Fino a quando gli enti comunali non concederanno finanziamenti, Niaz incoraggia la comunit&agrave; musulmana a costruire autonomamente i propri arsenali di risorse. Gli assistenti sociali e avvocati musulmani sono pochissimi, ha detto. &copy; IPS <\/p>\n<p>* Speciale da NYU Livewire per IPS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NEW YORK, 19 aprile 2010 (IPS) &#8211; Intervistata nella sua casa di Glen Oaks, nel Queens, Anna Mollah piange senza sosta ricordando le percosse subite dal marito.<\/p>\n","protected":false},"author":412,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[11,15,16,1,27,30,25],"tags":[],"class_list":["post-1205","post","type-post","status-publish","format-standard","hentry","category-columnas","category-diritti-umani","category-donne-e-sviluppo","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-nord-america","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1205\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}