{"id":1094,"date":"2009-02-25T16:46:58","date_gmt":"2009-02-25T16:46:58","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/02\/25\/eau-la-partecipazione-delle-donne-la-norma\/"},"modified":"2009-02-25T16:46:58","modified_gmt":"2009-02-25T16:46:58","slug":"eau-la-partecipazione-delle-donne-la-norma","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2009\/02\/25\/eau-la-partecipazione-delle-donne-la-norma\/","title":{"rendered":"EAU: La partecipazione delle donne &egrave; la norma"},"content":{"rendered":"<p>DUBAI, 25 febbraio 2009 (IPS) &#8211; Nei paesi del Golfo, tra gli ambienti sensibili al tema femminile, gli sforzi compiuti dagli Emirati Arabi Uniti (UAE) per l&rsquo;empowerment delle donne ed il loro riconoscimento come partner nel processo di costruzione della nazione sono molto apprezzati, ma gli esperti sottolineano che la situazione pu&ograve; ancora migliorare.<\/p>\n<p><!--more--><\/p>\n<p>Per riuscire a stare al passo con il rapido processo di modernizzazione seguito all&rsquo;istituzione della federazione degli EAU nel 1971, la visione strategica del governo nei confronti delle donne ha permesso di dotarle sempre di pi&ugrave; degli strumenti necessari alla loro partecipazione, sia nel settore pubblico che in quello privato.    &ldquo;Contrariamente alla falsa idea e agli stereotipi che le considerano un gruppo ristretto nella nostra societ&agrave;, le donne sono in prima linea sia nel governo che nel settore privato. Il ruolo di rilievo che hanno nella societ&agrave; ha visto dei progressi, e oggi &egrave; la norma, non un&rsquo;eccezione&rdquo;, ha osservato Anwar Gargash, Ministro di Stato per gli Affari esteri, alla presentazione del rapporto presso la Universal Periodic Review, condotto dal Consiglio per i diritti umani di Ginevra nel dicembre 2008&rdquo;. <\/p>\n<p>&ldquo;La leadership degli EAU &#8211; ha aggiunto Gargash &#8211; &egrave; impegnata ad assicurare l&rsquo;empowerment delle donne e ad utilizzare le loro competenze nella nostra economia in crescita. &Egrave; un impegno previsto dalla Costituzione, grazie a specifiche garanzie sulla parit&agrave; di genere e la giustizia sociale, cos&igrave; come nelle legislazioni, che si evolvono gradualmente cercando di mantenere l&rsquo;equilibrio tra modernizzazione, eredit&agrave; culturale e credenze islamiche&rdquo;. <\/p>\n<p>L&rsquo;educazione &egrave; senz&rsquo;altro servita da principale catalizzatore per lo sviluppo delle donne nel paese. Secondo una pubblicazione del governo che cita un rapporto di PricewaterhouseCoopers, al 77 per cento, &ldquo;gli EAU stanno registrando il pi&ugrave; alto tasso di presenza femminile nell&rsquo;educazione superiore al mondo&rdquo;. <\/p>\n<p>Secondo le statistiche ufficiali, anche se le donne rappresentano il 49,3 per cento della popolazione totale, di 4,6 milioni di persone, costituiscono circa il 60 per cento degli impiegati nel settore pubblico, di cui quasi la met&agrave; in ruoli di alto rilievo. <\/p>\n<p>Oltre ad essere funzionari pubblici, ingegneri e banchieri, e ad occuparsi delle attivit&agrave; tradizionali come l&rsquo;insegnamento e le cure sanitarie, di recente le donne sono diventate anche piloti aeronautici, ambasciatrici all&rsquo;estero, e sono sempre pi&ugrave; presenti nella magistratura. <\/p>\n<p>Il rapporto 2007 del Programma di sviluppo delle Nazioni Unite (UNDP) sugli Obiettivi di sviluppo del millennio, riconosceva i risultati positivi delle politiche mirate degli EAU in determinati settori, compreso l&rsquo;empowerment delle donne. Si osservava che le legislazioni negli EAU non prevedono discriminazioni sulla base del sesso nell&rsquo;istruzione, nell&rsquo;occupazione, o nella qualit&agrave; dei servizi forniti.    Secondo il dossier, gli indicatori dell&rsquo;istruzione mostrano che i risultati realizzati dalle donne nell&rsquo;educazione hanno raggiunto i livelli previsti, in alcuni casi superando quelli degli uomini, e questo per il forte desiderio di rendersi indipendenti finanziariamente e di avere successo a livello professionale.    L&rsquo;Indice di sviluppo dell&rsquo;UNDP in relazione al genere (Gender-Related Development Index, GDI) nel Rapporto sullo sviluppo umano 2007\/2008, pone gli EAU al 43esimo posto su 177 paesi, e 29esimo nel mondo secondo la &ldquo;Misura di sviluppo del genere&rdquo; (Gender Empowerment Measure, GEM): i primi classificati in tutto il mondo arabo. <\/p>\n<p>Le elezioni dello storico Consiglio nazionale federale (FNC) del dicembre 2006 hanno contribuito all&rsquo;accesso delle donne nello scenario politico nazionale. Pur rappresentando circa il 18 per cento del collegio elettorale, sul totale dei 452 candidati 63 erano donne. <\/p>\n<p>Solo una donna &egrave; stata eletta, ma il governo ne ha poi nominate altre otto per assicurare un&rsquo;equa rappresentativit&agrave;, il che si &egrave; tradotto in una quota del 22,5 per cento, ben oltre la media mondiale del 17 per cento. <\/p>\n<p>Nel febbraio 2008, un rimpasto di governo ha visto raddoppiare il numero delle donne ministro a quattro, il pi&ugrave; alto nella regione. <\/p>\n<p>Nel marzo 2008, Khouloud Ahmad Jouan Al Dhahiri &egrave; stata la prima donna negli EAU ad essere nominata magistrato. Cos&igrave;, gli EAU sono diventati il secondo paese arabo, dopo il Bahrain, ad aver nominato un giudice donna. <\/p>\n<p>Il contributo delle donne nell&rsquo;economia del paese &egrave; aumentato in modo significativo, dal 9,6 per cento nel 1986 al 33,4 per cento nel 2007, il che rappresenta una crescita annuale media di circa il 3,5 per cento. Secondo i dati del 2005, gli EAU hanno il maggior numero di donne imprenditrici nella regione.    Il Consiglio delle donne imprenditrici degli EAU, una rete nazionale di donne nel mondo imprenditoriale, professionale ed accademico, ha 12mila iscritte; ha avuto una crescita annuale del due per cento tra il 2002 e il 2006, e gestisce investimenti per circa 25 miliardi di dirham (6,8 miliardi di dollari Usa) in diversi settori. <\/p>\n<p>Eppure, il governo pensa che siano ancora &ldquo;lavori in corso&rdquo;, e spera di contribuire a produrre migliori risultati nei prossimi anni. <\/p>\n<p>Uno degli ambiti pi&ugrave; problematici nella sfera sociale &egrave; quello emerso qualche anno grazie alle donne degli Emirati sposate con stranieri, che hanno addirittura chiesto pubblicamente una reintegrazione delle loro indennit&agrave; della previdenza sociale.<\/p>\n<p>Secondo le leggi attuali, mentre per gli uomini non &egrave; previsto nessun ostacolo in caso di matrimonio con donne straniere, le donne che sposano cittadini di un altro paese si scontrano con diverse difficolt&agrave;, come la questione della cittadinanza per il loro figli e coniugi.<\/p>\n<p>Pur riconoscendo che il governo ha effettivamente operato un&rsquo;apertura nei confronti delle donne, Afnan Al-Mutawa, un&rsquo;impiegata del settore pubblico, ha spiegato che la sua famiglia merita maggiori riconoscimenti per averle permesso di perseguire le opportunit&agrave; di carriera a livello educativo e professionale. <\/p>\n<p>&rdquo;Senza il loro incoraggiamento, gli sforzi del governo sarebbero andati sprecati&rdquo;, ha osservato.   Allo stesso modo, pur apprezzando le iniziative del governo, Rima Sabban, una sociologa degli EAU, ha suggerito che sarebbero necessari degli sforzi per sostenere questo slancio sul lungo periodo, specificamente con &ldquo;leggi e regolamenti&rdquo;. <\/p>\n<p>In particolare, &ldquo;si dovrebbe far rispettare la legge sulle pari opportunit&agrave; per tutte le donne degli EAU, per garantire che anche chi non appartiene alle &eacute;lite si senta autorizzata ad esercitare il proprio potere, in particolare sullo scenario politico&rdquo;, ha spiegato. <\/p>\n<p>Sabban ha aggiunto che &ldquo;il governo dovrebbe adottare efficaci misure proattive per educare la societ&agrave; attraverso programmi orientati sulla famiglia, per contribuire ad una visione pi&ugrave; costruttiva delle donne, soprattutto rispetto alla parit&agrave; di genere negli ambiti lavorativi tradizionalmente riservati agli uomini&rdquo;. <\/p>\n<p>&rdquo;Capire a pieno come le donne organizzano la propria vita tra il lavoro domestico e le diverse fasi del loro ciclo vitale &egrave; altrettanto importante, per evitare reazioni sociali negative e disordini nel tessuto sociale&rdquo;, ha raccomandato il sociologo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DUBAI, 25 febbraio 2009 (IPS) &#8211; Nei paesi del Golfo, tra gli ambienti sensibili al tema femminile, gli sforzi compiuti dagli Emirati Arabi Uniti (UAE) per l&rsquo;empowerment delle donne ed il loro riconoscimento come partner nel processo di costruzione della&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2009\/02\/25\/eau-la-partecipazione-delle-donne-la-norma\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":351,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[16,1,26,25,32,35,36],"tags":[],"class_list":["post-1094","post","type-post","status-publish","format-standard","hentry","category-donne-e-sviluppo","category-headlines","category-iraq-e-asia-centrale","category-obiettivi-di-sviluppo-sostenibile","category-politica","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/351"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1094"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1094\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}