{"id":1072,"date":"2009-01-09T14:30:03","date_gmt":"2009-01-09T14:30:03","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/01\/09\/medioriente-bambini-trovati-in-fin-di-vita\/"},"modified":"2009-01-09T14:30:03","modified_gmt":"2009-01-09T14:30:03","slug":"medioriente-bambini-trovati-in-fin-di-vita","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/italiano\/2009\/01\/09\/medioriente-bambini-trovati-in-fin-di-vita\/","title":{"rendered":"MEDIORIENTE: Bambini trovati in fin di vita"},"content":{"rendered":"<p>RAMALLAH, 9 gennaio 2009 (IPS) &#8211; Un coro mondiale di condanna si &egrave; levato contro Israele per gli abusi dei diritti umani commessi a Gaza. L&rsquo;operazione Piombo fuso, giunta al suo tredicesimo giorno, ha gi&agrave; provocato oltre 700 vittime tra i palestinesi.<\/p>\n<p><!--more--><\/p>\n<p>Il Comitato internazionale della Croce Rossa (ICRC) ha chiesto gioved&igrave; un accesso sicuro, in modo che i suoi operatori e le ambulanze della Croce Rossa palestinese (PRC) possano evacuare i feriti. La Croce Rossa ha accusato Israele di aver deliberatamente ritardato l&rsquo;arrivo delle ambulanze.<\/p>\n<p>Le squadre d&rsquo;emergenza avrebbero gi&agrave; tentato in diverse occasioni di soccorrere i feriti e di recuperare i corpi in diverse aree di Gaza city, ma avrebbero visto negarsi l&rsquo;accesso dai soldati delle Forze di Difesa israeliane (IDF).<\/p>\n<p>Mercoled&igrave; scorso, dopo una settimana di intensi negoziati con i funzionari israeliani, gli operatori dell&rsquo;ICRC e le ambulanze della PRC sarebbero comunque riusciti a raggiungere alcuni dei sopravvissuti nel quartiere di Zeitoun a Gaza.<\/p>\n<p>L&rsquo;ICRC avrebbe trovato quattro bambini piccoli accanto ai corpi delle madri morte in una delle case della zona. Sembra che i bambini fossero affamati e troppo deboli per tenersi in piedi. Un uomo &egrave; stato trovato in fin di vita, e sempre nella stessa casa sarebbero stati trovati anche dodici corpi senza vita distesi sui materassi.<\/p>\n<p>In un altro edificio l&rsquo;ICRC avrebbe invece soccorso quindici sopravvissuti. In una casa adiacente sono stati trovati tre corpi. Le squadre di soccorso continuano a cercare sopravvissuti, nonostante gli ordini ricevuti dai soldati israeliani di lasciare la zona.<\/p>\n<p>&rdquo;&Egrave; sconvolgente&rdquo;, ha commentato all&rsquo;IPS Pierre Wettach, capo della delegazione dell&rsquo;ICRC per Israele e i territori palestinesi occupati. &ldquo;L&rsquo;esercito israeliano deve essersi reso conto della situazione, ma non ha soccorso i feriti. Ed ha anche impedito a noi e alla PRC di assisterli&rdquo;.<\/p>\n<p>Secondo l&rsquo;ICRC, Israele avrebbe violato il diritto umanitario internazionale.<\/p>\n<p>Mercoled&igrave; scorso, Amnesty International ha accusato l&rsquo;IDF e i cecchini palestinesi di aver utilizzato i civili palestinesi come scudi umani.<\/p>\n<p>&rdquo;Secondo le nostre fonti a Gaza, i soldati israeliani sarebbero entrati in alcune abitazioni palestinesi prendendo posizione, e costringendo le famiglie a rimanere nelle stanze a pianterreno per poter usare il resto della casa come base militare e per i loro cecchini&rdquo;, ha denunciato Malcom Smart, direttore del Programma Medio Oriente e Africa del Nord di Amnesty International.<\/p>\n<p>&ldquo;Questo ovviamente aumenta il rischio per le famiglie palestinesi coinvolte, e significa che di fatto vengono utilizzate come scudi umani&rdquo;, ha aggiunto.<\/p>\n<p>Anche i cecchini palestinesi avrebbero utilizzato le case dei civili come basi per attaccare le forze israeliane, ma le IDF starebbero impiegando questa tattica da diversi anni. &Egrave; una tipica strategia delle IDF nella West Bank occupata installarsi nelle case dei palestinesi usandole come basi militari, e confinando le famiglie in un&rsquo;unica stanza.<\/p>\n<p>I soldati israeliani sono stati ripresi mentre costringevano alcuni giovani palestinesi a camminare di fronte alle jeep dell&rsquo;esercito, o venivano mandati avanti nelle case dove si sospettava potessero nascondersi i cecchini o le trappole esplosive, per aprire la strada ai soldati.<\/p>\n<p>Anche Amnesty International ha condannato la decisione di Israele di stabilire un cessate il fuoco di sole tre ore al giorno, giudicato insufficiente per fronteggiare l&rsquo;escalation della crisi umanitaria.<\/p>\n<p>&ldquo;Un tregua di poche ore al giorno non basta. &Egrave; troppo breve per risolvere i bisogni urgenti e massicci dei civili coinvolti nelle ostilit&agrave; e tra cui si registrano enormi perdite umane&rdquo;, spiega Curt Goering, vice direttore esecutivo di Amnesty per gli USA.<\/p>\n<p>&ldquo;Israele ha bloccato gli aiuti per quasi tutto il 2008. L&rsquo;esercito israeliano non pu&ograve; lasciar entrare gli aiuti per tre ore e pensare che questo sia sufficiente. Una breve &lsquo;pausa&rsquo; giornaliera non pu&ograve; garantire la sicurezza degli operatori umanitari&rdquo;, ha osservato Goering.<\/p>\n<p>Intanto, le Nazioni Unite hanno chiesto che Israele fornisca le prove delle sue affermazioni, secondo cui alcuni cecchini palestinesi avrebbero sparato contro le forze israeliane da una scuola dell&rsquo;ONU nel nord di Gaza, prima che gli israeliani sferrassero il loro attacco sulla scuola uccidendo pi&ugrave; di 40 civili palestinesi.<\/p>\n<p> L&rsquo;ONU ha categoricamente negato che vi fossero uomini armati nella scuola in quel momento.<\/p>\n<p>&ldquo;Non abbiamo niente da nascondere&rdquo;, ha dichiarato alla CNN mercoled&igrave; scorso il portavoce dell&rsquo;UNRWA Chris Gunness. &ldquo;Vogliamo vedere le prove, per sgombrare ogni sospetto&rdquo;.<\/p>\n<p>Ci sono circa 14mila palestinesi rifugiati nelle scuole dell&rsquo;UNRWA. L&rsquo;ONU ribadisce che prima del lancio dell&rsquo;offensiva militare di Israele a Gaza, aveva fornito ad Israele le coordinate satellitari GPS di tutte le sue strutture a Gaza.<\/p>\n<p>Diversi anni fa Israele aveva suscitato scalpore con l&rsquo;accusa rivolta all&rsquo;UNRWA di trasportare cecchini nelle proprie ambulanze. Le IDF sostenevano di essere in possesso di foto satellitari di &ldquo;checchini&rdquo; che caricavano &ldquo;razzi&rdquo; nel retro di un ambulanza.<\/p>\n<p>Una successiva indagine stabil&igrave; che il &ldquo;razzo&rdquo; era in realt&agrave; una barella, e i &ldquo;cecchini&rdquo; medici. L&rsquo;UNRWA chiese delle scuse, che non ha mai ricevuto.<\/p>\n<p>Dopo lo scoppio, nel 2000, della seconda rivolta palestinese, o Intifada, Israele accus&ograve; l&rsquo;ICRC di trasportare in una delle sue ambulanze kamikaze con cinture di esplosivi intorno alla vita. L&rsquo;ICRC neg&ograve; fermamente l&rsquo;accusa, e chiese di vedere le prove, che per&ograve; non sono mai state fornite.<\/p>\n<p>Nel frattempo, si starebbe preparando un nuovo confronto al largo delle coste di Gaza, dove una nave internazionale con a bordo aiuti umanitari, attivisti dei diritti umani, giornalisti e politici sarebbe pronta a rompere il blocco navale di Israele su Gaza.<\/p>\n<p>Vi sono gi&agrave; stati diversi tentativi da parte di altre navi, conclusi senza successo; il pi&ugrave; recente, quello della nave umanitaria Dignity, che &egrave; stata intercettata e speronata da una motovedetta israeliana e scortata fino al porto di Beirut.<\/p>\n<p>A bordo, la rappresentante del Congresso USA Cynthia McKinney e una troupe della CNN, che ha ripreso l&rsquo;episodio con le telecamere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RAMALLAH, 9 gennaio 2009 (IPS) &#8211; Un coro mondiale di condanna si &egrave; levato contro Israele per gli abusi dei diritti umani commessi a Gaza. L&rsquo;operazione Piombo fuso, giunta al suo tredicesimo giorno, ha gi&agrave; provocato oltre 700 vittime tra&hellip; <a href=\"https:\/\/ipsnews.net\/italiano\/2009\/01\/09\/medioriente-bambini-trovati-in-fin-di-vita\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":314,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[15,1,28,25,32,33],"tags":[],"class_list":["post-1072","post","type-post","status-publish","format-standard","hentry","category-diritti-umani","category-headlines","category-medioriente","category-obiettivi-di-sviluppo-sostenibile","category-politica","category-popolazione"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/314"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}