{"id":7842,"date":"2020-07-06T07:49:00","date_gmt":"2020-07-06T07:49:00","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/?p=7842"},"modified":"2020-07-16T08:20:53","modified_gmt":"2020-07-16T08:20:53","slug":"covid-19-a-t-elle-pousse-les-femmes-en-politique-hors-du-programme-du-kenya","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2020\/07\/06\/covid-19-a-t-elle-pousse-les-femmes-en-politique-hors-du-programme-du-kenya\/","title":{"rendered":"COVID-19 a-t-elle pouss\u00e9 les femmes en politique hors du programme du Kenya?"},"content":{"rendered":"<p>NAIROBI, le 6 juillet 2020 (IPS) &#8211; En 2013, Alice Wahome s\u2019est pr\u00e9sent\u00e9e aux \u00e9lections dans sa troisi\u00e8me tentative de remporter le si\u00e8ge parlementaire tr\u00e8s contest\u00e9e de la circonscription de Kandara, du comt\u00e9 de Murang\u2019a, dans le centre du Kenya. Comme c&#8217;est caract\u00e9ristique dans la politique rurale, le terrain \u00e9tait domin\u00e9 par les hommes, les enjeux \u00e9tant \u00e9lev\u00e9s pour tous les candidats, mais plus particuli\u00e8rement pour Wahome &#8211; aucune femme n&#8217;avait jamais occup\u00e9 le si\u00e8ge parlementaire de la circonscription de Kandara.<br \/>\n<!--more--><\/p>\n<p>\u00abCe fut une campagne tr\u00e8s brutale. J&#8217;ai \u00e9t\u00e9 harcel\u00e9e, maltrait\u00e9e verbalement, menac\u00e9e de violence physique et de nombreuses choses non imprimables [m&#8217;ont \u00e9t\u00e9 dites] m\u00eame en public \u00bb, a d\u00e9clar\u00e9 Wahome \u00e0 IPS.<\/p>\n<p>Elle dit que les attributs qui sont consid\u00e9r\u00e9s comme admirables et souhaitables chez les hommes politiques ont \u00e9t\u00e9 utilis\u00e9s comme des armes contre elle et les autres femmes en politique.<\/p>\n<p>\u00abLorsque nous avons vocalis\u00e9 nos opinions, ils ont dit que nous parlions trop et le message sous-jacent est que les femmes d\u00e9centes ne parlent pas trop. Lorsque vous avez une position et \u00eates ferme dans vos convictions et valeurs politiques, ils disent que vous \u00eates combative, intol\u00e9rante et agressive. Les m\u00eames qualit\u00e9s chez les hommes sont acceptables \u00bb, explique Wahome.<\/p>\n<p>Le concours pour les \u00e9lecteurs de Kandara \u00e9tait si vicieux que le matin des \u00e9lections g\u00e9n\u00e9rales de 2013, la communaut\u00e9 s&#8217;est r\u00e9veill\u00e9e pour trouver des paquets de pr\u00e9servatifs portant le nom de Wahome. Sur les paquets se trouvaient des messages, pr\u00e9tendument de Wahome, encourageant les \u00e9lecteurs \u00e0 adopter la planification familiale.<\/p>\n<p>\u00abC&#8217;\u00e9tait une campagne de diffamation pour montrer \u00e0 mon peuple que je n&#8217;\u00e9tais pas apte \u00e0 \u00eatre leur leader. Il y a beaucoup de choses que les politiciens donnent aux \u00e9lecteurs, comme des produits alimentaires. La distribution de pr\u00e9servatifs dans une soci\u00e9t\u00e9 rurale et conservatrice le jour des \u00e9lections est un suicide politique \u00bb, explique Wahome, avocate.<\/p>\n<p>Heureusement, elle a pass\u00e9 des ann\u00e9es \u00e0 interagir avec la communaut\u00e9, \u00e0 promouvoir des initiatives de sant\u00e9, l&#8217;\u00e9ducation et l&#8217;autonomisation des femmes et des filles. Ainsi, malgr\u00e9 la campagne de diffamation, Wahome est devenue la premi\u00e8re femme \u00e0 remporter le si\u00e8ge de Kandara et exerce actuellement son deuxi\u00e8me mandat \u00e0 l&#8217;Assembl\u00e9e nationale apr\u00e8s sa r\u00e9\u00e9lection en 2017.<\/p>\n<p>La propagande, les menaces de violence et en particulier la violence sexuelle et physique, l&#8217;humiliation publique et les campagnes de d\u00e9nigrement vicieuses des m\u00e9dias sociaux sont quelques-uns des d\u00e9fis que les femmes en politique, comme Wahome, doivent surmonter pour gagner et maintenir un leadership politique.<\/p>\n<p>Cela s&#8217;ajoute aux d\u00e9fis globaux de la campagne tels que les ressources financi\u00e8res et humaines limit\u00e9es et les politiques internes vicieuses. Mais m\u00eame au niveau des partis politiques, le syst\u00e8me est toujours biais\u00e9 en faveur des hommes qui poss\u00e8dent et financent ces partis.<\/p>\n<p>\u00abL&#8217;ar\u00e8ne politique est tr\u00e8s hostile aux femmes. La campagne \u00e9lectorale est jonch\u00e9e d&#8217;exp\u00e9riences v\u00e9cues par des femmes qui ont \u00e9t\u00e9 brutalis\u00e9es pour avoir cherch\u00e9 \u00e0 diriger \u00bb, a expliqu\u00e9 \u00e0 IPS Wangechi Wachira, directrice ex\u00e9cutive du <em><strong>Centre for Rights, Education and Awareness (CREAW)<\/strong><\/em> (Centre pour les droits, l\u2019\u00e9ducation et la conscience).<\/p>\n<p>CREAW est un partenaire local de la campagne mondiale <em><strong>Deliver For Good<\/strong><\/em> qui poursuit une perspective de genre aux <a href=\"https:\/\/www.un.org\/sustainabledevelopment\/fr\/\" rel=\"noopener\" target=\"_blank\">Objectifs de D\u00e9veloppement Durable<\/a> et est propuls\u00e9 par l&#8217;organisation de plaidoyer mondiale <em><strong>Women Deliver<\/strong><\/em>. Les partenaires de la campagne \u00abDeliver for Good\u00bb pr\u00e9conisent de conduire des actions dans 12 domaines d&#8217;investissement critiques, notamment le renforcement de la participation politique des femmes et de leur pouvoir de d\u00e9cision.<\/p>\n<p>Wangechi a \u00e9t\u00e9 \u00e0 l&#8217;avant-garde pour tenir le gouvernement responsable de l&#8217;\u00e9galit\u00e9 et de l&#8217;\u00e9quit\u00e9 entre les sexes, comme le pr\u00e9voit la constitution 2010 kenyane progressiste en mati\u00e8re de genre, qui exige que tous les organes nomm\u00e9s et \u00e9lus soient constitu\u00e9s d\u2019un tiers des femmes.<\/p>\n<p><a href=\"https:\/\/klrc.go.ke\/index.php\/constitution-of-kenya\/112-chapter-four-the-bill-of-rights\/part-2-rights-and-fundamental-freedoms\/193-27-equality-and-freedom-from-discrimination\" rel=\"noopener\" target=\"_blank\">L\u2019article 27 (8) de la Charte des droits de la Constitution stipule<\/a>: \u00abL\u2019\u00c9tat doit prendre des mesures l\u00e9gislatives et autres pour appliquer le principe selon lequel au plus deux tiers des membres des organes \u00e9lectifs ou de nomination doivent \u00eatre du m\u00eame sexe.\u00bb<\/p>\n<p>L&#8217;Assembl\u00e9e nationale est sous l\u2019obligation de promulguer le projet 2018 d\u2019amendement de la Constitution du Kenya, \u00e9galement connu sous le nom de <em><strong>Gender Bill<\/strong><\/em>, pour mettre en \u0153uvre cette disposition. Mais plus de 10 ans plus tard, cette obligation n&#8217;est toujours pas remplie. En 2019, le Parlement ne disposait m\u00eame pas des deux tiers requis de membres pr\u00e9sents \u00e0 la Chambre &#8211; le quorum requis pour un amendement constitutionnel &#8211; pour voter sur le projet de loi. <\/p>\n<p>\u00abL&#8217;Assembl\u00e9e nationale a fait faux bond aux femmes du Kenya. Nous sommes all\u00e9es devant les tribunaux pour pousser l&#8217;Assembl\u00e9e nationale \u00e0 adopter une l\u00e9gislation pour corriger les in\u00e9galit\u00e9s flagrantes entre les sexes. Il y a trop de r\u00e9sistance et de refoulement d&#8217;un syst\u00e8me patriarcal \u00bb, explique Wangechi.<\/p>\n<p>C&#8217;est \u00e0 cette r\u00e9sistance que les femmes en politique se heurtent dans leur qu\u00eate de leadership. Les femmes ne repr\u00e9sentent que 9,2% des 1835 personnes \u00e9lues en 2017, une augmentation marginale par rapport \u00e0 7,7% en 2013, selon un rapport du <a href=\"https:\/\/www.ndi.org\/sites\/default\/files\/Gender%20Analysis%20of%202017%20GeneralElections%20FINAL%20High%20Res%20for%20Printer%20-%20NEW%20COVER_small.pdf\" rel=\"noopener\" target=\"_blank\">National Democratic Institute et de la F\u00e9d\u00e9ration des femmes juristes du Kenya<\/a>, cette derni\u00e8re \u00e9tant un autre partenaire local Deliver For Good.<\/p>\n<p>Ce rapport montre qu&#8217;aux \u00e9lections de 2017, 29% de femmes de plus se sont pr\u00e9sent\u00e9es aux \u00e9lections qu&#8217;aux \u00e9lections g\u00e9n\u00e9rales de 2013 et qu&#8217;il y a d\u00e9sormais plus de femmes aux postes \u00e9lectifs \u00e0 tous les niveaux du gouvernement. Mais Asha Abdi, une ancienne d\u00e9put\u00e9e de l&#8217;Assembl\u00e9e du comt\u00e9 de Nairobi, a d\u00e9clar\u00e9 \u00e0 IPS que les progr\u00e8s ont \u00e9t\u00e9 douloureusement lents.<\/p>\n<p>Au total, il y a maintenant 172 femmes \u00e0 des postes \u00e9lectifs &#8211; contre 145 en 2013. Aux \u00e9lections g\u00e9n\u00e9rales de 2017, 23 femmes ont \u00e9t\u00e9 \u00e9lues \u00e0 l&#8217;Assembl\u00e9e nationale contre 16 en 2013, et 96 autres ont \u00e9t\u00e9 \u00e9lues aux assembl\u00e9es de comt\u00e9 par rapport aux 82 femmes en 2013.<\/p>\n<p>En tant que telles, <a href=\"https:\/\/www.ndi.org\/sites\/default\/files\/Gender%20Analysis%20of%202017%20GeneralElections%20FINAL%20High%20Res%20for%20Printer%20-%20NEW%20COVER_small.pdf\" rel=\"noopener\" target=\"_blank\">les femmes repr\u00e9sentent 23% de l&#8217;Assembl\u00e9e nationale et du S\u00e9nat<\/a>, ce chiffre incluant les 47 si\u00e8ges r\u00e9serv\u00e9s exclusivement aux femmes repr\u00e9sentantes des comt\u00e9s.<\/p>\n<p>Les militants des droits de l&#8217;homme affirment que l&#8217;\u00e9lan pour tenir l&#8217;Assembl\u00e9e nationale responsable a repris mais comme la pand\u00e9mie de COVID-19 fait rage, les inqui\u00e9tudes sont nombreuses que le programme de genre n&#8217;est plus une priorit\u00e9.<\/p>\n<p>\u00abCOVID-19 n&#8217;a pas ralenti les activit\u00e9s politiques dans ce pays. En fait, les dirigeants se comportent comme si nous entamions des \u00e9lections demain et non en 2022. Nous avons de s\u00e9rieux r\u00e9alignements politiques et personne ne parle au nom des femmes \u00bb, a d\u00e9clar\u00e9 \u00e0 IPS Grace Gakii, activiste politique et de genre bas\u00e9e \u00e0 Nairobi.<\/p>\n<p>\u00abLes Kenyans ordinaires sont plus soucieux de se prot\u00e9ger du virus et de nourrir leurs familles. Ainsi, certains des petits gains que nous avons r\u00e9alis\u00e9s pourraient \u00eatre perdus pendant cette pand\u00e9mie parce qu&#8217;il n&#8217;y a personne pour tenir les partis politiques et les pouvoirs responsables \u00bb, dit-elle.<\/p>\n<p>Reconnu comme la puissance \u00e9conomique de l\u2019Afrique de l\u2019Est par la Banque mondiale, ce g\u00e9ant \u00e9conomique est \u00e0 la tra\u00eene de ses voisins en ce qui concerne la repr\u00e9sentation des femmes dans les organes gouvernementaux.<\/p>\n<p>Au Soudan du Sud, les chiffres concernant les femmes en politique sont plus \u00e9lev\u00e9s, avec 28,9% aux postes \u00e9lectifs. L&#8217;Ouganda en d\u00e9tient 34%, la Tanzanie et le Burundi 36% et le Rwanda 61%.<\/p>\n<p>\u00abLes campagnes politiques et le lobbying intense qui les accompagne sont tr\u00e8s difficiles pour les femmes. Il y a de nombreuses r\u00e9unions le soir et des r\u00e9unions exclusives dans les \u00abclubs de gar\u00e7ons\u00bb. La soci\u00e9t\u00e9 se r\u00e9chauffe aux femmes mais trop lentement. Lorsque vous affrontez des hommes, tous les adversaires masculins se liguent contre vous, car c&#8217;est consid\u00e9r\u00e9 comme une grande insulte d&#8217;\u00eatre vaincu par une femme \u00bb, explique Abdi.<\/p>\n<p>Alors que les \u00e9lections g\u00e9n\u00e9rales de 2017 ont montr\u00e9 un petit changement dans le paysage politique, entra\u00eenant l&#8217;\u00e9lection des trois premi\u00e8res femmes gouverneurs et des trois premi\u00e8res femmes s\u00e9natrices, Wahome dit que la route \u00e0 parcourir reste longue et sinueuse.<\/p>\n<p>Elle dit que les femmes en politique devraient et peuvent relever le d\u00e9fi avec succ\u00e8s.<\/p>\n<p>Wahome encourage les femmes \u00e0 tirer des forces de celles qui ont essay\u00e9 et r\u00e9ussi, en disant qu&#8217;avec le temps, les attitudes et les coutumes patriarcales changeront. Elle encourage particuli\u00e8rement les femmes \u00e0 s&#8217;engager dans des projets de transformation \u00e0 la base avec leurs communaut\u00e9s.<\/p>\n<p>\u00abIl existe de nombreux domaines parmi lesquels choisir, notamment l&#8217;\u00e9ducation et la sant\u00e9 communautaire. Laissez les gens voir ce que vous pouvez faire et plus tard, ils vous soutiendront jusqu&#8217;au sommet. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAIROBI, le 6 juillet 2020 (IPS) &#8211; En 2013, Alice Wahome s\u2019est pr\u00e9sent\u00e9e aux \u00e9lections dans sa troisi\u00e8me tentative de remporter le si\u00e8ge parlementaire tr\u00e8s contest\u00e9e de la circonscription de Kandara, du comt\u00e9 de Murang\u2019a, dans le centre du Kenya.&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2020\/07\/06\/covid-19-a-t-elle-pousse-les-femmes-en-politique-hors-du-programme-du-kenya\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":720,"featured_media":7841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1,30],"tags":[],"class_list":["post-7842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-afrique","category-headlines","category-special-culture-religion-et-genre"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/7842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/720"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=7842"}],"version-history":[{"count":3,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/7842\/revisions"}],"predecessor-version":[{"id":7844,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/7842\/revisions\/7844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media\/7841"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=7842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=7842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=7842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}