{"id":6022,"date":"2012-04-20T13:40:01","date_gmt":"2012-04-20T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2012\/04\/20\/benin-une-ferme-qui-sert-de-modele-agricole\/"},"modified":"2012-04-20T13:40:01","modified_gmt":"2012-04-20T13:40:01","slug":"benin-une-ferme-qui-sert-de-modele-agricole","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2012\/04\/20\/benin-une-ferme-qui-sert-de-modele-agricole\/","title":{"rendered":"BENIN: Une ferme qui sert de mod\u00e8le agricole"},"content":{"rendered":"<p>COTONOU, 20 avr (IPS) &#8211; La ferme \u00e9cole appel\u00e9e Solidarit\u00e9s agricoles int\u00e9gr\u00e9es (SAIN) s\u2019\u00e9tend sur 14 hectares \u00e0 Kakanitcho\u00e9, un petit village de la vall\u00e9e de l\u2019Ou\u00e9m\u00e9, dans le sud-est du B\u00e9nin. Le promoteur, Pascal Gb\u00e9nou, 41 ans, y produit, entre autres, des bananes plantains et du poisson.<\/p>\n<p><!--more--><\/p>\n<p>\u00abJ\u2019aime les bananes plantains de Pascal parce qu\u2019ils sont biologiques et d\u2019un embonpoint exceptionnel\u00bb, affirme \u00e0 IPS, Vodoungb\u00e9 Ayetond\u00e9, une consommatrice des produits de la ferme SAIN, situ\u00e9e \u00e0 72 kilom\u00e8tres de Cotonou, la capitale \u00e9conomique b\u00e9ninoise.<\/p>\n<p> La culture des bananes plantains, sur un sol \u00e0 la fois argileux et sablonneux de Kakanitcho\u00e9, n\u2019\u00e9tait pas gagn\u00e9e d\u2019avance, selon Gb\u00e9nou, le promoteur. \u00abPendant longtemps, je n\u2019arrivais pas \u00e0 produire le bananier plantain du c\u00f4t\u00e9-est de ma ferme. Un jour, j\u2019ai rencontr\u00e9 un vieux paysan qui m\u2019a donn\u00e9 la recette des feuilles d\u2019acacia\u00bb, indique-t-il \u00e0 IPS.  \u00abDe retour \u00e0 la ferme, j\u2019ai mis en terre les crottes de lapins avec les feuilles d\u2019acacia, et le sol difficile a produit des miracles. Aujourd\u2019hui, nous vendons jusqu\u2019\u00e0 deux millions de bananes plantains par an\u00bb, ajoute-t-il.<\/p>\n<p> Bernardin Lokossou, agrochimiste chercheur \u00e0 l\u2019Institut national des recherches agricoles (INRAB) du B\u00e9nin, explique \u00e0 IPS: \u00abLes feuilles d&#39;acacia et les crottes de lapins sont des mati\u00e8res organiques qui se d\u00e9composent dans le sol et lib\u00e8rent des \u00e9l\u00e9ments nutritifs comme l\u2019azote, le phosphore, le potassium, directement assimilables par la plante pour assurer sa nutrition. C\u2019est pourquoi, nous avons ce r\u00e9sultat\u00bb.<\/p>\n<p> La ferme SAIN d\u00e9veloppe les trois p\u00f4les de production: animale (lapins, pintades, cailles, apiculture&#8230;), v\u00e9g\u00e9tale (mara\u00eechage, riz, oranger, cocotier), et piscicole (carpes et silures).<\/p>\n<p> \u00abNous accordons une attention particuli\u00e8re au silure que nous produisons par ins\u00e9mination artificielle dans les \u00e9tangs piscicoles parce qu\u2019il se reproduit g\u00e9n\u00e9ralement en eau profonde\u00bb, explique Gb\u00e9nou \u00e0 IPS.<\/p>\n<p> Selon Prosp\u00e8re S\u00e8nouvo, ing\u00e9nieur chercheur en \u00e9cologie marine \u00e0 l\u2019INRAB, les silures (clarias) se mangent facilement entre eux; en pisciculture, il faut donc y mettre du soin. \u00abBeaucoup de pisciculteurs de l&#39;Ou\u00e9m\u00e9-Plateau sont form\u00e9s \u00e0 sa reproduction en captivit\u00e9 par des encadreurs techniciens du minist\u00e8re de l\u2019Agriculture, du Centre Songha\u00ef (centre de formation agricole \u00e0 Porto-Novo, la capitale politique du B\u00e9nin)\u00bb, souligne-t-il.<\/p>\n<p> Dans la ferme, la pisciculture du silure est m\u00e9thodique. \u00abIl faut affamer pendant quelques heures les poissons s\u00e9lectionn\u00e9s, prendre un ratio de huit femelles pour quatre m\u00e2les; tenir avec une serviette mouill\u00e9e la t\u00eate des poissons devant subir les injections pour l\u2019ins\u00e9mination artificielle et s\u2019assurer que le poids des poissons dont l\u2019hypophyse devra \u00eatre utilis\u00e9e d\u00e9passe d\u2019au moins 0,2 kilogramme celui des femelles\u00bb, indique Gb\u00e9nou.  \u00abAinsi, nous produisons et vendons de poissons jusqu\u2019\u00e0 cinq ou six millions de francs CFA (entre 10.000 et 12.000 dollars environ) par an\u00bb, ajoute-t-il.<\/p>\n<p> Selon Gb\u00e9nou, les productions v\u00e9g\u00e9tales de la ferme avoisinent les 150 tonnes par an. Les produits mara\u00eechers donnent environ 85 tonnes, les oranges, environ 15 tonnes, le riz en production normale donne 50 tonnes. Avec le syst\u00e8me de riziculture intensive, le promoteur obtient le m\u00eame r\u00e9sultat, mais avec moins d\u2019eau et un tiers de la superficie normale.  Depuis 2003, la ferme SAIN est devenue une \u00e9cole qui accueille des jeunes, candidats \u00e0 l\u2019exode rural, issus de familles en difficult\u00e9s, pour une formation de 18 mois. Ancien stagiaire du Centre Songha\u00ef, Gb\u00e9nou s\u2019emploie \u00e0 transmettre le savoir-faire qu\u2019il a acquis aux jeunes en les encourageant \u00e0 aller vers l\u2019agriculture.<\/p>\n<p> Prosp\u00e8re Zannou, 26 ans, \u00e9l\u00e8ve \u00e0 la ferme SAIN, qui apprend la pisciculture et l\u2019\u00e9levage du lapin, d\u00e9clare \u00e0 IPS: \u00abJ\u2019ai choisi la ferme apr\u00e8s mon baccalaur\u00e9at parce que mes parents sont cultivateurs. De plus, les longues \u00e9tudes ne m\u00e8nent \u00e0 rien. Nos fr\u00e8res sont au ch\u00f4mage malgr\u00e9 leurs grands dipl\u00f4mes. Avec la terre, c\u2019est plus s\u00fbr\u00bb.<\/p>\n<p> Abordant la question de la terre, Gb\u00e9nou affirme que le foncier reste un luxe au B\u00e9nin. \u00abLes lev\u00e9s topographiques co\u00fbtent une fortune et du coup, le retour des jeunes \u00e0 la terre tant chant\u00e9 par nos gouvernements semble bien loin de la r\u00e9alit\u00e9\u00bb, dit-il.<\/p>\n<p> Gb\u00e9nou affirme avoir achet\u00e9 les terres progressivement aupr\u00e8s des propri\u00e9taires terriens du village Kakanitcho\u00e9. Les 12 premiers hectares lui ont co\u00fbt\u00e9 2,4 millions FCFA (4.800 dollars), et les deux derniers, 700.000 FCFA (1.400 dollars).  Toutefois, l\u2019Assembl\u00e9e nationale a vot\u00e9 une loi en octobre 2007 sur le R\u00e9gime foncier rural. \u00abUne disposition de cette loi permet notamment aux jeunes d\u2019exploiter les terres laiss\u00e9es en friche pendant plus de cinq ans\u00bb, a indiqu\u00e9 \u00e0 IPS, Omoulara Adjadi, la directrice de la promotion et de la l\u00e9gislation rurale au minist\u00e8re de l\u2019Agriculture, de l\u2019Elevage et de la P\u00eache.  Adjadi travaille avec une \u00e9quipe pour une large vulgarisation de cette loi qui devrait, selon elle, permettre de booster le d\u00e9veloppement local par l\u2019agriculture.<\/p>\n<p> Si les terres sont plus ou moins accessibles, le cr\u00e9dit agricole, par contre, ne l\u2019est pas. Il est difficile avec un taux d\u2019int\u00e9r\u00eat exorbitant, selon Gb\u00e9nou. \u00abEn 2009, j\u2019ai fait la p\u00e9nible exp\u00e9rience de la Caisse locale de cr\u00e9dit agricole mutuel qui me prenait un taux d\u2019int\u00e9r\u00eat de 24 pour cent\u00bb, a-t-il expliqu\u00e9 \u00e0 IPS.<\/p>\n<p> Mais, le directeur de la Banque r\u00e9gionale de solidarit\u00e9 (BRS), Roger Kokou, exprime une autre opinion: \u00abLes B\u00e9ninois n\u2019aiment pas rembourser les pr\u00eats. N\u00e9anmoins, \u00e0 la BRS, nous accompagnons les projets agricoles dans les limites de nos possibilit\u00e9s\u00bb.<\/p>\n<p> Gb\u00e9nou a \u00e9t\u00e9 d\u00e9cor\u00e9 de la m\u00e9daille de chevalier du m\u00e9rite agricole en 2007 par le pr\u00e9sident b\u00e9ninois, Boni Yayi.  Il existe au B\u00e9nin d\u2019autres agriculteurs m\u00e9ritants comme Gb\u00e9nou, indique le directeur de la Soci\u00e9t\u00e9 nationale de promotion agricole, Idrissou Bako. C\u2019est le cas des agriculteurs d\u2019ananas dont les productions sont export\u00e9es \u00e0 l\u2019ext\u00e9rieur, notamment vers l\u2019Europe et les Etats-Unis.  Selon Bako, le B\u00e9nin a d\u00e9j\u00e0 atteint la s\u00e9curit\u00e9 alimentaire pour les c\u00e9r\u00e9ales comme le ma\u00efs dont il vend l\u2019exc\u00e9dent au Programme alimentaire mondial. \u00abCe qui reste \u00e0 couvrir aujourd\u2019hui, c\u2019est le riz\u00bb, dit-il. \u00abNous avons une production nationale d\u2019environ 200.000 tonnes alors que la demande avoisine les 300.000 tonnes\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COTONOU, 20 avr (IPS) &#8211; La ferme \u00e9cole appel\u00e9e Solidarit\u00e9s agricoles int\u00e9gr\u00e9es (SAIN) s\u2019\u00e9tend sur 14 hectares \u00e0 Kakanitcho\u00e9, un petit village de la vall\u00e9e de l\u2019Ou\u00e9m\u00e9, dans le sud-est du B\u00e9nin. Le promoteur, Pascal Gb\u00e9nou, 41 ans, y produit,&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2012\/04\/20\/benin-une-ferme-qui-sert-de-modele-agricole\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":829,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,37,11,6,1,39,29],"tags":[],"class_list":["post-6022","post","type-post","status-publish","format-standard","hentry","category-afrique","category-afrique-cultiver-le-futur","category-developpement","category-economie-finances-le-commerce","category-headlines","category-jeunes-agriculteurs","category-west-africa"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/6022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/829"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=6022"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/6022\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=6022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=6022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=6022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}