{"id":2817,"date":"2006-01-13T13:40:01","date_gmt":"2006-01-13T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2006\/01\/13\/repetition-corrigee-forum-social-mondial-la-rencontre-de-bamakova-t-elle-aborder-les-sujets-sensibles-de-lafrique\/"},"modified":"2006-01-13T13:40:01","modified_gmt":"2006-01-13T13:40:01","slug":"repetition-corrigee-forum-social-mondial-la-rencontre-de-bamakova-t-elle-aborder-les-sujets-sensibles-de-lafrique","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2006\/01\/13\/repetition-corrigee-forum-social-mondial-la-rencontre-de-bamakova-t-elle-aborder-les-sujets-sensibles-de-lafrique\/","title":{"rendered":"\/REPETITION CORRIGEE*\/ FORUM SOCIAL MONDIAL: La rencontre de Bamakova-t-elle aborder les sujets sensibles de l&#39;Afrique?"},"content":{"rendered":"<p>JOHANNESBURG, 13 jan (IPS) &#8211; Le volet africain du Forum social mondial (FSM) d\u00e9marre la semaine prochaine dans la capitale malienne, Bamako, avec beaucoup de questions \u00e0 l&#39;ordre du jour : la guerre et le militarisme, le commerce mondial et la dette, pour n&#39;en citer que quelques-uns.\n<\/p>\n<p><!--more--><\/p>\n<p>\n Le site Internet de la conf\u00e9rence o\u00f9 ces sujets sont \u00e9num\u00e9r\u00e9s ne fait toutefois pas directement mention du SIDA, ou de la n\u00e9cessit\u00e9 d&#39;une bonne gouvernance dans les Etats africains &#8212; m\u00eame si ces sujets font partie des principales questions de d\u00e9veloppement auxquelles est confront\u00e9 le continent aujourd&#39;hui.  Malgr\u00e9 ces omissions, l&#39;activiste Vitalis Meja reste persuad\u00e9 que le VIH et la bonne gouvernance seront abord\u00e9s durant le FSM. Il travaille pour le Forum africain et r\u00e9seau sur la dette et le d\u00e9veloppement &#8211; &#39;African Forum and Network on Debt and Development&#39;, bas\u00e9 \u00e0 Harare, et prendra part \u00e0 la rencontre de Bamako &#8212; pr\u00e9vue du 19 au 23 janvier.  &quot;Le point focal de la conf\u00e9rence sera de critiquer la nouvelle donne n\u00e9olib\u00e9rale. Mais cela ne signifie pas que les questions de VIH\/SIDA et de gouvernance ont \u00e9t\u00e9 n\u00e9glig\u00e9es; elles seront d\u00e9battues dans une perspective plus large&quot;, a d\u00e9clar\u00e9 Meja \u00e0 IPS. (Le terme n\u00e9olib\u00e9ralisme d\u00e9crit une philosophie politique et \u00e9conomique qui rejette l&#39;intervention de l&#39;Etat dans l&#39;\u00e9conomie, et pr\u00f4ne peu de restrictions dans les affaires).  &quot;Les questions de VIH\/SIDA et de gouvernance surgiront toujours. Par exemple, s&#39;il y a des abus contre les femmes au Darfour, ils seront \u00e9voqu\u00e9s comme faisant partie de la question de gouvernance&quot;.  Le Darfour, une r\u00e9gion de l&#39;ouest du Soudan, est devenu le th\u00e9\u00e2tre de l&#39;une des pires situations humanitaires au monde depuis que le conflit a commenc\u00e9 dans cette r\u00e9gion entre deux mouvements rebelles et le gouvernement.  L&#39;Afrique porte \u00e0 elle seule le fardeau de 80 pour cent de tous les cas de VIH\/SIDA au monde, selon le Programme conjoint des Nations Unies sur le VIH\/SIDA.  &quot;Le programme (n\u00e9olib\u00e9ral) ne fait pas assez pour r\u00e9duire la pauvret\u00e9 : toute la richesse va aux nations riches, appauvrissant l&#39;Afrique. En cons\u00e9quence, l&#39;Afrique subsaharienne n&#39;a pas de tr\u00e8s bons r\u00e9sultats en mati\u00e8re d&#39;indicateurs sociaux, d&#39;\u00e9ducation, de s\u00e9curit\u00e9 alimentaire et de sant\u00e9&quot;, a not\u00e9 Meja.  &quot;Le taux de croissance \u00e9conomique de l&#39;Afrique est de 4,6 pour cent, mais sur le terrain, la pauvret\u00e9 reste end\u00e9mique&#8230;Jusqu&#39;en septembre 2005, il y avait environ 60 pour cent des populations de l&#39;Afrique subsaharienne qui vivaient en dessous du seuil de pauvret\u00e9&quot;, a-t-il ajout\u00e9.  Mais Ayesha Kajee, de l&#39;Institut sud-africain des affaires internationales bas\u00e9 \u00e0 Johannesburg, n&#39;est pas d&#39;avis qu&#39;on prenne le n\u00e9olib\u00e9ralisme comme \u00e9tant la cause de la plupart &#8212; si ce n&#39;est pas de tous &#8212; les maux de l&#39;Afrique.  &quot;C&#39;est un bouc \u00e9missaire facile. Nous devons accepter nos responsabilit\u00e9s l\u00e0 o\u00f9 nos dirigeants ont \u00e9chou\u00e9&quot;, a-t-elle dit \u00e0 IPS. &quot;Attribuer tous les probl\u00e8mes de l&#39;Afrique au n\u00e9olib\u00e9ralisme, m\u00eame s&#39;il est la cause de certains d&#39;entre eux, n&#39;est pas juste, ni exact. Nous devons viser au-del\u00e0 de la donne du n\u00e9olib\u00e9ralisme&quot;.  &quot;Nous devons voir les cas o\u00f9 une Constitution est manipul\u00e9e par un gouvernement cherchant un troisi\u00e8me mandat, comme en Ouganda&quot;, a ajout\u00e9 Kajee, faisant allusion \u00e0 la d\u00e9cision du pr\u00e9sident Yoweri Museveni de modifier la Constitution, afin de briguer un troisi\u00e8me mandat.  En v\u00e9rit\u00e9, la soci\u00e9t\u00e9 civile ferait bien de s&#39;examiner \u00e0 la loupe \u00e0 Bamako, a-t-elle sugg\u00e9r\u00e9.  &quot;Nous avons eu des soci\u00e9t\u00e9s civiles dynamiques (en Afrique) ces dix derni\u00e8res ann\u00e9es, mais elles n&#39;ont pas pass\u00e9 assez d&#39;informations pour renforcer les populations locales. La circulation de l&#39;information fait d\u00e9faut en Afrique &#8212; et c&#39;est l\u00e0 ou les soci\u00e9t\u00e9s civiles ont \u00e9chou\u00e9&quot;, a not\u00e9 Kajee, ajoutant que les militants asiatiques auraient quelque chose \u00e0 enseigner \u00e0 l&#39;Afrique \u00e0 cet \u00e9gard.  &quot;Le bon exemple est l&#39;Asie o\u00f9 la soci\u00e9t\u00e9 civile met la bonne information dans les mains des populations locales pour op\u00e9rer des changements dans la fourniture de services comme l&#39;eau potable, les voies de transport et la communication&#8230;En Afrique, les gens ont besoin d&#39;information pour contraindre les gouvernements \u00e0 changer de politique&quot;.  Le FSM a lieu chaque ann\u00e9e, r\u00e9unissant des groupes civiques qui s&#39;opposent \u00e0 l&#39;ordre politique et \u00e9conomique mondial. Il a commenc\u00e9 en 2001 en r\u00e9ponse au Forum \u00e9conomique mondial, une rencontre annuelle dans la capitale suisse de Davos qui attire des chefs d&#39;Etat, des dirigeants d&#39;entreprises et des personnalit\u00e9s du genre.  A ce jour, le FSM s&#39;est principalement tenu dans la ville br\u00e9silienne de Porto Alegre. Cette ann\u00e9e marquera la premi\u00e8re occasion o\u00f9 un forum se d\u00e9roule en Afrique (deux autres FSM sont \u00e9galement pr\u00e9vus pour se tenir dans la capitale v\u00e9n\u00e9zuelienne, Caracas &#8212; et la capitale \u00e9conomique pakistanaise, Karachi).  Des centaines de militants sont attendus pour participer au FSM de Bamako, la plupart d&#39;entre eux \u00e9tant des d\u00e9l\u00e9gu\u00e9s de groupes de la soci\u00e9t\u00e9 civile.<\/p>\n<p>Bien que la d\u00e9cision de tenir un forum au Mali a \u00e9t\u00e9 sans aucun doute motiv\u00e9e en partie par le d\u00e9sir de rendre les d\u00e9bats plus accessibles aux populations sur le continent, on esp\u00e8re que les d\u00e9l\u00e9gu\u00e9s venant de contr\u00e9es plus lointaines seront \u00e9galement pr\u00e9sents.  &quot;Une telle conf\u00e9rence requiert la participation des amis de l&#39;Afrique en provenance de l&#39;Europe et de l&#39;Am\u00e9rique du nord&quot;, a dit \u00e0 IPS, Sam Ndlovu, un chercheur \u00e0 l&#39;Universit\u00e9 d&#39;Afrique du Sud. &quot;Sans leur soutien, leur lobbying et leur campagne, l&#39;Afrique &#8212; \u00e0 elle seule &#8212; n&#39;arrivera pas \u00e0 grand-chose&quot;.  Meja est de cet avis. &quot;Nous esp\u00e9rons que nos amis d&#39;outre-mer, en particulier d&#39;Europe et des Etats-Unis se joindront \u00e0 nous \u00e0 Bamako&quot;, a-t-il not\u00e9. (*Cet article pr\u00e9alablement diffus\u00e9 le 12 janvier contient une erreur au 17\u00e8me paragraphe. Notez bien que Karachi est bien la capitale \u00e9conomique du Pakistan et non sa capitale comme \u00e9crit pr\u00e9c\u00e9demment.)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOHANNESBURG, 13 jan (IPS) &#8211; Le volet africain du Forum social mondial (FSM) d\u00e9marre la semaine prochaine dans la capitale malienne, Bamako, avec beaucoup de questions \u00e0 l&#39;ordre du jour : la guerre et le militarisme, le commerce mondial et&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2006\/01\/13\/repetition-corrigee-forum-social-mondial-la-rencontre-de-bamakova-t-elle-aborder-les-sujets-sensibles-de-lafrique\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11,27,6,1,7,28,29],"tags":[],"class_list":["post-2817","post","type-post","status-publish","format-standard","hentry","category-afrique","category-developpement","category-east-africa","category-economie-finances-le-commerce","category-headlines","category-politique","category-southern-africa","category-west-africa"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=2817"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2817\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=2817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=2817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=2817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}