{"id":2726,"date":"2005-11-11T13:40:01","date_gmt":"2005-11-11T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2005\/11\/11\/culture-afrique-du-sud-voir-plutot-quetre-vu\/"},"modified":"2005-11-11T13:40:01","modified_gmt":"2005-11-11T13:40:01","slug":"culture-afrique-du-sud-voir-plutot-quetre-vu","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2005\/11\/11\/culture-afrique-du-sud-voir-plutot-quetre-vu\/","title":{"rendered":"CULTURE-AFRIQUE DU SUD: Voir, plut\u00f4t qu&#39;\u00eatre vu"},"content":{"rendered":"<p>JOHANNESBURG, 11 nov (IPS) &#8211; Les femmes noires en Afrique du Sud ne sont pas \u00e9trang\u00e8res \u00e0 la photographie. Toutefois, elles se sont jadis retrouv\u00e9es g\u00e9n\u00e9ralement devant l&#39;objectif &#8212; souvent repr\u00e9sent\u00e9es comme &#8220;&#39;m\u00e8re de la nation&#39;, &#39;objet de sexe noir&#39;, ou &#39;victime noire, pauvre, sans agence&#39;,&#8221; selon les mots de l&#39;activiste de genre Janine Moolman.\n <\/p>\n<p><!--more--><\/p>\n<p> Maintenant, cette situation est en train de changer. Des photographes comme Neo Ntsoma &#8212; la premi\u00e8re femme \u00e0 gagner le prix Mohamed Amin &#8212; fait partie d&#39;une liste croissante de femmes noires qui sont en train d&#39;avoir du succ\u00e8s derri\u00e8re l&#39;appareil photo.  Nomm\u00e9e ainsi en souvenir d&#39;un photographe et cameraman bas\u00e9 au Kenya qui est mort dans le d\u00e9tournement d&#39;un avion des lignes \u00e9thiopiennes, en 1996, cette r\u00e9compense est remise pendant la comp\u00e9tition annuelle du &#39;Cable News Network&#39;s&#39; (CNN) honorant le meilleur du journalisme africain.  Ntsoma a remport\u00e9 le prix l&#39;ann\u00e9e derni\u00e8re pour une s\u00e9rie d&#39;images intitul\u00e9es &#39;Their World in Flames&#39; (Leur monde en flammes), qui montrait en d\u00e9tails le sort des familles d&#39;une installation de squatters, dans la capitale \u00e9conomique Johannesburg, lorsque leurs maisons ont \u00e9t\u00e9 d\u00e9truites par le feu.<\/p>\n<p> Elle \u00e9tait \u00e9galement l&#39;une des quatre photographes choisis pour exposer leur travail \u00e0 Los Angeles et \u00e0 Washington D.C plus t\u00f4t cette ann\u00e9e durant le &#39;All Roads Photography Programme&#39;, une initiative soutenue par la &#39;National Geographic Society&#39; (Soci\u00e9t\u00e9 nationale de g\u00e9ographie). Le programme vise \u00e0 donner une plate-forme aux photographes qui montrent comment leurs communaut\u00e9s sont en train d&#39;\u00eatre m\u00e9tamorphos\u00e9es par le changement.<\/p>\n<p> La photographie n&#39;a pas \u00e9t\u00e9 le premier choix de profession de Ntsoma. La danse la tentait, mais elle s&#39;est d\u00e9cid\u00e9e contre sur le conseil de son proviseur de lyc\u00e9e, qui voyait cela comme &quot;une profession pour les perdants&quot;. Une carri\u00e8re dans la t\u00e9l\u00e9vision semblait la meilleure option apr\u00e8s, mais trouvant les opportunit\u00e9s de formation dans ce domaine limit\u00e9es, Ntsoma a choisi d&#39;\u00e9tudier la photographie.   A cette \u00e9poque, l&#39;Afrique du Sud \u00e9tait encore dans les affres de l&#39;apartheid, et elle \u00e9tait la seule noire dans sa classe. Un d\u00e9fi, peut-\u00eatre plus grand, est venu, toutefois, sous la forme d&#39;une lettre de l&#39;un de ses professeurs estimant qu&#39;elle n&#39;avait pas ce qu&#39;il fallait pour devenir une photographe &#8212; et qu&#39;elle devrait arr\u00eater le cours.<\/p>\n<p> &quot;Ceci a \u00e9t\u00e9 le plus grand coup de ma vie et je ne l&#39;oublierai jamais&quot;, affirme-t-elle. &quot;Mais cela m&#39;a enseign\u00e9 la vraie signification de la pers\u00e9v\u00e9rance et de la d\u00e9termination&quot;.<\/p>\n<p> Ironie du sort, ces qualit\u00e9s lui ont \u00e9t\u00e9 tr\u00e8s utiles apr\u00e8s qu&#39;elle a gagn\u00e9 le prix CNN.<\/p>\n<p> &quot;Ma r\u00e9compense CNN a surpris et suscit\u00e9 des interrogations chez plusieurs personnes qui pensent toujours que c&#39;est le fait que je sois une femme noire qui m&#39;a permis de gagner&quot;, d\u00e9clare-t-elle.<\/p>\n<p> Ntsoma, une grande photographe pour un quotidien de Johannesburg, a trouv\u00e9 l&#39;inspiration dans la vie et le travail de la photographe am\u00e9ricaine Dorothea Lange, affirmant qu&#39;elle avait la capacit\u00e9 de &quot;capturer les \u00e2mes&quot; des personnes qu&#39;elle photographiait.<\/p>\n<p> Lange est mieux inscrite dans les m\u00e9moires pour ses images poignantes des pauvres travailleurs immigr\u00e9s qui, \u00e0 la recherche d&#39;une vie meilleure, se sont rendus en grand nombre en Californie durant la Grande D\u00e9pression de la fin des ann\u00e9es 1920 et 1930. Sa photographie d&#39;une femme avec trois enfants, intitul\u00e9e &#39;Migrant Mother&quot; (M\u00e8re immigr\u00e9e), en 1936, est devenue une image embl\u00e9matique aux Etats-Unis, et au-del\u00e0.<\/p>\n<p> Les photos de Ntsoma, elle-m\u00eame, insistent sur les angles bizarres dont elles sont prises, ainsi que l&#39;interaction entre ce qui est net &#8212; et ce qui ne l&#39;est pas. &quot;J&#39;ai l&#39;habitude de prendre des photos pour amener (les gens) \u00e0 croire en moi&quot;, d\u00e9clare-t-elle. &quot;Maintenant je prends des images pour amener les gens \u00e0 croire au sujet de mes photos&quot;.<\/p>\n<p> Elle est \u00e9galement devenue un mentor enthousiaste pour de jeunes journalistes photographes.<\/p>\n<p> Ruth Motau, l&#39;une des premi\u00e8res femmes photographes noires \u00e0 se faire un nom en Afrique du Sud, dirige maintenant la section photo d&#39;un important quotidien.<\/p>\n<p> Mais, toutes ne sont pas dans le photo-journalisme. Zanele Muholi, par exemple, se d\u00e9crit comme une &quot;photographe activiste&quot; &#8212; poussant les fronti\u00e8res de la tol\u00e9rance sociale en traitant de questions li\u00e9es \u00e0 la sexualit\u00e9.<\/p>\n<p> Son exposition de 2004 sur le lesbianisme a capt\u00e9 des moments priv\u00e9s inimaginables \u00e0 l&#39;int\u00e9rieur des restrictions de la culture africaine. Cela comprenait une photo d&#39;une lesbienne attachant ses seins avec une courroie, une autre photo d&#39;une femme pla\u00e7ant un godemich\u00e9 (phallus artificiel destin\u00e9 au plaisir sexuel), et une photo de deux femmes en train de s&#39;embrasser.<\/p>\n<p> Une autre photographe, Nontsikelelo &#8220;Lolo&#8221; Veleko, r\u00e9alise un travail qui refl\u00e8te une fascination pour les concepts orientaux de beaut\u00e9, et les modes en vogue dans les ann\u00e9es 1970. Maintenant repr\u00e9sent\u00e9e par un prestigieux lieu artistique \u00e0 Johannesburg, la Goodman Gallery (Galerie Goodman), sa plus r\u00e9cente exposition comprenait un portrait d&#39;une jeune femme dont les traits typiquement africains \u00e9taient accentu\u00e9s par le mascara noir, et un rouge \u00e0 l\u00e8vres \u00e9clatant.<\/p>\n<p> &quot;Je me posais des questions sur les id\u00e9es de la beaut\u00e9 et pourquoi le maquillage est utilis\u00e9&quot;, explique Veleko.<\/p>\n<p> Melissa Mboweni, un conservateur \u00e0 la Goodman Gallery, consid\u00e8re Veleko comme faisant partie d&#39;une nouvelle vague de photographes sud-africains qui sont attir\u00e9s par la repr\u00e9sentation de l&#39;identit\u00e9 changeante de la jeunesse, plut\u00f4t que par la pauvret\u00e9, le SIDA et le scandale politique.<\/p>\n<p> Le critique d&#39;art, Sean O&#39;Toole, met en garde contre le fait de voir les femmes photographes noires comme un ensemble homog\u00e8ne : &quot;M\u00eame s&#39;il y a beaucoup de choses qui relient leur travail, je ne pense pas que la race et le genre soient la seule fa\u00e7on de l&#39;\u00e9tiqueter&quot;.<\/p>\n<p> Ce qui est important, toutefois, c&#39;est la repr\u00e9sentation des femmes noires &quot;par nous-m\u00eames, contrairement au fait d&#39;\u00eatre le sujet de recherche, de discussion ou d&#39;imagerie comme interpr\u00e9t\u00e9 par d&#39;autres&quot;, affirme Moolman.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOHANNESBURG, 11 nov (IPS) &#8211; Les femmes noires en Afrique du Sud ne sont pas \u00e9trang\u00e8res \u00e0 la photographie. Toutefois, elles se sont jadis retrouv\u00e9es g\u00e9n\u00e9ralement devant l&#39;objectif &#8212; souvent repr\u00e9sent\u00e9es comme &#8220;&#39;m\u00e8re de la nation&#39;, &#39;objet de sexe noir&#39;,&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2005\/11\/11\/culture-afrique-du-sud-voir-plutot-quetre-vu\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":270,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,13,1,30],"tags":[],"class_list":["post-2726","post","type-post","status-publish","format-standard","hentry","category-afrique","category-culture-religion-sport","category-headlines","category-special-culture-religion-et-genre"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/270"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=2726"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2726\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=2726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=2726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=2726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}