{"id":2420,"date":"2005-02-14T13:40:01","date_gmt":"2005-02-14T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2005\/02\/14\/sante-afrique-du-sud-les-arv-difficiles-a-obtenir-pour-les-refugies-etles-immigres-etrangers\/"},"modified":"2005-02-14T13:40:01","modified_gmt":"2005-02-14T13:40:01","slug":"sante-afrique-du-sud-les-arv-difficiles-a-obtenir-pour-les-refugies-etles-immigres-etrangers","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2005\/02\/14\/sante-afrique-du-sud-les-arv-difficiles-a-obtenir-pour-les-refugies-etles-immigres-etrangers\/","title":{"rendered":"SANTE-AFRIQUE DU SUD: Les ARV difficiles \u00e0 obtenir pour les r\u00e9fugi\u00e9s etles immigr\u00e9s \u00e9trangers"},"content":{"rendered":"<p>JOHANNESBURG, 14 f\u00e9v (IPS) &#8211; Chaque ann\u00e9e, des milliers d&#39;Africains fuyant la guerre et les difficult\u00e9s \u00e9conomiques font un voyage p\u00e9rilleux vers la pointe du continent avec l&#39;espoir d&#39;avoir une vie meilleure dans la puissance r\u00e9gionale, l&#39;Afrique du Sud.\n<\/p>\n<p><!--more--><\/p>\n<p>\n Avec l&#39;espoir d&#39;un avenir meilleur, nombreux d&#39;entre eux emm\u00e8nent avec eux le virus du SIDA.<\/p>\n<p> Mais au moment o\u00f9 l&#39;Afrique du Sud est aux prises avec le d\u00e9fi consistant \u00e0 fournir des m\u00e9dicaments anti-r\u00e9troviraux (ARV) \u00e0 ceux de ces citoyens qui sont s\u00e9ropositifs, tr\u00e8s peu de choses sont dites sur la meilleure fa\u00e7on de traiter le SIDA dans la population substantielle de r\u00e9fugi\u00e9s et d&#39;immigr\u00e9s ill\u00e9gaux.  En cons\u00e9quence, les quelques-uns qui remplissent les conditions pour recevoir les ARV, manquent souvent l&#39;opportunit\u00e9 de prendre ces m\u00e9dicaments prolongeant la vie &#8211; tandis que ceux qui ne les remplissent pas sont confront\u00e9s aux souffrances de la vie d&#39;immigr\u00e9, aggrav\u00e9e par le VIH.<\/p>\n<p> &quot;Les r\u00e9fugi\u00e9s sont regard\u00e9s avec suspicion en Afrique du Sud et sont par cons\u00e9quent victimes de discrimination, et \u00e0 peine int\u00e9gr\u00e9s dans la soci\u00e9t\u00e9, sans parler des initiatives du VIH et du SIDA&quot;, d\u00e9clare Melita Sunjie, un chercheur au bureau du Haut commissariat des Nations Unies aux r\u00e9fugi\u00e9s (HCR) de Pretoria.<\/p>\n<p> Ces propos ont \u00e9t\u00e9 repris en \u00e9cho par Nathan Geffen, un porte-parole de Treatment Action Campaign (Campagne d&#39;action pour le traitement &#8211; TAC) &#8211; un important groupe anti-SIDA en Afrique du Sud : &quot;Il existe toujours des niveaux \u00e9lev\u00e9s de x\u00e9nophobie en Afrique du Sud, et parce que les immigr\u00e9s ill\u00e9gaux n&#39;ont pas de pouvoir, leurs int\u00e9r\u00eats ne sont pas repr\u00e9sent\u00e9s&quot;.<\/p>\n<p> Selon le d\u00e9partement des Affaires int\u00e9rieures, environ 100.000 personnes ont le statut de r\u00e9fugi\u00e9s en Afrique du sud. Les immigr\u00e9s ill\u00e9gaux sont sans papiers, m\u00eame si Zonke Majodima, en charge du volet des non-nationaux \u00e0 la Commission des droits de l&#39;Homme, affirme qu&#39;ils pourraient atteindre des &quot;millions&quot;. La commission a \u00e9t\u00e9 cr\u00e9\u00e9e par le gouvernement pour enraciner la d\u00e9mocratie en Afrique du sud apr\u00e8s l&#39;\u00e9mergence du pays de la p\u00e9riode d&#39;apartheid.<\/p>\n<p> La plupart des r\u00e9fugi\u00e9s sont originaires de la R\u00e9publique d\u00e9mocratique du Congo, du Burundi, du Rwanda, de l&#39;Angola, de la Somalie et &#8211; de plus en plus &#8211; du Zimbabwe, o\u00f9 des troubles politiques et \u00e9conomiques ont pouss\u00e9 plusieurs \u00e0 traverser la fronti\u00e8re pour se rendre en Afrique du Sud.<\/p>\n<p> Les taux de pr\u00e9valence de VIH dans ces pays varient entre 5,1 pour cent au Rwanda et 24,6 pour cent au Zimbabwe. Le taux d&#39;infection de l&#39;Afrique du Sud est estim\u00e9 \u00e0 28 pour cent.<\/p>\n<p> Une fois le statut d&#39;asile obtenu, les r\u00e9fugi\u00e9s en Afrique du Sud ont le droit de demander un traitement aupr\u00e8s du syst\u00e8me national de soins de sant\u00e9 en cas de maladie (les migrants ill\u00e9gaux ne jouissent pas de tels droits). Ceux \u00e0 qui on accorde l&#39;asile se voient \u00e9galement d\u00e9livrer des cartes d&#39;identification \u00e0 montrer dans des h\u00f4pitaux o\u00f9 ils vont se faire soigner. N\u00e9anmoins, en pratique, avoir une carte peut ne pas signifier grand-chose.<\/p>\n<p> &quot;Lorsqu&#39;un r\u00e9fugi\u00e9 vient \u00e0 l&#39;h\u00f4pital, il doit pr\u00e9senter ses papiers pour prouver son statut de r\u00e9fugi\u00e9, mais le personnel pr\u00e9sent sur le lieu de l&#39;enregistrement ne reconna\u00eet pas la l\u00e9gitimit\u00e9 de leurs cartes d&#39;identification parce qu&#39;ils n&#39;ont pas \u00e9t\u00e9 correctement instruits&quot;, indique Dr Bernard Uzabakirilo, qui exerce \u00e0 l&#39;h\u00f4pital Ekhuruleni, non loin de la capitale sud-africaine &#8211; Pretoria.<\/p>\n<p> En cons\u00e9quence, ajoute-t-il, le malade est enregistr\u00e9 comme un immigr\u00e9 ill\u00e9gal qui doit payer des frais de consultation \u00e0 l&#39;avance, avant de recevoir le traitement. Les frais \u00e0 payer varient entre 290 et 2.450 dollars, selon la gravit\u00e9 de l&#39;affection du patient.<\/p>\n<p> &quot;Ils n&#39;ont \u00e9videmment pas les moyens de payer cela, on ne leur constitue alors pas un dossier et on leur refuse l&#39;acc\u00e8s \u00e0 un m\u00e9decin. Sans la consultation d&#39;un m\u00e9decin, un patient s\u00e9ropositif ne peut pas recevoir un traitement dans une clinique&quot;, d\u00e9clare Uzabakirilo, qui fait \u00e9galement pression pour le &#39;Coordinating Body of Refugee Organisations&#39; (Organe de coordination des organisations de r\u00e9fugi\u00e9s), un regroupement chapeautant plusieurs autres, bas\u00e9 \u00e0 Johannesburg.<\/p>\n<p> Suite \u00e0 une d\u00e9cision prise par la Cour constitutionnelle en 2002 ordonnant au gouvernement de fournir des ARV aux Sud-Africains, les autorit\u00e9s sanitaires ont lanc\u00e9 un programme pour distribuer gratuitement les m\u00e9dicaments. Toutefois, des r\u00e9fugi\u00e9s qui se voient exclus des dispensaires \u00e0 cause de la confusion sur les cartes d&#39;identit\u00e9, sont contraints d&#39;acheter les m\u00e9dicaments aupr\u00e8s des priv\u00e9s, \u00e0 un co\u00fbt d&#39;environ 50 dollars le mois. Une fois encore, c&#39;est un montant que tr\u00e8s peu de gens ont les moyens de payer.<\/p>\n<p> Les barri\u00e8res de langue font parfois que le traitement est retard\u00e9 &#8211; s&#39;il n&#39;est pas refus\u00e9.<\/p>\n<p> &quot;Lorsque des r\u00e9fugi\u00e9s t\u00e9l\u00e9phonent ou viennent \u00e0 l&#39;h\u00f4pital et qu&#39;ils ne peuvent pas parler anglais, on les fait asseoir pour attendre un interpr\u00e8te. J&#39;ai vu des patients qu&#39;on a fait attendre pendant huit heures&quot;, affirme Uzabakirilo.<\/p>\n<p> Des efforts r\u00e9p\u00e9t\u00e9s de IPS pour recueillir les commentaires du d\u00e9partement de la Sant\u00e9 sur les difficult\u00e9s v\u00e9cues par des r\u00e9fugi\u00e9s dans des h\u00f4pitaux publics ont \u00e9t\u00e9 infructueux.<\/p>\n<p> Ce qui aggrave davantage les choses, c&#39;est le fait que le syst\u00e8me de l&#39;Etat pour le traitement des demandes d&#39;asile est terriblement peu performant.<\/p>\n<p> Le manque de personnel et l&#39;incomp\u00e9tence au minist\u00e8re des Affaires int\u00e9rieures ont entra\u00een\u00e9 un retard dans le traitement de plus de 50.000 demandes pour le statut de r\u00e9fugi\u00e9s.<\/p>\n<p> &quot;A cause de ce retard, ce processus (de demande) prend jusqu&#39;\u00e0 cinq ans&quot;, indique Carnita Ernest, un chercheur au &#39;Centre for the Study of Violence and Reconciliation&#39; (Centre d&#39;\u00e9tude sur la violence et la r\u00e9conciliation) bas\u00e9 \u00e0 Johannesburg, qui \u00e9tudie l&#39;acc\u00e8s des r\u00e9fugi\u00e9s aux soins de sant\u00e9.<\/p>\n<p> M\u00eame si le directeur-g\u00e9n\u00e9ral du d\u00e9partement des Affaires int\u00e9rieures, Barry Gilder, dit que des mesures sont en train d&#39;\u00eatre prises pour sortir de cet encombrement administratif, il admet \u00e9galement que le d\u00e9nouement de l&#39;\u00e9tat actuel des choses prendra des mois.<\/p>\n<p> Une \u00e9tude de 2003 men\u00e9e par l&#39;Agence communautaire pour l&#39;enqu\u00eate sociale (CASE), la plus r\u00e9cente analyse sur les r\u00e9fugi\u00e9s et des demandeurs d&#39;asile en Afrique du Sud, a not\u00e9 que sur les 1.500 immigr\u00e9s interrog\u00e9s, 11 pour cent seulement s&#39;\u00e9taient vu d\u00e9livrer des cartes d&#39;identification par le d\u00e9partement des Affaires int\u00e9rieures. Les 89 pour cent restants attendaient depuis plus de trois ans le statut d&#39;asile.<\/p>\n<p> Selon l&#39;Etude nationale de base sur les r\u00e9fugi\u00e9s (National Refugee Baseline Survey) de la CASE, pr\u00e8s de 20 pour cent de ceux qui avaient essay\u00e9 d&#39;avoir acc\u00e8s aux soins de sant\u00e9 d&#39;urgence se sont vu refuser l&#39;aide, principalement de la part du personnel administratif de l&#39;h\u00f4pital. La CASE est une organisation non-gouvernementale bas\u00e9e \u00e0 Johannesburg.<\/p>\n<p> Puisque la Loi sur les r\u00e9fugi\u00e9s de 1998 impose des restrictions aux demandeurs d&#39;asile en interdisant leur emploi pendant la p\u00e9riode o\u00f9 leurs demandes sont en cours de traitement, les immigr\u00e9s s\u00e9ropositifs se retrouvent dans l&#39;incertitude : incapables de profiter des centres de sant\u00e9 de l&#39;Etat &#8211; ou de travailler pour gagner de l&#39;argent qui peut couvrir les co\u00fbts des soins de sant\u00e9 dans le priv\u00e9.<\/p>\n<p> Avec le fort taux de ch\u00f4mage qui fait beaucoup de victimes en Afrique du Sud, l&#39;ouverture du march\u00e9 de l&#39;emploi aux non-nationaux est \u00e0 juste titre une question d\u00e9licate. Toutefois, ne pas le faire rendrait les r\u00e9fugi\u00e9s et immigr\u00e9s ill\u00e9gaux beaucoup plus vuln\u00e9rables au SIDA.<\/p>\n<p> Uzabakirilo dit que son exp\u00e9rience a montr\u00e9 que la pr\u00e9valence du VIH parmi les r\u00e9fugi\u00e9s et les immigr\u00e9s ill\u00e9gaux dans le pays &quot;est plus \u00e9lev\u00e9e que la pr\u00e9valence locale parce que les jeunes femmes r\u00e9fugi\u00e9es ne peuvent pas travailler et sont presque contraintes de se prostituer. Le taux de viol est \u00e9galement tr\u00e8s \u00e9lev\u00e9 parmi les r\u00e9fugi\u00e9s&quot;.<\/p>\n<p> Sunjie ajoute : &quot;M\u00eame si des donn\u00e9es sur la pr\u00e9valence du VIH parmi les r\u00e9fugi\u00e9s en Afrique du Sud sont rares, les r\u00e9fugi\u00e9s et les immigr\u00e9s ill\u00e9gaux sont de plus en plus expos\u00e9s au risque de contracter le virus durant et apr\u00e8s le d\u00e9placement&quot;.<\/p>\n<p> Contrairement \u00e0 d&#39;autres pays africains, l&#39;Afrique du Sud ne dispose d&#39;aucun camp de r\u00e9fugi\u00e9s pour abriter les non-nationaux. Les demandeurs d&#39;asile et les r\u00e9fugi\u00e9s vivent en zones urbaines, et survivent en grande partie sans assistance.<\/p>\n<p> Peut-\u00eatre que des efforts pour am\u00e9liorer l&#39;acc\u00e8s aux services de sant\u00e9 pour des r\u00e9fugi\u00e9s et des migrants ill\u00e9gaux ne pourront gagner en vitesse qu&#39;au moment o\u00f9 un nombre suffisamment grand de Sud-Africains s\u00e9ropositifs recevront des ARV.<\/p>\n<p> Alors que le gouvernement envisage de mettre sous traitement 53.000 personnes d&#39;ici \u00e0 la fin de l&#39;ann\u00e9e, il n&#39;avait atteint que 19.000 personnes \u00e0 la fin de 2004 &#8211; ceci \u00e0 la grande inqui\u00e9tude des groupes comme la TAC, qui a traduit le gouvernement en justice il y a trois ans en vue de l&#39;obliger \u00e0 distribuer des ARV.<\/p>\n<p> Pr\u00e8s de 5,6 millions de Sud-Africains sont infect\u00e9s par le VIH. La TAC estime que 300.000 personnes ont besoin d&#39;ARV pour les maintenir en vie.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>JOHANNESBURG, 14 f\u00e9v (IPS) &#8211; Chaque ann\u00e9e, des milliers d&#39;Africains fuyant la guerre et les difficult\u00e9s \u00e9conomiques font un voyage p\u00e9rilleux vers la pointe du continent avec l&#39;espoir d&#39;avoir une vie meilleure dans la puissance r\u00e9gionale, l&#39;Afrique du Sud.<\/p>\n","protected":false},"author":312,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1,4],"tags":[],"class_list":["post-2420","post","type-post","status-publish","format-standard","hentry","category-afrique","category-headlines","category-sante"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/312"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=2420"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2420\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=2420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=2420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=2420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}