{"id":2418,"date":"2005-02-11T13:40:01","date_gmt":"2005-02-11T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2005\/02\/11\/politique-une-nouvelle-force-de-lonu-pour-le-soudan-eludera-la-crise-dudarfour\/"},"modified":"2005-02-11T13:40:01","modified_gmt":"2005-02-11T13:40:01","slug":"politique-une-nouvelle-force-de-lonu-pour-le-soudan-eludera-la-crise-dudarfour","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2005\/02\/11\/politique-une-nouvelle-force-de-lonu-pour-le-soudan-eludera-la-crise-dudarfour\/","title":{"rendered":"POLITIQUE: Une nouvelle force de l&#39;ONU pour le Soudan \u00e9ludera la crise duDarfour"},"content":{"rendered":"<p>NATIONS UNIES, 11 f\u00e9v (IPS) &#8211; Au cours des six prochains mois, les Nations Unies envisagent de d\u00e9ployer une nouvelle force militaire compos\u00e9e de 10.000 hommes pour observer l&#39;accord de paix r\u00e9cemment conclu au Soudan, qui a mis fin \u00e0 une guerre civile de 21 ans entre le nord et le sud.\n<\/p>\n<p><!--more--><\/p>\n<p>\n La force d&#39;observation actuelle de l&#39;Union africaine (UA) au Darfour, dans l&#39;ouest du Soudan &#8212; dont l&#39;effectif devrait passer de 900 \u00e0 4.000 &#8212; &quot;n&#39;est pas assez importante&quot; et son &quot;d\u00e9ploiement est trop lent&quot;, a d\u00e9clar\u00e9 au Conseil de s\u00e9curit\u00e9, Jan Pronk, repr\u00e9sentant sp\u00e9cial de l&#39;ONU pour le Soudan, mardi, 8 f\u00e9vrier.<\/p>\n<p> Pronk a indiqu\u00e9 qu&#39;on avait besoin d&#39;avoir une &quot;tierce force robuste&quot; pour maintenir la paix au Soudan d\u00e9vast\u00e9e par la guerre. Mais la nouvelle force de l&#39;ONU sera principalement bas\u00e9e au Sud-Soudan, et non dans l&#39;ouest du Soudan.<\/p>\n<p> Le conflit, entre le gouvernement du Soudan et le Mouvement populaire de lib\u00e9ration du Soudan (SPLM), a officiellement pris fin avec la signature d&#39;un accord de paix, d\u00e9but janvier, cette ann\u00e9e.<\/p>\n<p> Dans un rapport au Conseil de s\u00e9curit\u00e9, le secr\u00e9taire g\u00e9n\u00e9ral de l&#39;ONU, Kofi Annan, a dit que l&#39;accord de paix met fin \u00e0 &quot;l&#39;une des plus longues et tr\u00e8s difficiles guerres d&#39;Afrique, durant laquelle plus de deux millions de personnes ont \u00e9t\u00e9 tu\u00e9es, quatre millions ont \u00e9t\u00e9 d\u00e9racin\u00e9es et quelque 600.000 ont \u00e9t\u00e9 contraintes de chercher asile au-del\u00e0 des fronti\u00e8res du Soudan en tant que r\u00e9fugi\u00e9s&quot;.<\/p>\n<p> &quot;Le Conseil de s\u00e9curit\u00e9 sera dispos\u00e9 \u00e0 mettre sur pied une v\u00e9ritable op\u00e9ration de maintien de paix (au Soudan) afin d&#39;appliquer l&#39;accord de paix nord-sud&quot;, a indiqu\u00e9 aux d\u00e9l\u00e9gu\u00e9s, Jo\u00ebl Ad\u00e9chi du B\u00e9nin, pr\u00e9sident du Conseil de s\u00e9curit\u00e9.<\/p>\n<p>  Sur les 16 op\u00e9rations de maintien de paix actuellement en cours d&#39;ex\u00e9cution, sept sont en Afrique : au Sahara occidental, en Sierra Leone, en R\u00e9publique d\u00e9mocratique du Congo, en Ethiopie et en Erythr\u00e9e, au Liberia, en C\u00f4te d&#39;Ivoire et au Burundi.<\/p>\n<p> Pendant ce temps, Pronk peignait un &quot;tableau sombre&quot; de la situation dans la r\u00e9gion du Darfour o\u00f9 quelque 400.000 Soudanais ont \u00e9t\u00e9 tu\u00e9s dans la violence ethnique.<\/p>\n<p> Ann-Louise Colgan de &#39;Africa Action&#39; bas\u00e9 \u00e0 Washington, a soulign\u00e9 \u00e0 IPS que m\u00eame si la mise en \u0153uvre r\u00e9ussie de l&#39;accord de paix est tr\u00e8s importante pour l&#39;avenir du Soudan, une telle force de maintien de paix, ayant un gros effectif, &quot;est n\u00e9cessaire de mani\u00e8re beaucoup plus urgente pour sauver des vies au Darfour, \u00e0 l&#39;heure actuelle &quot;.<\/p>\n<p> &quot;Pour certains commentateurs, le d\u00e9ploiement d&#39;une force de maintien de paix de 10.000 hommes au Sud-Soudan pourrait apporter finalement &#39;un maintien de paix \u00e0 la d\u00e9rob\u00e9e&quot; au Darfour, parce que, notent-ils, une fois que ces soldats seront en place au Soudan, il sera plus tard possible de les red\u00e9ployer pour satisfaire les besoins urgents au Darfour&quot;, a-t-elle d\u00e9clar\u00e9.<\/p>\n<p> Mais ceci ne fait pas grand-chose pour aider les populations du Darfour dans l&#39;imm\u00e9diat. &quot;C&#39;est honteux que la communaut\u00e9 internationale ne r\u00e9agisse pas plus directement et avec plus de fermet\u00e9 au g\u00e9nocide au Darfour&quot;, a affirm\u00e9 Colgan.<\/p>\n<p> Elle a \u00e9galement soulign\u00e9 la n\u00e9cessit\u00e9 d&#39;une force beaucoup plus grande et plus robuste au Darfour que ce que la pr\u00e9sence de l&#39;Union africaine actuelle fournit.<\/p>\n<p> &quot; A l&#39;heure actuelle, les troupes de l&#39;UA sur le terrain manquent d&#39;effectifs, de capacit\u00e9 logistique et de mandat pour prot\u00e9ger les grands nombres de d\u00e9plac\u00e9s et de civils vuln\u00e9rables dans le Darfour&quot;, a-t-elle ajout\u00e9.<\/p>\n<p>            Pronk a d\u00e9clar\u00e9 que la pression exerc\u00e9e par la communaut\u00e9 internationale et la pr\u00e9sence de l&#39;UA avaient eu un certain effet sur le Darfour, &quot;mais pas assez&quot;.<\/p>\n<p> &quot;Le conflit au Darfour \u00e9tait tr\u00e8s compliqu\u00e9, avec diverses dimensions&quot;, a-t-il expliqu\u00e9.<\/p>\n<p> C&#39;\u00e9tait plus qu&#39;une guerre civile, a-t-il dit, parce que le conflit incluait une bataille \u00e9conomique, avec des impacts environnementaux. &quot;Les milices (Janjaweed) \u00e9taient fortes et bien-organis\u00e9es. Et il y avait des forces au Soudan &#8212; non pas dans le gouvernement, mais puissantes tout de m\u00eame &#8212; qui \u00e9taient capables de r\u00e9pandre la terreur sur le terrain&quot;, a-t-il ajout\u00e9.<\/p>\n<p> S&#39;adressant au Conseil de s\u00e9curit\u00e9 mardi, le leader du SPLM John Garang a indiqu\u00e9 qu&#39;ayant conclu son propre accord de paix avec le gouvernement, son mouvement rebelle \u00e9tait s\u00fbr que ceci pourrait \u00e9galement accro\u00eetre les chances d&#39;une solution durable au conflit du Darfour.<\/p>\n<p> &quot;Toutefois&quot;, a-t-il averti, &quot;la milice des Janjaweed doit \u00eatre ma\u00eetris\u00e9e et finalement traduite en justice apr\u00e8s l&#39;obtention d&#39;une solution&quot;. Le SPLM est pr\u00eat \u00e0 offrir son assistance.<\/p>\n<p> Dans son rapport au Conseil de s\u00e9curit\u00e9, Annan a d\u00e9clar\u00e9 que malgr\u00e9 les nombreux rounds de pourparlers de paix, &quot;le processus politique du Darfour n&#39;a pas r\u00e9ussi jusqu&#39;ici \u00e0 porter les fruits esp\u00e9r\u00e9s&quot;.<\/p>\n<p> &quot;Ceci est principalement d\u00fb aux complexit\u00e9s de la crise au Darfour, le manque de confiance entre les parties, aliment\u00e9 par les violations continues du cessez-le-feu et aggrav\u00e9 par le fait que les deux parties succombent \u00e0 la tentation de consolider leurs positions militaire et politique avant d&#39;aller \u00e0 la phase critique de n\u00e9gociations&quot;, a ajout\u00e9 Annan.<\/p>\n<p> Une commission de l&#39;ONU sur le Darfour, qui a publi\u00e9 un rapport la semaine derni\u00e8re, a conclu que les crimes actuellement commis au Darfour n&#39;\u00e9taient pas moins graves qu&#39;un g\u00e9nocide.<\/p>\n<p> Le Conseil de s\u00e9curit\u00e9 de 15 membres est maintenant divis\u00e9 sur la mani\u00e8re dont il devrait traiter des atrocit\u00e9s perp\u00e9tr\u00e9es actuellement dans le Darfour.<\/p>\n<p> La commission onusienne a &quot;fortement&quot; recommand\u00e9 que la situation au Darfour soit soumise \u00e0 la juridiction de la Cour p\u00e9nale internationale (CPI) \u00e0 La Haye, qui a pour mandat de juger des affaires impliquant des crimes de guerre et le g\u00e9nocide.<\/p>\n<p> Mais les Etats-Unis, qui sont demeur\u00e9s oppos\u00e9s \u00e0 la cr\u00e9ation m\u00eame de la CPI, veulent qu&#39;un tribunal s\u00e9par\u00e9 de l&#39;ONU, charg\u00e9 de conna\u00eetre des crimes de guerre en Tanzanie, traite des crimes au Darfour.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>NATIONS UNIES, 11 f\u00e9v (IPS) &#8211; Au cours des six prochains mois, les Nations Unies envisagent de d\u00e9ployer une nouvelle force militaire compos\u00e9e de 10.000 hommes pour observer l&#39;accord de paix r\u00e9cemment conclu au Soudan, qui a mis fin \u00e0&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2005\/02\/11\/politique-une-nouvelle-force-de-lonu-pour-le-soudan-eludera-la-crise-dudarfour\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10,1,7,3],"tags":[],"class_list":["post-2418","post","type-post","status-publish","format-standard","hentry","category-afrique","category-droits-humains","category-headlines","category-politique","category-population-refugies"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=2418"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2418\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=2418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=2418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=2418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}