{"id":1574,"date":"2003-05-06T13:40:01","date_gmt":"2003-05-06T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2003\/05\/06\/politique-nigeria-une-faible-participation-marqueles-elections-des-assemblees-des-etats\/"},"modified":"2003-05-06T13:40:01","modified_gmt":"2003-05-06T13:40:01","slug":"politique-nigeria-une-faible-participation-marqueles-elections-des-assemblees-des-etats","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2003\/05\/06\/politique-nigeria-une-faible-participation-marqueles-elections-des-assemblees-des-etats\/","title":{"rendered":"POLITIQUE-NIGERIA: Une faible participation marqueles \u00e9lections des Assembl\u00e9es des Etats"},"content":{"rendered":"<p>LAGOS, 6 mai (IPS) &#8211; Contrairement aux \u00e9lections de l&#39;Assembl\u00e9e nationale et du S\u00e9nat ainsi qu&#39;\u00e0 celles des gouverneurs et du pr\u00e9sident tenues les 12 et 19 avril respectivement, le scrutin du samedi 3 mai, pour \u00e9lire les repr\u00e9sentants aux diff\u00e9rents parlements des Etats, a \u00e9t\u00e9 marqu\u00e9 par une faible participation des \u00e9lecteurs.\n<\/p>\n<p><!--more--><\/p>\n<p>\n Des responsables de la Commission \u00e9lectorale nationale ind\u00e9pendante (INEC), qui supervise les \u00e9lections, des agents de s\u00e9curit\u00e9 et le mat\u00e9riel \u00e9lectoral sont arriv\u00e9s dans la plupart des bureaux de vote \u00e0 sept heures du matin et c&#39;est seulement une heure apr\u00e8s l&#39;heure pr\u00e9vue pour le d\u00e9marrage des op\u00e9rations de vote que les \u00e9lecteurs ont commenc\u00e9 par venir au compte-goutte.<\/p>\n<p> Deux heures apr\u00e8s le d\u00e9but du scrutin, 91 personnes seulement avaient vot\u00e9 dans l&#39;un des bureaux de vote.<\/p>\n<p>Selon un responsable de l&#39;INEC, &quot;\u00e0 ce moment, au cours des deux derni\u00e8res \u00e9lections, plus de 200 \u00e9lecteurs avaient vot\u00e9. Je pense que les gens ne sont pas int\u00e9ress\u00e9s par l&#39;\u00e9lection d&#39;aujourd&#39;hui&quot;. Dans un autre centre, seuls 79 \u00e9lecteurs avaient exerc\u00e9 leur droit de vote apr\u00e8s deux heures de scrutin.<\/p>\n<p> Malgr\u00e9 les fortes pluies pendant les deux derni\u00e8res \u00e9lections, les Nig\u00e9rians \u00e9taient sortis en grand nombre pour voter. Mais avec un temps d\u00e9gag\u00e9 le samedi 3 mai, plusieurs \u00e9lecteurs potentiels sont rest\u00e9s chez eux, la plupart riv\u00e9s \u00e0 leurs postes t\u00e9l\u00e9viseurs, comme par surprise, la soci\u00e9t\u00e9 distributrice d&#39;\u00e9lectricit\u00e9, la &#39;National Electric Power Authority&#39; (NEPA), n&#39;avait pas coup\u00e9 le courant.<\/p>\n<p> Les jeunes ont transform\u00e9 les rues en terrain de football, installant leurs poteaux de but avec des pneus usag\u00e9s. Les femmes n&#39;\u00e9taient pas exclues des matchs de football organis\u00e9s \u00e0 la h\u00e2te dans les rues puisque IPS a constat\u00e9 que quelques filles jouaient \u00e9galement au football, les pieds nus, sur les rues pav\u00e9es.<\/p>\n<p> Les v\u00e9hicules \u00e9taient \u00e9galement hors des rues, \u00e0 part les ambulances, les camionnettes de patrouille de la police et des v\u00e9hicules appartenant aux responsables de l&#39;INEC et aux journalistes. Tandis que quelques mobylettes, commun\u00e9ment connus sous le nom de Okada, faisaient la navette avec certains agents de parti. Le gouvernement avait interdit l&#39;utilisation de voiture de huit heures du matin \u00e0 18 heures pour les besoins de l&#39;\u00e9lection.<\/p>\n<p> &quot;Nous avions d\u00fb commencer par aller dans la maison des \u00e9lecteurs pour leur demander de sortir voter, contrairement \u00e0 la derni\u00e8re \u00e9lection o\u00f9 ils \u00e9taient tous en rangs avant huit heures pour accomplir leur devoir \u00e9lectoral. Les gens semblaient ne pas \u00eatre int\u00e9ress\u00e9s par cette \u00e9lection qui, selon eux, n&#39;est pas importante. Mais elle est aussi importante que l&#39;\u00e9lection du gouverneur national et des gouverneurs des Etats puisque les l\u00e9gislateurs d&#39;un Etat sont responsables du vote de lois qui touchent les populations au sein de l&#39;Etat&quot;, affirme Ajibola Fajobi, un repr\u00e9sentant de l&#39;Alliance pour la d\u00e9mocratie (AD) dans l&#39;un des centres.<\/p>\n<p> Fajobi estime que la mobilisation, qui avait pr\u00e9c\u00e9d\u00e9 les deux derni\u00e8res Elections, \u00e9tait pratiquement absente dans les \u00e9lections des Assembl\u00e9es des Etats.<\/p>\n<p>&quot;Nos campagnes n&#39;ont pas \u00e9t\u00e9 aussi vigoureuses que celles d&#39;avant les \u00e9lections des membres du S\u00e9nat, de la Chambre des repr\u00e9sentants ainsi que les \u00e9lections des gouverneurs des Etats et du pr\u00e9sident&quot;.<\/p>\n<p> Selon lui, l&#39;AD s&#39;est lanc\u00e9e dans un programme de porte \u00e0 porte pour appeler les \u00e9lecteurs \u00e0 voter parce que le parti voulait s&#39;assurer qu&#39;il allait \u00e9galement remporter la majorit\u00e9 au parlement d&#39;Etat afin que le gouverneur r\u00e9\u00e9lu, Bola Tinubu, n&#39;ait pas de probl\u00e8mes pour travailler avec la branche l\u00e9gislative.<\/p>\n<p> Sur les six Etats contr\u00f4l\u00e9s par l&#39;AD dans le sud-ouest du Nigeria, seul l&#39;Etat de Lagos n&#39;a pas \u00e9t\u00e9 pris par le parti au pouvoir, Peoples Democratic Party (PDP) dans les \u00e9lections de l&#39;Assembl\u00e9e nationale ainsi que les \u00e9lections du gouverneur et du pr\u00e9sident, tenues en avril.  Toutefois, le combat entre le gouverneur sortant Tinubu et le candidat du PDP Funsho Williams \u00e9tait si serr\u00e9 que Williams parle de fraudes et envisage d&#39;aller devant le tribunal charg\u00e9 du contentieux \u00e9lectoral pour un recours. Tinubu a obtenu 911.613 voix contre 740.506 pour Williams.<\/p>\n<p> Selon des analystes politiques \u00e0 Lagos, sur cette base, il est devenu n\u00e9cessaire pour l&#39;AD de faire tout ce qu&#39;elle pouvait, y compris le porte \u00e0 porte pour demander aux \u00e9lecteurs de sortir voter avant la fin du scrutin \u00e0 15 heures, pour obtenir la majorit\u00e9 des si\u00e8ges dans l&#39;\u00e9lection du 3 mai, afin d&#39;\u00e9viter d&#39;\u00eatre mis en accusation devant le Congr\u00e8s, au cas o\u00f9 le PDP jouirait d&#39;une majorit\u00e9 de si\u00e8ges.<\/p>\n<p> L&#39;AD avait all\u00e9gu\u00e9 jeudi qu&#39;il y avait un plan foment\u00e9 par les chefs du PDP dans l&#39;Etat pour ajouter Lagos \u00e0 la liste des Etats remport\u00e9s par eux, pour compl\u00e9ter leur conqu\u00eate dans la zone g\u00e9opolitique du sud-ouest.<\/p>\n<p> Plusieurs gouverneurs \u00e9lus savourent actuellement leur succ\u00e8s avec prudence, \u00e9tant donn\u00e9 que leur victoire ne peut \u00eatre scell\u00e9e que lorsque leurs partis obtiendront la majorit\u00e9 des voix dans les \u00e9lections des Assembl\u00e9es des Etats.<\/p>\n<p> Les analystes sont pr\u00e9occup\u00e9s par la faible participation qu&#39;ils ont qualifi\u00e9 de mauvaise pour la d\u00e9mocratie.<\/p>\n<p> Lai Osho, politologue et professeur, met la faible affluence sur le manque de campagne et le fait que les directions des partis croient que depuis qu&#39;ils ont gagn\u00e9, ou qu&#39;ils n&#39;ont pas gagn\u00e9, dans les pr\u00e9c\u00e9dentes \u00e9lections, le m\u00e9canisme va probablement continuer cette fois-ci.<\/p>\n<p> &quot;Au cours de la semaine pass\u00e9e, il n&#39;y a eu aucune campagne. Tout le monde au niveau du parti croit qu&#39;une fois que les Nig\u00e9rians sont sortis voter pour les partis et non pour des individus, la tendance allait continuer, et ils se rel\u00e2ch\u00e9s. Les \u00e9lecteurs croient \u00e9galement que les l\u00e9gislateurs n&#39;ont rien fait pour eux pendant les quatre derni\u00e8res ann\u00e9es, pourquoi devons-nous sortir voter pour eux encore ou \u00e9lire d&#39;autres?&quot;, a affirm\u00e9 Lai.   Il a indiqu\u00e9 qu&#39;en dehors de la faible mobilisation pour les \u00e9lections de l&#39;assembl\u00e9e d&#39;Etat, les Nig\u00e9rians ont, au cours des quatre derni\u00e8res ann\u00e9s, focalis\u00e9 leur attention sur l&#39;Assembl\u00e9e nationale, le pr\u00e9sident et les gouverneurs. &quot;C&#39;est mauvais parce que tous les niveaux sont importants, les d\u00e9put\u00e9s sont beaucoup plus importants que les gouverneurs parce qu&#39;ils votent les lois qui affectent les citoyens&quot;.<\/p>\n<p> Remi Bukola, une m\u00e9nag\u00e8re, a attribu\u00e9 la faible participation au grand nombre de partis politiques.<\/p>\n<p>&quot;Les gens ne sortent pas pour voter parce qu&#39;il y a tellement de partis et nous ne les connaissons pas.<\/p>\n<p>Nous ne connaissons pas aussi les candidats qui nous sont pr\u00e9sent\u00e9s. Pourquoi perdons-nous alors notre temps en allant voter pour quelqu&#39;un que nous ne connaissons pas?&quot;, a-t-elle demand\u00e9 \u00e0 IPS.<\/p>\n<p> Mais certains analystes croient que le changement dans le m\u00e9canisme de scrutin dans lequel les \u00e9lections commencent avec les postes les plus bas pour aller progressivement vers le plus important, qui est l&#39;\u00e9lection pr\u00e9sidentielle, a d\u00e9teint un peu sur la faible participation dans les bureaux de vote, samedi dernier.<\/p>\n<p> &quot;Si nous avons commenc\u00e9 avec les \u00e9lections du gouvernement local et que nous sommes pass\u00e9s aux assembl\u00e9es d&#39;Etat, aux fonctions de gouverneur, \u00e0 l&#39;Assembl\u00e9e nationale et \u00e0 l&#39;\u00e9lection pr\u00e9sidentielle, comme c&#39;\u00e9tait le cas auparavant, les gens auraient \u00e9t\u00e9 int\u00e9ress\u00e9s jusqu&#39;au dernier jour&quot;, a indiqu\u00e9 un analyste.<\/p>\n<p> Il a demand\u00e9 : &quot;Pensez-vous que si aujourd&#39;hui devait \u00eatre l&#39;\u00e9lection pr\u00e9sidentielle, les gens n&#39;allaient pas sortir?&quot; Non, ils seraient sortis, quel que sois le temps qu&#39;il fait en raison de l&#39;importance, mais ils croient que les \u00e9lections ont \u00e9t\u00e9 perdues ou gagn\u00e9es, le vote dans les \u00e9lections du parlement d&#39;Etat ne changera rien&quot;.<\/p>\n<p> Selon lui, le changement dans le m\u00e9canisme \u00e9lectoral, qui a commenc\u00e9 avec la pr\u00e9sidentielle pour descendre au gouvernement local, \u00e9tait un arrangement d\u00e9lib\u00e9r\u00e9 de l&#39;Assembl\u00e9e nationale sortante, conduite par le PDP, pour s&#39;assurer que le parti au pouvoir remporte les \u00e9lections d&#39;importance d&#39;abord, et que d&#39;autres \u00e9lections suivent le m\u00eame m\u00e9canisme.<\/p>\n<p> IPS a constat\u00e9 que le scrutin avait pris fin dans la plupart des bureaux visit\u00e9s \u00e0 Lagos avant midi, certains trois heures avant l&#39;heure officielle de cl\u00f4ture du vote, tandis que des agents \u00e9lectoraux, des agents de s\u00e9curit\u00e9 et des repr\u00e9sentants des partis \u00e9taient assis oisifs, attentant le d\u00e9compte des voix.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>LAGOS, 6 mai (IPS) &#8211; Contrairement aux \u00e9lections de l&#39;Assembl\u00e9e nationale et du S\u00e9nat ainsi qu&#39;\u00e0 celles des gouverneurs et du pr\u00e9sident tenues les 12 et 19 avril respectivement, le scrutin du samedi 3 mai, pour \u00e9lire les repr\u00e9sentants aux&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2003\/05\/06\/politique-nigeria-une-faible-participation-marqueles-elections-des-assemblees-des-etats\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1,7],"tags":[],"class_list":["post-1574","post","type-post","status-publish","format-standard","hentry","category-afrique","category-headlines","category-politique"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=1574"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1574\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=1574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=1574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=1574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}