{"id":1571,"date":"2003-04-30T13:40:01","date_gmt":"2003-04-30T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2003\/04\/30\/droits-liberia-la-guerre-menace-la-survie-des-enfants\/"},"modified":"2003-04-30T13:40:01","modified_gmt":"2003-04-30T13:40:01","slug":"droits-liberia-la-guerre-menace-la-survie-des-enfants","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2003\/04\/30\/droits-liberia-la-guerre-menace-la-survie-des-enfants\/","title":{"rendered":"DROITS-LIBERIA: La guerre menace la survie des enfants"},"content":{"rendered":"<p>MONROVIA, 30 avr (IPS) &#8211; La longue guerre du Liberia coupl\u00e9e avec les sanctions des Nations Unies sur le commerce du diamant, et le fort taux de pauvret\u00e9 et de ch\u00f4mage &#8211; menacent s\u00e9rieusement la survie des enfants de ce pays.\n<\/p>\n<p><!--more--><\/p>\n<p>\n Le ministre de la Sant\u00e9, Dr Peter Coleman, a fait l&#39;\u00e9valuation de la situation dans sa contribution \u00e0 un forum des Nations Unies pour le dialogue du d\u00e9veloppement dans la capitale, Monrovia, la semaine derni\u00e8re.<\/p>\n<p>Pendant les pourparlers, des agents de l&#39;administration, des organisations non gouvernementales et des groupes de la soci\u00e9t\u00e9 civile ont discut\u00e9 de &quot;l&#39;investissement comp\u00e9titif&quot; pour la survie de l&#39;enfant.<\/p>\n<p> Coleman a indiqu\u00e9 que le &quot;taux de mortalit\u00e9 infantile&quot; du Liberia a &quot;empir\u00e9&quot; dans un pays accabl\u00e9 par une &quot;situation critique complexe&quot; depuis 13 ans.<\/p>\n<p> La guerre a &quot;rendu les enfants vuln\u00e9rables \u00e0 la malnutrition, aux maladies infectieuses, aux d\u00e9c\u00e8s et \u00e0 d&#39;autres maladies \u00e9vitables de l&#39;enfance &#8211; en particulier parmi les personnes d\u00e9plac\u00e9es et les r\u00e9fugi\u00e9s&quot;, a-t-il soulign\u00e9.<\/p>\n<p> Pour Dr Cyrille Niameogo, responsable du Fonds des Nations Unies pour l&#39;enfance (UNICEF) au Liberia, &quot;80 pour cent des 200.000 personnes d\u00e9plac\u00e9es au Liberia sont des enfants et des femmes, qui ont \u00e9t\u00e9 t\u00e9moins de toutes sortes d&#39;atrocit\u00e9s de la guerre&quot;.<\/p>\n<p> Dans les conflits arm\u00e9s du monde entier, croit-il, &quot;les enfants ont \u00e9t\u00e9 d\u00e9lib\u00e9r\u00e9ment des cibles de la violence &#8211; ce qui fait que des millions d&#39;entre eux sont tu\u00e9s, mutil\u00e9s, qu&#39;ils sont devenus orphelins, qu&#39;ils sont enlev\u00e9s et recrut\u00e9s comme des soldats, soustraits de leurs maisons, s\u00e9par\u00e9s de leurs familles et expos\u00e9s au risque de la maladie et de la malnutrition&quot;.<\/p>\n<p> Selon Coleman, les enfants survivent \u00e0 peine au Liberia, dont &quot;le revenu par t\u00eate d&#39;habitant &#8211; l&#39;un des plus \u00e9lev\u00e9s en Afrique dans les ann\u00e9es 80 &#8211; a chut\u00e9, le pays \u00e9tant class\u00e9 174\u00e8me sur 175 pays dans l&#39;indice de d\u00e9veloppement des Nations Unies&quot;.<\/p>\n<p> &quot;Le Liberia est maintenant une nation tr\u00e8s appauvrie avec plus de 80 pour cent de sa population vivant en dessous du seuil de pauvret\u00e9 (avec moins d&#39;un dollar US) par jour, tandis que 15 \u00e0 20 pour cent vit dans la pauvret\u00e9 absolue (avec moins de 50 cents US) par jour&quot;, a-t-il ajout\u00e9.<\/p>\n<p> &quot;Quatre vingt-dix pour cent des travailleurs lib\u00e9riens&quot;, selon Coleman, &quot;sont au ch\u00f4mage et comme si cela ne causait pas assez de tort, les sanctions des Nations Unies, coupl\u00e9es avec les conflits arm\u00e9s continus, sont des insultes suppl\u00e9mentaires&quot;.<\/p>\n<p> La sanction, comme l&#39;a dit un participant, &quot;perturbe la distribution des vivres, des produits pharmaceutiques, et les fournitures d&#39;installations sanitaires. Elle r\u00e9duit la capacit\u00e9 du syst\u00e8me de sant\u00e9 publique \u00e0 maintenir la qualit\u00e9 des vivres, de l&#39;eau, de l&#39;air et des m\u00e9dicaments&quot;..<\/p>\n<p> Pour Coleman, &quot;alors que les adultes peuvent r\u00e9sister \u00e0 de longues p\u00e9riodes de privations et d&#39;\u00e9preuves, les enfants ont moins de r\u00e9sistance et moins de chances de survivre \u00e0 des p\u00e9nuries persistantes&quot;.<\/p>\n<p> Citant des statistiques du minist\u00e8re de la Sant\u00e9 sur l&#39;invalidit\u00e9 au Liberia, il a soulign\u00e9 que &quot;pr\u00e8s de 17 pour cent de la population du pays est handicap\u00e9e, une tr\u00e8s grande proportion \u00e9tant constitu\u00e9e d&#39;enfants&quot;.<\/p>\n<p> La situation a provoqu\u00e9 une fuite des cerveaux au Liberia o\u00f9 &quot;430 m\u00e9decins et 8.000 infirmiers, sages-femmes, techniciens et auxiliaires m\u00e9dicaux, sont r\u00e9duits maintenant \u00e0 seulement 80 m\u00e9decins et moins de 1.800 membres du personnel soignant&quot;.<\/p>\n<p> Avec la balkanisation du pays par la guerre incessante, des analystes estiment que les enfants sont dans l&#39;impossibilit\u00e9 de recevoir la vaccination de routine contre des maladies qu&#39;on peut pr\u00e9venir \u00e0 cause d&#39;un effondrement du syst\u00e8me sanitaire et de l&#39;infrastructure sociale du pays.  Selon des rapports officiels, 80 pour cent des infrastructures sanitaires du Liberia ont \u00e9t\u00e9 pill\u00e9es ou d\u00e9truites entre 1989 et 1997. Au cours des trois \u00e0 quatre derni\u00e8res ann\u00e9es, 55 pour cent des installations sanitaires dans huit r\u00e9gions ont \u00e9t\u00e9 saccag\u00e9es ou abandonn\u00e9es aux combats entre le gouvernement et les rebelles des Lib\u00e9riens unis pour la r\u00e9conciliation et la d\u00e9mocratie (LURD)&quot;.<\/p>\n<p> Le taux de couverture vaccinale du Liberia, de 65 pour cent est pass\u00e9 \u00e0 environ 27 pour cent. &quot;Maintenant, sans acc\u00e8s \u00e0 huit des quinze r\u00e9gions engouffr\u00e9es dans la guerre&quot;, a affirm\u00e9 Coleman, &quot; la couverture devrait chuter consid\u00e9rablement&quot;.<\/p>\n<p> Paul P. Najue, directeur des Foyers catholiques Don-Bosco, une institution d&#39;assistance \u00e0 l&#39;enfance, a \u00e9t\u00e9 associ\u00e9 pour sortir de la rue des enfants capricieux, des enfants soldats, des prostitu\u00e9s qui ont maille \u00e0 partir avec la justice, pour mouler leur esprit afin qu&#39;ils deviennent de futurs dirigeants.   A Monrovia, a-t-il indiqu\u00e9, &quot;les enfants sont utilis\u00e9s actuellement par leurs familles comme le principal soutien du m\u00e9nage. Ag\u00e9s d&#39;\u00e0 peine huit ans, certains sont engag\u00e9s dans le concassage et la vente de diamants avec leurs parents. D&#39;autres travaillent avec leurs parents dans la collecte et le transport de latex dans les plantations d&#39;arbres \u00e0 caoutchouc&quot;.<\/p>\n<p> Genevi\u00e8ve Jackson, sept ans, est l&#39;un des mineurs engag\u00e9s dans le travail des enfants \u00e0 Rock Field, dans les banlieues sud de Monrovia. Elle a dit \u00e0 IPS que &quot;ses parents l&#39;obligeaient \u00e0 concasser les pierres&quot; pour trouver un moyen de subsistance. Ceci, dit-elle, parce que sa m\u00e8re &quot;n&#39;a pas d&#39;argent pour l&#39;envoyer&quot; \u00e0 l&#39;\u00e9cole. Le p\u00e8re de Genevi\u00e8ve \u00e9tait un charg\u00e9 de relations industrielles qui a \u00e9t\u00e9 tu\u00e9 dans un assaut contre Monrovia en avril 1996.<\/p>\n<p> Sa m\u00e8re, B\u00e9atrice Sundayguy, 46 ans, a \u00e9galement cinq autres enfants, dont trois filles. &quot;Concasser des pierres est actuellement le seul moyen disponible pour survivre. Nous ne pouvons pas am\u00e9liorer la situation si ce n&#39;est d&#39;endurer les conditions \u00e9conomiques d\u00e9favorables dans ce pays. Tout le monde est oblig\u00e9 de faire toutes sortes de travaux d\u00e9shumanisants pour gagner sa vie&quot;, a-t-elle indiqu\u00e9 \u00e0 IPS, la semaine derni\u00e8re.<\/p>\n<p> Aux centres de d\u00e9plac\u00e9s dans les banlieues ouest de Monrovia, une crise humanitaire majeure menace des milliers de gens &#8211; surtout les femmes et les enfants qui ont fui les combats dans leurs villes et villages et vivent dans des conditions abjectes &#8211; d\u00e9cid\u00e9es \u00e0 ne pas retourner chez eux avant le d\u00e9sarmement des combattants.<\/p>\n<p> &quot;Le niveau des soins qu&#39;on nous donne a baiss\u00e9 consid\u00e9rablement au cours des derniers mois \u00e0 cause des pr\u00e9occupations s\u00e9curitaires&quot;, a indiqu\u00e9 une personne d\u00e9plac\u00e9e \u00e0 IPS.<\/p>\n<p> En cons\u00e9quence, affirme Patrick Sando, un ancien enseignant : &quot;plusieurs enfants ont contract\u00e9 la teigne. Leur avenir est sombre, puisqu&#39;il n&#39;y a aucun soutien futur pour eux. Leurs parents sont incapables de les envoyer \u00e0 l&#39;\u00e9cole. L&#39;\u00e9pid\u00e9mie, la malnutrition et le d\u00e9sespoir sont end\u00e9miques parmi eux&quot;.<\/p>\n<p> Mais Niameogo de l&#39;UNICEF dit qu&#39;il a un plan pour assurer la survie des enfants lib\u00e9riens. Selon lui, les &quot;Nations Unies &#8211; sous la coordination du minist\u00e8re lib\u00e9rien de la Sant\u00e9 et du Bien-\u00eatre social &#8211; se sont lanc\u00e9es dans plusieurs interventions sanitaires, y compris les services de soins de sant\u00e9 primaires, l&#39;aide alimentaire, la s\u00e9curit\u00e9 alimentaire et la nutrition, l&#39;eau et les installations sanitaires environnementales ainsi que d&#39;autres questions passe-partout comme le VIH\/SIDA&quot;.<\/p>\n<p> Il n&#39;est pas entr\u00e9 dans les d\u00e9tails.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONROVIA, 30 avr (IPS) &#8211; La longue guerre du Liberia coupl\u00e9e avec les sanctions des Nations Unies sur le commerce du diamant, et le fort taux de pauvret\u00e9 et de ch\u00f4mage &#8211; menacent s\u00e9rieusement la survie des enfants de ce&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2003\/04\/30\/droits-liberia-la-guerre-menace-la-survie-des-enfants\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":241,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10,1],"tags":[],"class_list":["post-1571","post","type-post","status-publish","format-standard","hentry","category-afrique","category-droits-humains","category-headlines"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/241"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=1571"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1571\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=1571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=1571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=1571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}