{"id":1269,"date":"2002-08-07T13:40:01","date_gmt":"2002-08-07T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2002\/08\/07\/travail-afrique-du-sud-une-greve-fera-suite-au-sommetmondial\/"},"modified":"2002-08-07T13:40:01","modified_gmt":"2002-08-07T13:40:01","slug":"travail-afrique-du-sud-une-greve-fera-suite-au-sommetmondial","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2002\/08\/07\/travail-afrique-du-sud-une-greve-fera-suite-au-sommetmondial\/","title":{"rendered":"TRAVAIL-AFRIQUE DU SUD: Une gr\u00e8ve fera suite au Sommetmondial"},"content":{"rendered":"<p>JOHANNESBURG, 7 ao\u00fbt (IPS) &#8211; Une s\u00e9rie de r\u00e9unions politiques, tenues le mois dernier, a mis en relief le foss\u00e9 grandissant entre le Congr\u00e8s national africain (ANC) d&#39;une part, et ses alli\u00e9s communistes et syndicaux d&#39;autre part.\n<\/p>\n<p><!--more--><\/p>\n<p>\n Le Congr\u00e8s des syndicats sud-africains (COSATU), qui compte 1,7 million membres, entreprendra une gr\u00e8ve g\u00e9n\u00e9rale peu apr\u00e8s le Sommet mondial sur un d\u00e9veloppement durable en septembre pour mettre en lumi\u00e8re une crise de l&#39;emploi et faire pression sur le gouvernement afin qu&#39;il ne privatise pas les &quot;soci\u00e9t\u00e9s semi-publiques qui sont importantes pour la classe ouvri\u00e8re&quot;, selon le COSATU.<\/p>\n<p> Le COSATU est la plus grande conf\u00e9d\u00e9ration syndicale de l&#39;Afrique du Sud.<\/p>\n<p> A son dernier congr\u00e8s tenu il y a deux week-ends, le Parti communiste sud-africain a d\u00e9cid\u00e9 d&#39;apporter tout son soutien \u00e0 l&#39;appel du COSATU.<\/p>\n<p>&quot;Nous n&#39;aimons pas la privatisation. Un point, c&#39;est tout&quot;, d\u00e9clare le secr\u00e9taire g\u00e9n\u00e9ral adjoint du parti, Jeremy Cronin.  Etant donn\u00e9 que des n\u00e9gociations assidues avec les syndicalistes et les communistes avaient enregistr\u00e9 un soutien sans enthousiasme au gouvernement dans ses efforts de &quot;restructuration&quot; des soci\u00e9t\u00e9s semi-publiques dans les secteurs du transport, de la d\u00e9fense, des t\u00e9l\u00e9communications et du transport a\u00e9rien, ces n\u00e9gociations pourraient s&#39;enliser avec le durcissement de la positions des syndicalistes.<\/p>\n<p> Les syndicalistes croient que la privatisation est l&#39;une des causes de la crise de l&#39;emploi en Afrique du Sud. Le secr\u00e9taire g\u00e9n\u00e9ral du COSATU, Zwelinzima Vavi, a r\u00e9v\u00e9l\u00e9 deux semaines auparavant que sa f\u00e9d\u00e9ration avait perdu 65.000 membres \u00e0 cause des licenciements pour raisons \u00e9conomiques.  Et Vavi craint qu&#39;on en laisse davantage de c\u00f4t\u00e9, au fur et \u00e0 mesure que les soci\u00e9t\u00e9s semi-publiques sont restructur\u00e9es pour attirer des soumissionnaires \u00e9trangers, soit par des liquidations directes soit par introduction en Bourse.<\/p>\n<p> Faisant remarquer que l&#39;op\u00e9rateur national des t\u00e9l\u00e9communications, TELKOM, avait coup\u00e9 223.300 lignes l&#39;ann\u00e9e derni\u00e8re, il a ajout\u00e9 : &quot;Les coupures de t\u00e9l\u00e9phone sont la cons\u00e9quence de tarifs locaux inabordables, augment\u00e9s par TELKOM pour satisfaire son co-actionnaire strat\u00e9gique (malais)&quot;.<\/p>\n<p> Le taux de ch\u00f4mage officiel d&#39;Afrique du Sud s&#39;\u00e9l\u00e8ve \u00e0 29 pour cent, m\u00eame si officieusement, il approche 40 pour cent. La diff\u00e9rence est attribu\u00e9e au fait que les statistiques officielles ne prennent pas en compte &quot;les chercheurs d&#39;emploi d\u00e9courag\u00e9s&quot; ni les gens qui n&#39;ont pas cherch\u00e9 d&#39;emploi au cours des quatre semaines ayant pr\u00e9c\u00e9d\u00e9 l&#39;\u00e9tude sur le ch\u00f4mage.<\/p>\n<p> &quot;Nous devons nous lever et dire trop, c&#39;est trop&quot;, d\u00e9clare Vavi au congr\u00e8s des communistes. &quot;Vous devez tenir compte de nos difficult\u00e9s et si vous ne voulez pas le faire, nous vous y forcerons&quot;.<\/p>\n<p> A Pretoria, la capitale de l&#39;Afrique du Sud, cette m\u00eame semaine, le pr\u00e9sident Thabo Mbeki a fait une description tr\u00e8s diff\u00e9rente de l&#39;\u00e9conomie sud-africaine. Il a attir\u00e9 l&#39;attention sur un rapport r\u00e9cent du Fonds mon\u00e9taire international (FMI) qui a fait l&#39;\u00e9loge de la gestion \u00e9conomique de l&#39;Afrique du Sud, contestant le fait qu&#39;elle souffrait d&#39;un &quot;accroissement du taux de ch\u00f4mage&quot;, l\u00e0 o\u00f9 il y a une croissance \u00e9conomique moyenne de 2,5 pour cent par an. Mais cette croissance ne cr\u00e9e pas suffisamment d&#39;emplois pour r\u00e9gler le probl\u00e8me de ch\u00f4mage.<\/p>\n<p> &quot;Je ne serais pas d&#39;accord que l&#39;\u00e9conomie sud-africaine est une \u00e9conomie de croissance sans emplois&quot;, affirme-t-il, faisant remarquer que les journaux regorgent d&#39;offres d&#39;emploi.<\/p>\n<p> Selon les analystes du march\u00e9, il y a des demandes d&#39;emploi en Afrique du Sud, mais c&#39;est surtout en amont du march\u00e9, o\u00f9 l&#39;\u00e9migration et le besoin accru dans la fonction publique ont cr\u00e9\u00e9 des insuffisances dans les secteurs de gestion, de l&#39;ing\u00e9nierie et de la technologie de l&#39;information.<\/p>\n<p> Selon Mbeki, une gr\u00e8ve n&#39;est pas n\u00e9cessaire puisque le Conseil des ministres est en train de mettre la derni\u00e8re main \u00e0 une strat\u00e9gie de l&#39;emploi et qu&#39;un plan national pour les comp\u00e9tences commence \u00e0 porter des fruits. Mais avec les prix de la nourriture montant en fl\u00e8che et l&#39;inflation galopante, la tension politique est \u00e9lev\u00e9e alors que les gens perdent patience.<\/p>\n<p> En plus de la campagne contre la privatisation, le COSATU s&#39;attaque \u00e9galement aux soci\u00e9t\u00e9s alimentaires et au secteur agricole, se plaignant du fait que les prix du ma\u00efs &#8211; un aliment de base &#8211; \u00e9tait fix\u00e9 sur la base des prix des mati\u00e8res premi\u00e8res fix\u00e9s au plan international, bien que l&#39;Afrique du Sud ne soit pas importatrice mais auto-suffisante.<\/p>\n<p> Le COSATU se rapproche de plus en plus des mouvements sociaux qui deviennent une force avec laquelle il faut compter. Ceci marque un regroupement important des forces politiques en Afrique du Sud et retrace les barri\u00e8res entre les classes.<\/p>\n<p> La f\u00e9d\u00e9ration est, par exemple, dans une alliance tactique avec la Treatment Action Campaign, une organisation de masse faisant pression pour que le gouvernement \u00e9largisse l&#39;acc\u00e8s aux m\u00e9dicaments anti-SIDA qui sauvent la vie aux porteurs du VIH\/SIDA.<\/p>\n<p> Par ailleurs, la f\u00e9d\u00e9ration tient compte du nombre croissant des mouvements populaires qui font pression pour diverses questions dont la r\u00e9forme agraire et l&#39;\u00e9lectricit\u00e9 gratuite \u00e0 la base.<\/p>\n<p> Le COSATU a fait savoir au Parti communiste sud-africain qu&#39;il avait besoin de reconqu\u00e9rir son espace politique. &quot;Trop souvent, nous avons laiss\u00e9 l&#39;espace \u00e0 d&#39;autres organisations et mouvements pour combattre en faveur de l&#39;int\u00e9r\u00eat des pauvres, y compris les coupures d&#39;\u00e9lectricit\u00e9, les expulsions et la non-possession de terre&quot;, ajoute Vavi.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>JOHANNESBURG, 7 ao\u00fbt (IPS) &#8211; Une s\u00e9rie de r\u00e9unions politiques, tenues le mois dernier, a mis en relief le foss\u00e9 grandissant entre le Congr\u00e8s national africain (ANC) d&#39;une part, et ses alli\u00e9s communistes et syndicaux d&#39;autre part.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1,20],"tags":[],"class_list":["post-1269","post","type-post","status-publish","format-standard","hentry","category-afrique","category-headlines","category-travail"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=1269"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1269\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=1269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=1269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=1269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}