{"id":1166,"date":"2002-05-10T13:40:01","date_gmt":"2002-05-10T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2002\/05\/10\/politique-mali-la-cour-constitutionnelle-confirme-toumani-toure-etsoumaila-cisse-pour-le-second-tour\/"},"modified":"2002-05-10T13:40:01","modified_gmt":"2002-05-10T13:40:01","slug":"politique-mali-la-cour-constitutionnelle-confirme-toumani-toure-etsoumaila-cisse-pour-le-second-tour","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2002\/05\/10\/politique-mali-la-cour-constitutionnelle-confirme-toumani-toure-etsoumaila-cisse-pour-le-second-tour\/","title":{"rendered":"POLITIQUE-MALI: La Cour constitutionnelle confirme Toumani Tour\u00e9 etSouma\u00efla Ciss\u00e9 pour le second tour"},"content":{"rendered":"<p>BAMAKO, 10 mai (IPS) &#8211; La Cour constitutionnelle du Mali a proclam\u00e9 jeudi les r\u00e9sultats d\u00e9finitifs du premier tour de l&#39;\u00e9lection pr\u00e9sidentielle du 28 avril, confirmant Amadou Toumani Tour\u00e9 et Souma\u00efla Ciss\u00e9 pour le second tour pr\u00e9vu le 12 mai.\n<\/p>\n<p><!--more--><\/p>\n<p>\n Sur les 24 candidats en lice au premier tour, l&#39;ancien pr\u00e9sident de la transition (1991-1992), Toumani Tour\u00e9 et l&#39;ex-Premier ministre du pr\u00e9sident Alpha Oumar Konar\u00e9, Souma\u00efla Ciss\u00e9, candidat de l&#39;ADEMA (le parti au pouvoir), sont arriv\u00e9s en t\u00eate, avec respectivement 449.176 voix (28,71 pour cent) et 333.525 suffrages (21,31 pour cent).  Le troisi\u00e8me est Ibrahim Boubacar Keita avec 329.143 voix, soit 21,03 pour cent.<\/p>\n<p>Entre les trois premiers et les autres candidats, il existe un grand \u00e9cart..<\/p>\n<p>Par exemple, le quatri\u00e8me n&#39;a obtenu que 62.493 voix, soit 3,99 pour cent.<\/p>\n<p> Mais suite \u00e0 la vingtaine de requ\u00eates d\u00e9pos\u00e9es par les diff\u00e9rents candidats, la Cour constitutionnelle, pr\u00e9sid\u00e9e \u00e0 Bamako, la capitale, par Abdramane Baba Tour\u00e9, a annul\u00e9 541.019 bulletins de vote. Elle n&#39;a tenu compte que de 1.564.776 voix sur les 2.201.154 votants, \u00e0 cause de nombreuses irr\u00e9gularit\u00e9s.<\/p>\n<p> Le taux de participation est de 38,31 pour cent.<\/p>\n<p> Si les op\u00e9rations de vote, en d\u00e9pit de quelques incidents, se sont d\u00e9roul\u00e9es normalement, le traitement et la centralisation des r\u00e9sultats ont fait l&#39;objet de suspicion et de pol\u00e9mique au sein de la classe politique malienne. La m\u00e9thode de traitement utilis\u00e9e a \u00e9t\u00e9 d\u00e9cri\u00e9e par toutes les parties.<\/p>\n<p> D&#39;abord les mandataires des candidats de l&#39;Alliance &quot;Espoir 2002&quot; &#8211; un groupement de 15 partis politiques de l&#39;opposition &#8211; avaient protest\u00e9 aupr\u00e8s de la Commission de centralisation des votes, avant de suspendre leur participation aux travaux de d\u00e9pouillement, arguant de l&#39;absence des proc\u00e8s verbaux lors du d\u00e9compte des voix.<\/p>\n<p> Dans la m\u00eame lanc\u00e9e, le pr\u00e9sident de la Commission \u00e9lectorale nationale ind\u00e9pendante (CENI), Moustapha Ciss\u00e9, a d\u00e9nonc\u00e9 la violation de la loi \u00e9lectorale, en d\u00e9clarant : &quot;La totalisation des r\u00e9sultats, par la commission, s&#39;effectue en l&#39;absence des proc\u00e8s verbaux r\u00e9capitulatifs des commissions de centralisation (&#8230;), le traitement in\u00e9quitable r\u00e9serv\u00e9 par le ministre de l&#39;Administration aux r\u00e9sultats provisoires du district de Bamako\u00e0&quot;  R\u00e9agissant \u00e0 cette d\u00e9claration, le ministre de l&#39;Administration territoriale, Ousmane Sy, a tenu un point de presse pour d\u00e9noncer, \u00e0 son tour, &quot;la mauvaise interpr\u00e9tation de la loi par la CENI&quot;.<\/p>\n<p> Selon l&#39;article 141 de la loi \u00e9lectorale, &quot;la totalisation des r\u00e9sultats s&#39;effectue en pr\u00e9sence des proc\u00e8s verbaux r\u00e9capitulatifs des commissions de centralisation devant provenir des cercles, ambassades, consulats&quot;.  Les r\u00e9sultats officiels provisoires, rendus publics le 3 mai par le minist\u00e8re de l&#39;Administration territoriale, avaient d\u00e9gag\u00e9 d\u00e9j\u00e0 les tendances en confirmant la position des trois grands favoris \u00e0 savoir, Tour\u00e9, Ciss\u00e9 et l&#39;ancien Premier ministre Ibrahim Boubacar K\u00e9ita.<\/p>\n<p> D&#39;apr\u00e8s ces r\u00e9sultats, Tour\u00e9 avait \u00e9t\u00e9 cr\u00e9dit\u00e9 de 602.998 voix, soit 27,98 pour cent des suffrages exprim\u00e9s, Ciss\u00e9 avait obtenu 489.957 voix (22,74 pour cent) tandis que K\u00e9ita r\u00e9unissait 445.030 voix (20,65 pour cent).<\/p>\n<p> D\u00e8s l&#39;annonce des r\u00e9sultats provisoires, Keita avait r\u00e9agi en les qualifiant de &quot;fraude grossi\u00e8re et grotesque&quot;. &quot;C&#39;est clair qu&#39;il y a eu manipulation. Dans certaines zones, le nombre de votant est sup\u00e9rieur au nombre d&#39;inscrits&quot;, avait-il d\u00e9clar\u00e9 \u00e0 la presse.<\/p>\n<p> Le lendemain de la proclamation de ces r\u00e9sultats, les responsables de l&#39;Alliance Espoir 2002, dont K\u00e9ita, avaient organis\u00e9 un grand meeting \u00e0 Bamako pour demander l&#39;annulation pure et simple des r\u00e9sultats et la reprise du scrutin.<\/p>\n<p> Par contre, dans une d\u00e9claration rendue publique le 2 mai, le R\u00e9seau d&#39;appui au processus \u00e9lectoral au Mali (APEM), une organisation non gouvernementale (ONG) locale, qui avait d\u00e9ploy\u00e9 570 observateurs nationaux lors du scrutin, avait estim\u00e9 que les \u00e9lections &quot;se sont d\u00e9roul\u00e9es normalement&quot; malgr\u00e9 quelques imperfections.  De son cot\u00e9, le Centre Carter, une ONG bas\u00e9e aux Etats-Unis, qui avait envoy\u00e9 sept observateurs, avait \u00e9galement affirm\u00e9, dans une d\u00e9claration, que &quot;de mani\u00e8re g\u00e9n\u00e9rale, (&#8230;) le scrutin s&#39;est d\u00e9roul\u00e9 dans la paix et a \u00e9t\u00e9 correctement conduit dans un esprit de transparence&quot;. Cette ONG a toutefois soulign\u00e9 de nombreuses irr\u00e9gularit\u00e9s, estimant que &quot;le d\u00e9roulement de certains aspects du processus \u00e9lectoral est susceptible de provoquer des inqui\u00e9tudes quant \u00e0 l&#39;exactitude et \u00e0 la fiabilit\u00e9 des r\u00e9sultats&quot;..<\/p>\n<p> Pour le second tour pr\u00e9vu le 12 mai, Toumani Tour\u00e9 part favori devant Souma\u00efla Ciss\u00e9, avec d\u00e9j\u00e0 le soutien annonc\u00e9 de plus de 30 partis politiques, dont notamment celui de Ibrahim Boubacar K\u00e9ita et de toute l&#39;Alliance Espoir 2002.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BAMAKO, 10 mai (IPS) &#8211; La Cour constitutionnelle du Mali a proclam\u00e9 jeudi les r\u00e9sultats d\u00e9finitifs du premier tour de l&#39;\u00e9lection pr\u00e9sidentielle du 28 avril, confirmant Amadou Toumani Tour\u00e9 et Souma\u00efla Ciss\u00e9 pour le second tour pr\u00e9vu le 12 mai.<\/p>\n","protected":false},"author":195,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1,7],"tags":[],"class_list":["post-1166","post","type-post","status-publish","format-standard","hentry","category-afrique","category-headlines","category-politique"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=1166"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1166\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=1166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=1166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=1166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}