{"id":1049,"date":"2000-10-30T13:40:01","date_gmt":"2000-10-30T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2000\/10\/30\/politique-les-forces-onusiennes-en-sierra-leone-perdent-encore-des-soldats\/"},"modified":"2000-10-30T13:40:01","modified_gmt":"2000-10-30T13:40:01","slug":"politique-les-forces-onusiennes-en-sierra-leone-perdent-encore-des-soldats","status":"publish","type":"post","link":"https:\/\/ipsnews.net\/francais\/2000\/10\/30\/politique-les-forces-onusiennes-en-sierra-leone-perdent-encore-des-soldats\/","title":{"rendered":"POLITIQUE: Les forces onusiennes en Sierra Leone perdent encore  des soldats"},"content":{"rendered":"<p>NATIONS UNIES, 30 oct. (IPS) &#8211; Alors que la plupart des nations<br \/>\noccidentales<br \/>\ncontinuent de prendre leurs distances par rapport aux conflits<br \/>\nafricains et<br \/>\naux missions de maintien de la paix des Nations Unies, la Jordanie<br \/>\nest<br \/>\ndevenue le deuxi\u00e8me pays du Tiers Monde \u00e0 se retirer des forces<br \/>\nonusiennes<br \/>\nop\u00e9rant en Sierra Leone.<\/p>\n<p><!--more--><\/p>\n<p>La proposition jordanienne de retirer ses 1830 soldats intervient<br \/>\nune semaine<br \/>\napr\u00e8s la d\u00e9cision de l&#39;Inde de d\u00e9sengager ses 3000 soldats de<br \/>\ncette nation<br \/>\nd&#39;Afrique de l&#39;Ouest, ce qui du coup, r\u00e9duit l&#39;effectif des forces<br \/>\nonusiennes de 4830 soldats.<br \/>\n La Mission des Nations Unies en Sierra Leone (MINUSIL) a<br \/>\nactuellement un<br \/>\neffectif total de 12.440 soldats, mais ce chiffre tombera \u00e0 7.610<br \/>\napr\u00e8s le<br \/>\nretrait de la Jordanie et de l&#39;Inde, bien que le Conseil de<br \/>\nS\u00e9curit\u00e9 ait<br \/>\ncherch\u00e9 \u00e0 accro\u00eetre \u00e9ventuellement ces forces \u00e0 20.500.<br \/>\n La proposition d&#39;augmentation a \u00e9t\u00e9 motiv\u00e9e par les attaques<br \/>\ncontinues<br \/>\ncontre les soldats de maintien de la paix des Nations Unies par<br \/>\nles forces<br \/>\nrebelles du Front R\u00e9volutionnaire Uni (RUF), qui tentent de<br \/>\nrenverser le<br \/>\ngouvernement de Sierra Leone.<br \/>\n Les Nations Unies doivent encore remplir le vide qui serait cr\u00e9\u00e9<br \/>\nsuite au<br \/>\nd\u00e9part des troupes indiennes, qui ont accept\u00e9 un retrait<br \/>\nprogressif de leurs<br \/>\nsoldats au cours des prochains mois.<br \/>\n Les Jordaniens avaient pr\u00e9c\u00e9demment menac\u00e9 de retirer leurs<br \/>\nsoldats \u00e0 moins<br \/>\nque les nations occidentales &#8211; en particulier les pays membres de<br \/>\nl&#39;Organisation du Trait\u00e9 de l&#39;Atlantique Nord (OTAN) &#8211; acceptent<br \/>\nde<br \/>\nrenforcer la MINUSIL en y d\u00e9p\u00eachant des troupes suppl\u00e9mentaires.<br \/>\n Pr\u00e9sentement, 32 pays fournissent des troupes \u00e0 la MINUSIL, les<br \/>\ntrois plus<br \/>\ngrands pourvoyeurs \u00e9tant le Nigeria (3.205 soldats), l&#39;Inde<br \/>\n(3.073), la<br \/>\nJordanie (1.830), le Bangladesh (795), et la Guin\u00e9e (789).<br \/>\n Confirmant le retrait, Annan a d\u00e9clar\u00e9 aux journalistes la semaine<br \/>\nderni\u00e8re<br \/>\nque la d\u00e9cision jordanienne soulevait &quot;une question tr\u00e8s grave&quot;.<br \/>\n Comment est-ce que le Conseil de S\u00e9curit\u00e9 peut-il adopter des<br \/>\nr\u00e9solutions<br \/>\ndestin\u00e9es \u00e0 obtenir le d\u00e9ploiement de troupes, s&#39;est-il interrog\u00e9,<br \/>\nlorsque<br \/>\nde grandes puissances disposant de vastes forces militaires<br \/>\nrefusent de<br \/>\nfournir des soldats aux fins de missions de maintien de la paix ?<br \/>\n Le nombre total de soldats impliqu\u00e9s dans 15 missions de maintien<br \/>\nde la paix<br \/>\nest d&#39;environ 37.940. Les 10 plus grands pourvoyeurs de troupes<br \/>\nsont :<br \/>\nl&#39;Inde (4.507 soldats), le Nigeria (3.439), la Jordanie (3.400),<br \/>\nle<br \/>\nBangladesh (2.362), le Ghana (1.906), l&#39;Australie (1.710), le<br \/>\nPakistan<br \/>\n(1.209), le Kenya (1.197), la Pologne (1.077), et le N\u00e9pal<br \/>\n(1.037).<br \/>\n L&#39;Australie est la seule nation occidentale parmi ces 10 pays &#8211;<br \/>\nprincipalement en raison de son engagement politique \u00e0 une force<br \/>\nde maintien<br \/>\nde la paix dans son voisinage : la Mission des Nations Unies au<br \/>\nTimor Oriental.<br \/>\n Parmi les cinq grandes puissances membres du Conseil de S\u00e9curit\u00e9,<br \/>\nles Etats<br \/>\nUnis fournissent seulement 901 soldats pour les op\u00e9rations de<br \/>\nmaintien de la<br \/>\npaix, en grande partie pour des missions en dehors des Nations<br \/>\nUnies, la<br \/>\nGrande Bretagne (561), la France (490), la Russie (302), et la<br \/>\nChine (95).<br \/>\n Lorsque les journalistes ont demand\u00e9 \u00e0 Annan si l&#39;offre<br \/>\nbritannique de<br \/>\nfournir &quot;une force-parapluie&quot; n&#39;\u00e9tait pas suffisante pour<br \/>\nconvaincre la<br \/>\nJordanie de rester en Sierra Leone, le Secr\u00e9taire G\u00e9n\u00e9ral des<br \/>\nNations Unies<br \/>\na r\u00e9pondu que les Jordaniens ne jugeaient pas l&#39;offre britannique<br \/>\nsuffisante.<br \/>\n &quot;Ils avaient esp\u00e9r\u00e9 que d&#39;autres pays s&#39;y joindraient. Au moins<br \/>\nles<br \/>\nBritanniques ont fait un geste ; d&#39;autres n&#39;ont rien fait&quot;, a<br \/>\nd\u00e9clar\u00e9 Annan.<br \/>\n Lorsque 500 soldats des Nations Unies ont \u00e9t\u00e9 pris en otage par<br \/>\nles forces<br \/>\nrebelles au mois de mai dernier en Sierra Leone, Annan a demand\u00e9<br \/>\nque soit<br \/>\nmise sur pied une force de r\u00e9action rapide compos\u00e9e en majorit\u00e9 de<br \/>\ntroupes<br \/>\nmilitaires occidentales &quot;bien form\u00e9es et bien \u00e9quip\u00e9es&quot;.<br \/>\n &quot;Cela n&#39;a pas \u00e9t\u00e9 fait, mais l&#39;arriv\u00e9e des troupes britanniques<br \/>\net la<br \/>\npr\u00e9sence de la flotte navale britannique ont eu le bon impact<br \/>\npsychologique,<br \/>\nce qui nous a permis de consolider et de renforcer nos troupes&quot;,<br \/>\na ajout\u00e9<br \/>\nAnnan.<br \/>\n Les soldats et les navires de guerre britanniques ont \u00e9t\u00e9 d\u00e9p\u00each\u00e9s<br \/>\nen Sierra<br \/>\nLeone dans le seul but d&#39;aider \u00e0 \u00e9vacuer les citoyens britanniques<br \/>\nqui<br \/>\nfuyaient les combats dans ce pays.<br \/>\n Annan a indiqu\u00e9 qu&#39;il projetait de faire remplacer les soldats<br \/>\nindiens et<br \/>\njordaniens, &quot;mais cela va prendre du temps&#8230; J&#39;ai demand\u00e9 aux<br \/>\ngouvernements concern\u00e9s (Inde et Jordanie) de faire preuve de<br \/>\nflexibilit\u00e9<br \/>\ndans le retrait de leurs troupes. C&#39;est une d\u00e9cision souveraine et<br \/>\nc&#39;est<br \/>\nleur d\u00e9cision&quot;, a-t-il ajout\u00e9.<br \/>\n Le Bangladesh, le Kenya et le Ghana ont d\u00e9j\u00e0 offert plus de 3.000<br \/>\nsoldats<br \/>\npour remplacer quelques-uns des contingents en partance, mais<br \/>\nl&#39;Ukraine et<br \/>\nla Slovaquie vont vraisemblablement fournir des v\u00e9hicules<br \/>\nmilitaires<br \/>\n Le mois dernier, le Bangladesh, qui a fourni environ 795 soldats \u00e0<br \/>\nla<br \/>\nMINUSIL, a offert deux bataillons d&#39;infanterie additionnels. Si<br \/>\nAnnan<br \/>\naccepte l&#39;offre, ces deux bataillons additionnels d&#39;environ 900<br \/>\nsoldats<br \/>\nchacun pourraient porter le nombre total des troupes du Bangladesh<br \/>\nen Sierra<br \/>\nLeone \u00e0 environ 2.595.<br \/>\n Le retrait des troupes indiennes a \u00e9t\u00e9 attribu\u00e9 \u00e0 la tension<br \/>\ncroissante qui<br \/>\nexiste entre le Commandant de la MINUSIL, le G\u00e9n\u00e9ral Major Vijay<br \/>\nJetley de<br \/>\nl&#39;Inde, et son adjoint, le G\u00e9n\u00e9ral de Brigade Mohammed Garba du<br \/>\nNigeria.<br \/>\n Selon des articles de presse, Jetley a accus\u00e9 certains soldats<br \/>\nnig\u00e9rians de<br \/>\nrefuser d&#39;ob\u00e9ir aux ordres et d&#39;\u00eatre complices des forces rebelles<br \/>\ndans le<br \/>\ncommerce illicite des diamants en Sierra Leone. Ce sont les<br \/>\ndiamants qui ont<br \/>\nattis\u00e9 la guerre civile dans ce pays.<br \/>\n Dans un article intitul\u00e9 &quot;Retrait de la magouille&quot; publi\u00e9<br \/>\nr\u00e9cemment dans<br \/>\nle T\u00e9l\u00e9graphe de Calcutta, un ancien Secr\u00e9taire indien aux<br \/>\nAffaires<br \/>\nEtrang\u00e8res, J. N. Dixit, a critiqu\u00e9 &quot;l&#39;enthousiasme mal plac\u00e9&quot;<br \/>\nde l&#39;Inde \u00e0<br \/>\nparticiper aux op\u00e9rations de maintien de la paix des Nations<br \/>\nUnies.<br \/>\n &quot;Nos forces arm\u00e9es ont assez de probl\u00e8mes \u00e0 r\u00e9gler \u00e0 domicile&quot;,<br \/>\na d\u00e9clar\u00e9<br \/>\nDixit, qui a accus\u00e9 les Nations Unies de jouer le jeu de la<br \/>\npolitique<br \/>\nr\u00e9gionale en ce qui concerne les missions de maintien de la paix.<br \/>\n&quot;Il n&#39;y a<br \/>\naucun besoin pour les soldats indiens de laisser leur vie ou<br \/>\nd&#39;\u00e9prouver de<br \/>\nl&#39;embarras lorsque aucun des int\u00e9r\u00eats vitaux de l&#39;Inde ne se<br \/>\ntrouve en jeu&quot;.<br \/>\n Les op\u00e9rations de maintien de la paix d&#39;apr\u00e8s la guerre froide, a-<br \/>\nt-il<br \/>\nsoulign\u00e9, ont perdu de leur caract\u00e8re d&#39;impartialit\u00e9 et d&#39;adh\u00e9sion<br \/>\nstricte \u00e0<br \/>\nla Charte des Nations Unies, ainsi que la capacit\u00e9 de jouer un<br \/>\nr\u00f4le<br \/>\nau-dessus de la politique locale et r\u00e9gionale.<br \/>\n &quot;Le Secr\u00e9tariat des Nations Unies est devenu un objet des<br \/>\nmotivations<br \/>\nstrat\u00e9giques des grandes puissances mondiales et r\u00e9gionales, ainsi<br \/>\nque de<br \/>\nl&#39;influence politique et r\u00e9gionale \u00e0 courte vue des pays dans des<br \/>\nzones en<br \/>\ncrise&quot;, a-t-il estim\u00e9.<br \/>\n Jetley, le Commandant des Forces de l&#39;ONU, n&#39;a pas re\u00e7u l&#39;appui<br \/>\nn\u00e9cessaire<br \/>\ndu secr\u00e9tariat des Nations Unies, selon Dixit. Au d\u00e9but de la<br \/>\nmission, on ne<br \/>\nlui a permis non plus de prendre des actions militaires d\u00e9cisives<br \/>\npour<br \/>\nassurer la sauvegarde des soldats indiens. Le bon sens a pr\u00e9valu<br \/>\nen derni\u00e8re<br \/>\nanalyse, et Jetley a \u00e9t\u00e9 autoris\u00e9 \u00e0 lancer une op\u00e9ration militaire<br \/>\npour<br \/>\nsauver les soldats indiens qui \u00e9taient pris en otage par les<br \/>\nforces rebelles.<br \/>\n Dixit d\u00e9clare que l&#39;adjoint de Jetley, un officier militaire<br \/>\nnig\u00e9rian, a<br \/>\njug\u00e9 l&#39;impartialit\u00e9 et la franchise de Jetley &quot;inacceptables et<br \/>\nd\u00e9sagr\u00e9ables&#39;. En cons\u00e9quence, il y a eu des tentatives pour<br \/>\ncontrevenir aux<br \/>\nordres de Jetley et faire \u00e9chouer ses plans d&#39;op\u00e9ration.<br \/>\n Dixit a \u00e9galement d\u00e9clar\u00e9 que le Secr\u00e9tariat des Nations Unies a<br \/>\npropos\u00e9 au<br \/>\ngouvernement indien de faire remplacer Jetley par un G\u00e9n\u00e9ral<br \/>\nlieutenant de<br \/>\nl&#39;arm\u00e9e indienne, un officier de rang plus \u00e9lev\u00e9.<br \/>\n &quot;Ceci constitue sans aucun doute une insulte \u00e0 l&#39;int\u00e9grit\u00e9 et \u00e0<br \/>\nla<br \/>\ncr\u00e9dibilit\u00e9 de l&#39;Inde en tant que pourvoyeur de troupes aux<br \/>\nop\u00e9rations<br \/>\nonusiennes de maintien de la paix depuis la guerre de Cor\u00e9e et les<br \/>\nconflits<br \/>\ndans la bande de Gaza au d\u00e9but des ann\u00e9es &#39;50&quot;, a d\u00e9clar\u00e9 Dixit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NATIONS UNIES, 30 oct. (IPS) &#8211; Alors que la plupart des nations occidentales continuent de prendre leurs distances par rapport aux conflits africains et aux missions de maintien de la paix des Nations Unies, la Jordanie est devenue le deuxi\u00e8me&hellip; <a href=\"https:\/\/ipsnews.net\/francais\/2000\/10\/30\/politique-les-forces-onusiennes-en-sierra-leone-perdent-encore-des-soldats\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1049","post","type-post","status-publish","format-standard","hentry","category-headlines"],"_links":{"self":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=1049"}],"version-history":[{"count":0,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/1049\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=1049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=1049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=1049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}