{"id":97,"date":"2004-05-19T05:32:27","date_gmt":"2004-05-19T05:32:27","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2004\/05\/19\/thailandia-leccesso-di-forza-che-genera-martiri\/"},"modified":"2004-05-19T05:32:27","modified_gmt":"2004-05-19T05:32:27","slug":"thailandia-leccesso-di-forza-che-genera-martiri","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2004\/05\/19\/thailandia-leccesso-di-forza-che-genera-martiri\/","title":{"rendered":"THAILANDIA: L&#8217;eccesso di forza che genera martiri"},"content":{"rendered":"<p>Bangkok, 19 maggio 2004 (IPS) &#8211; Se gli Stati Uniti possono imporre l&#8217;uso eccessivo della forza nella conquista dell&#8217;Iraq e se Israele pu&ograve; fare lo stesso nella lotta alla resistenza palestinese, perch&eacute; non dovrebbe il governo thailandese ricorrere agli stessi metodi contro i separatisti del sud&#39;<\/p>\n<p><!--more--><\/p>\n<p>Questo sembra pensare il primo ministro Thaksin Shinawatra quando risponde con l&#8217;esercito ai gruppi separatisti della minoranza musulmana, che vive nelle cinque principali regioni a sud del paese.<\/p>\n<p>Venerd&igrave;, tutti i giornali parlavano delle politiche di &#8216;get tough&#8217; (colpire duro) e di &#8216;search and destroy&#8217; (cerca e uccidi) approvate dal governo di Banckok in seguito all&#8217;esplosione di violenza della settimana scorsa che ha causato la morte di 110 persone.<\/p>\n<p>&#8220;Gioved&igrave;, l&#8217;esercito ha dispiegato 500 unit&agrave; di &#8216;rapido intervento&#8217; contro 5000 militanti musulmani, in una missione denominata &#8216;cerca e uccidi&#8217;&#8221;, si legge sul quotidiano &#8220;The Nation&#8221;.<\/p>\n<p>Inoltre, come ha dichiarato il Ministro alla Difesa Chettha Thanajaro, la presenza militare nel sud del paese &egrave; stata rinforzata da altri due battaglioni che contano un totale di mille unit&agrave;.<\/p>\n<p>Pnitan Wattanayagorn, esperto di sicurezza nazionale per l&#8217;universit&agrave; Chulalongkorn di Bangkok, ha detto all&#8217;IPS: &#8220;Le forze di sicurezza sono state esortate ad agire con cautela, ma se attaccate, risponderanno con forza&#8221;.<\/p>\n<p>Mercoled&igrave; mattina, la polizia e le forze di sicurezza hanno dimostrato ampiamente quanto possono colpire &#8216;duro&#8217;, usando una potenza di fuoco inaudita contro militanti adolescenti e armati di coltelli e machete.<\/p>\n<p>Una strategia che ha evocato parole come &#8216;carneficina&#8217; e &#8216;genocidio&#8217; tra giornalisti e sostenitori dei diritti umani. Sunai Phasuk, rappresentante thailandese dell&#8217;Human Right Watch (HRW), ha dichiarato in un&#8217;intervista: &#8220;Le truppe dell&#8217;esercito erano chiaramente intenzionate a non lasciare vivi&#8221;. <\/p>\n<p>La moschea di Krue Se a Pattani, una delle tre regioni dove sono esplosi gli scontri con i separatisti, &egrave; diventata il simbolo di quella che &egrave; stata gi&agrave; definita da molti un&#8217;orgia di violenza.<\/p>\n<p>Trentadue militanti si erano rifugiati nell&#8217;antica moschea e sono stati trucidati. Un massacro inutile che secondo molti testimoni poteva essere evitato. <\/p>\n<p>I musulmani del luogo ricorderanno la violenza di mercoled&igrave; non solo per i morti. Il sacro libro del Corano e il pavimento della moschea, costruita nel XVI sec. e molto amata dai fedeli, sono intrisi di sangue.   Ora, tutti associano il governo di Thaskin alle immagini del strage e &#8220;le conseguenze sul piano politico potrebbero essere molto serie&#8221;, ha dichiarato Chaiwat Satha-Anand, direttore del Peace Information Centre dell&#8217;universit&agrave; di Thammasat a Bangkok.<\/p>\n<p>I rapporti potrebbero deteriorarsi. Le forze di sicurezza, che hanno l&#8217;opportunit&agrave; di mediare e sedare la violenza, scelgono invece di imporre il potere dello stato &#8220;e addirittura, violano la casa di Allah&#8221;, continua Chaiwat, membro della comunit&agrave; islamica.<\/p>\n<p>Il massacro di mercoled&igrave; ha in qualche modo consacrato i morti a martiri della guerra santa. Chaiwat ha aggiunto: &#8220;Molte famiglie stanno gi&agrave; celebrando i riti particolari per chi muore difendendo il suo dio&#8221;.<\/p>\n<p>Venerd&igrave;, il Bangkok Post ha scritto: &#8220;Ou Mameh, segretario generale del Comitato Islamico di Pattani, ha proclamato le vittime guerrieri di Allah e chiesto che i loro corpi non venissero lavati prima della sepoltura&#8221;.<\/p>\n<p>La Thailandia, un paese di 63 milioni di persone a maggioranza buddista, non contempla il martirio. I musulmani, che abitano principalmente le regioni al confine con la Malaysia, sono sei milioni.<\/p>\n<p>&#8220;E&#8217; la prima volta che in questo paese qualcuno sceglie di combattere l&#8217;autorit&agrave; centrale sacrificando la propria vita&#8221;, ha detto Sunay sui fatti di mercoled&igrave;.<\/p>\n<p>I giovani musulmani, alcuni tra15 e 20 anni, armati di coltelli, hanno attaccato alcune stazioni di polizia delle province di Yala, Songkhla e Pattani. <\/p>\n<p>Secondo alcuni, la reazione di Bangkok alla carneficina di mercoled&igrave;, in cui sono morti 108 musulmani e cinque membri delle forze di sicurezza, potrebbe spingere altri giovani a intraprendere la via del martirio. <\/p>\n<p>Questa ipotesi &egrave; purtroppo reale, se si considera la quasi totale assenza del governo e il crescente senso di umiliazione e alienazione da parte di alcune frange della minoranza musulmana.<\/p>\n<p>Venerd&igrave;, &#8220;The Nation&#8221; ha pubblicato l&#8217;articolo di Pravit Rojanaphruk, che evidenzia l&#8217;eredit&agrave; di anni di abbandono e marginalizzazione della comunit&agrave; islamica: &#8220;Chiunque sia stato a capo del governo thailandese, ha sempre osteggiato ogni tentativo di valorizzare la storia e la religione del sud&#8221;.<\/p>\n<p>&#8220;Negli ultimi anni, la legge marziale &egrave; prassi; non &egrave; permesso eleggere rappresentanti locali ed i leader islamici eletti da Bangkok sembrano seguire fedelmente la linea del governo&#8221;, ha aggiunto.<\/p>\n<p>L&#8217;anno scorso, per esempio, in seguito all&#8217;assalto a due uffici del governo, Thaksin ha autorizzato le forze di sicurezza a usare la violenza ed a emanare &#8216;condanne a morte&#8217;.<\/p>\n<p>Dall&#8217;inizio dell&#8217;anno c&#8217;&egrave; stato un insorgere della violenza e scuole, posti di polizia e campi militari sono stati attaccati a pi&ugrave; riprese. Circa sessanta persone tra poliziotti, soldati e monaci buddisti, sono rimaste uccise.<\/p>\n<p>L&#8217;attivit&agrave; militare del governo nel sud &egrave; volta principalmente a contrastare i movimenti islamici separatisti, sorti trenta anni fa nel paese. Gi&agrave; agli inizi degli anni &#8217;80, Bangkok sembrava avere la situazione sotto controllo.<\/p>\n<p>L&#8217;ostilit&agrave; verso il governo centrale ha le sue radici nella storia di queste province. Pi&ugrave; di un secolo fa, Narathiwat, Pattani, Satun, Songkhla e Yala appartenevano al Sultanato di Pattani, ma nel 1902 vennero annesse al Siam, la Thailandia di oggi. <\/p>\n<p>Nei conflitti di allora, non esisteva il concetto di martirio, indice che il risentimento del sud ha acquisito oggi un nuovo, preoccupante linguaggio.<\/p>\n<p>&#8220;Nel sud si vive nella rabbia e si guarda alla morte in modo differente; il governo non pu&ograve; trascurare questi nuovi elementi&#8221;, ha affermato Chaiwat, acceso sostenitore della pace. &#8220;Un passo falso pu&ograve; spingere i giovani a sentirsi ancora pi&ugrave; umiliati e a vedere nel martirio una soluzione onorevole&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bangkok, 19 maggio 2004 (IPS) &#8211; Se gli Stati Uniti possono imporre l&#8217;uso eccessivo della forza nella conquista dell&#8217;Iraq e se Israele pu&ograve; fare lo stesso nella lotta alla resistenza palestinese, perch&eacute; non dovrebbe il governo thailandese ricorrere agli stessi&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2004\/05\/19\/thailandia-leccesso-di-forza-che-genera-martiri\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[8,15,1,32],"tags":[],"class_list":["post-97","post","type-post","status-publish","format-standard","hentry","category-asia-e-oceania","category-diritti-umani","category-headlines","category-politica"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}