{"id":962,"date":"2008-05-08T11:42:48","date_gmt":"2008-05-08T11:42:48","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2008\/05\/08\/birmania-il-ciclone-nargis-mostra-il-volto-anti-umano-della-giunta\/"},"modified":"2008-05-08T11:42:48","modified_gmt":"2008-05-08T11:42:48","slug":"birmania-il-ciclone-nargis-mostra-il-volto-anti-umano-della-giunta","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2008\/05\/08\/birmania-il-ciclone-nargis-mostra-il-volto-anti-umano-della-giunta\/","title":{"rendered":"BIRMANIA: Il ciclone Nargis mostra il volto anti-umano della giunta"},"content":{"rendered":"<p>BANGKOK, 8 maggio 2008 (IPS) &#8211; Il ciclone Nargis, il pi&ugrave; grave disastro naturale della Birmania a memoria d&rsquo;uomo, ha consolidato nel paese l&rsquo;immagine della giunta militare come forza interessata unicamente a perpetuare il controllo del potere, trascurando la popolazione che finge di proteggere.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1186\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1186\" class=\"size-full wp-image-1186\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/burmacyclone3.jpg\" alt=\"In cerca di cibo a Rangoon colpita dal ciclone Nargis Mizzima News\" width=\"200\"\/><p id=\"caption-attachment-1186\" class=\"wp-caption-text\">In cerca di cibo a Rangoon colpita dal ciclone Nargis<br \/>Mizzima News<\/p><\/div><\/div>\n<p>Secondo le stime ufficiali, Nargis ha provocato la morte di oltre 30 mila persone, 40 mila sono disperse e oltre un milione i senzatetto. Ma pi&ugrave; che dei soccorsi, il governo sembra preoccupato del referendum che dovrebbe prolungare la sua stretta sul paese. <\/p>\n<p>La sola concessione a un popolo che cerca di riprendersi dalla devastazione causata dal ciclone, &egrave; lo spostamento della data delle elezioni, programmate per il 10 maggio e rinviate al 25 maggio in alcune delle aree pi&ugrave; colpite, come Rangoon e il Delta dell&rsquo;Irrawaddy. <\/p>\n<p>A Rangoon, vecchia capitale, la gente inizia a manifestare la rabbia per l&rsquo;indifferenza delle autorit&agrave; di fronte al disastro. <\/p>\n<p>&rdquo;Dov&rsquo;erano (i militari) quando ne avevamo bisogno, per pulire le strade, offrirci acqua e un rifugio, e per proteggerci mentre la tempesta ci colpiva&rdquo;, ha detto una casalinga birmana di mezza et&agrave; all&rsquo;IPS, chiedendo l&rsquo;anonimato. &ldquo;Hanno impiegato un solo giorno per reprimere la protesta dei monaci (a settembre), ma a quattro giorni dal ciclone non si sono ancora visti&rdquo;, ha aggiunto la donna con rabbia. <\/p>\n<p>A Rangoon, la maggior parte della gente la pensa allo stesso modo, dicono all&rsquo;IPS diplomatici e giornalisti che vivono qui. &ldquo;Sono stati i monaci a condurre le operazioni di pulizia&rdquo;, ha detto un anziano impiegato statale in pensione. &ldquo;Che Dio li benedica&rdquo;.<\/p>\n<p>Le immagini di soldati che rimuovono gli alberi caduti e puliscono le strade di Rangoon sulla televisione di stato hanno sollevato la rabbia di molti in citt&agrave;. &ldquo;&Egrave; pura propaganda, ben lontana dalla verit&agrave;&rdquo;, ha scritto via mail un giornalista birmano, chiedendo l&rsquo;anonimato nel timore di ritorsioni. &ldquo;Perch&eacute; le televisioni straniere trasmettono quelle immagini? La propaganda del governo birmano &egrave; una vera disgrazia per il giornalismo&rdquo;, ha inveito l&rsquo;uomo. <\/p>\n<p>&rdquo;Ieri ho visto alcuni soldati salire su un camion&rdquo;, ha detto un residente di una cinquantina d&rsquo;anni. &ldquo;Non erano affatto sudati, malgrado le immagini trasmesse in TV!&rdquo; &rdquo;Mia moglie ha visto tre camion di soldati parcheggiati di fronte a un albero caduto, ma nessuno si &egrave; mosso per rimuoverlo&rdquo;, ha aggiunto. <\/p>\n<p>Il peggio &egrave; che le autorit&agrave; militari avevano ricevuto un ampio preavviso della tempesta in arrivo dalla Baia del Bengala, ma hanno deciso di ignorare la notizia, o di tenerla nascosta. <\/p>\n<p>Il Dipartimento meteorologico indiano (IMD, Indian Meteorological Department), che tiene dettagliatamente traccia degli eventi geo-climatici nella Baia del Bengala, avverte delle emergenze non solo le province della costa indiana orientale, ma anche i paesi costieri pi&ugrave; a rischio. L&rsquo;IMO ha dichiarato di aver avvertito le autorit&agrave; birmane della formazione del ciclone Nargis, e di un suo possibile avvicinamento, gi&agrave; intorno al 26 aprile. <\/p>\n<p>&rdquo;Noi aggiorniamo continuamente le autorit&agrave; del Myanmar (nome ufficiale della Birmania) e il 30 aprile avevamo dato anche dettagli del possibile percorso, velocit&agrave; e luoghi interessati&rdquo;, ha detto il direttore dell&rsquo;IMD, B.P. Yadav, al corrispondente dell&rsquo;IPS a Nuova Delhi, Ranjit Devraj. <\/p>\n<p>Il dipartimento meteorologico birmano aveva pubblicato l&#039;allarme sul suo sito ufficiale il 27 aprile, ma non si &egrave; fatto alcuno sforzo per divulgare l&rsquo;informazione, e ancor meno per evacuare la popolazione lungo la costa, o dalle isole sul Delta dell&rsquo;Irrawaddy. <\/p>\n<p>Quando l&rsquo;informazione di stato &#8211; che trasmetteva continuamente propaganda elettorale esortando il pubblico a votare &ldquo;s&igrave;&rdquo; al referendum costitutivo di sabato &#8211; ha mandato il primo allarme-ciclone venerd&igrave; pomeriggio, era troppo tardi per gli sfortunati residenti di Rangoon. <\/p>\n<p>La maggior parte dei residenti della citt&agrave; sono troppo traumatizzati per interessarsi ad altro che non sia sopravvivere e proteggere la propria famiglia. Nei dintorni della citt&agrave;, lungo il fiume dove vive &ndash; o viveva &#8211; la classe pi&ugrave; povera dei lavoratori, le incerte abitazioni costruite sono state completamente spazzate via. Tutti a Rangoon stanno freneticamente cercando di raccogliere acqua, riferiscono testimoni oculari. <\/p>\n<p>Il ciclone, con un vento che superava i 200 chilometri orari, ha divelto il centro commerciale di Rangoon, che oggi somiglia a una zona di guerra. Gli alberi sono stati sradicati e i tetti di case e palazzi divelti. La tempesta ha interrotto anche elettricit&agrave; e comunicazioni. <\/p>\n<p>L&rsquo;area densamente popolata a est di Rangoon, il Delta dell&rsquo;Irrawaddy, soprannominata la ciotola di riso della Birmania, &egrave; stata la pi&ugrave; gravemente colpita. Il ciclone ha provocato onde alte oltre due metri, e il terreno pi&ugrave; basso &egrave; ancora quasi interamente allagato. <\/p>\n<p>Si ritiene che in quest&rsquo;area fertile del paese vivano oltre 20 milioni di persone. Senza alcun allarme preventivo, sono stati completamente abbandonati alla maledizione di questi venti e alla furia dell&#039;acqua.    Il tributo di morte pare destinato a crescere, secondo gli operatori umanitari presenti nel paese. Potrebbe raggiungere le 150 mila vittime, ha detto un operatore birmano all&rsquo;IPS. &ldquo;&Egrave; il peggior disastro che abbia colpito la Birmania a memoria umana, &egrave; il nostro tsunami&rdquo;; ha detto, chiedendo l&rsquo;anonimato. &ldquo;Ma potremmo non sapere mai il reale numero di morti&rdquo;.<\/p>\n<p>Le agenzie internazionali di aiuto e le Nazioni Unite sono ancora in attesa che la giunta dia il via libera per distribuire gli aiuti. Squadre veloci ed esperte sono in allerta e stanno aspettando da diversi giorni. <\/p>\n<p>&rdquo;La nostra pi&ugrave; grande preoccupazione &egrave; che il dopo-ciclone potrebbe addirittura essere pi&ugrave; fatale della stessa tempesta&rdquo;, ha detto all&rsquo;IPS Richard Horsey, portavoce dell&rsquo;ufficio regionale dell&rsquo;Onu per il  coordinamento degli affari umanitari (UNOCHA), con sede a Bangkok. &ldquo;Bisogna al pi&ugrave; presto pulire le strade dall&rsquo;acqua e garantire le scorte di farmaci nelle aree colpite, per prevenire una seconda ondata di epidemie con malattie che potrebbero provenire dall&rsquo;acqua&rdquo;.  <\/p>\n<p>Aerei carichi di scorte ed equipaggi dovrebbero essere atterrati a Rangoon marted&igrave;. La maggior parte proviene da India, Tailandia e Giappone, ma anche alcune agenzie dell&rsquo;Onu avrebbero cercato di far arrivare rifornimenti, come lenzuola plastificate, tende, zanzariere, farmaci e tavolette per purificare l&rsquo;acqua. <\/p>\n<p>Il Comitato internazionale della Croce Rossa ha inviato farmaci, mentre la principale organizzazione alimentare dell&rsquo;Onu, il Programma alimentare mondiale (PAM), ha mandato riso e biscotti altamente energetici. &ldquo;Speriamo di riuscire a portare altro nei prossimi giorni&rdquo;; ha detto all&rsquo;IPS il portavoce regionale del PAM, Paul Risely. &ldquo;Tuttavia, la sfida &egrave; quella di garantire assistenza alle aree colpite nel Delta dell&rsquo;Irrawaddy, dove le strade sono bloccate&rdquo;. <\/p>\n<p>L&rsquo;Onu ha iniziato a distribuire cibo ai senzatetto di Rangoon. &ldquo;L&rsquo;assistenza alimentare del PAM ha raggiunto persone senza un rifugio e prive di risorse alimentari all&rsquo;interno e fuori Yangon (Rangoon)&rdquo;, ha detto Chris Kaye, direttore del PAM nel paese. Le agenzie di aiuto stanno cercando di raggiungere il delta, e il governo ha fornito elicotteri e barche per agevolare la distribuzione. <\/p>\n<p>La giunta ha capito tardivamente quanto fosse necessaria un&rsquo;azione per prevenire l&rsquo;accaparramento e la speculazione dei prezzi. &ldquo;Stiamo coordinando e cooperando col mondo del business. Abbiamo chiesto a tutti gli imprenditori di non speculare sul disastro&rdquo;, ha dichiarato durante una conferenza stampa il ministro per dell&#039;informazione birmano, Generale Maggiore Kyaw Hsan. <\/p>\n<p>Tuttavia, per la maggior parte dei birmani questo appello sembra aggiungere insulto all&rsquo;offesa, dato che il governo &egrave; accusato di aver fatto salire alle stelle i prezzi alimentari &ndash; circostanza che aveva generato le massicce proteste dei monaci dello scorso anno, brutalmente soppresse. <\/p>\n<p>&rdquo;A Rangoon la gente sa di aver perso tutto, e di non avere nient&rsquo;altro da perdere&rdquo;, ha detto uno studente attivista. Riprenderanno probabilmente le proteste iniziate a settembre per il prezzo del riso, soprattutto se il governo continuer&agrave; a trascurare le paure della gente schiacciata dal ciclone. <\/p>\n<p>&rdquo;La giunta ha mostrato la sua vera indole, completamente disinteressata alla disgrazie della popolazione&rdquo;, ha detto Win Min, professore birmano che vive nella cittadina di Chiang Mai, in Tailandia. &ldquo;Questo potrebbe essere l&rsquo;ultimo chiodo per la bara dei militari; ora non si tratta pi&ugrave; di capire &lsquo;se&rsquo;, ma &lsquo;quando&rsquo;&rdquo;, ha aggiunto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BANGKOK, 8 maggio 2008 (IPS) &#8211; Il ciclone Nargis, il pi&ugrave; grave disastro naturale della Birmania a memoria d&rsquo;uomo, ha consolidato nel paese l&rsquo;immagine della giunta militare come forza interessata unicamente a perpetuare il controllo del potere, trascurando la popolazione&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2008\/05\/08\/birmania-il-ciclone-nargis-mostra-il-volto-anti-umano-della-giunta\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[15,1,26,25,32,33,35,36],"tags":[],"class_list":["post-962","post","type-post","status-publish","format-standard","hentry","category-diritti-umani","category-headlines","category-iraq-e-asia-centrale","category-obiettivi-di-sviluppo-sostenibile","category-politica","category-popolazione","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}