{"id":536,"date":"2006-04-14T16:04:14","date_gmt":"2006-04-14T16:04:14","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2006\/04\/14\/sud-africa-la-doccia-che-ha-lavato-via-gli-sforzi-anti-aids\/"},"modified":"2006-04-14T16:04:14","modified_gmt":"2006-04-14T16:04:14","slug":"sud-africa-la-doccia-che-ha-lavato-via-gli-sforzi-anti-aids","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2006\/04\/14\/sud-africa-la-doccia-che-ha-lavato-via-gli-sforzi-anti-aids\/","title":{"rendered":"SUD AFRICA: La doccia che ha lavato via gli sforzi anti-Aids"},"content":{"rendered":"<p>JOHANNESBURG, 14 aprile 2006 (IPS) &#8211; Gli attivisti impegnati nella lotta all&rsquo;AIDS sono preoccupati per le conseguenze delle dichiarazioni dell&#039;ex vicepresidente sudafricano Jacob Zuma, il quale ha affermato di aver scongiurato il rischio di contrarre il virus dopo aver avuto rapporti sessuali con una donna sieropositiva facendo immediatamente una doccia.<\/p>\n<p><!--more--><\/p>\n<p>Zuma sostiene inoltre che il rischio di contrarre il virus da una donna &egrave; minimo per un uomo in salute.<\/p>\n<p>&#8220;&Egrave; una sciocchezza, non c&#039;&egrave; alcuna prova a sostegno di ci&ograve;&#8221;, ha dichiarato Nathan Geffen della TAC (Treatment Action Campaign), organizzazione non governativa con sede nella citt&agrave; costiera di Citt&agrave; del Capo, che si batte per un maggiore accesso ai farmaci anti-retrovirali. <\/p>\n<p>&#8220;Ci sono pi&ugrave; di due milioni di uomini siero-positivi in Sud Africa. La maggior parte di loro ha contratto il virus tramite rapporti sessuali con donne. Chiaramente, gli uomini contraggono spesso il virus dalle donne&#8221;, ha detto all&#039;IPS. <\/p>\n<p>&#8220;(Il commento di Zuma) ha provocato enorme danno e confusione&#8221;.<\/p>\n<p>Zuma ha rilasciato quelle dichiarazioni mentre &egrave; in corso il processo contro di lui per lo stupro di una trentunenne attivista anti-Aids e sieropositiva, avvenuto nel novembre dello scorso anno. Secondo il Programma delle Nazioni Unite contro l&#039;Aids (UNAIDS), in Sud Africa, il tasso di adulti sieropositivi &egrave; di circa il 25 per cento. <\/p>\n<p>Le affermazioni di Zuma, gi&agrave; presidente del Consiglio nazionale sudafricano per l&#039;Aids e padre del Movimento di rigenerazione morale (Moral Regeneration Movement) nel paese, hanno provocato un certo stupore. Pi&ugrave; di cinque milioni di persone in Sud Africa vivono con Hiv e Aids, un numero superiore ad ogni altra nazione. <\/p>\n<p>I commenti di Geffen hanno avuto larga eco anche tra gli attivisti in altre parti del paese..<\/p>\n<p>&#8220;Questa &egrave; un&#039;affermazione assurda. Scientificamente, non si pu&ograve; ridurre il rischio di infezione con una semplice doccia. Penso che l&#039;idea (di una doccia) si riferisca alla distruzione delle prove&#8221;, ha detto in un&#039;intervista all&#039;IPS Dorothy Odhiambo, dela sede keniota del Network of African People Living with HIV and AIDS (NAP+), (NAP+ &egrave; un gruppo non governativo del continente, con uffici in Africa orientale, meridionale e occidentale). <\/p>\n<p>&#8220;Se fosse vero che &egrave; possibile non contrarre il virus dopo un rapporto occasionale, allora chiunque potrebbe semplicemente fare una doccia dopo aver avuto rapporti sessuali&#8221;, ha fatto notare l&#039;attivista. &#8220;(La dichiarazione di Zuma) pu&ograve; rallentare gli effetti della campagna per la riduzione del tasso di infezione di Hiv in Sud Africa entro cinque anni&#8221;. <\/p>\n<p>Jefter Mxotshwa, coordinatore del NAP+, ha aggiunto: &#8220;Zuma &egrave; un leader politico. Esercita una grande influenza, soprattutto nelle aree rurali, e il suo paese, il Sud Africa, &egrave; considerato una guida in questa regione. La gente ascolta attentamente una persona influente come Zuma nell&#039;Africa meridionale&#8221;. <\/p>\n<p>&#8220;Per esempio, gli stupratori continueranno a stuprare e subito dopo faranno una doccia. Diranno che l&#039;(ex) vice presidente lo ha fatto. Perch&eacute; non dovremmo farlo anche noi?&#8221;, ha aggiunto Mxotshwa. <\/p>\n<p>Le cifre diffuse dall&#039;UNAIDS dimostrano che in Africa meridionale alla fine del 2005 viveva pi&ugrave; di un terzo del numero totale di sieropositivi, circa 15 milioni. <\/p>\n<p>Odhiambo e Mxotshwa hanno parlato durante un incontro della International Federation of Red Cross and Red Crescent Societies con sede a Ginevra, tenutosi all&#039;inizio del mese nel centro commerciale di Johannesburg. Il meeting, durato due giorni, ha riunito pi&ugrave; di 200 partecipanti &ndash; in maggioranza dell&#039;Africa meridionale &ndash; concentrandosi sul flagello di Hiv e Aids nella regione. <\/p>\n<p>Zuma non &egrave; il primo leader sudafricano che suscita controversie sull&#039;Aids. Il presidente Thabo Mbeki, a sua volta, &egrave; stato accusato di minacciare gli sforzi per contenere l&#039;epidemia mettendo in discussione il legame tra Hiv e Aids. <\/p>\n<p>Il processo di Zuma ha anche rinfocolato il dibattito in Sud Africa sullo stupro &ndash; questione sempre calda in un paese in cui, secondo People Opposing Woman Abuse, viene stuprata una donna ogni 26 secondi. <\/p>\n<p>Il gruppo civico con sede a Johannesburg riferisce inoltre che solo uno stupro su nove viene denunciato, e appena il sette per cento dei colpevoli viene punito. <\/p>\n<p>Insistendo sull&#039;innocenza di Zuma, centinaia di sostenitori dell&#039;ex vicepresidente si riuniscono al tribunale di Johannesburg ad ognuna delle sue apparizioni. La settimana scorsa il suo avvocato ha ricevuto un&#039;accoglienza da eroe uscendo dal tribunale insieme al suo team. <\/p>\n<p>I dimostranti hanno mandato in collera la TAC, che ha chiesto a Zuma di trattenere i suoi sostenitori dal tentativo &#8220;di intimidire la donna che denuncia lo stupro sottoponendola a domande imbarazzanti, insultandola o tirando oggetti contro di lei&#8221;. <\/p>\n<p>&#8220;Sottoporre chi denuncia uno stupro a minacce e intimidazioni dimostra l&#039;inguaribile disprezzo verso tutte le donne e i diritti umani tutelati dalla costituzione, che rappresentano la pietra miliare della nostra democrazia conquistata a fatica&#8221;, riporta una dichiarazione del gruppo. <\/p>\n<p> &#8220;In Sud Africa stupro e violenza sessuale contro donne e ragazze sono le cause fondamentali dell&#039;epidemia di Hiv. La violenza contro le donne &egrave; un attacco quotidiano alla dignit&agrave;, all&#039;uguaglianza delle donne, e ai nostri valori sociali&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOHANNESBURG, 14 aprile 2006 (IPS) &#8211; Gli attivisti impegnati nella lotta all&rsquo;AIDS sono preoccupati per le conseguenze delle dichiarazioni dell&#039;ex vicepresidente sudafricano Jacob Zuma, il quale ha affermato di aver scongiurato il rischio di contrarre il virus dopo aver avuto&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2006\/04\/14\/sud-africa-la-doccia-che-ha-lavato-via-gli-sforzi-anti-aids\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":43,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,11,15,16,1,27,25,33,34],"tags":[],"class_list":["post-536","post","type-post","status-publish","format-standard","hentry","category-africa","category-columnas","category-diritti-umani","category-donne-e-sviluppo","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile","category-popolazione","category-salute"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=536"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/536\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=536"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}