{"id":462,"date":"2005-12-24T15:21:06","date_gmt":"2005-12-24T15:21:06","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2005\/12\/24\/africa-la-disoccupazione-di-massa-vanifica-lo-sviluppo\/"},"modified":"2005-12-24T15:21:06","modified_gmt":"2005-12-24T15:21:06","slug":"africa-la-disoccupazione-di-massa-vanifica-lo-sviluppo","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2005\/12\/24\/africa-la-disoccupazione-di-massa-vanifica-lo-sviluppo\/","title":{"rendered":"AFRICA: La disoccupazione di massa vanifica lo sviluppo"},"content":{"rendered":"<p>NAZIONI UNITE, 24 dicembre 2005 (IPS) &#8211; Secondo un recente rapporto Onu, la crescente povert&agrave; nel continente africano, afflitto anche da fame, malattia e guerre, &egrave; dovuta principalmente agli alti tassi di disoccupazione.<\/p>\n<p><!--more--><\/p>\n<p>Malgrado il significativo aumento del prodotto interno lordo (PIL) globale, &ldquo;la povert&agrave; &egrave; rimasta indifferente alla crescita economica&rdquo;.<\/p>\n<p>&rdquo;Alla base di questa tendenza, c&rsquo;&egrave; il fatto che la maggior parte della popolazione (in Africa) non ha impiego o fonti sicure di reddito&rdquo;, dichiara la ricerca intitolata &ldquo;Rapporto economico sull&rsquo;Africa 2005: rispondere alle sfide di disoccupazione e povert&agrave;&rdquo;.<\/p>\n<p>Lo studio di 279 pagine, il sesto di una serie annuale pubblicata dalla Commissione economica delle Nazioni Unite per l&rsquo;Africa (ECA), con sede ad Addis Abeba, sottolinea che la disoccupazione &egrave; una delle &ldquo;sfide pi&ugrave; grandi&rdquo; per lo sviluppo africano.<\/p>\n<p>Max Lawson, dell&rsquo;agenzia internazionale di aiuto Oxfam, ha dichiarato che l&rsquo;ECA ha tradizionalmente assunto un punto di vista meno ortodosso sui problemi dell&rsquo;Africa &shy; ben lontano dalle indicazioni della Banca mondiale e del Fondo Monetario Internazionale (FMI).<\/p>\n<p>Lawson sostiene che la maggior parte dei governi africani sono vincolati dalle politiche stabilite da Banca mondiale e FMI, e hanno pochissimo margine per agire autonomamente.<\/p>\n<p>&rdquo;Dovrebbero smettere di spingere i governi africani verso modelli che non funzionano&rdquo;, ha detto Lawson all&rsquo;IPS, aggiungendo che a questi governi dovrebbe essere permesso controllare le proprie economie nazionali.<\/p>\n<p>La ricerca ECA afferma che i tassi medi di disoccupazione, che vanno dal 10 all&rsquo;11 per cento circa, si riferiscono a persone in cerca di lavoro in Africa sub-sahariana e nord Africa.<\/p>\n<p>&rdquo;Rappresentano i secondi e terzi tassi di disoccupazione pi&ugrave; elevati del mondo, mentre il pi&ugrave; alto in assoluto si ha nella regione medio- orientale&ldquo;, riferisce lo studio.<\/p>\n<p>Tuttavia, il quadro &egrave; pi&ugrave; drammatico, perch&eacute; queste cifre non includono i numerosi lavoratori poveri e coloro che hanno rinunciato a cercare un lavoro dignitoso e quindi non rientrano nella statistica.<\/p>\n<p>Sulla base delle attuali tendenze demografiche, si stima che l&rsquo;Africa avrebbe bisogno di creare circa otto milioni di posti di lavoro ogni anno, per assorbire il crescente numero di persone alla ricerca di un impiego.<\/p>\n<p>&rdquo;La creazione di lavori pi&ugrave; dignitosi, accessibili ai poveri, costituisce lo strumento pi&ugrave; efficace per affrontare la povert&agrave; in Africa&rdquo;, sostiene K.Y. Amoako, segretario esecutivo uscente dell&rsquo;ECA, il quale sottolinea che negli ultimi trenta anni il collegamento tra povert&agrave; e disoccupazione stato riconosciuto ai livelli politici pi&ugrave; alti.<\/p>\n<p>Durante un incontro al vertice svoltosi lo scorso anno a Burkina Faso, i capi di stato africani hanno approvato la &ldquo;Dichiarazione sullo sviluppo e riduzione della povert&agrave;&rdquo;, promettendo di combattere la miseria attraverso l&rsquo;occupazione.<\/p>\n<p>Lo studio illustra quattro sfide: raggiungere una trasformazione strutturale per allontanarsi dal sotto-utilizzo del lavoro rurale; combattere la diffusione della disoccupazione giovanile; indirizzare la globalizzazione per creare lavori dignitosi; e creare un ambiente che consenta una rapida diffusione della creazione di occupazione nel settore privato attraverso maggiori investimenti.<\/p>\n<p>Secondo lo studio, mentre la performance macroeconomica in Africa segnatamente migliorata dagli anni &lsquo;90, l&rsquo;impatto sulla disoccupazione sembra essere minimo. La crescita annuale media del PIL &egrave; aumentata stabilmente, da meno del tre per cento nel 1998 al 4,6 per cento nel 2004. &ldquo;Eppure, la disoccupazione oscilla intorno al 10 per cento dal 1995&rdquo;, riferisce la ricerca.<\/p>\n<p>Il rapporto sostiene che i prerequisiti per la creazione di occupazione comprendono la trasformazione delle economie africane da un&rsquo;agricoltura tradizionale a bassa produttivit&agrave;, verso un&rsquo;agricoltura intensiva ad alto valore &shy; e verso i settori in crescita dell&rsquo;industria e dei servizi, traendo vantaggio dalle opportunit&agrave; della globalizzazione.<\/p>\n<p>Nella gestione delle economie africane, prosegue la ricerca, &egrave; dunque richiesta una leadership politica che dia priorit&agrave; alla creazione di posti di lavoro su ampia scala nei programmi di sviluppo nazionali, e comprenda strategie di riduzione della povert&agrave;.<\/p>\n<p>Dr. Kwame Akonor, direttore dell&rsquo;Istituto africano per lo sviluppo, ha un&rsquo;idea differente sulla leadership politica in Africa.<\/p>\n<p>&rdquo;La responsabilit&agrave; dei fallimenti dello sviluppo africano, malgrado quasi mezzo secolo di indipendenza dalle dominazioni europee, sono fondamentalmente dei suoi leader politici&rdquo;, ha dichiarato.<\/p>\n<p>Anzich&eacute; usare lungimiranza e originalit&agrave; nelle loro scelte pubbliche, le autorit&agrave; africane continuano ad abbracciare politiche che tolgono potere alla societ&agrave; africana.<\/p>\n<p>&rdquo;Le riforme neoliberiste da sole, con la loro enfasi sulla crescita economica a discapito dell&rsquo;uguaglianza sociale, non possono trasformare le economie subordinate dell&rsquo;Africa in entit&agrave; vitali e autosostenibili&rdquo;, ha detto Akonor all&rsquo;IPS.<\/p>\n<p>I leader africani devono cercare di modificare e orientare in maniera diversa la posizione dell&rsquo;Africa in tema di economia politica globale, verso una politica di indipendenza, mirando ad una pianificazione economica continentale.<\/p>\n<p>Senza una leadership che si impegni in questa direzione economica pan-africana, ha concluso, &ldquo;il ciclo della miseria in Africa non sar&agrave; mai attenuato&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAZIONI UNITE, 24 dicembre 2005 (IPS) &#8211; Secondo un recente rapporto Onu, la crescente povert&agrave; nel continente africano, afflitto anche da fame, malattia e guerre, &egrave; dovuta principalmente agli alti tassi di disoccupazione.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,38,11,18,1,27,25],"tags":[],"class_list":["post-462","post","type-post","status-publish","format-standard","hentry","category-africa","category-sviluppo","category-columnas","category-economia","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=462"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/462\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=462"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}