{"id":352,"date":"2005-08-21T10:45:12","date_gmt":"2005-08-21T10:45:12","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2005\/08\/21\/impatto-tsunami-le-donne-di-aceh-riscoprono-il-loro-ruolo\/"},"modified":"2005-08-21T10:45:12","modified_gmt":"2005-08-21T10:45:12","slug":"impatto-tsunami-le-donne-di-aceh-riscoprono-il-loro-ruolo","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2005\/08\/21\/impatto-tsunami-le-donne-di-aceh-riscoprono-il-loro-ruolo\/","title":{"rendered":"IMPATTO TSUNAMI: Le donne di Aceh riscoprono il loro ruolo"},"content":{"rendered":"<p>JAKARTA, 21 agosto 2005 (IPS) &#8211; Un tempo, le donne comandavano il defunto Sultanato di Aceh, la cui storia parla di ammiraglie e di successioni matrilineari. Tuttavia, dopo l&rsquo;annessione del principato all&rsquo;Indonesia nel 1949, le donne sono state emarginate e hanno avuto bisogno di un devastante tsunami perch&eacute; riscoprissero il loro ruolo fondante nella societ&agrave; di Aceh.<\/p>\n<p><!--more--><\/p>\n<p>&rdquo;Lo tsunami ha cambiato il panorama sociale e politico; &egrave; ora che le donne ritornino ad esercitare il loro ruolo nella societ&agrave; di Aceh&rdquo;, ha dichiarato Arabiyani, che lavora per il Progetto Aceh del Fondo di sviluppo delle Nazioni Unite per la donna (UNIFEM).    La regione, situata all&rsquo;estremit&agrave; nord dell&rsquo;isola di Sumatra, &egrave; stata gravemente colpita dallo tsunami del 26 dicembre. Quando l&rsquo;acqua si &egrave; ritirata, pi&ugrave; di 130.000 persone erano morte e la maggior parte dell&rsquo;area era ridotta in macerie. <\/p>\n<p>Secondo Oxfam, in alcuni villaggi, il maremoto e il conseguente tsunami hanno ucciso in proporzione quattro donne per ogni uomo.<\/p>\n<p>La catastrofe ha costretto il presidente Susilo Bambang Yudhoyono ad aprire la porta ai soccorsi stranieri. Aceh &ndash; teatro di una guerra lunga 30 anni &ndash; &egrave; rimasta isolata e gli sguardi giudicanti del mondo si sono posati su pi&ugrave; di due anni di brutale repressione. <\/p>\n<p>Le donne &ndash; stuprate, torturate, uccise o rese vedove &ndash;  hanno subito l&rsquo;impatto del conflitto che ha portato alla morte pi&ugrave; di 15.000 persone, e proprio le donne sono state in prima linea nelle strategie di sopravvivenza che hanno sostenuto famiglie e comunit&agrave; durante il conflitto. <\/p>\n<p>Lo tsunami ha portato i media mondiali ad Aceh e i riflettori accesi hanno sollecitato la pressione internazionale sia su Jakarta che sul gruppo ribelle, il Movimento per Aceh libera (GAM), per fermare la guerra civile. <\/p>\n<p>L&rsquo;opportunit&agrave; &egrave; stata accolta dal presidente Yudhoyono, che ha dato via libera al nuovo dialogo di pace a Helsinki. Al termine del quinto round di consultazioni, mediate dall&rsquo;ex-presidente finlandese Maarti Ahtisaari, le due parti in lotta si sono accordate per fermare le ostilit&agrave;, raggiungendo un accordo formale di pace firmato il 15 agosto. <\/p>\n<p>&Egrave; una nuova alba per Aceh, ma ci vorr&agrave; molto tempo prima che le donne possano reclamare il ruolo cruciale che hanno storicamente esercitato nella provincia. <\/p>\n<p>I mercanti navali arabi, che hanno portato l&rsquo;Islam nell&rsquo;arcipelago indonesiano, avevano rilevato la struttura matriarcale di Aceh, dove le donne occupavano ruoli fondamentali nella politica e nella societ&agrave;.  Anche dopo aver abbracciato l&rsquo;Islam, il sultanato aveva avuto una successione di sovrane donne e nella sua storia si annovera la presenza di una donna ammiraglio, Laksamana Koemalahayati, capo della marina militare reale alla fine del XV secolo. Durante il periodo coloniale, alcune donne a capo della guerriglia, come Cut Nya&#039; Dhien, Cut Meutia, Pocut Baren e Pocut Mirah Inteun, hanno combattuto e resistito tra il 1871 e il 1901 ai piani degli olandesi sulla provincia.    I ruoli femminili sono venuti meno solo dopo che l&rsquo;Indonesia ha ottenuto l&rsquo;indipendenza e che la nuova repubblica ha sopraffatto pi&ugrave; di cento diverse etnie nel vasto arcipelago. Ad Aceh, il sistema matriarcale si &egrave; sbriciolato di fronte a un&rsquo;elite politica e religiosa dominata dagli uomini.  <\/p>\n<p>&rdquo;&Egrave; come un soffitto di vetro. &Egrave; chiaro che, a livello base, le donne hanno una loro funzione, ma il problema &egrave; ai livelli alti. &Egrave; l&igrave; che sono sottomesse&rdquo;, sostiene Arabiyani. <\/p>\n<p>Tuttavia, si intravedono i segni del cambiamento. Pi&ugrave; del 70 per cento delle organizzazioni locali non governative (Ong) che operano ad Aceh sono gruppi femminili oppure impiegano principalmente donne. <\/p>\n<p>Dopo lo tsunami, il ruolo delle donne &egrave; diventato fondamentale. Hanno iniziato a curare  bambini e feriti, a partecipare alle operazioni di ricerca e di soccorso, e la maggior parte dello staff assunto dalle organizzazioni internazionali che gravitano nell&rsquo;area &egrave; costituito da donne. <\/p>\n<p>Oggi, le rivendicazioni sono aumentate. Circa 400 donne provenienti da tutta la provincia si sono riunite a Banda Aceh in giugno, per la seconda Conferenza delle donne di Aceh. La prima conferenza si era tenuta nel 2000. Durante l&rsquo;evento di quattro giorni, le donne hanno reclamato il diritto di parola nella fase di ricostruzione e per il futuro della provincia. <\/p>\n<p>&rdquo;Le donne sono al centro delle famiglie e possono aiutare a restaurare il tessuto sociale della societ&agrave;, ma per farlo devono esercitare un ruolo pi&ugrave; importante&rdquo;, ha dichiarato Arabiyani. <\/p>\n<p>Kuntoro Mangkusubroto, direttore dell&rsquo;Agenzia per la ricostruzione di Aceh, concorda. &ldquo;Sono convinto che le donne saranno le promotrici del cambiamento&rdquo;, ha dichiarato subito dopo la conferenza. <\/p>\n<p>Poco prima, docenti universitarie, avvocatesse, attiviste e studentesse avevano marciato fino al Consiglio legislativo provinciale di Aceh, chiedendo una revisione della normativa che regola l&rsquo;elezione del capo del governo regionale. <\/p>\n<p>Attualmente, l&rsquo;articolo 41 della legge stabilisce che i candidati devono essere &ldquo;capaci di amministrare la legge islamica, di leggere il santo corano e in grado di fungere da capi per la preghiera della comunit&agrave; e da predicatori in una moschea&rdquo;.<\/p>\n<p>Aceh &egrave; la sola provincia indonesiana dove la legge islamica della sharia proibisce alle donne di svolgere funzioni di guida per la preghiera comunitaria o di esercitare il ruolo di predicatrici, il che di fatto le esclude da qualunque duello elettorale. <\/p>\n<p>Le elezioni regionali si terranno ad Aceh nell&rsquo;aprile 2006, ma la rappresentanza politica &egrave; ancora una preoccupazione secondaria per le donne dei villaggi e dell&rsquo;hinterland della provincia. <\/p>\n<p>Dedik Harianty, capo dell&rsquo;Ong locale Perampuan Merdeka (Libert&agrave; delle donne), ha dichiarato che la violazione dei diritti umani, la violenza domestica e il diritto allo studio sono i problemi pi&ugrave; urgenti per la maggioranza delle donne nei villaggi. <\/p>\n<p>&rdquo;Non parliamo di politica, ma di questioni quotidiane. Cerchiamo di costruire la fiducia in loro stesse, perch&eacute; un giorno possano parlare dei loro diritti&rdquo;, ha dichiarato l&rsquo;attivista. <\/p>\n<p>Fondata nel 2000, Perampuan Merdeka ha avuto tempi difficili ad Aceh a causa della guerra civile. L&rsquo;ufficio &egrave; stato assaltato e chiuso dall&rsquo;Esercito indonesiano (TNI) nel luglio del 2003. <\/p>\n<p>L&rsquo;Ong si &egrave; ricostituita altrove, ma il TNI &egrave; tornato: il 26 agosto del 2004 le attivit&agrave; sono state nuovamente cessate e tre leader dell&rsquo;organizzazione &#8211; Krisna, Irma e Samsidar &ndash; sono state arrestate.    Dopo lo tsunami, lo scenario di Aceh &egrave; stato determinante per il ritorno dell&rsquo;Ong nel marzo del 2005. &rdquo;Abbiamo usato i problemi legati allo tsunami per arrivare alla popolazione. Adesso abbiamo maggior  coraggio, perch&eacute; la situazione &egrave; cambiata&rdquo;, ha dichiarato Harianty, aggiungendo che lo tsunami ha portato molti giornalisti, e quindi la questione della violazione dei diritti umani ad Aceh oggi &egrave; universalmente nota. <\/p>\n<p>Rina, 24 anni, &egrave; una delle giovani donne che si &egrave; unita a Perampuan Merdeka poco dopo che la Ong ha riavviato la missione. &ldquo;Non avevo davvero idea dei diritti delle donne; oggi non posso dire di conoscerli appieno, ma sicuramente ne so di pi&ugrave; e non posso tornare indietro&rdquo;, ha dichiarato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JAKARTA, 21 agosto 2005 (IPS) &#8211; Un tempo, le donne comandavano il defunto Sultanato di Aceh, la cui storia parla di ammiraglie e di successioni matrilineari. Tuttavia, dopo l&rsquo;annessione del principato all&rsquo;Indonesia nel 1949, le donne sono state emarginate e&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2005\/08\/21\/impatto-tsunami-le-donne-di-aceh-riscoprono-il-loro-ruolo\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":118,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[38,6,8,11,13,15,16,1,27,25,32],"tags":[],"class_list":["post-352","post","type-post","status-publish","format-standard","hentry","category-sviluppo","category-apocalisse-tsunami","category-asia-e-oceania","category-columnas","category-cooperazione","category-diritti-umani","category-donne-e-sviluppo","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-obiettivi-di-sviluppo-sostenibile","category-politica"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=352"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/352\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=352"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}