{"id":2035,"date":"2018-10-19T11:13:46","date_gmt":"2018-10-19T11:13:46","guid":{"rendered":"http:\/\/ipsnews.net\/italiano\/?p=2035"},"modified":"2018-10-19T15:23:09","modified_gmt":"2018-10-19T15:23:09","slug":"ipernutrizione-e-denutrizione-due-facce-della-stessa-moneta-malsana","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2018\/10\/19\/ipernutrizione-e-denutrizione-due-facce-della-stessa-moneta-malsana\/","title":{"rendered":"Ipernutrizione e denutrizione: due facce della stessa moneta malsana"},"content":{"rendered":"<p>NAZIONI UNITE, ott 2018 (IPS) &#8211; Il bisogno di un cambiamento drastico nel modo in cui mangiamo e pensiamo al cibo \u00e8 pi\u00f9 urgente che mai per prevenire un ulteriore degrado ambientale e una epidemia sanitaria ancora pi\u00f9 grande.<!--more--><\/p>\n<p>Diversi esperti provenienti da mondo accademico, societ\u00e0 civile e agenzie delle Nazioni Unite si sono riuniti a margine dell\u2019Assemblea Generale per discutere del problema dilagante dell\u2019insicurezza alimentare e della malnutrizione e cercare possibili soluzioni per riformare \u00a0il sistema.<\/p>\n<p>\u201c\u00c8 allarmante, nonostante gli evidenti progressi scientifici e tecnologici, che esista ancora un divario tra coloro che mangiano troppo e coloro che non hanno abbastanza cibo\u201d, ha detto all\u2019IPS il capo della <a href=\"https:\/\/www.barillacfn.com\/it\/\">Barilla Centre for Food and Nutrition Foundation<\/a>, Luca Di Leo.<\/p>\n<p>Secondo lo <a href=\"http:\/\/www.who.int\/nutrition\/publications\/foodsecurity\/state-food-security-nutrition-2018\/en\/\">State of Food Security and Nutrition in the World 2018<\/a>, il numero di persone affamate \u00e8 aumentato a 820 milioni nel 2017 dagli 804 milioni del 2016, dei livelli mai visti per quasi dieci anni.<\/p>\n<p>Allo stesso tempo, forse paradossalmente, il tasso globale d\u2019obesit\u00e0 \u00e8 rapidamente aumentato nell\u2019ultimo decennio dall\u201911,7 percento del 2012 al 13,2 percento del 2016. Questo vuol dire che nel 2017, pi\u00f9 di un adulto su otto, ossia pi\u00f9 di 670 milioni di persone nel mondo, erano obese.<\/p>\n<p>L\u2019obesit\u00e0 in et\u00e0 adulta e il maggiore tasso di incremento dell&#8217;obesit\u00e0 si registra in America del Nord, anche se adesso comincia a riscontrarsi una tendenza all\u2019incremento anche in Africa e Asia.<\/p>\n<p>I partecipanti del Forum Internazionale su alimentazione e nutrizione hanno ribadito la necessit\u00e0 di affrontare entrambe le forme di malnutrizione, evidenziando le responsabilit\u00e0 per la mancanza di accesso a cibi sani.<\/p>\n<p>\u201cIl punto non \u00e8 cosa c\u2019\u00e8 nel cibo, ma cosa c\u2019\u00e8 nel discorso sul cibo\u2026 ci sono molti modi per mangiare male\u201d, ha detto David Katz, direttore del Centro di ricerca per la prevenzione della Yale University.<\/p>\n<p>Molti hanno osservato per\u00f2 che manca un accordo unificato e concreto su cosa costituisce una dieta sana correlata ad un sistema alimentare sostenibile.<\/p>\n<p>\u201cSenza obiettivi mirati ad un\u2019azione \u00a0collettiva, e senza meccanismi per coordinare e monitorare i progressi, \u00e8 davvero difficile produrre un cambiamento del sistema su larga scala\u201d, ha detto Gunhild Stordalen, fondatore della <a href=\"https:\/\/eatforum.org\/\">Fondazione EAT<\/a>, un piattaforma scientifica globale orientata a una trasformazione del sistema alimentare.<\/p>\n<p>Katz si \u00e8 detto concorde, affermando che \u201cnon potremmo mai raggiungere degli obiettivi se non riusciamo ad accordarci su di essi\u2026 dobbiamo essere uniti su alcuni principi di base fondamentali&#8221;.<\/p>\n<p><b>Combattere il sistema<\/b><\/p>\n<p>Tra questi principi c\u2019\u00e8 il bisogno di riformare l\u2019intero sistema alimentare e agricolo.<\/p>\n<p>Nonostante i noti e scioccanti particolari rivelati dal documentario del 2004 \u201cSupersize Me\u201d, il consumo di cibi e zuccheri trattati e non salutari \u00e8 solo aumentato.<\/p>\n<p>Secondo l\u2019indice di sostenibilit\u00e0 alimentare (<a href=\"http:\/\/foodsustainability.eiu.com\/wp-content\/uploads\/sites\/34\/2016\/09\/FoodSustainabilityIndex2017GlobalExecutiveSummary.pdf\">Food Sustainability Index<\/a>, FSI) 2017 della Fondazione Barilla Center for Food &amp; Nutrition, gli Stati Uniti registrano il maggior consumo di zucchero tra le 34 nazioni censite nel 2017.<\/p>\n<p>L\u2019americano medio consuma pi\u00f9 di 126 grammi di zucchero al giorno, il doppio del consumo giornaliero raccomandato dalla Organizzazione Mondiale per la Sanit\u00e0.<\/p>\n<p>Questo non solo porta a maggiori tassi di obesit\u00e0, ma ha anche contribuito all\u2019aumento dei livelli di malattie cardiovascolari e diabete.<\/p>\n<p>\u201cIl numero di anni persi per carenze nutrizionali e malattie cardiovascolari sta aumentando bruscamente negli Stati Uniti\u201d, dice Leo Abruzzese della Economist Intelligence Unit, che ha elaborato l\u2019Indice.<\/p>\n<p>\u201cUno delle esportazioni meno ammirevoli degli USA \u00e8 stata proprio la cattiva alimentazione \u2026 le persone non ne stanno morendo, ma vivono vite alquanto infelici. In queste circostanze, non pensate che bisogna agire in qualche modo?&#8221;, ha detto all\u2019IPS.<\/p>\n<p>Grazie all\u2019indice FSI \u00e8 anche emerso che il consumo di carne e grassi saturi negli USA \u00e8 tra i pi\u00f9 alti al mondo, contribuendo a diete squilibrate e persino al cambiamento climatico.<\/p>\n<p>Secondo la U.N. University, le emissioni prodotte dal bestiame rappresentano il 15 percento delle emissioni globali di gas serra. Solamente i bovini e i caseifici rappresentano il 65 percento di tutte le emissioni dovute al bestiame.<\/p>\n<p>Le aziende di carne e latticini sono sulla buona strada per diventare le maggiori responsabili del cambiamento climatico, superando l\u2019industria dei \u00a0combustibili fossili.<\/p>\n<p>Stordalen ha per\u00f2 osservato che assicurare diete sane e sostenibili \u00e8 alla nostra portata.<\/p>\n<p>Le alternative alla carne hanno preso molte nazioni d\u2019assalto, e potrebbero poco a poco trasformare le industrie della carne e di fast food. Adesso i consumatori possono trovare l\u2019\u201chamburger impossibile,\u201d un hamburger senza carne e solo vegetale, in molti ristoranti e catene di fast food come il White Castle.<\/p>\n<p>Recentemente, le compagnie vegane Beyond Meat e Impossible food basate negli Stati Uniti hanno ricevuto dall\u2019ONU per l\u2019ambiente (UN Environment) il premio Campioni della Terra.<\/p>\n<p>\u201cLe scelte alimentari sostenibili cominciano ad avere un bell\u2019aspetto e \u00a0anche un buon sapore, e non era cos\u00ec nel passato,\u201d dice Stordalen.<\/p>\n<p>\u201cQuando le persone avranno assaporato soluzioni migliori, non solo cominceranno a desiderare ma persino a pretendere un futuro migliore. Si raggrupperanno per fare in modo che questo accada\u201d, ha aggiunto.<\/p>\n<p>Il FSI \u00e8 anche uno strumento fondamentale per guidare i governi e i responsabili politici a guardare con maggiore attenzione ai progressi e alle criticit\u00e0 dei loro sistemi alimentari nazionali.<\/p>\n<p>\u201cRiunendo tutti questi [indicatori] noi abbiamo, essenzialmente, un quadro chiaro di ci\u00f2 che consideriamo un buon sistema alimentare\u201d, ha aggiunto Abruzzese.<\/p>\n<p><strong>Un problema di potere<br \/>\n<\/strong><\/p>\n<p>La mancanza di accesso al cibo sano e le sue conseguenze sono evidenti anche all\u2019altro capo della catena di valore alimentare, i produttori.<\/p>\n<p>Le donne rappresentano il 60 percento della forza lavoro agricola in Africa, per\u00f2 hanno ancora un accesso limitato a semi di qualit\u00e0, fertilizzanti ed attrezzature meccaniche. Allo stesso tempo, devono anche occuparsi della casa, dell\u2019educazione dei loro figli e della cucina.<\/p>\n<p>\u00c8 emerso che questa diseguaglianza di genere contribuisce ad una alimentazione familiare pi\u00f9 povera e aumenta l&#8217;arresto della crescita nei bambini.<\/p>\n<p>I partecipanti al Forum hanno sottolineato la necessit\u00e0 di rendere autonome le coltivatrici e affrontare la disuguaglianza di genere nell\u2019agricoltura per migliorare la sicurezza alimentare e nutrizionale e creare societ\u00e0 sostenibili.<\/p>\n<p>\u201cIl contrario della fame \u00e8 il potere&#8221;, ha detto il cattedratico ricercatore Raj Patel dell\u2019Universit\u00e0 del Texas, riguardo al caso del Malawi.<\/p>\n<p>In Malawi, pi\u00f9 della met\u00e0 dei bambini soffre di malnutrizione cronica. La raccolta del mais, principale alimento di questo paese del sudest dell\u2019Africa, \u00e8 compito delle donne, incaricate anche del lavoro di cura.<\/p>\n<p>\u201cAnche quando c\u2019era pi\u00f9 cibo, c\u2019era pi\u00f9 malnutrizione&#8221;, ha detto Patel.<\/p>\n<p>Un villaggio del nord del Malawi ha affrontato il problema tramite il progetto \u2018Terreni, Cibo e Comunit\u00e0 Sane\u2019, ottenendo risultati straordinari.<\/p>\n<p>Oltre alle attivit\u00e0 per diversificare le colture, il progetto ha riunito uomini e donne per condividere il lavoro, ad esempio cucinando insieme e coinvolgendo gli uomini nel lavoro di cura.<\/p>\n<p>Non solo hanno raggiunto la parit\u00e0 di genere nell\u2019agricoltura, ma il villaggio ha anche visto un calo drastico nella malnutrizione infantile.<\/p>\n<p>\u201cDobbiamo dare valore al lavoro delle donne\u201d, ha detto Patel.<\/p>\n<p><b>Il futuro del cibo <\/b><\/p>\n<p>Riorganizzare il sistema alimentare e agricolo non \u00e8 certo un compito facile, ma deve essere fatto, hanno detto i partecipanti.<\/p>\n<p>\u201cSappiamo quali sono i problemi e abbiamo anche individuato le possibili soluzioni\u2026 e la soluzione \u00e8 ciascuno di noi e tutti noi\u201d, ha detto Di Leo all\u2019IPS.<\/p>\n<p>Une delle soluzioni fondamentali \u00e8 l\u2019educazione e dare la possibilit\u00e0 alle persone di diventare agenti del cambiamento.<\/p>\n<p>\u201cUna produzione sana sar\u00e0 possibile solo se i consumatori chiederanno cibo sano. E il cibo sano ci sar\u00e0 solo se il consumatore avr\u00e0 il diritto all\u2019educazione e all\u2019informazione\u201d, ha detto Di Leo.<\/p>\n<p>Per esempio, molti non vedono o non conoscono il legame che esiste tra cibo e cambiamento climatico, ha aggiunto.<\/p>\n<p>Uno studio del 2016 ha infatti rivelato una scarsa consapevolezza del legame tra il consumo di carne e il cambiamento climatico, e una resistenza all\u2019idea di ridurre il consumo individuale di carne.<\/p>\n<p>\u201c\u00c8 un tipo di cambiamento che richiede un approccio dal basso\u201d, ha detto Di Leo.<\/p>\n<p>Stordalen ha condiviso i commenti di Di Leo, appellandosi ad un \u2018dugnad\u2019 globale &#8211; una parola norvegese che descrive l\u2019azione di una comunit\u00e0 che si unisce e lavora insieme per raggiungere un obiettivo utile per tutti.<\/p>\n<p>\u201cLo stato del sistema alimentare globale richiede una nuova azione collaborativa\u201d, ha detto Di Leo. Tutte le persone coinvolte devono darsi da fare insieme per offrire un giusto futuro alle nostre popolazioni e al nostro pianeta\u201d.<\/p>\n<p>[editing a cura di Francesca Buffo]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAZIONI UNITE, ott 2018 (IPS) &#8211; Il bisogno di un cambiamento drastico nel modo in cui mangiamo e pensiamo al cibo \u00e8 pi\u00f9 urgente che mai per prevenire un ulteriore degrado ambientale e una epidemia sanitaria ancora pi\u00f9 grande.<\/p>\n","protected":false},"author":576,"featured_media":2036,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[1,25],"tags":[],"class_list":["post-2035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-headlines","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/2035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/576"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=2035"}],"version-history":[{"count":4,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/2035\/revisions"}],"predecessor-version":[{"id":2041,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/2035\/revisions\/2041"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media\/2036"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=2035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=2035"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=2035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}