{"id":1817,"date":"2013-11-08T18:43:52","date_gmt":"2013-11-08T18:43:52","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2013\/11\/08\/larabia-saudita-senza-diritti-umani-vuole-un-seggio-nel-consiglio-2\/"},"modified":"2013-11-08T18:43:52","modified_gmt":"2013-11-08T18:43:52","slug":"larabia-saudita-senza-diritti-umani-vuole-un-seggio-nel-consiglio-2","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2013\/11\/08\/larabia-saudita-senza-diritti-umani-vuole-un-seggio-nel-consiglio-2\/","title":{"rendered":"L&#8217;Arabia Saudita, senza diritti umani, vuole un seggio nel Consiglio"},"content":{"rendered":"<p>NAZIONI UNITE, nov, 2013 (IPS) &#8211; Quando l&rsquo;anno scorso l&rsquo;Arabia Saudita ha concesso il diritto di voto alle donne ma non il permesso di guidare, la vignetta di un quotidiano ha ritratto questa ingiustizia con cupa ironia.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1934\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1934\" class=\"size-full wp-image-1934\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/burqas640-629x401.jpg\" alt=\"Rebecca Murray\/IPS Rebecca Murray\/IPS\" width=\"200\" \/><p id=\"caption-attachment-1934\" class=\"wp-caption-text\">Rebecca Murray\/IPS<br \/>Rebecca Murray\/IPS<\/p><\/div><\/div>\n<p>Mentre un gruppo di donne in burqa &egrave; in coda per votare nel seggio di Riyadh, uno scrutatore con fare aggressivo dice loro, &ldquo;C&rsquo;&egrave; un piccolo problema. Ci servono le vostre patenti di guida per identificarvi&rdquo;.<\/p>\n<p>L&rsquo;unico paese al mondo in cui alle donne non &egrave; ancora permesso guidare ha buone possibilit&agrave; di ottenere un seggio nel Consiglio per i Diritti Umani (HRC) di Ginevra per un periodo di tre anni, a partire da gennaio 2014.<\/p>\n<p>Le elezioni per i quattro seggi vacanti nel gruppo dei paesi dell&rsquo;Asia-Pacifico, in base al criterio di rotazione geografica, si terranno in occasione dell&rsquo;Assemblea Generale del 12 novembre. I cinque candidati in lista sono Cina, Giordania, Maldive, Vietnam e Arabia Saudita.<\/p>\n<p>In seguito al rifiuto dell&rsquo;Arabia Saudita di entrare a far parte del Consiglio di Sicurezza poco dopo essere stata eletta, ci si chiede se far&agrave; la stessa cosa con il Consiglio per i Diritti Umani, qualora dovesse ottenere il seggio.<\/p>\n<p>&ldquo;Da un sondaggio realizzato dal nostro team di Ginevra emerge che nessuno ha sentito dire che l&rsquo;Arabia Saudita potrebbe non accettare il posto alla HRC&rdquo;, ha riferito all&rsquo;IPS Adam Coogle di Human Rights Watch (HRW). Ovviamente questo non esclude che ci&ograve; accada, ma non abbiamo altri commenti per ora&rdquo;.<\/p>\n<p>Suad Abu-Dayyeh della Equality Now di New York riferisce all&rsquo;IPS che l&rsquo;Arabia Saudita, come molti paesi nel mondo, deve migliorare significativamente per quanto riguarda la tutela dei diritti delle donne.<\/p>\n<p>&ldquo;Questi abusi nei diritti umani fondamentali, come la mancanza di un&rsquo;et&agrave; minima per il matrimonio o il divieto per le donne di guidare, sono stati ben documentati e sono estremamente dannosi&rdquo;, afferma.<\/p>\n<p>Per le donne e le ragazze saudite, la vita di ogni giorno dipende esclusivamente dalla bont&agrave; dei sorveglianti: una situazione che limita completamente la libert&agrave; di movimento delle donne e delle ragazze, e che deve assolutamente cambiare. Le recenti dichiarazioni secondo cui l&rsquo;Arabia Saudita starebbe facendo qualche passo avanti per risolvere il problema sono positive ma non sufficienti, aggiunge. <\/p>\n<p>&ldquo;Cerchiamo di incoraggiare il Regno a sfruttare ogni occasione per dare il via a una trasformazione radicale nella condizione delle donne&rdquo;, ha aggiunto.<\/p>\n<p>Alla fine di ottobre, molte donne hanno sfidato il governo sfilando per le citt&agrave; dell&rsquo;Arabia Saudita alla guida di un&rsquo;auto. La polizia, secondo i resoconti ufficiali, ha fermato diverse dimostranti obbligandole a sottoscrivere l&#039;impegno di non tornare a guidare in futuro.<\/p>\n<p>Lo sceicco Mohammed al-Nujaimi, un capo religioso saudita, ha recentemente affermato che la campagna per concedere alle donne il diritto di guidare in Arabia Saudita avrebbe portato alla rovina di matrimoni, abbassato il tasso di natalit&agrave;, diffuso l&rsquo;adulterio, aumentato gli incidenti stradali e comportato &ldquo;un&rsquo;eccessiva spesa nei prodotti di bellezza&rdquo;.<\/p>\n<p>L&rsquo;Arabia Saudita era tra i paesi segnalati ad ottobre dall&rsquo;HRC per il monitoraggio sul rispetto dei diritti umani dell&rsquo;Universal Periodic Review (UPR) .<\/p>\n<p>Ma secondo Adam Coogle della HRC, l&rsquo;Arabia Saudita si sarebbe limitata a consegnare alla UPR dichiarazioni gi&agrave; pronte, senza rispondere alle critiche specifiche sul rispetto dei diritti umani.<\/p>\n<p>&ldquo;L&rsquo;Arabia Saudita ha considerato l&rsquo;UPR come un obbligo di politica estera di routine, non come un&rsquo;opportunit&agrave; per impegnarsi in riforme urgenti&rdquo;, afferma.<\/p>\n<p>In una recente dichiarazione, la HRW aveva presentato un lungo elenco di violazioni dei diritti umani ad opera dell&rsquo;Arabia Saudita.<\/p>\n<p>Dall&rsquo;inizio del 2013, l&rsquo;Arabia Saudita ha condannato sette noti attivisti per la difesa dei diritti umani e della societ&agrave; civile con accuse che vanno dal &ldquo;tentativo di rovinare la reputazione del regno&rdquo;, alla &ldquo;mancanza di lealt&agrave; al sovrano&rdquo; alla &ldquo;fondazione di organizzazioni non autorizzate&rdquo;.<\/p>\n<p>Joe Stork, vice deputato dell&rsquo;HRW per il Medioriente, ha affermato che molti paesi hanno pessimi precedenti nel campo dei diritti umani, &ldquo;ma l&rsquo;Arabia Saudita spicca per i suoi elevati livelli di repressione e il suo fallimento nel mantenere le promesse fatte al Consiglio per i Diritti Umani&rdquo;.<\/p>\n<p>Secondo una dichiarazione dell&rsquo;HRW, nonostante le promesse di riforma di lunga data, il governo dell&rsquo;Arabia Saudita non &egrave; riuscito a realizzare cambiamenti sostanziali. &ldquo;In particolare, dovrebbe riformare un sistema giudiziario penale arbitrario, abolire il sistema di controllo degli uomini sulle donne, ed eliminare gli aspetti discriminatori del sistema di aiuti per i lavoratori stranieri, che li rende vulnerabili agli abusi, come il lavoro forzato.<\/p>\n<p>L&rsquo;Arabia Saudita spicca anche per la mancata adesione alle raccomandazioni dell&rsquo;ultimo Consiglio per i Diritti Umani del febbraio 2009.<\/p>\n<p>Secondo l&rsquo;HRW, l&rsquo;Arabia Saudita dovrebbe firmare e approvare i trattati fondamentali delle Nazioni Unite sui diritti umani e altri accordi quali il Patto internazionale sui diritti civili e politici, il Patto internazionale sui diritti economici, sociali e culturali, la Convenzione internazionale sull&#039;eliminazione di ogni forma di discriminazione razziale e la Convenzione internazionale sulla protezione dei diritti dei lavoratori migranti e dei membri delle loro famiglie.<\/p>\n<p>Hillel Neure, direttore esecutivo della sede di Ginevra della U.N. Watch, un&#039;organizzazione non governativa fortemente filo-israeliana, ha affermato che &ldquo;fare dell&rsquo;Arabia Saudita un giudice mondiale dei diritti delle donne e della libert&agrave; religiosa sarebbe come nominare un piromane a capo dei vigili del fuoco&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAZIONI UNITE, nov, 2013 (IPS) &#8211; Quando l&rsquo;anno scorso l&rsquo;Arabia Saudita ha concesso il diritto di voto alle donne ma non il permesso di guidare, la vignetta di un quotidiano ha ritratto questa ingiustizia con cupa ironia.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[15,16,1,26,28,25,35,36],"tags":[],"class_list":["post-1817","post","type-post","status-publish","format-standard","hentry","category-diritti-umani","category-donne-e-sviluppo","category-headlines","category-iraq-e-asia-centrale","category-medioriente","category-obiettivi-di-sviluppo-sostenibile","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1817"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1817\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1817"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}