{"id":1792,"date":"2013-11-11T18:24:12","date_gmt":"2013-11-11T18:24:12","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2013\/11\/11\/i-danni-alleconomia-siriana-potrebbero-durare-30-anni\/"},"modified":"2013-11-11T18:24:12","modified_gmt":"2013-11-11T18:24:12","slug":"i-danni-alleconomia-siriana-potrebbero-durare-30-anni","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2013\/11\/11\/i-danni-alleconomia-siriana-potrebbero-durare-30-anni\/","title":{"rendered":"I danni all&#8217;economia siriana potrebbero durare 30 anni"},"content":{"rendered":"<p>WASHINGTON, nov, 2013 (IPS) &#8211; La guerra civile che dura ormai da quasi tre anni in Siria &egrave; stata una &ldquo;guerra silenziosa contro lo sviluppo umano ed economico&rdquo;, che ha distrutto ogni possibilit&agrave; dei cittadini siriani di mantenere un livello minimo di sostentamento, secondo quanto riferisce un rapporto pubblicato da due agenzie delle Nazioni Unite.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1935\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1935\" class=\"size-full wp-image-1935\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/homs640-629x472.jpg\" alt=\"Freedom House\/cc by 2.0 Freedom House\/cc by 2.0\" width=\"200\" \/><p id=\"caption-attachment-1935\" class=\"wp-caption-text\">Freedom House\/cc by 2.0<br \/>Freedom House\/cc by 2.0<\/p><\/div><\/div>\n<p>&ldquo;Secondo una norma non ufficiale, in genere un paese impiega sette anni a riprendersi per ogni anno di guerra civile&rdquo;, ha spiegato all&rsquo;IPS Michael Bowers, direttore della squadra di pronto intervento della Mercy Corps, un&rsquo;organizzazione umanitaria che lavora a stretto contatto con i rifugiati siriani in Libano e in Giordania.<\/p>\n<p>&ldquo;E sebbene sia una stima difficile da dimostrare, se si guarda ai conflitti civili del passato come quelli della Yugoslavia o dell&rsquo;Iraq, ci si rende conto che a un paese servono almeno una decina d&rsquo;anni per riprendersi&rdquo;.<\/p>\n<p>Il massiccio sfollamento della popolazione siriana e la forte disoccupazione hanno contribuito a un &ldquo;drammatico calo dei consumi &#8230; che sono crollati del 18,8 percento nel 2012 &#8230; e del 47 percento nel 2013&rdquo;, secondo un rapporto della Agenzia delle Nazioni Unite per il Soccorso e l&rsquo;Occupazione dei profughi palestinesi (UNRWA) e dal Programma delle Nazioni Unite per lo Sviluppo.<\/p>\n<p>I consumi privati, osservano gli esperti delle Nazioni Unite, sono indicatori diretti del benessere familiare.<\/p>\n<p>Inoltre, dall&rsquo;inizio del conflitto sono stati cancellati ben 2,3 milioni di posti di lavoro, principalmente a causa della sospensione su larga scala delle attivit&agrave; economiche nelle aree densamente popolate.<\/p>\n<p>Il rapporto arriva in un momento critico: i leader mondiali stanno cercando una data per la conferenza &ldquo;Ginevra 2&rdquo;, volta a trovare una soluzione politica ad un conflitto che ha causato la morte di almeno 100mila persone. <\/p>\n<p>Anche se la conferenza dovesse svolgersi, e pur trovando una soluzione politica, l&rsquo;impatto socioeconomico della guerra si far&agrave; comunque sentire ancora per decenni, sostengono gli esperti. Secondo Alex Pollock, direttore del dipartimento di micro finanza della UNRWA, l&rsquo;agenzia delle Nazioni Unite che fornisce assistenza ai rifugiati palestinesi nel Medioriente, l&rsquo;economia siriana impiegher&agrave; 30 anni prima di riprendere il tasso di crescita del cinque percento del PIL che aveva nel 2010.<\/p>\n<p><b>Gli effetti collaterali<\/b><\/p>\n<p>Ma l&rsquo;impatto economico non &egrave; tutto. La guerra ha avuto effetti devastanti anche su aspetti fondamentali del benessere sociale, tra cui educazione, assistenza sanitaria e sfollamento della popolazione: elementi che influiranno negativamente sul livello di sviluppo umano del paese.<\/p>\n<p>Secondo il rapporto, a partire da luglio 2013, quasi 3mila scuole sono state parzialmente o totalmente danneggiate, e di queste molte sono state trasformate in rifugi per le centinaia di sfollati interni (IDP, internally displaced persons). Il tasso di abbandono scolastico ha anche amplificato la profonda crisi educativa che affligge il paese: al primo trimestre del 2013, il 49 percento degli studenti, un bambino su due, era stato costretto a lasciare la scuola.<\/p>\n<p>E non solo gli edifici scolastici di tutto il paese hanno subito gli effetti della guerra, ma anche le strutture mediche non sono state risparmiate. Il rapporto stima che oltre il 40 percento degli ospedali sono al momento inattivi, con enormi difficolt&agrave; nel garantire l&rsquo;assistenza medica di base alla popolazione, per non parlare delle pi&ugrave; serie minacce alla salute rappresentate da epidemie particolarmente estese e devastanti.<\/p>\n<p>Nonostante la comunit&agrave; internazionale, con gli Stati Uniti e l&rsquo;Unione Europea in prima linea, abbiano fornito milioni di dollari in aiuti umanitari e fondi per promuovere lo sviluppo economico, &egrave; comunque improbabile che questo basti a risollevare la Siria dal baratro socioeconomico.<\/p>\n<p><b>Assistenza internazionale <\/b><\/p>\n<p>Agenzie internazionali come la UNWRA si sono impegnate in diversi progetti di sviluppo economico per aiutare la popolazione siriana a mantenere almeno un livello minimo di sostentamento, ad esempio con la costruzione di progetti di microfinanza, attrezzature scolastiche ed infrastrutture sanitarie. <\/p>\n<p> &ldquo;Abbiamo ricevuto molti aiuti, soprattutto dai paesi europei, ma anche da alcuni paesi arabi della regione&rdquo;, ha detto Pollock all&rsquo;IPS. &ldquo;E anche se gli aiuti dal mondo arabo sono stati poco consistenti, paesi come l&rsquo;Arabia Saudita hanno fornito assistenza alimentare agli sfollati nel loro paese&rdquo;. Lo stesso governo siriano ha sostenuto il lavoro della UNWRA, ha spiegato l&rsquo;esperto.<\/p>\n<p>&ldquo;Ci siamo impegnati soprattutto con il partito al governo, il partito Ba&rsquo;ath, che &egrave; il nostro principale contatto al ministero degli Affari Esteri siriano&rdquo; ha affermato, sottolineando che il governo centrale ha anche agevolato l&rsquo;assistenza ai numerosi rifugiati palestinesi nel paese.<\/p>\n<p>Ma nonostante l&rsquo;appoggio politico ricevuto da queste organizzazioni, il futuro dell&rsquo;economia siriana resta buio.<\/p>\n<p>L&rsquo;escalation del conflitto civile ha portato alla nascita di fazioni armate &ldquo;che distruggono l&rsquo;assetto economico e produttivo del paese&rdquo;, spiega il rapporto. Una situazione che ha spinto la popolazione siriana ad affidarsi molto all&rsquo;agricoltura, un settore instabile ed imprevedibile nel paese.<\/p>\n<p>All&rsquo;inizio di novembre, la guerra aveva prodotto quasi tre milioni di rifugiati siriani, di cui solo 2,2 milioni hanno ottenuto il riconoscimento dello status di rifugiato, riferisce l&rsquo;Alto Commissariato delle Nazioni Unite per i rifugiati. Quasi il 40 percento sono bambini sotto i 12 anni.<\/p>\n<p>La catastrofica crisi umanitaria non sembra comunque essere vicina ad una soluzione. La settimana scorsa, la responsabile Onu per gli affari umanitari Valerie Amos ha affermato in una riunione a porte chiuse del Consiglio di Sicurezza che &ldquo;la situazione umanitaria in Siria continua a peggiorare rapidamente ed inesorabilmente&rdquo;, secondo quanto riferito dalla sua portavoce Amanda Pitt, che ha aggiunto: &ldquo;il numero di cittadini siriani bisognosi di assistenza umanitaria potrebbe aver raggiunto i nove milioni&rdquo;.<\/p>\n<p>Le potenze mondiali stanno ancora tentando di coordinare delle strategie per giungere ad una soluzione politica al conflitto. Marted&igrave; scorso, i diplomatici di Sati Uniti, Russia e Nazioni Unite si sono incontrati a Ginevra per cercare di fissare la data per la conferenza &ldquo;Ginevra 2&rdquo;, ma invano.<\/p>\n<p>In un briefing sui negoziati del Dipartimento di Stato Usa, un alto rappresentante americano ha sottolineato che anche in mancanza di un accordo, &ldquo;la conferenza si terr&agrave; entro la fine dell&rsquo;anno&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, nov, 2013 (IPS) &#8211; La guerra civile che dura ormai da quasi tre anni in Siria &egrave; stata una &ldquo;guerra silenziosa contro lo sviluppo umano ed economico&rdquo;, che ha distrutto ogni possibilit&agrave; dei cittadini siriani di mantenere un livello&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2013\/11\/11\/i-danni-alleconomia-siriana-potrebbero-durare-30-anni\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":540,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[18,1,28],"tags":[],"class_list":["post-1792","post","type-post","status-publish","format-standard","hentry","category-economia","category-headlines","category-medioriente"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/540"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1792"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1792\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1792"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}