{"id":1791,"date":"2013-12-07T16:25:45","date_gmt":"2013-12-07T16:25:45","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2013\/12\/07\/gli-imprenditori-mediorientali-guardano-allistruzione\/"},"modified":"2013-12-07T16:25:45","modified_gmt":"2013-12-07T16:25:45","slug":"gli-imprenditori-mediorientali-guardano-allistruzione","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2013\/12\/07\/gli-imprenditori-mediorientali-guardano-allistruzione\/","title":{"rendered":"Gli imprenditori mediorientali guardano all&#8217;istruzione"},"content":{"rendered":"<p>IL CAIRO, dic, 2013 (IPS) &#8211; In Medioriente ci sono alcuni dei migliori e al tempo stesso dei peggiori modelli educativi al mondo, che stanno attirando l&rsquo;attenzione di imprenditori intenzionati a cambiare le cose &ndash; e a guadagnarci.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1937\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1937\" class=\"size-full wp-image-1937\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/girl1-583x472.jpg\" alt=\"Rachel Williamson\/IPS Rachel Williamson\/IPS\" width=\"200\" \/><p id=\"caption-attachment-1937\" class=\"wp-caption-text\">Rachel Williamson\/IPS<br \/>Rachel Williamson\/IPS<\/p><\/div><\/div>\n<p>Grazie ad internet e alla tecnologia mobile, hanno creato dei prodotti che supportano, o addirittura sostituiscono, il tradizionale sistema scolastico, come nel caso della TAGUINI e-university in Giordania. Nuove start-up come la Hilaal Animation Workshop a Dubai e la Ibtaker in Palestina, organizzano corsi in presenza e stanno sviluppando materiali e programmi educativi basati sulle Tecnologie dell&rsquo;Informazione e della Comunicazione (TIC). <\/p>\n<p>Ma impresari ed esperti non concordano sugli effetti concreti di questi nuovi organismi, viste le lacune del sistema scolastico del mondo arabo. Alcuni sono scettici sull&rsquo;effettiva natura di queste iniziative come societ&agrave; a scopo di lucro, o semplicemente imprese sociali. <\/p>\n<p>Hossam Allam, fondatore della Cairo Angels, una piattaforma che mette in collegamento imprenditori e investitori, pensa che debbano essere le organizzazioni non governative (Ong) ad occuparsi dell&rsquo;istruzione, non gli imprenditori. Allam ha spiegato all&rsquo;IPS che le start-up da lui esaminate non sembrano molto proficue e hanno un potenziale di crescita limitato, sia a livello nazionale che internazionale.<\/p>\n<p>Secondo Hany Sonbaty, cofondatrice di Flat6Labs, incubatore d&rsquo;impresa del Cairo, le aziende private riescono a lavorare solo nel quadro di sistemi di istruzione statali fortemente regolamentati.<\/p>\n<p>&ldquo;Ovunque nel mondo, l&rsquo;istruzione &egrave; regolata da programmi nazionali e da esami standardizzati. Perci&ograve; &#8211; ha detto &#8211; se questo non cambia&#8230; &ldquo;. L&rsquo;unica possibilit&agrave; per chi &egrave; esterno al sistema scolastico nazionale sarebbe quella di fornire degli strumenti per portare avanti un&rsquo;istruzione autonoma, e sempre che si tratti di persone particolarmente portate. <\/p>\n<p>Ma Lamia Tubbaa-Bibi e Rama Jardeneh, della Giordania, non sono d&rsquo;accordo.<\/p>\n<p>Sono proprietari di Little Thinking Mind, una delle sempre pi&ugrave; numerose imprese online che producono programmi televisivi in lingua araba per i bambini della scuola dell&rsquo;infanzia e primaria. Come spiegano, la produzione di programmi televisivi rappresenta un settore ormai maturo per l&rsquo;intervento di aziende private. <\/p>\n<p>&ldquo;Molti bambini entrano nella scuola primaria, pubblica o privata che sia, senza saper ancora leggere e scrivere bene in arabo e con un vocabolario molto limitato&rdquo;, dice all&rsquo;IPS Jardeneh, che spiega come sia stata attribuita una eccessiva importanza all&rsquo;insegnamento dell&rsquo;inglese ai bambini. <\/p>\n<p>Jardeneh aggiunge che i suoi figli, che frequentano una prestigiosa scuola privata giordana, hanno delle difficolt&agrave; perch&eacute; possiedono uno scarso vocabolario sia in inglese che in arabo.<\/p>\n<p>Il Rapporto sulla Competitivit&agrave; Mondiale del Forum Economico Mondiale 2013-2014 ha classificato il sistema di istruzione primaria egiziano come il peggiore al mondo, e su un piano generale il suo sistema scolastico figura al 145esimo posto su 148 paesi esaminati.<\/p>\n<p>Eppure Libano, Qatar ed Emirati Arabi Uniti sono rispettivamente al settimo, undicesimo e diciannovesimo posto per l&rsquo;&rsquo;istruzione primaria, mentre il Qatar &egrave; al terzo posto per la qualit&agrave; del suo sistema educativo.<\/p>\n<p>&ldquo;Ci auguriamo di poter rafforzare le loro capacit&agrave; linguistiche, ampliare il vocabolario e insegnare i primi rudimenti della lettura gi&agrave; in et&agrave; pre- scolare&rdquo;, riferisce Jardeneh. <\/p>\n<p>Il rapporto &ldquo;Unlocking Arab Youth Entrepreneurship Potential&rdquo; (sbloccare il potenziale d&rsquo;imprenditoria giovanile dei paesi arabi) pubblicato lo scorso maggio dalla organizzazione non governativa Injaz al Arab, che si occupa di formazione imprenditoriale, sottolinea le falle del sistema scolastico della regione. Il rapporto spiega che l&rsquo;insegnamento scolastico si basa sulla ripetizione e sulla memorizzazione e non sulla risoluzione di problemi e il pensiero critico. <\/p>\n<p>&ldquo;I giovani passano dalla scuola al mondo del lavoro senza quel margine competitivo necessario a garantire un impiego remunerativo in un mercato del lavoro difficile&rdquo;, si legge nel rapporto.<\/p>\n<p>Secondo l&rsquo;organizzazione non governativa di imprenditoria globale Endeavor, il 39 percento delle imprese di &ldquo;Medio Oriente e Nord Africa&rdquo; (MENA) indicano come loro principale problema una forza lavoro poco istruita. In una regione in cui pi&ugrave; della met&agrave; della popolazione &egrave; sotto i 25 anni e oltre un quarto di questi giovani non trova lavoro, quello dell&rsquo;istruzione &egrave; un problema serio. <\/p>\n<p>Ma gli imprenditori, come Lana Karrain, si stanno anche impegnando nell&rsquo;orientamento professionale e nella formazione di competenze. Karrain spera di ridurre la disoccupazione giovanile grazie al suo sito internet Fakker, con sede in Giordania, che si occupa di orientamento e sviluppo delle competenze. Tramite software basati su giochi, il sito mostra agli studenti quali sono i loro punti deboli e su cosa devono lavorare di pi&ugrave;. <\/p>\n<p>&ldquo;Agli studenti mancano competenze di comunicazione e di presentazione gi&agrave; da bambini&rdquo;, dice all&rsquo;IPS, sottolineando poi l&rsquo;importanza per la Giordania, che non dispone di risorse naturali, di investire specialmente sulle sue giovani risorse umane.<\/p>\n<p>La modifica del programma educativo, il curriculum, &egrave; una questione delicata in tutto il mondo, ma in paesi come l&rsquo;Egitto assume una valenza politica.<\/p>\n<p>Secondo Deona Boraie, vice rettore della Scuola di formazione permanente dell&rsquo;Universit&agrave; Americana del Cairo, questo sarebbe in parte dovuto al fatto che il governo teme la possibilit&agrave; di &ldquo;manomissione&rdquo; da parte di attori stranieri, e anche al sospetto che il settore privato stia cercando di speculare sull&rsquo;istruzione. <\/p>\n<p>&ldquo;Perch&eacute; l&rsquo;istruzione &egrave; un tema fortemente politico&#8230; Non credo sia una questione di tempo, ma piuttosto della capacit&agrave; di comunicare e &#8230; &Egrave; molto difficile adesso per il settore privato entrare in quello pubblico&rdquo;, spiega all&rsquo;IPS.<\/p>\n<p>Boraie afferma che le imprese private possono esercitare pi&ugrave; influenza nel modificare il sistema scolastico di paesi come la Giordania o il Libano, che hanno una popolazione rispettivamente di 6,3 milioni e 4,4 milioni di abitanti.<\/p>\n<p>In Egitto, dove il numero di abitanti raggiunge gli 80 milioni, il volume degli studenti &egrave; tale che un piccolo cambiamento non sarebbe troppo effettivo, o visibile.<\/p>\n<p>&ldquo;Ma la netta preferenza per risorse e servizi online o tecnologici contribuir&agrave; ad ampliare il &lsquo;divario digitale&rsquo; tra chi dispone della tecnologia e chi no&rdquo;, afferma Muhammad Faour, un esperto di riforme dell&rsquo;istruzione che collabora con il Carnegie Middle East Center a Beirut.<\/p>\n<p>&ldquo;Il problema dei corsi online &egrave; che si rischia di escludere una parte degli studenti perch&eacute;, soprattutto nelle aree pi&ugrave; povere, i bambini o gli studenti spesso non possono permettersi il computer o la rete internet&rdquo;, dice all&rsquo;IPS.<\/p>\n<p>Il risultato &egrave; che quando questi giovani entrano nel mondo del lavoro non riescono a competere con quelli che hanno avuto una formazione supplementare online.<\/p>\n<p>Ma lo scarso entusiasmo degli esperti non basta a scoraggiare imprenditori come Tubbaa-Bibi e Jardeneh.<\/p>\n<p>Entrambi concordano sul fatto che sia molto difficile entrare nella burocrazia scolastica e portare i loro libri di testo e DVD nelle biblioteche delle scuole, ma stanno lavorando ad un programma scolastico per bambini sopra ai sei anni per un progetto finanziato dalla U.S Agency for International Development.<\/p>\n<p>&ldquo;Abbiamo molta fiducia in questo progetto e siamo in procinto di stabilire una collaborazione con le scuole, le organizzazioni non governative e altri istituti di istruzione&rdquo;, ci scrive Jardeneh via email.<\/p>\n<p>&ldquo;Il nostro obiettivo &egrave; ottenere che il nostro materiale venga inserito nei programmi di tutti i Ministeri dell&rsquo;Istruzione della regione&rdquo;.<\/p>\n<p>Fino a quando i governi non riusciranno a garantire il grado di educazione che promettono o che i genitori si aspettano, imprese private come la Little Thinking Minds e la Fakker continueranno a rivolgersi a chi, per necessit&agrave; e perch&eacute; ne ha la possibilit&agrave;, cerca qualcosa di pi&ugrave;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IL CAIRO, dic, 2013 (IPS) &#8211; In Medioriente ci sono alcuni dei migliori e al tempo stesso dei peggiori modelli educativi al mondo, che stanno attirando l&rsquo;attenzione di imprenditori intenzionati a cambiare le cose &ndash; e a guadagnarci.<\/p>\n","protected":false},"author":542,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[14,16,19,1,28,25],"tags":[],"class_list":["post-1791","post","type-post","status-publish","format-standard","hentry","category-cultura","category-donne-e-sviluppo","category-educazione","category-headlines","category-medioriente","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/542"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1791"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1791\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1791"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}