{"id":1645,"date":"2009-09-08T14:19:59","date_gmt":"2009-09-08T14:19:59","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/09\/08\/uganda-il-commercio-del-carbonio-porta-allespulsione-delle-comunit-locali\/"},"modified":"2009-09-08T14:19:59","modified_gmt":"2009-09-08T14:19:59","slug":"uganda-il-commercio-del-carbonio-porta-allespulsione-delle-comunit-locali","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2009\/09\/08\/uganda-il-commercio-del-carbonio-porta-allespulsione-delle-comunit-locali\/","title":{"rendered":"UGANDA: Il commercio del carbonio porta all&#8217;espulsione delle comunit&agrave; locali"},"content":{"rendered":"<p>MOUNT ELGON, Uganda, 8 settembre 2009 (IPS) &#8211; Mentre l&rsquo;attenzione mondiale &egrave; puntata sull&rsquo;impatto dei cambiamenti climatici, un programma di riduzione delle emissioni di carbonio promosso dalla comunit&agrave; internazionale sembra abbia provocato l&rsquo;espulsione di una comunit&agrave; locale dalle sue terre ancestrali in Uganda.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1488\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1488\" class=\"size-full wp-image-1488\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/200909_BenetGirls_Edited.jpg\" alt=\"Wambi Michael\/IPS Wambi Michael\/IPS\" width=\"200\" \/><p id=\"caption-attachment-1488\" class=\"wp-caption-text\">Wambi Michael\/IPS<br \/>Wambi Michael\/IPS<\/p><\/div><\/div>\n<p>Secondo i piani di commercio del carbonio, le imprese responsabili del rilascio dei gas serra possono scegliere tra la riduzione delle emissioni, oppure il pagamento del diritto di continuare ad inquinare, investendo in progetti di riduzione dei gas in altri paesi. <\/p>\n<p>Le Nazioni Unite considerano il mercato del carbonio un sistema efficace per orientare gli investimenti verso la riduzione dei gas serra. Il Meccanismo di sviluppo pulito (CDM, dall&rsquo;acronimo inglese) previsto dal Protocollo di Kyoto, firmato nel 1997 e in vigore dal 2005, ammette due tipi di progetti forestali per assorbire i gas nocivi: il rimboschimento, ossia ricoprire di alberi terreni dove il bosco era presente fino ad epoca pi&ugrave; o meno recente, oppure l&rsquo;&ldquo;imboschimento&#8221;, ossia piantare nuovi alberi in aree che da oltre 50 anni sono prive di vegetazione. <\/p>\n<p>Una di queste iniziative attuate in Uganda ha suscitato grandi controversie. <\/p>\n<p>Il progetto, lanciato dall&rsquo;organizzazione olandese FACE (Forests Absorbing Carbon-Dioxide Emissions), coinvolta nel mercato volontario del carbonio, ha causato l&rsquo;espulsione della comunit&agrave; benet dai suoi territori ancestrali, l&rsquo;area scelta per piantare gli alberi. <\/p>\n<p>La Fondazione FACE collabora con l&rsquo;Autorit&agrave; per la Fauna e la flora dell&rsquo;Uganda (Uwa, dalla sigla inglese) nella semina di alberi entro i limiti del Parco Nazionale Monte Elgon, nella regione orientale del paese. <\/p>\n<p>Il piano della Fondazione prevedeva la semina di 25mila ettari di alberi per assorbire il biossido di carbonio e cos&igrave; compensare l&rsquo;inquinamento di una nuova centrale termica a carbone per la produzione di 600 megawatt di elettricit&agrave; in Olanda. <\/p>\n<p>L&rsquo;autorit&agrave; ugandese emetter&agrave; certificati di riduzione delle emissioni grazie agli alberi piantati, che vender&agrave; all&rsquo;impresa olandese GreenSeat, che si occupa di negoziare crediti di carbonio per i suoi clienti ricchi del Nord, in particolare compagnie aeree. <\/p>\n<p>GreenSeat ha calcolato per esempio all&rsquo;inizio dello scorso anno che con 28 dollari si coprono i costi della semina di 66 alberi, &ldquo;compensando&rdquo; le emissioni di biossido di carbonio di un aereo che vola dalla citt&agrave; tedesca di Francoforte, a Kampala.<\/p>\n<p>Il progetto ha una vita utile garantita di 99 anni, ma le comunit&agrave; indigene montane si oppongono strenuamente. <\/p>\n<p>Lo sgombero ha provocato gravi disagi agli abitanti della zona, divenuti occupanti illegali che hanno perso le loro terre e altri possedimenti per mano delle guardie forestali, ci ha spiegato Moses Mwanga, presidente del gruppo di pressione Benet, che difende i diritti della comunit&agrave;. <\/p>\n<p>&ldquo;Ci sono persone che vivono in condizioni patetiche. Dopo gli sgomberi sono venuti molti funzionari, ma non &egrave; servito. &Egrave; gi&agrave; passato un anno e continuano gli oltraggi delle guardie forestali armate dell&rsquo;Uwa&rdquo;, ha denunciato. &ldquo;Ci fermano quando cerchiamo il bamb&ugrave;, di cui abbiamo bisogno per vivere, o quando portiamo gli animali al pascolo, o se vogliamo prendere il miele. Ci sono stati addirittura dei morti&rdquo;, ha aggiunto. <\/p>\n<p>Mwanga ha ribadito che le espulsioni sono avvenute in terreni che sono poi stati imboschiti. <\/p>\n<p>&ldquo;Quando si parla di foresta, si ha l&rsquo;impressione che i benet siano arrivati qui da altre zone. Ma non &egrave; questa la verit&agrave;. Siamo un popolo indigeno che vive sul Monte Elgon da tempo immemorabile&rdquo;, ha segnalato. <\/p>\n<p>&ldquo;&Egrave; la nostra casa, non una foresta&rdquo;, ha sottolineato. <\/p>\n<p>&ldquo;Il governo, nel 1993, ha stabilito che l&rsquo;area sarebbe dovuta diventare un parco nazionale senza che noi ne fossimo informati. Ci disturba che dicano che viviamo in una foresta, perch&eacute; questa &egrave; la nostra casa: nei nostri confronti sono sempre state commesse ingiustizie&rdquo;, ha aggiunto.<\/p>\n<p>Nel 1993, un anno prima dell&rsquo;avvio del progetto dell&rsquo;Uwa con la Fondazione FACE, il governo dell&rsquo;Uganda ha dichiarato il Monte Elgon parco nazionale, e da allora, la popolazione che ha continuato a vivere al suo interno ha perso ogni diritto sulle proprie terre. <\/p>\n<p>Ma il responsabile dell&rsquo;Uwa per il Monte Elgon, Richard Matanda, ha smentito che l&rsquo;espulsione dei benet avesse a che vedere con il progetto della Fondazione FACE. <\/p>\n<p>&ldquo;Quella gente ha invaso la foresta che dobbiamo preservare. Sono stati espulsi per permetterci di piantare gli alberi, e contribuire a conservare la fauna e la flora. Tutto quello che facciamo nella zona, compresi gli sgomberi, deve attenersi ai principi di una gestione responsabile e alle leggi dell&rsquo;Uganda&rdquo;, ha sostenuto. <\/p>\n<p>Il Meccanismo di sviluppo pulito ha prodotto nel 2008 intorno ai 32mila milioni di dollari in certificati di riduzione delle emissioni nel mondo, il doppio dell&rsquo;anno precedente, secondo la consulente di Point Carbon, con sede a Oslo. &copy;IPS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MOUNT ELGON, Uganda, 8 settembre 2009 (IPS) &#8211; Mentre l&rsquo;attenzione mondiale &egrave; puntata sull&rsquo;impatto dei cambiamenti climatici, un programma di riduzione delle emissioni di carbonio promosso dalla comunit&agrave; internazionale sembra abbia provocato l&rsquo;espulsione di una comunit&agrave; locale dalle sue terre&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2009\/09\/08\/uganda-il-commercio-del-carbonio-porta-allespulsione-delle-comunit-locali\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":338,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,4,15,18,1,25,35,36],"tags":[],"class_list":["post-1645","post","type-post","status-publish","format-standard","hentry","category-africa","category-ambiente","category-diritti-umani","category-economia","category-headlines","category-obiettivi-di-sviluppo-sostenibile","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/338"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1645"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1645\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1645"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}