{"id":1578,"date":"2008-08-25T12:27:58","date_gmt":"2008-08-25T12:27:58","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2008\/08\/25\/cina-le-olimpiadi-del-millennio\/"},"modified":"2008-08-25T12:27:58","modified_gmt":"2008-08-25T12:27:58","slug":"cina-le-olimpiadi-del-millennio","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2008\/08\/25\/cina-le-olimpiadi-del-millennio\/","title":{"rendered":"CINA: Le Olimpiadi del millennio?"},"content":{"rendered":"<p>PECHINO, 26 agosto 2008 (IPS) &#8211; Mentre cala il sipario sulle Olimpiadi di Pechino, si apre la gara per stabilire quale sia l&#039;eredit&agrave; di una delle edizioni pi&ugrave; controverse della storia. Per il paese ospitante, sono stati i &ldquo;giochi del millennio&rdquo;, che annunciano l&rsquo;alba del &ldquo;secolo asiatico&rdquo; in cui la Cina regna sovrana.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1270\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1270\" class=\"size-full wp-image-1270\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/flicker3.jpg\" alt=\"Antoaneta Bezlova\/IPS Antoaneta Bezlova\/IPS\" width=\"200\" \/><p id=\"caption-attachment-1270\" class=\"wp-caption-text\">Antoaneta Bezlova\/IPS<br \/>Antoaneta Bezlova\/IPS<\/p><\/div><\/div>\n<p>Per i difensori dei diritti umani, per&ograve;, le etichette da dare ai giochi variano dalle &ldquo;Olimpiadi del genocidio&rdquo; alle &ldquo;Olimpiadi della repressione&rdquo;.<\/p>\n<p>La Cina ha impressionato o no? E il mondo esterno avr&agrave; visto il vero volto di questa superpotenza in ascesa? Il divario di percezioni tra la Cina e il mondo esterno si profila sempre pi&ugrave; ampio nella definizione di questi giochi tanto contestati.<\/p>\n<p>Il tono dei media cinesi &egrave; stato improntato alla massima solennit&agrave;. &ldquo;Sono le Olimpiadi del millennio&rdquo;, proclamava un editoriale del China Times. &ldquo;Il XXI secolo appartiene all&rsquo;Asia e le Olimpiadi di Pechino ne sono il simbolo pi&ugrave; appropriato&rdquo;.<\/p>\n<p>Il 21st Century Business Herald le ha giudicate &ldquo;le Olimpiadi del rinascimento cinese&rdquo;, ricordando agli stranieri che nel 1830 la Cina era un paese ricco e rappresentava un terzo della produzione economica mondiale. &ldquo;L&rsquo;ascesa attuale della Cina &egrave; solamente un ripristino del vecchio status quo&rdquo;, ha scritto.<\/p>\n<p>&ldquo;I giochi olimpici di Pechino sono una tappa fondamentale nel grande percorso di rinvigorimento della nazione cinese&rdquo;, concordava un commento dell&rsquo;agenzia stampa governativa Xinhua.<\/p>\n<p>Il ritorno alla ribalta dopo un secolo di debolezza e umiliazioni, in cui la Cina era considerata il &ldquo;malato d&rsquo;Asia&rdquo;, qui viene descritto come una vittoria consegnata al popolo dal partito comunista. &Egrave; stata profusa una quantit&agrave; di lavoro straordinaria per pianificare tempi e luoghi dei giochi olimpici in modo tale da inserirli nel grande affresco della rinascita cinese nel ruolo di grande nazione.<\/p>\n<p>&ldquo;Tutto &egrave; permeato dall&rsquo;idea che questa rara combinazione di fortuna cosmica e dignit&agrave; nazionale &egrave; stata consegnata al popolo dai suoi leader&rdquo;, spiega Liu Junning, analista dell&rsquo;Istituto di studi culturali cinesi di Pechino.<\/p>\n<p>Governando uno stato a partito unico, i leader cinesi non devono preoccuparsi del tasso di consenso pubblico. Eppure le apparenze fanno pensare che la loro legittimit&agrave; abbia guadagnato una forte spinta dalla perfetta organizzazione dei giochi.<\/p>\n<p>Si stima che la cerimonia d&rsquo;apertura dell&rsquo;8 agosto sia stata seguita da un miliardo di telespettatori. Secondo il Comitato Olimpico Internazionale, i giochi di Pechino sono stati i giochi olimpici pi&ugrave; seguiti di sempre. I turisti confluiti in citt&agrave; sono rimasti abbagliati dagli impianti olimpici favolosi, dall&rsquo;organizzazione superba e dalla calda accoglienza di Pechino.<\/p>\n<p>A completare il tutto, la Cina ha dato prova di valore sportivo, accaparrandosi il pi&ugrave; alto numero di medaglie d&rsquo;oro nella storia della sua partecipazione olimpica. Per la prima volta, inoltre, la Cina ha superato gli Stati Uniti nel conteggio delle medaglie d&rsquo;oro. Nel medagliere complessivo, vincono gli Stati Uniti.<\/p>\n<p>Vista da qui, ci sono pochi motivi di controversia a guastare la grande festa della Cina. Le autorit&agrave; cinesi hanno revocato il visto dello statunitense Joey Cheek, medaglia d&rsquo;oro alle Olimpiadi e grande critico del presunto ruolo cinese nella crisi umanitaria del Sudan. Per quanto infastidite dall&rsquo;etichetta di &ldquo;Olimpiadi del genocidio&rdquo; che i sostenitori della causa del Darfur hanno cucito loro addosso, le autorit&agrave; sono riuscite a relegare ai margini delle Olimpiadi il dibattito sul ruolo della Cina nelle crisi del Darfur.<\/p>\n<p>Ferree misure di sicurezza hanno garantito che nessuna protesta rovinasse il corso dei giochi.<\/p>\n<p>Dopo aver concesso tre zone per manifestazioni di protesta, le autorit&agrave; pechinesi hanno negato tutte le autorizzazioni alle persone che volevano protestare. Due signore settantenni sono state condannate questa settimana a un anno di &ldquo;rieducazione attraverso il lavoro&rdquo; dopo aver chiesto ripetutamente l&rsquo;autorizzazione per manifestare contro lo sfratto immotivato dalle loro case di Pechino.<\/p>\n<p>I giornalisti che riportavano i pochi e isolati tentativi da parte di stranieri di inscenare proteste sono stati maltrattati e minacciati. I trasgressori sono stati immediatamente espulsi e nessun mezzo di informazione interno ha mai accennato agli episodi.<\/p>\n<p>Ma le iniziative per ricordare le polemiche sull&rsquo;assegnazione dei giochi alla Cina hanno continuato a sorgere persino mentre gli ospiti marciavano spediti verso il gran finale.<\/p>\n<p>Il Dalai Lama ha condannato le violenze perpetrate questa settimana contro i manifestanti tibetani, mentre Pechino ospitava le Olimpiadi. Parlando in Francia, il leader spirituale tibetano in esilio ha detto che le truppe cinesi hanno aperto il fuoco sulla folla il 18 agosto nella regione del Kham, nel Tibet orientale, uccidendo e ferendo diversi manifestanti.<\/p>\n<p>In un&rsquo;intervista rilasciata a Le Monde, il Dalai Lama ha affermato che da marzo 400 tibetani sono stati uccisi soltanto nella capitale tibetana, dopo il giro di vite deciso dai cinesi. &ldquo;Uccisi da proiettili, anche se protestavano senza armi. I loro corpi non sono mai stati restituiti alle famiglie. Se si considera tutto il Tibet, il numero delle vittime &egrave; ovviamente pi&ugrave; alto&rdquo;, riportava l&rsquo;articolo.<\/p>\n<p>I disordini sono scoppiati a Lhasa a marzo dopo quattro giorni di proteste contro il dominio cinese. La dura reazione cinese ha attirato proteste durante la staffetta della torcia olimpica in molti paesi. Nel periodo che ha preceduto le Olimpiadi e durante i primi giorni, le minoranze combattenti Uighur, nella irrequieta regione dello Xinjiang, hanno compiuto diversi attentati contro il personale statale e le forze di polizia.<\/p>\n<p>A Pechino, per&ograve;, i giochi sono proseguiti dietro un imponente muro di sicurezza.<\/p>\n<p>&ldquo;Come temevamo, le Olimpiadi di Pechino sono state un periodo utile per compiere arresti, condanne, censure, controlli e persecuzioni nei confronti di oltre cento giornalisti, blogger e dissidenti&rdquo;, ha affermato il segretario generale di Reporter Senza Frontiere Robert M&eacute;nard in un comunicato stampa.<\/p>\n<p>&ldquo;Questa repressione sar&agrave; ricordata come una delle caratteristiche principali dei giochi di Pechino&rdquo;, ha dichiarato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PECHINO, 26 agosto 2008 (IPS) &#8211; Mentre cala il sipario sulle Olimpiadi di Pechino, si apre la gara per stabilire quale sia l&#039;eredit&agrave; di una delle edizioni pi&ugrave; controverse della storia. Per il paese ospitante, sono stati i &ldquo;giochi del&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2008\/08\/25\/cina-le-olimpiadi-del-millennio\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":293,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[8,15,1,25,33,35,36],"tags":[],"class_list":["post-1578","post","type-post","status-publish","format-standard","hentry","category-asia-e-oceania","category-diritti-umani","category-headlines","category-obiettivi-di-sviluppo-sostenibile","category-popolazione","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1578"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1578\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1578"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}