{"id":155,"date":"2004-09-27T02:52:26","date_gmt":"2004-09-27T02:52:26","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2004\/09\/27\/cina-shanghai-rompe-il-tab-del-secondo-figlio\/"},"modified":"2004-09-27T02:52:26","modified_gmt":"2004-09-27T02:52:26","slug":"cina-shanghai-rompe-il-tab-del-secondo-figlio","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2004\/09\/27\/cina-shanghai-rompe-il-tab-del-secondo-figlio\/","title":{"rendered":"CINA: Shanghai rompe il tab&ugrave; del secondo figlio"},"content":{"rendered":"<p>PECHINO, 27 settembre 2004 (IPS) &#8211; La citt&agrave; di Shanghai nella Cina orientale &egrave; stata il modello della rigida politica di un solo figlio per coppia, applicata dal governo sin dalla fine degli anni &rsquo;70. Adesso per&ograve; sono autorizzate le eccezioni, ed &egrave; stata lanciata una campagna contro il modello della coppia &ldquo;Dink&rdquo; (dalla sigla in inglese di &ldquo;double income, no kids&rdquo;, due stipendi, niente figli), un tempo presentata come esempio di prosperit&agrave; e successo.<\/p>\n<p><!--more--><\/p>\n<p>Ci&ograve; &egrave; dovuto al fatto che la florida citt&agrave;, uno dei primi fulcri della liberalizzazione economica avviata pi&ugrave; di venti anni fa, ha visto diminuire la sua popolazione ogni anno, dal 1993.<\/p>\n<p>Alla fine dello scorso anno, quasi il 19 per cento dei suoi 16,4 milioni di abitanti aveva almeno 60 anni, e si prevede che il rapporto salir&agrave; al 20 per cento nel 2005, al 33 per cento nel 2020, se non si contraster&agrave; la tendenza con misure come quelle che si cominciano ad applicare adesso.<\/p>\n<p>Fino ad oggi, lo Stato ricompensava le coppie sposate che decidevano di non riprodursi, ma adesso incoraggia 11 tipi di famiglia ad avere un secondo figlio.<\/p>\n<p>&ldquo;Se le coppie non vogliono riprodursi, la societ&agrave; non pu&ograve; svilupparsi in modo sano&rdquo;, ha dichiarato il medico Xia Yi, della Commissione pianificazione familiare e popolazione di Shanghai. <\/p>\n<p>Se le attuali tendenze demografiche non cambiano, &ldquo;un numero relativamente esiguo di persone dovr&agrave; mantenere un gran numero di pensionati&rdquo;, ha osservato Xie Lingli, direttore della Commissione popolazione della citt&agrave;.<\/p>\n<p>Negli anni &rsquo;80 nascevano 180.000 neonati all&rsquo;anno a Shanghai, mentre attualmente ne nascono meno di 60.000. L&rsquo;anno scorso ci sono state 57.000 nascite e 100.700 decessi, il che ha determinato un calo demografico del 3,24 per mille.<\/p>\n<p>Secondo alcuni funzionari della Commissione popolazione, negli anni &rsquo;50 la media era di cinque bambini per famiglia, un numero pi&ugrave; elevato di quello tradizionalmente alto delle zone rurali. Ma dagli anni &rsquo;70, Shanghai &egrave; stata all&rsquo;avanguardia nella politica di un figlio per famiglia, lanciata con la motivazione che il paese poteva crollare per un eccesso di abitanti in rapporto alle risorse, e applicata mediante forti multe a chi aveva un secondo figlio, salvo con l&rsquo;autorizzazione delle autorit&agrave;.<\/p>\n<p>Una delle conseguenze di questa politica &egrave; lo squilibrio di genere, con 1,2 uomini ogni donna (mentre nel mondo c&rsquo;&egrave; una lieve maggioranza di donne), questo perch&eacute; le coppie spinte ad avere un solo figlio preferiscono un maschio, ed &egrave; frequente l&rsquo;aborto se si viene a sapere che &egrave; in arrivo una femmina.<\/p>\n<p>I demografi, come il professor Peng Xizhe dell&rsquo;Universit&agrave; Fudan di Shanghai, sostengono che questa politica &egrave; stata applicata con particolare severit&agrave; nella citt&agrave;, che &egrave; la pi&ugrave; ricca del paese e costituisce, insieme all&rsquo;area rurale circostante, una divisione amministrativa corrispondente a una provincia.<\/p>\n<p>Nel 1979, il 90 per cento delle coppie urbane di Shanghai si erano gi&agrave; impegnate ad avere un solo figlio, e negli anni &rsquo;80 la citt&agrave; e la sua zona rurale, dove vivevano cinque milioni di persone, avevano un tasso medio di 1,6 figli per ogni donna, simile a quello dei paesi europei con una popolazione anziana come l&rsquo;Italia. <\/p>\n<p>Le coppie Dink ricevevano un risarcimento economico secondo il precedente modello, e questo si diffuse soprattutto tra le coppie sposate formate da donne con un livello educativo pi&ugrave; alto.<\/p>\n<p>Secondo un sondaggio realizzato dalla Federazione municipale delle donne di Shanghai, la percentuale di nuclei familiari tradizionali caratterizzati dalla convivenza di tre generazioni &egrave; diminuita notevolmente, mentre aumentava la proporzione di famiglie Dink, che sono diventate il 12,4 per cento sull&rsquo;insieme dei nuclei nel 2003.<\/p>\n<p>La stessa tendenza si registra in tutte le grandi citt&agrave; della Cina, dove ci sono almeno 600.000 coppie Dink, soprattutto nelle principali metropoli come Pechino, Shanghai, Tianjin, vicina alla capitale, e Guangzhou, nel sud. A Pechino, quasi il 10 per cento delle coppie giovani dice di non volere figli.<\/p>\n<p>&ldquo;Non si tratta solo dei costi per mantenere ed educare un figlio, ma anche della libert&agrave; di scelta&rdquo;, ha osservato Xu Jie, un professionista di poco pi&ugrave; di 30 anni residente a Pechino.<\/p>\n<p>Il sociologo Li Yinhe pensa che il crescente numero di coppie Dink dimostra una maggiore libert&agrave; di scegliere tra diversi stili di vita.<\/p>\n<p>&ldquo;La gente che decide di non avere figli d&agrave; pi&ugrave; importanza alla felicit&agrave; nel presente. Apprezza il rapporto con la coppia pi&ugrave; della paternit&agrave; o della maternit&agrave;&rdquo;, ha detto Li all&rsquo;agenzia stampa statale Xinhua.<\/p>\n<p>Ma la scarsit&agrave; di bambini nelle grandi metropoli come Shanghai fa venire il mal di testa ai funzionari per la popolazione, che cercano di equilibrare la politica di controllo delle nascite con il tentativo di evitare l&rsquo;invecchiamento della societ&agrave;.<\/p>\n<p>Tra gli 11 tipi di coppia che oggi possono essere autorizzate ad avere un secondo figlio ci sono quelle composte da due figli unici, integrate da persone che hanno sciolto legami matrimoniali precedenti ed entrambe hanno gi&agrave; un figlio.<\/p>\n<p>Se una persona residente nell&rsquo;area urbana ha una disabilit&agrave; che non le permette di lavorare, &egrave; autorizzata ad avere un secondo figlio senza pagare una multa, come gi&agrave; avveniva per l&rsquo;area rurale.<\/p>\n<p>Secondo le statistiche della Commissione popolazione e pianificazione familiare, sin dall&rsquo;avvio della nuova politica ad aprile 2004 le richieste di autorizzazione per un secondo figlio sono notevolmente aumentate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PECHINO, 27 settembre 2004 (IPS) &#8211; La citt&agrave; di Shanghai nella Cina orientale &egrave; stata il modello della rigida politica di un solo figlio per coppia, applicata dal governo sin dalla fine degli anni &rsquo;70. Adesso per&ograve; sono autorizzate le&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2004\/09\/27\/cina-shanghai-rompe-il-tab-del-secondo-figlio\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":66,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[38,8,1,32,33],"tags":[],"class_list":["post-155","post","type-post","status-publish","format-standard","hentry","category-sviluppo","category-asia-e-oceania","category-headlines","category-politica","category-popolazione"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=155"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/155\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=155"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}