{"id":1546,"date":"2008-04-28T14:05:41","date_gmt":"2008-04-28T14:05:41","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2008\/04\/28\/afghanistan-lemergenza-mondiale-infiamma-le-rivolte-per-il-cibo\/"},"modified":"2008-04-28T14:05:41","modified_gmt":"2008-04-28T14:05:41","slug":"afghanistan-lemergenza-mondiale-infiamma-le-rivolte-per-il-cibo","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2008\/04\/28\/afghanistan-lemergenza-mondiale-infiamma-le-rivolte-per-il-cibo\/","title":{"rendered":"AFGHANISTAN: L&#8217;emergenza mondiale infiamma le rivolte per il cibo"},"content":{"rendered":"<p>KABUL, 28 aprile 2008 (IPS) &#8211; Nei brulicanti e densi mercati di farina a Kabul &egrave; difficile non avvertire la rabbia della gente.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1171\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1171\" class=\"size-full wp-image-1171\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/kabulcamp3.jpg\" alt=\"Ann Ninan Ann Ninan\" width=\"200\" \/><p id=\"caption-attachment-1171\" class=\"wp-caption-text\">Ann Ninan<br \/>Ann Ninan<\/p><\/div><\/div>\n<p>&ldquo;Qualcosa deve cambiare&#8230; la mia vita &egrave; orribile&rdquo;, dice Zahir, che per vivere raccoglie rifiuti. Zahir &egrave; qui per comprare della farina per la sua famiglia di 11 persone, un semplice atto che negli ultimi mesi &egrave; diventato sempre pi&ugrave; difficile per gli afgani. &ldquo;Non possiamo mangiare altro perch&eacute; i prezzi sono diventati troppo alti&rdquo;.<\/p>\n<p>&ldquo;Mio figlio piccolo piange ogni giorno per un po&rsquo; di pane&rdquo;, prosegue. &ldquo;Guarda queste persone intorno a me&rdquo;, dice, indicando un gruppo di lavoratori dall&#039;aspetto trasandato. &ldquo;Ormai non possono pi&ugrave; permettersi di mangiare tutti i giorni&rdquo;.<\/p>\n<p>Gli afgani in tutto il paese si sentono frustrati davanti ai forti aumenti nei prezzi del cibo, che rispecchiano la tendenza diffusa in tutto il mondo. Gli osservatori temono che la persistente insicurezza alimentare spinger&agrave; milioni di persone alla fame aumentando l&#039;instabilit&agrave;. <\/p>\n<p>Il prezzo della farina &egrave; salito di quasi il 100 per cento nei primi mesi di quest&rsquo;anno. Lo scorso anno, i prezzi del riso sono aumentati di circa il 38 per cento, ma anche i prezzi di altri alimenti di base hanno visto aumenti analoghi, secondo le notizie locali.<\/p>\n<p>Gli aumenti dei prezzi hanno scatenato rivolte e saccheggi in diverse citt&agrave; dell&rsquo;Afghanistan. Nella citt&agrave; orientale di Jalalabad, questa settimana i dimostranti hanno bloccato una delle autostrade principali di collegamento con Kabul chiedendo al governo di imporre un controllo dei prezzi dei generi alimentari. Nei mercati della citt&agrave; settentrionale di Kunduz e alla periferia di Kabul, i commercianti denunciano che la popolazione locale comincia a rubare sacchi di farina. <\/p>\n<p>Per molti, sono i politici i responsabili di questi forti aumenti. &ldquo;I parlamentari ricevono centinaia di migliaia di dollari dai donatori, ma non si preoccupano minimamente di risolvere questo problema&rdquo;, protesta Zahir. Mentre grida, una folla indignata si raccoglie intorno a lui. Tutti accusano il governo e lamentano che i prezzi del cibo stanno strangolando le loro vite. <\/p>\n<p>&ldquo;Guarda le mie gambe&rdquo;, dice uno dei presenti, indicando le gambe mutilate. &ldquo;Non posso permettermi le medicine perch&eacute; devo spendere tutto per comprare il pane&rdquo;.<\/p>\n<p>Anche se i funzionari di governo dovrebbero darsi da fare per risolvere il problema, il problema dell&rsquo;insicurezza alimentare &egrave; dovuto a molti fattori, che vanno al di l&agrave; delle politiche del governo afgano, sostengono gli esperti. Ci sono cause sia locali che globali dietro l&rsquo;insicurezza alimentare, dice Haroun Mir, ricercatore politico dell&rsquo;Afghanistan Centre for Research and Policy Studies.<\/p>\n<p>L&rsquo;Afghanistan non ha una grande variet&agrave; di fonti alimentari, spiega Mir. Nonostante gli sforzi di rianimare l&rsquo;agricoltura locale, la maggior parte del cibo viene importato dai paesi vicini come Pakistan e Iran. E questo rende il mercato alimentare molto sensibile a fluttuazioni nelle forniture. Per esempio, &ldquo;l&rsquo;Iran compra le eccedenze alimentari regionali per assicurarsi le proprie scorte alimentari, causando un&rsquo;impennata dei prezzi regionali&rdquo;, segnala Mir.<\/p>\n<p>Quando il Pakistan ha deciso recentemente di limitare le esportazioni per proteggere il proprio mercato, i prezzi sono ulteriormente saliti, alimentando un diffuso risentimento tra gli afgani nei confronti del loro vicino. Durante le proteste a Jalalabad la scorsa settimana, i dimostranti hanno cantato &ldquo;abbasso il Pakistan&rdquo;, oltre ad altri slogan contro il governo. <\/p>\n<p>Anche la guerra e gli stupefacenti riducono le forniture alimentari nazionali, contribuendo all&rsquo;aumento dei prezzi, dicono gli esperti. La terra pi&ugrave; fertile del paese viene spesso destinata alla coltivazione dell&rsquo;oppio &#8211; una coltura molto pi&ugrave; redditizia del grano &#8211; e i campi minati impediscono che altre zone altrimenti fertili vengano usate per coltivare generi alimentari. E poi ci sono i tanti anni di guerra, che hanno provocato un&rsquo;emigrazione forzata dalle aree fertili. <\/p>\n<p>Ma gli analisti attribuiscono a fattori globali le cause principali della situazione attuale. Secondo un nuovo rapporto dell&rsquo;International Assessment of Agricultural Science and Technology for Development (IAASTD), che riunisce pi&ugrave; di 400 scienziati, l&rsquo;insicurezza alimentare non &egrave; causata da una riduzione globale delle forniture, ma piuttosto dalla distribuzione iniqua. <\/p>\n<p>&ldquo;L&rsquo;agricoltura moderna ha portato aumenti significativi nella produzione alimentare. Ma i benefici sono stati distribuiti in modo ineguale, raggiungendo prezzi sempre pi&ugrave; insostenibili, che sono i piccoli agricoltori e i lavoratori a pagare&#8230; oltre all&rsquo;ambiente&rdquo;, si legge nel rapporto.<\/p>\n<p>Il rapporto critica poi i paesi pi&ugrave; ricchi, &ldquo;che si oppongono con forza a qualsiasi cambiamento nei regimi commerciali o nei sistemi dei sussidi. Senza le riforme, qui molti paesi pi&ugrave; poveri dovranno affrontare tempi duri&rdquo;. L&rsquo;Afghanistan &egrave; tra questi, sempre in fondo a quasi tutti gli indici di sviluppo, e con pi&ugrave; della met&agrave; della popolazione al di sotto della soglia di povert&agrave;. <\/p>\n<p>L&rsquo;Organizzazione delle Nazioni Unite per l&rsquo;alimentazione e l&rsquo;agricoltura (FAO) stima che l&rsquo;Afghanistan avrebbe bisogno di importare oltre 500mila tonnellate di grano, per soddisfare i bisogni dell&rsquo;attuale crisi. Ma il direttore del Programma alimentare mondiale dell&#039;Onu per l&rsquo;Afghanistan Rick Corsino si dice pessimista sulla possibilit&agrave; che la situazione si risolva presto. &ldquo;Pochissime persone, credo, pensano che i fattori che hanno causato questo aumento record nel prezzo del grano nella prima parte di quest&rsquo;anno scompariranno&rdquo;, ha detto di recente ai giornalisti. &ldquo;Nessuno crede, per esempio, che potremo tornare ai prezzi di 12 o 18 mesi fa&rdquo;. <\/p>\n<p>Il governo afgano ha annunciato la settimana scorsa che stanzier&agrave; 50 milioni di dollari per comprare cibo dai paesi vicini. Ma per molti afgani, questa notizia non basta per rispondere alla richiesta principale: il controllo dei prezzi, qualcosa che i pi&ugrave; anziani ricordano dai tempi dell&rsquo;occupazione sovietica. <\/p>\n<p>&ldquo;Il governo tassa i negozianti, ma non ci aiuta mentre moriamo di fame&rdquo;, dice Zahir. La folla si &egrave; riunita qui al mercato della farina &#8211; una zona conosciuta come Baghe Qazi, o Giardino della giustizia &#8211; facendo cenni di assenso per incoraggiare l&rsquo;uomo. &ldquo;Se il governo non risolve questo problema, moriremo&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KABUL, 28 aprile 2008 (IPS) &#8211; Nei brulicanti e densi mercati di farina a Kabul &egrave; difficile non avvertire la rabbia della gente.<\/p>\n","protected":false},"author":289,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[11,15,1,26,27,29,33],"tags":[],"class_list":["post-1546","post","type-post","status-publish","format-standard","hentry","category-columnas","category-diritti-umani","category-headlines","category-iraq-e-asia-centrale","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-migrazioni","category-popolazione"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/289"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1546"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1546\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1546"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}