{"id":1417,"date":"2014-11-23T13:43:25","date_gmt":"2014-11-23T13:43:25","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2014\/11\/23\/la-voce-delle-donne-siriane-per-un-nuovo-futuro\/"},"modified":"2014-11-23T13:43:25","modified_gmt":"2014-11-23T13:43:25","slug":"la-voce-delle-donne-siriane-per-un-nuovo-futuro","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2014\/11\/23\/la-voce-delle-donne-siriane-per-un-nuovo-futuro\/","title":{"rendered":"La voce delle donne siriane per un nuovo futuro"},"content":{"rendered":"<p>Gaziantep, TURCHIA, nov, 2014 (IPS) &#8211; Per la maggior parte delle donne siriane, la<br \/>\nguerra &egrave; stata una catastrofe. Per alcune di loro,<br \/>\n&egrave; stata anche in parte liberatoria.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1949\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1949\" class=\"size-full wp-image-1949\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/Two-young-girls-look-on-as-a-veiled-woman-passes-by-in-Aleppo-August-2014.-photo-by-Shelly-Kittleson--629x414.jpg\" alt=\"Due bambine osservano una donna a passeggio coperta dal velo integrale ad Aleppo, Siria. Shelly Kittleson\/IPS\" width=\"200\" \/><p id=\"caption-attachment-1949\" class=\"wp-caption-text\">Due bambine osservano una donna a passeggio coperta dal velo integrale ad Aleppo, Siria.<br \/>Shelly Kittleson\/IPS<\/p><\/div><\/div>\n<p>Per Yasmine Merei, caporedattrice della rivista  femminile siriana Saiedet Souria (Donne  Siriane), il ribaltamento dei ruoli familiari  tradizionali e l&rsquo;affrancamento da una cultura  della paura sono stati effetti senz&rsquo;altro  positivi.<\/p>\n<p>Molte donne siriane si sono ritrovate a dover  mantenere da sole la propria famiglia, in  mancanza dei mariti, finiti in carcere, feriti  o uccisi, ha spiegato all&rsquo;IPS: doversela cavare  da sole pu&ograve; essere un&rsquo;esperienza terribile ma  pu&ograve; anche liberare le donne dai vincoli imposti  loro dalla tradizione.<\/p>\n<p>&ldquo;Se non &egrave; pi&ugrave; il marito a pagare per ogni cosa  e ad avere quel determinato ruolo nella  societ&agrave;, non ha pi&ugrave; il diritto di dirti cosa  fare&rdquo;, ha aggiunto Mohammad Mallak, fondatore e  redattore capo della rivista, fondata lo scorso  anno. Mallak gestisce anche la rivista partner  Dawda (Rumore), dallo stesso ufficio di  Gaziantep, nella Turchia meridionale.<\/p>\n<p>Solo alcune delle foto contenute nella rivista  mostrano donne a capo coperto. Merei ha deciso  di togliere il velo all&rsquo;inizio di quest&rsquo;anno,  dopo averlo indossato &ldquo;per circa vent&rsquo;anni&rdquo;,  essendo cresciuta in una famiglia sunnita  povera e conservatrice.<\/p>\n<p>Merei ha cominciato a partecipare alle proteste  del 2011 contro l&rsquo;ingiustizia della legge  siriana, in particolare nei confronti delle  donne, racconta. Per una vecchia legge, ad  esempio, le donne non possono trasmettere la  cittadinanza ai figli; o ancora, il delitto  d&rsquo;onore &egrave; molto diffuso e resta tuttora  impunito. <\/p>\n<p>Dopo essersi specializzata in linguistica,  Merei, come molte donne siriane, ha dovuto  farsi carico della propria famiglia, mandando  denaro alla madre e ai fratelli, entrambi in  carcere e rilasciati solo dopo il pagamento di  cospicue mazzette.<\/p>\n<p>Il padre anziano &egrave; morto poco dopo essere  finito anche lui in prigione, e dopo che la  famiglia era stata sfollata dalla loro casa. <\/p>\n<p>Raccontare storie di donne non vuol dire per&ograve;  soltanto riportare le storie di vittime di  orrori e di stenti. Merei vuole soprattutto  offrire le informazioni e gli strumenti  necessari perch&eacute; le donne acquisiscano una  visione pi&ugrave; ampia del mondo e possano far  sentire la loro voce, in una rivoluzione che le  ha per lo pi&ugrave; ignorate.<\/p>\n<p>Sfogliando le pagine della rivista e visitando  la sua <a href=\"https:\/\/www.facebook.com\/saiedetsouria? ref=profile\" target=\"_blank\"> pagina  Facebook<\/a> leggiamo il resoconto di prima  mano di una donna torturata nelle prigioni del  regime siriano, accanto a una recensione del  libro &ldquo;L&rsquo;eunuco femmina&rdquo; di Germaine Greer, e  all&rsquo;intervista con una agente di polizia nelle  aree occupate dall&rsquo;opposizione.<\/p>\n<p>Troviamo articoli che analizzano le  ripercussioni negative di una dipendenza  economica forzata, sia sulle donne sia sulle  economie nazionali; altri, in cui si esaminano  le complicazioni sulla salute riscontrate nei  campi profughi, come la tubercolosi; un  editoriale firmato da un&rsquo;avvocatessa che vive  ancora nei territori occupati dal regime dopo  13 anni passati in carcere per motivi politici;  e ancora, alcuni articoli tradotti dai media  internazionali, che danno un ampio respiro alle  circa 50 pagine da cui &egrave; formato ogni numero  del periodico.<\/p>\n<p>Saiedet Souria ha anche una sezione dedicata  alla Convenzione sull&rsquo;eliminazione di ogni  forma di discriminazione contro le donne  (Cedaw) &ndash; la &ldquo;carta dei diritti internazionale  delle donne&rdquo; adottata dall&rsquo;Assemblea Generale  dell&rsquo;Onu nel 1979 &ndash; che sar&agrave; pubblicata  integralmente con il prossimo numero, dice  Merei.<\/p>\n<p>La tiratura &egrave; di circa 4500-5000 copie per ogni  edizione (di cui circa 3500 distribuite in  Siria attraverso uno dei suoi quattro uffici) e  la pagina Facebook, dove gli articoli vengono  regolarmente inseriti, ha pi&ugrave; di 40.000  followers.<\/p>\n<p>Per un paese dove Facebook e Youtube sono stati  banditi dal 2007 a febbraio 2011, e dove  internet ed elettricit&agrave; scarseggiano, sono  cifre importanti. Dal 2006, peraltro, la Siria  &egrave; sulla  lista dei <a href=\"https:\/\/en.rsf.org\/internet-enemie- syria,39779.html\" target=\"_blank\"> nemici di  Internet <\/a> di Reporter senza Frontiere. <\/p>\n<p>Oltre agli uffici che abbiamo a Daraa, Damasco,  Suweida e Qamishli, presto apriremo un nuovo  ufficio ad Aleppo, dice Merei. &ldquo;Le dieci donne  che lavorano per noi hanno un salario fisso di  200 dollari &ndash; spiega &#8211; e sono responsabili  della distribuzione, per lo pi&ugrave; nei mercati e  nei consigli locali, ma anche di organizzare  incontri con le donne e altre iniziative  analoghe&rdquo;.<\/p>\n<p>Reporter senza Frontiere ha promosso due  workshop per aiutare il periodico, in aprile e  in settembre di quest&rsquo;anno, proponendo di  donare attrezzature, ma &ldquo;noi avevamo gi&agrave; un  equipaggiamento di base, con stampanti e  computer&rdquo;, grazie a un investimento iniziale di  Mallak, ha spiegato. <\/p>\n<p>&ldquo;Ci&ograve; di cui avevamo bisogno in realt&agrave; era carta  e inchiostro, per far arrivare la rivista al  maggior numero di donne possibile&rdquo;. Perci&ograve;, RSF  ha fatto un&rsquo;eccezione e ci ha dato quello che  ci serviva&rdquo;.<\/p>\n<p>L&rsquo;obiettivo, afferma Merei, &egrave; &ldquo;aiutare le donne  siriane a riconquistare la fiducia in se  stesse&rdquo;.<\/p>\n<p>Una fiducia minata dalla guerra e da una  &ldquo;religione&rdquo; utilizzata per controllare le donne  nelle aree islamiche, dove &ldquo;sembra che il paese  sia tornato indietro all&rsquo;et&agrave; della pietra&rdquo;.<\/p>\n<p>&ldquo;Io sono musulmana sunnita ma l&rsquo;Islam in quei  territori non somiglia a niente che io  conosca&rdquo;.<\/p>\n<p>&ldquo;Uno dei problemi principali &egrave; che  l&rsquo;intellighenzia siriana &egrave; in prigione,  all&rsquo;estero oppure &egrave; morta&rdquo;, ha spiegato all&rsquo;IPS  un cittadino siriano che ha vissuto quasi tutta  la vita all&rsquo;estero ma &egrave; tornato di recente per  aiutare ad aprire dei corsi universitari ad  Aleppo, zona occupata dall&rsquo;opposizione. &ldquo;Non &egrave;  rimasto pi&ugrave; nessuno per creare qualcosa,  nessuno per avanzare delle idee&rdquo;.<\/p>\n<p>&Egrave; anche a questo che la rivista, con le sue  attivit&agrave; correlate, sta cercando di rivolgersi,  dice Merei. &ldquo;Stiamo tentando di dare ai siriani  le informazioni e le conoscenze di cui avranno  bisogno in futuro&rdquo;. <\/p>\n<p>(Traduzione e editing a cura di Francesca  Buffo)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gaziantep, TURCHIA, nov, 2014 (IPS) &#8211; Per la maggior parte delle donne siriane, la guerra &egrave; stata una catastrofe. Per alcune di loro, &egrave; stata anche in parte liberatoria.<\/p>\n","protected":false},"author":549,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[12,14,16,1,26],"tags":[],"class_list":["post-1417","post","type-post","status-publish","format-standard","hentry","category-comunicazione-nuove-tecnologie-e-media","category-cultura","category-donne-e-sviluppo","category-headlines","category-iraq-e-asia-centrale"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/549"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1417"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1417\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1417"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}