{"id":1416,"date":"2014-10-20T19:46:14","date_gmt":"2014-10-20T19:46:14","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2014\/10\/20\/op-ed-riportare-il-potere-della-gente-al-centro-dellazione-cittadina\/"},"modified":"2014-10-20T19:46:14","modified_gmt":"2014-10-20T19:46:14","slug":"op-ed-riportare-il-potere-della-gente-al-centro-dellazione-cittadina","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2014\/10\/20\/op-ed-riportare-il-potere-della-gente-al-centro-dellazione-cittadina\/","title":{"rendered":"OP-ED: Riportare il potere della gente al centro dell&#8217;azione cittadina"},"content":{"rendered":"<p>JOHANNESBURG, ott, 2014 (IPS) &#8211; Alcune settimane fa sono stato co-firmatario<br \/>\ndella <a href=\"http:\/\/blogs.civicus.org\/civicus\/2014\/08\/06\/\nan-open-letter-to-our-fellow-activists-across-the-\nglobe-building-from-below-and-\nbeyond-borders\/#more-1750\" target=\"_blank\">lettera<br \/>\naperta<\/a> pi&ugrave; importante della mia carriera:<br \/>\nun&rsquo;aperta provocazione agli amici e colleghi<br \/>\nattivisti, ai membri della nostra<br \/>\norganizzazione e a tutti coloro che, come me,<br \/>\nsi guadagnano da vivere nel settore della<br \/>\nsociet&agrave; civile.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1948\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1948\" class=\"size-full wp-image-1948\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/Danny-Sriskandarajah-200x300.jpg\" alt=\" Foto: Danny Sriskandarajah\" width=\"200\" \/><p id=\"caption-attachment-1948\" class=\"wp-caption-text\"><br \/>Foto: Danny Sriskandarajah<\/p><\/div><\/div>\n<p><A href=\"http:\/\/civicus.org\/index.php\/en\/\" target=\"_blank\">CIVICUS <\/A>, l&rsquo;organizzazione  che conduco, &egrave; nata per rafforzare la societ&agrave;  civile e l&rsquo;azione dei cittadini di tutto il  mondo. Ciononostante, ho firmato una lettera  aperta critica nei confronti della societ&agrave;  civile, in cui si dice che il nostro lavoro sta  finendo per rafforzare i sistemi sociale,  economico e politico che un tempo volevamo  cambiare; che siamo diventati troppo  istituzionalizzati, troppo professionalizzati,  co-optati in reti e sistemi dentro i quali  siamo stati manovrati e sconfitti. <\/p>\n<p>Il problema della &ldquo;cooptazione&rdquo; della societ&agrave;  civile &egrave; importantissimo, perch&eacute; stiamo  perdendo la guerra &ndash; la guerra contro la  povert&agrave;, contro il cambiamento climatico e  l&rsquo;ingiustizia sociale. Molte organizzazioni e  persone coraggiose e motivate combattono una  lotta giusta. Ma troppi di noi &ndash; me compreso &ndash;  si sono allontanati dalle persone e dai  movimenti che guidano il vero cambiamento  politico e sociale.<\/p>\n<p>La corporativizzazione della societ&agrave; civile ha  imbrigliato le nostre ambizioni; troppo spesso  ci ha reso agenti piuttosto che agitatori del  sistema.<\/p>\n<p>L&rsquo;intenzione di questa lettera non era quella  di biasimare ma di sollevare un dibattito, di  lanciare una sfida a tutti noi per  riconfigurare, ripensare e ridare energia alla  societ&agrave; civile. Un primo, piccolo passo &egrave; stato  quello di aprire un dibattito su <A href=\"https:\/\/storify.com\/CIVICUSalliance\/peopl espower\" target=\"_blank\"> Twitter<\/A>, chiedendo  di rispondere alle idee avanzate nella lettera.  E sembra che molti attivisti nel mondo  condividano le nostre stesse preoccupazioni. <\/p>\n<p>Nel corso della <A href=\"http:\/\/civicus.org\/ICSW\/\" target=\"_blank\">Settimana internazionale della  societ&agrave; civile <\/A>, che si terr&agrave; a novembre a  Johannesburg, si dedicher&agrave; gran parte dello  spazio al dibattito sui temi sollevati nella  lettera. Prevediamo che in questa occasione pi&ugrave;  di 500 attivisti provenienti da ogni parte del  mondo si riuniranno per discutere, esaminare,  imparare e condividere esperienze per far  fronte agli ostacoli che noi tutti ci troviamo  davanti.   Il tema della settimana sar&agrave; &#8220;Azione cittadina,  potere del popolo&#8221;: sono previsti pi&ugrave; di 40  eventi organizzati dai membri e dai partner  internazionali di Civicus incentrati su diversi  temi &#8211; dalle buone pratiche nella concessione  di sovvenzioni (good grant-making) a nuovi modi  per favorire la &#8220;responsabilit&agrave; promossa dalla  societ&agrave;&#8221; (people-powered accountability).<\/p>\n<p>Gli incontri si concluderanno con la <A href=\"http:\/\/civicus.org\/worldassembly\/\" target=\"_blank\">CIVICUS World Assembly<\/A> e la  cerimonia per il <A href=\"http:\/\/www.civicus.org\/awards\/#\/home\" target=\"_blank\"> Premio dell&rsquo;Innovazione di Gra&ccedil;a  Machel e Nelson Mandela <\/A>.<\/p>\n<p>Continuo ad essere fermamente convinto del  potere della societ&agrave; civile per cambiare il  mondo. Dobbiamo solo formulare nuovi principi  organizzativi globali, un nuovo paradigma e un  modello alternativo a quello attuale. <\/p>\n<p>Ma perch&eacute; ci&ograve; sia possibile, dobbiamo riportare  al cuore del nostro lavoro la voce e l&rsquo;azione  degli individui. L&rsquo;alleanza globale  protagonista della Settimana Internazionale  della Societ&agrave; Civile sar&agrave; legata da questo  obiettivo comune: essere fondata sulle voci e  le azioni delle persone.<\/p>\n<p>Sono molto entusiasta all&rsquo;idea di vedere cos&igrave;  tante menti brillanti concentrate in uno spazio  creativo, per riunire forze che alimentano il  cambiamento sociale positivo, condividere  strumenti utili a potenziare le azioni della  cittadinanza e celebrare modelli stimolanti di  potere del popolo. <\/p>\n<p>La nostra prima responsabilit&agrave; non deve essere  nei confronti dei donatori, ma verso tutti  coloro che si battono per la giustizia sociale.  Dobbiamo combattere il corporativismo dentro le  nostre fila, riconnetterci con il potere delle  reti informali e della base, attingere  all&rsquo;esperienza dei diversi attivisti e  riequilibrare le nostre risorse. Questo non  vuol dire abbandonare le organizzazioni che  abbiamo creato ma lasciarle evolvere perch&eacute;  siano davvero responsabili, tenute a rispondere  nei confronti dei veri destinatari della loro  azione. <\/p>\n<p>Io spero che grazie al dialogo che abbiamo  avviato potremo tornare a confrontarci con  un&rsquo;idea di societ&agrave; civile come concetto  profondamente umano, come elemento facilitatore  di relazioni sociali. Sar&agrave; cruciale in tal  senso riflettere sul ruolo delle nostre stesse  organizzazioni. E solamente le soluzioni al  tempo stesso pragmatiche e radicali ci  permetteranno di fronteggiare le sfide che ci  attendono. (IPS Columnist Service). <\/p>\n<p>(Traduzione e editing a cura di Francesca  Buffo)<\/p>\n<p>Vai alla <a href=\"http:\/\/www.ipsnews.net\/2014\/10\/opinion-put-people-power-back-at-centre-of-citizen-action\/\" target=\"_blank\">versione originale<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOHANNESBURG, ott, 2014 (IPS) &#8211; Alcune settimane fa sono stato co-firmatario della lettera aperta pi&ugrave; importante della mia carriera: un&rsquo;aperta provocazione agli amici e colleghi attivisti, ai membri della nostra organizzazione e a tutti coloro che, come me, si guadagnano&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2014\/10\/20\/op-ed-riportare-il-potere-della-gente-al-centro-dellazione-cittadina\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":548,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[1,35,36],"tags":[],"class_list":["post-1416","post","type-post","status-publish","format-standard","hentry","category-headlines","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/548"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1416"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1416\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1416"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}