{"id":1396,"date":"2012-07-19T18:32:19","date_gmt":"2012-07-19T18:32:19","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2012\/07\/19\/sri-lanka-lotta-alla-tratta-di-migranti\/"},"modified":"2012-07-19T18:32:19","modified_gmt":"2012-07-19T18:32:19","slug":"sri-lanka-lotta-alla-tratta-di-migranti","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2012\/07\/19\/sri-lanka-lotta-alla-tratta-di-migranti\/","title":{"rendered":"Sri Lanka, lotta alla tratta di migranti"},"content":{"rendered":"<p>COLOMBO, luglio 2012 (IPS) &#8211; Chi possiede un passaporto pakistano o afgano dovr&agrave; prepararsi a una procedura eccezionalmente lunga per attraversare lo Sri Lanka.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1889\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1889\" class=\"size-full wp-image-1889\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/asylum12-629x429.jpg\" alt=\"Migranti disperati provenienti dallo Ski Lanka e da altri paesi usano pescherecci come questo per partire nella speranza di un futuro Amantha Perera\/IPS.\" width=\"200\" \/><p id=\"caption-attachment-1889\" class=\"wp-caption-text\">Migranti disperati provenienti dallo Ski Lanka e da altri paesi usano pescherecci come questo per partire nella speranza di un futuro<br \/>Amantha Perera\/IPS.<\/p><\/div><\/div>\n<p>Le autorit&agrave; dell&rsquo;immigrazione dell&rsquo;isola hanno riferito a IPS di aver costituito procedure speciali per controllare i passeggeri provenienti da questi due Paesi. Questo dopo la prova sempre pi&ugrave; evidente che quest&rsquo;isola dell&rsquo;Asia meridionale al largo della costa sud-orientale dell&rsquo;India viene utilizzata come punto di partenza da parte di clandestini in cerca di asilo che decidono di prendere il largo, la maggior parte diretti in Australia. &ldquo;Abbiamo speciali misure di sicurezza per interrogare afgani e pakistani&rdquo;, ha affermato Prabath Aluthge, a capo della sezione contro l&rsquo;immigrazione clandestina al Dipartimento Immigrazione.<\/p>\n<p>Venticinque persone con passaporto afgano sono state deportate di recente, mentre negli ultimi cinque mesi sono state trasferite 250 persone senza visto d&rsquo;entrata. I casi di stranieri che usano falsi passaporti dello Sri Lanka per entrare e ricevere asilo sono pochi, ma continuano a verificarsi. <\/p>\n<p>La tendenza attuale con centinaia di persone che usano l&rsquo;isola come punto di sosta costituisce un nuovo sviluppo, dichiarano degli agenti delle forze dell&rsquo;ordine a IPS. Il 21 giugno, una nave  che trasportava circa 200 afgani e iraniani in cerca di asilo si &egrave; capovolta al largo dell&rsquo;Isola del Natale, a circa 2.600 km dal territorio dell&rsquo;Australia continentale. Circa 90 passeggeri a bordo sono morti. Si sospetta che l&rsquo;imbarcazione fosse partita dallo Sri Lanka, nonostante i tragitti diretti dall&rsquo;isola dell&rsquo;Asia meridionale all&rsquo;Australia, che dista pi&ugrave; di 8.000 km, siano rari.<\/p>\n<p>In passato molti immigrati in cerca di asilo avevano usato Tailandia e Indonesia come punti di transito. Questa tendenza ora sembra essere cambiata. &ldquo;Lo Sri Lanka &egrave; stato identificato come punto di transito (usato da trafficanti di esseri umani)&rdquo;, ha affermato Aluthge. Gli incidenti che coinvolgono stranieri che utilizzano lo Sri Lanka per imbarcarsi sono in aumento e arrivano in un momento in cui le autorit&agrave; di sicurezza nazionale hanno riportato un picco nel numero di locali che intraprendono la stessa pericolosa rotta.<\/p>\n<p>Il 12 maggio, 113 persone sono state arrestate nella capitale, Colombo, durante il trasporto per l&rsquo;imbarco a un porto di pesca. Un mese dopo la Marina Militare ha arrestato 53 persone su un&rsquo;imbarcazione a circa 60 miglia nautiche al largo della costa. Altri gruppi pi&ugrave; piccoli sono stati intercettati. Altre cinque persone sono state arrestate vicino alla citt&agrave; meridionale di Kataragama.<\/p>\n<p>&ldquo;In questi giorni stiamo registrando molti casi di tratta&rdquo;, ha dichiarato il portavoce della polizia Ajith Rohana. &ldquo;Il novanta per cento di migranti in cerca di asilo provengono dalle comunit&agrave; tamil e musulmane&rdquo;. Quindi, afferma, sono loro i principali organizzatori delle imbarcazioni. I funzionari dell&rsquo;immigrazione australiana si sono rifiutati di divulgare i dettagli sul numero delle barche partite dallo Sri Lanka quest&rsquo;anno, per motivi di sicurezza. Tuttavia le informazioni disponibili dicono che fini aolla fine di giugno sono state individuate o abbiano raggiunto l&rsquo;Australia 72 imbarcazioni. Con un totale di 5.242 immigrati.<\/p>\n<p>Le statistiche sull&rsquo;immigrazione pubblicate dal Dipartimento Immigrazione e Cittadinanza australiano rivelano che entro la fine di maggio erano presenti 682 persone originarie dello Sri Lanka all&rsquo;interno delle strutture detentive, circa il 14 per cento su un totale di 4.906 persone. La percentuale pi&ugrave; alta era costituita da afgani, circa il 41 per cento del totale. Quello proveniente dallo Sri Lanka era il secondo gruppo pi&ugrave; consistente.<\/p>\n<p>I dati australiani rivelano anche un&rsquo;insolita crescita nel numero degli immigrati arrivati via mare a partire da gennaio 2010. Le persone nei centri detentivi per immigrati, che erano meno di 500 a gennaio del 2009, sono salite a oltre 6.500 entro gennaio del 2011. La lunga guerra civile in Sri Lanka &egrave; finita nel maggio del 2009.<\/p>\n<p>Secondo Rohana, il modus operandi pi&ugrave; comune per coloro che vogliono imbarcarsi &egrave; di aspettare in pochi, circa 5 o 6 persone per gruppo, vicino alla costa. Verranno poi trasferiti in gruppi pi&ugrave; numerosi a un porto di pesca e molto probabilmente portati fino ad un peschereccio ancorato al largo. Rohana afferma che i locali che sono stati arrestati per aver organizzato queste imbarcazioni sembrano essere mediatori tra coloro che cercano un posto sulle barche e coloro che controllano la tratta di immigrati.<\/p>\n<p>&ldquo;Si &egrave; scoperto che i sospetti principali operano da Paesi come Inghilterra, Europa e Australia&rdquo;. L&rsquo;agente ha citato il caso di oltre 200 emigrati dello Sri Lanka che si sono trovati arenati nello stato africano del Togo nell&rsquo;ottobre 2011 dopo essere stati abbandonati dai trafficanti che gli avevano assicurato di arrivare in Canada. &ldquo;I quattro sospetti principali in quel caso si trovano in Francia&rdquo;, ha detto Rohana. Le vittime sono state trasferite fino allo stato africano in aereo attraverso Mumbai e Addis Abeba in Etiopia usando dei veri visti d&rsquo;ingresso per visitatori.<\/p>\n<p>I dettagli su come i migranti si imbarcano rimangono vaghi. La maggior parte di coloro che aspettano un&rsquo;opportunit&agrave; o che hanno visto fallire i loro tentativi rimangono in silenzio. E&rsquo; questo il caso di Akilan (nome cambiato su richiesta dell&rsquo;interessato), un giovane di venti anni della costa orientale, che adesso si trova in prigione dopo un tentativo di giungere in Australia non andato a buon fine. &ldquo;Non sapevamo niente fino al momento del suo arresto&rdquo;, racconta sua madre a IPS. Dice che suo figlio progettava di fare il test d&rsquo;ingresso per l&rsquo;universit&agrave; per la terza volta, ma preparava di nascosto il suo viaggio clandestino.<\/p>\n<p>Si &egrave; scoperto che le imbarcazioni partivano dalla costa nord occidentale di Puttalam e arrivavano ai porti orientali come Valechchennei. Le barche usate sono per la maggior parte pescherecci fatti di legno. I migranti devono pagare l&rsquo;equivalente di circa 9 mila dollari nella valuta locale in due tranche. Secondo le informazioni della polizia, viene chiesto loro di pagare 2.500 dollari prima di salire a bordo. I membri della famiglia e gli amici pagano il resto quando &ndash; e se &ndash; vengono portati a destinazione.<\/p>\n<p>La madre di Akilan non sa se il figlio resister&agrave; alla tentazione di provare a partire di nuovo. &ldquo;Voleva andarsene perch&eacute; siamo poveri e disperati, e ancora adesso siamo poveri e disperati&rdquo;.&copy; IPS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COLOMBO, luglio 2012 (IPS) &#8211; Chi possiede un passaporto pakistano o afgano dovr&agrave; prepararsi a una procedura eccezionalmente lunga per attraversare lo Sri Lanka.<\/p>\n","protected":false},"author":126,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[8,15,1,29,25,33],"tags":[],"class_list":["post-1396","post","type-post","status-publish","format-standard","hentry","category-asia-e-oceania","category-diritti-umani","category-headlines","category-migrazioni","category-obiettivi-di-sviluppo-sostenibile","category-popolazione"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1396"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1396\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1396"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}