{"id":1361,"date":"2011-10-19T18:49:18","date_gmt":"2011-10-19T18:49:18","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2011\/10\/19\/editoriale-microcredito-espansione-e-nuovi-problemi\/"},"modified":"2011-10-19T18:49:18","modified_gmt":"2011-10-19T18:49:18","slug":"editoriale-microcredito-espansione-e-nuovi-problemi","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2011\/10\/19\/editoriale-microcredito-espansione-e-nuovi-problemi\/","title":{"rendered":"EDITORIALE: Microcredito, espansione e nuovi problemi"},"content":{"rendered":"<p>WASHINGTON, 19 ottobre 2011 (IPS) &#8211; Il primo Vertice sul Microcredito si &egrave; tenuto nel 1997. Nove anni dopo, quando i delegati si sono riuniti in occasione del Vertice Mondiale sul Microcredito a Halifax, in Canada, nel 2006, &egrave; stato annunciato che Muhammad Yunus avrebbe condiviso il premio Nobel per la pace con la Grameen Bank, l&rsquo;istituto da lui fondato trent&rsquo;anni prima.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1814\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1814\" class=\"size-full wp-image-1814\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/Sam_Daley-Harris_smiling_head_shot2.jpg\" alt=\"Sam Daley-Harris, co-fondatore e direttore della Campagna per il microcredito (Microcredit Summit Campaign) IPS\/MSC\" width=\"200\" \/><p id=\"caption-attachment-1814\" class=\"wp-caption-text\">Sam Daley-Harris, co-fondatore e direttore della Campagna per il microcredito (Microcredit Summit Campaign)<br \/>IPS\/MSC<\/p><\/div><\/div>\n<p>L&rsquo;anno precedente, le Nazioni Unite celebravano l&rsquo;Anno del Microcredito e, solo un anno dopo, la Microcredit Summit Campaign ha superato l&rsquo;obiettivo che si era prefissata nel 1997: aiutare i 100 milioni di famiglie pi&ugrave; povere al mondo attraverso crediti per avviare delle attivit&agrave; in proprio e altri servizi finanziari e commerciali. Erano anni di grande entusiasmo per la microfinanza.<\/p>\n<p>Adesso, cinque anni dopo, 2.000 delegati si incontreranno a Valladolid, in Spagna (14-17 Novembre), in occasione del Vertice Mondiale sul Microcredito 2011. Questa volta per&ograve; il summit si terr&agrave; in un clima pi&ugrave; controverso rispetto ai precedenti. All&rsquo;inizio di quest&rsquo;anno, Muhammad Yunus ha dovuto rassegnare le dimissioni dalla Grameen Bank in seguito a una serie di violenti attacchi da parte del governo del Bangladesh, che molti temono possa cancellare le conquiste raggiunte nel paese nel campo dell&rsquo;emancipazione femminile. <\/p>\n<p>Per molti anni il microcredito &egrave; stato considerato un nuovo ed emozionante rimedio contro la povert&agrave;. Un caso che ne dimostra il potenziale in termini di capacit&agrave; di trasformazione &egrave; quello osservato durante una visita in Bangladesh 15 anni fa. Un&rsquo;amica statunitense stava intervistando la beneficiaria di un prestito in un villaggio rurale, quando l&rsquo;interprete disse alla mia amica che l&rsquo;intervistata ci teneva a farle sapere che il figlio avrebbe iniziato il college l&rsquo;anno seguente. Anche il figlio della mia amica avrebbe iniziato il college l&rsquo;anno seguente, cos&igrave; le fece le sue congratulazioni. Quando l&rsquo;interprete torn&ograve; a interrompere il colloquio per ripetere la stessa notizia, la mia amica si rese conto che dietro quella storia doveva esserci qualcos&rsquo;altro.<\/p>\n<p>&ldquo;Lei o suo marito sapete leggere o scrivere?&rdquo; chiese la mia amica.<\/p>\n<p>&ldquo;No&rdquo;, rispose lei.<\/p>\n<p>&ldquo;Suo padre o sua madre sanno leggere o scrivere?&rdquo; prosegu&igrave; la mia amica.<\/p>\n<p>&ldquo;No&rdquo;, rispose la donna.<\/p>\n<p>Quando l&rsquo;intervistatrice chiese se la madre o il padre del marito sapessero leggere o scrivere e si sent&igrave; rispondere un altro &ldquo;no&rdquo;, cominci&ograve; ad avere un quadro completo della situazione e si profuse nei complimenti: stava assistendo alla rottura di un ciclo di analfabetismo intergenerazionale e anche probabilmente di povert&agrave; intergenerazionale. <\/p>\n<p>Sono storie di trasformazioni che continuano anche oggi, cui per&ograve; si aggiungono anche casi di indebitamenti e paure che una parte del settore della microfinanza lascia lungo il cammino. Un breve sguardo all&rsquo;agenda del Vertice del microcredito del prossimo mese ci mostra un settore che comincia a fare i conti con qualche fallimento. In risposta alle accuse di usura e tassi di interesse poco trasparenti, Chuck Waterfield ha creato il sito Microfinance Transparency e ha preparato una relazione da presentare al summit. Beth Rhyane dirige il Centro per l&rsquo;inclusione finanziaria presso l&rsquo;organizzazione ACCION e ha redatto un rapporto incentrato sulla tutela dei clienti, un argomento di cui vent&rsquo;anni fa nessuno avrebbe mai pensato di doversi occupare. Laura Foose, a capo della Social Performance Task Force, ha redatto un rapporto per il Vertice sulla necessit&agrave; che un&rsquo;organizzazione dedichi agli aspetti sociali la stessa importanza che d&agrave; ai profitti economici. <\/p>\n<p>Ci&ograve; che &egrave; fondamentale considerare di queste iniziative &egrave; che non sono esperienze minori, ma stanno diventando sempre pi&ugrave; cruciali. Ma al Vertice non si parler&agrave; solo dei problemi della microfinanza. I delegati potranno conoscere gli enti che assegnano decine di migliaia di prestiti e borse di studio ai figli di famiglie analfabete. In altre sessioni verranno illustrati i programmi attivi nelle aree rurali e negli slum urbani pi&ugrave; poveri. Ai delegati verr&agrave; spiegato come le organizzazioni collegano la microfinanza all&rsquo;energia verde, all&rsquo;agricoltura e all&rsquo;acqua pulita. Ci si occuper&agrave; anche delle innovazioni nel campo dei risparmi e delle micro-assicurazioni, le operazioni bancarie via cellulare e la microfinanza islamica.<\/p>\n<p>Molti potrebbero sostenere che, se si &egrave; arrivati a questo punto, la colpa &egrave; della spinta incontrollata a massimizzare i profitti di alcuni istituti. Anche questo tema verr&agrave; affrontato in una della sessioni del summit. <\/p>\n<p>La voce discordante rispetto alla massimizzazione dei profitti ci riporta al premio Nobel per la pace Muhammad Yunus, e alle riflessioni sul primo Vertice del Microcredito nel 1997 tratte dal suo libro &ldquo;Il banchiere dei poveri&rdquo;:<\/p>\n<p>&ldquo;Insegnando economia ho imparato molto sul denaro e adesso, in qualit&agrave; di direttore di banca, presto denaro, e il successo della nostra impresa dipende da quante cambiali sgualcite i nostri membri, un tempo vittime della fame, hanno oggi in mano. Ma il movimento del microcredito, costruito intorno, per e con il denaro, paradossalmente, per la sua natura e radici pi&ugrave; profonde, non riguarda affatto il denaro. Riguarda la volont&agrave; di aiutare ogni singolo individuo a realizzare pienamente il proprio potenziale. Non riguarda il capitale monetario, ma il capitale umano. Il denaro &egrave; solo uno strumento che libera i sogni dell&rsquo;uomo e aiuta anche le persone pi&ugrave; povere e meno fortunate del pianeta a conquistare dignit&agrave;, rispetto, e dare un senso alla loro vita&rdquo;.<\/p>\n<p>Forse queste parole sono rivolte a tutti noi, e non solo al settore delle microfinanza. &copy; IPS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, 19 ottobre 2011 (IPS) &#8211; Il primo Vertice sul Microcredito si &egrave; tenuto nel 1997. Nove anni dopo, quando i delegati si sono riuniti in occasione del Vertice Mondiale sul Microcredito a Halifax, in Canada, nel 2006, &egrave; stato&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2011\/10\/19\/editoriale-microcredito-espansione-e-nuovi-problemi\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":501,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[38,13,18,1,25],"tags":[],"class_list":["post-1361","post","type-post","status-publish","format-standard","hentry","category-sviluppo","category-cooperazione","category-economia","category-headlines","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/501"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1361"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1361\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1361"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}