{"id":1334,"date":"2011-06-14T18:39:50","date_gmt":"2011-06-14T18:39:50","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2011\/06\/14\/india-microfinanza-una-luce-di-speranza-per-i-poveri\/"},"modified":"2011-06-14T18:39:50","modified_gmt":"2011-06-14T18:39:50","slug":"india-microfinanza-una-luce-di-speranza-per-i-poveri","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2011\/06\/14\/india-microfinanza-una-luce-di-speranza-per-i-poveri\/","title":{"rendered":"INDIA: Microfinanza, una luce di speranza per i poveri"},"content":{"rendered":"<p>BHUBANESWAR, India, 14 giugno 2011 (IPS) &#8211; Sambari Naik non &egrave; mai andata a scuola, ma &egrave; decisa a dare un&rsquo;istruzione adeguata alla figlia Rebati. La bambina, di 13 anni, fino a poco tempo fa non andava molto bene negli studi, quando poteva leggere solo alla luce tremolante di una lampada al cherosene.<\/p>\n<p><!--more--><\/p>\n<p>Ma le cose sono cambiate quando Sambari, 45 anni, ha potuto acquistare un impianto a energia solare al costo di appena 900 rupie (20 dollari), grazie a un programma di microcredito dell&rsquo;Agenzia di benessere sociale integrato di Bharat (Biswa), un&rsquo;organizzazione senza fini di lucro che lavora in 18 stati in India ed ha sede ad est di Orissa, tra le zone con i pi&ugrave; bassi indicatori socioeconomici. <\/p>\n<p>Rebati adesso va bene a scuola, mentre Sambari e il marito Khedu lavorano al forno di mattoni vicino al paese di Ankhadihi, nella provincia di Sambalpur. <\/p>\n<p>Insieme guadagnano 140 rupie (3 dollari) per immagazzinare 800 mattoni al giorno. Ma spesso guadagnano anche di pi&ugrave;, lavorando alcune ore extra la sera. La famiglia Naik adesso pu&ograve; risparmiare 200 rupie (cinque dollari) al mese, non dovendo pi&ugrave; comprare tra i sette e gli otto litri di cherosene che le servivano per accendere la cucina a legna e le lampade. Con questi risparmi pu&ograve; restituire il prestito ricevuto da Biswa. <\/p>\n<p>&ldquo;Queste nuove lanterne illuminano tutti gli angoli di casa nostra, un monolocale, anche durante le piogge e i temporali, e non si spengono come quelle a cherosene. Possiamo andare a fare i nostri bisogni senza paura dei serpenti&rdquo;, ha detto Khedu. <\/p>\n<p>La famiglia Naik appartiene al gruppo di auto aiuto di Sambalpur, che ha ricevuto sostegno da Biswa, associata all&rsquo;Istituto di energia e risorse con sede a New Delhi, che fornisce fonti di energia rinnovabile per i poveri attraverso programmi di microfinanza. <\/p>\n<p>La Biswa tenta di coprire pi&ugrave; villaggi nei vicini stati di Chhattisgarh e Jharkhand. L&rsquo;organizzazione ha cominciato nel 1994, estendendo il microcredito ai poveri, per la maggior parte donne, perch&eacute; potessero aumentare le loro entrate attraverso piccole attivit&agrave;. La loro idea era far convergere finanza sociale e iniziative di sviluppo. <\/p>\n<p>Migliaia di donne come Sambari, legate a gruppi di auto aiuto, hanno beneficiato di Biswa. La finanza sociale permette ai loro figli di ricevere un&rsquo;istruzione superiore e di combattere la malaria, attraverso prestiti per la salute e accesso all&rsquo;acqua potabile e a strutture mediche. <\/p>\n<p>La capitale di Orissa, Bhubaneswar, &egrave; una delle citt&agrave; a pi&ugrave; rapida crescita nell&rsquo;est del India. Il governo locale, che sta riconvertendo la parte antica con 2mila anni di storia in un centro turistico internazionale, tenta di sradicare la pratica comune della popolazione di fare i loro bisogni all&rsquo;aria aperta. <\/p>\n<p>Nella baraccopoli di Gyana Nagar, con 87 tuguri, nel cuore dell&rsquo;area benestante di Bhubaneswar, 24 donne di quattro gruppi di auto aiuto hanno ricevuto nel 2008 prestiti da Biswa, tra gli 8mila e le 17mila rupie (180-380 dollari) per ristrutturare vecchi bagni o costruirne di nuovi. <\/p>\n<p>&ldquo;Anche se il prestito viene chiesto dalle donne, tutta la famiglia comprende la sua importanza e si assume la responsabilit&agrave; di restituirlo&rdquo;, dice Mini Behera, una dei beneficiari. Molte donne come Sambari Naik e Mini Behera sostengono che grazie a questi prestiti adesso hanno pi&ugrave; voce all&rsquo;interno del nucleo familiare. <\/p>\n<p>Il microcredito rafforza la capacit&agrave; delle popolazioni povere di raggiungere gli Obiettivi di sviluppo del millennio dell&rsquo;Organizzazione delle Nazioni Unite per il Millennio, ha dichiarato il fondatore e presidente di Biswa, Khirod Chandra Malick. <\/p>\n<p>L&rsquo;organizzazione lavora insieme a un milione di donne delle zone rurali dell&rsquo;India, e il numero di chi beneficia dei loro programmi di microfinanza &egrave; in aumento. <\/p>\n<p>&ldquo;La microfinanza &egrave; uno strumento chiave contro la povert&agrave;. Quando i pi&ugrave; poveri, soprattutto le donne, ricevono dei prestiti, diventano attori economici e vedono rafforzato il loro ruolo&rdquo;, ha sottolineato Malick. <\/p>\n<p>&ldquo;Possono migliorare non solo la loro vita ma anche quella delle loro famiglie, delle comunit&agrave; cui appartengono e del loro paese &#8211; ha aggiunto. La microfinanza pu&ograve; contribuire ad una crescita economica dell&rsquo;India pi&ugrave; inclusiva&rdquo;. <\/p>\n<p>La Biswa lavora con diverse organizzazioni, enti corporativi e tra le principali agenzie di governo, concedendo crediti attraverso i gruppi di auto aiuto, che vengono rimborsati mensilmente con tassi di interesse sempre pi&ugrave; bassi.<\/p>\n<p>&ldquo;Questo modello &egrave; fondamentale per la sostenibilit&agrave; dell&rsquo;attivit&agrave; di microfinanza di Biswa&rdquo;, ha affermato Jharana Mishra, responsabile per la ricerca e documentazione dell&rsquo;organizzazione. @ IPS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BHUBANESWAR, India, 14 giugno 2011 (IPS) &#8211; Sambari Naik non &egrave; mai andata a scuola, ma &egrave; decisa a dare un&rsquo;istruzione adeguata alla figlia Rebati. La bambina, di 13 anni, fino a poco tempo fa non andava molto bene negli&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2011\/06\/14\/india-microfinanza-una-luce-di-speranza-per-i-poveri\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":485,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[8,16,18,1,25],"tags":[],"class_list":["post-1334","post","type-post","status-publish","format-standard","hentry","category-asia-e-oceania","category-donne-e-sviluppo","category-economia","category-headlines","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/485"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1334"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1334\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1334"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}