{"id":1152,"date":"2009-09-30T11:02:42","date_gmt":"2009-09-30T11:02:42","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/09\/30\/editoriale-perch-abolire-le-armi-nucleari\/"},"modified":"2009-09-30T11:02:42","modified_gmt":"2009-09-30T11:02:42","slug":"editoriale-perch-abolire-le-armi-nucleari","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2009\/09\/30\/editoriale-perch-abolire-le-armi-nucleari\/","title":{"rendered":"EDITORIALE: Perch&egrave; abolire le armi nucleari"},"content":{"rendered":"<p>TOKYO, Settembre 2009 (IPS) &#8211; Perch&eacute; dovremmo abolire le armi nucleari?<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1494\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1494\" class=\"size-full wp-image-1494\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/Umebayashi.JPG\" alt=\"Hiromichi Umebayashi, fondatore e consulente speciale di Peace Depot, Inc. Japan. Peace Depot\/IPS\" width=\"200\"\/><p id=\"caption-attachment-1494\" class=\"wp-caption-text\">Hiromichi Umebayashi, fondatore e consulente speciale di Peace Depot, Inc. Japan.<br \/>Peace Depot\/IPS<\/p><\/div><\/div>\n<p>La domanda, apparentemente ingenua, ha suscitato un acceso dibattito. Nel Giappone reduce dall&rsquo;olocausto nucleare di Hiroshima e Nagasaki, il desiderio di abolire il nucleare &egrave; molto forte, radicato nell&rsquo;esperienza diretta dei danni devastanti causati dalle armi nucleari. <\/p>\n<p>Questa devastazione, per&ograve;, non sembra sufficiente per avere &#8220;un mondo denuclearizzato&#8221;. L&rsquo;impegno a abolire le armi nucleari &egrave; imprescindibile e inscindibile dalla sfida che ci impone di creare una societ&agrave; globale pi&ugrave; equa, giusta e umana.<\/p>\n<p>Quando &egrave; tornata alla ribalta l&rsquo;idea di &#8220;un mondo libero da armi nucleari&#8221;, come obiettivo concreto stimolato dalle nuove iniziative anti-nucleare condotte negli USA, mi sono ritrovato a chiedermi di nuovo &ldquo;perch&eacute;?&rdquo;. <\/p>\n<p>La necessit&agrave; di dare una risposta globale a problemi come la povert&agrave; e i cambiamenti climatici &egrave; un dato di fatto, quasi tacitamente imposta dai valori che guidano la societ&agrave; civile. <\/p>\n<p>L&rsquo;abolizione del nucleare, invece, tende a rimanere un tema confinato ai tipi di armi connessi alla sicurezza nazionale e non viene considerata una questione morale globale. Per avere successo, il movimento per l&rsquo;abolizione delle armi nucleari deve raggiungere una sfera pi&ugrave; ampia del pensiero comune.<\/p>\n<p>Dieci anni fa ho tradotto in giapponese &#8220;Fast Track to Zero Nuclear Weapons&rdquo;, un libro di Robert D. Green, ex capitano della marina militare britannica. <\/p>\n<p>Il libro contiene un&rsquo;affermazione che ancora oggi mi avvince. Illustrando l&rsquo;analogia tra la campagna per l&rsquo;abolizione della schiavit&ugrave; condotta duecento anni fa e quella per il disarmo nucleare, Green scrive che la prima ha avuto successo perch&eacute; &ldquo;era incentrata sull&rsquo;illegalit&agrave; della schiavit&ugrave;, non solo sulla sua crudelt&agrave;&#8221;.<\/p>\n<p>Green ci insegna dunque che, storicamente, i dolori pi&ugrave; forti e le battaglie pi&ugrave; dure dell&rsquo;umanit&agrave; possono stimolare la volont&agrave; politica per mettere in atto leggi importanti, sia nazionali che internazionali. Anche laddove per varare nuove leggi &egrave; necessario scendere a compromessi, la legislazione che ne deriva contiene norme giuridiche, un linguaggio e un assetto concettuale utili per avviare un cambiamento epocale.<\/p>\n<p>Le premesse dei trattati e delle convenzioni internazionali che bandiscono o limitano l&rsquo;uso di armi, invocano norme giuridiche e principi fondamentali. <\/p>\n<p>Tuttavia, la differenza tra gli strumenti che limitano le armi nucleari e quelli su altri tipi di armamenti &egrave; considerevole. La Convenzione sulle Armi Biologiche, quella sulle Armi Chimiche, quella di Ottawa che bandisce le mine antipersona e la pi&ugrave; recente Convenzione sulle munizioni a grappolo, contengono tutte una spiegazione chiara dei fondamenti umani e morali delle proibizioni che, chiariscono, sono un prerequisito per un mondo civilizzato e soggetto alle leggi dettate dalla coscienza umana. <\/p>\n<p>Stranamente, ci&ograve; non avviene nei trattati sulle armi nucleari, ad esempio quello di Non-proliferazione Nucleare (TNP) e quello di Bando Complessivo dei Test Nucleari (CTBT).<\/p>\n<p>Credo che tutti i lettori si aspetterebbero di trovare la prescrizione dei principi fondamentali per la messa al bando delle armi biologiche e chimiche anche tra le norme dei trattati sulle armi nucleari, ma non &egrave; cos&igrave;. <\/p>\n<p>Nessun trattato, neppure il TNP n&eacute; il CTBT, invoca simili criteri umani e morali. Possiamo davvero creare un mondo libero dalle armi nucleari con basi giuridiche cos&igrave; deboli?<\/p>\n<p>La spiegazione del fenomeno ci &egrave; nota: servono degli eufemismi per convincere i detentori di armi nucleari a dotarsi di questi strumenti normativi, vincolanti anche per loro stessi. <\/p>\n<p>Finch&eacute; accettiamo questa prassi, per&ograve;, temo non riusciremo a dotarci di norme che riconoscono la reale natura delle armi nucleari e delle loro implicazioni per le generazioni future. E che non riusciremo neppure a figurarci un mondo denuclearizzato come un mondo migliore per l&rsquo;intera umanit&agrave;.<\/p>\n<p>Il nostro primo compito, dunque, &eacute; valutare come dotarci di uno strumento giuridico internazionale efficace, anche se i paesi detentori di armi nucleari non lo accettano in quanto espressione di norme morali coerenti in grado di governare l&rsquo;orrore smisurato delle armi nucleari. <\/p>\n<p>Come ha scritto Rebecca Johnson in un recente articolo su Disarmament Diplomacy, (primavera 2009), uno strumento internazionale che metta fuorilegge l&rsquo;uso e la minaccia di uso di armi nucleari, potrebbe essere un primo passo. <\/p>\n<p>Il cosiddetto &ldquo;processo di Ottawa&rdquo;, fondato sulla collaborazione della societ&agrave; civile e di nazioni unite da una visione affine potrebbe rivelarsi il giusto approccio.<\/p>\n<p>Infine, dobbiamo denunciare la grande distorsione globale, radicata nell&rsquo;abitudine a fare uso della forza e della diplomazia armata, la cui massima espressione &egrave; stata proprio la minaccia di usare armi nucleari. Le norme della Carta delle Nazioni Unite tese a favorire &#8220;rapporti amichevoli tra le nazioni, basati sul rispetto del principio di uguaglianza dei diritti e sull&rsquo;autodeterminazione dei popoli&#8221; e sul &#8220;rispetto dei diritti umani e delle libert&agrave; fondamentali di tutti, senza discriminazione alcuna&#8221; non saranno mai ottemperate, in un mondo dominato dall&rsquo;orrore delle armi nucleari. <\/p>\n<p>Il cammino verso un mondo denuclearizzato dovrebbe anche permetterci di immaginare la nuova societ&agrave; pi&ugrave; umana, che ne incarna le norme. @COPYRIGHT IPS<\/p>\n<p>(*) Hiromichi Umebayashi &egrave; fondatore e consulente speciale di Peace Depot, Inc. Japan e titolare di un dottorato di ricerca in fisica applicata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOKYO, Settembre 2009 (IPS) &#8211; Perch&eacute; dovremmo abolire le armi nucleari?<\/p>\n","protected":false},"author":391,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[8,1,25,32,35,36],"tags":[],"class_list":["post-1152","post","type-post","status-publish","format-standard","hentry","category-asia-e-oceania","category-headlines","category-obiettivi-di-sviluppo-sostenibile","category-politica","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/391"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}