{"id":1120,"date":"2009-04-27T19:50:11","date_gmt":"2009-04-27T19:50:11","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/04\/27\/editoriale-i-governi-arabi-assolvono-in-darfur-ci-che-condannano-in-palestina\/"},"modified":"2009-04-27T19:50:11","modified_gmt":"2009-04-27T19:50:11","slug":"editoriale-i-governi-arabi-assolvono-in-darfur-ci-che-condannano-in-palestina","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2009\/04\/27\/editoriale-i-governi-arabi-assolvono-in-darfur-ci-che-condannano-in-palestina\/","title":{"rendered":"EDITORIALE: &quot;I governi arabi assolvono in Darfur ci&ograve; che condannano in Palestina&quot;"},"content":{"rendered":"<p>FREDERICKSBERG, VIRGINIA, 27 aprile 2009 (IPS) &#8211; Dall&rsquo;inizio del conflitto nella regione del Darfur, Sudan, sei anni fa, la violenza di basso livello si &egrave; trasformata progressivamente in una serie incessante e sistematica di &ldquo;atrocit&agrave; di massa&rdquo; contro i civili, portate avanti dalle milizie appoggiate dallo stato e dalle stesse forze di governo.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1432\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1432\" class=\"size-full wp-image-1432\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/Jody_Williams9.jpg\" alt=\"Jody Williams, vincitrice del Premio Nobel per la pace 1997 e presidente del Nobel Women's Initiative. Nobel Women's Initiative\/IPS\" width=\"200\"\/><p id=\"caption-attachment-1432\" class=\"wp-caption-text\">Jody Williams, vincitrice del Premio Nobel per la pace 1997 e presidente del Nobel Women&#8217;s Initiative.<br \/>Nobel Women&#8217;s Initiative\/IPS<\/p><\/div><\/div>\n<p>Il 4 marzo scorso, la Corte penale internazionale (ICC) ha accusato il presidente sudanese Omar Al-Bashir di crimini di guerra e contro l&rsquo;umanit&agrave;. Il 5 marzo, Bashir ha messo ulteriormente in pericolo la vita di 4,7 milioni di persone, con l&rsquo;espulsione degli organismi nazionali e internazionali di aiuti dal Darfur. <\/p>\n<p>Il 30 marzo, i leader arabi, vista la situazione, si sono incontrati al Vertice della Lega araba a Doha e hanno sottolineato, nelle loro stesse parole, &ldquo;la nostra solidariet&agrave; con il Sudan e il nostro rifiuto della decisione dell&rsquo;ICC [di incriminare Bashir]. <\/p>\n<p>Vorrei poter dire che le parole di questi uomini &#8211; pronunciate a diversi milioni di chilometri di distanza dalla dura realt&agrave; del Darfur &#8211; non sono importanti. Invece contano eccome:<\/p>\n<p>Approvano la volont&agrave; del presidente Bashir di negare gli aiuti al popolo del Darfur. Promuovono l&#039;intento di sfidare il mandato d&rsquo;arresto dell&rsquo;ICC. Preferiscono la politica ai diritti umani, e dicono al popolo del Darfur che nessun comportamento di Bashir potr&agrave; mai compromettere il sostegno di cui gode da parte dei suoi alleati. Inoltre, minano la stessa ICC &#8211; un&rsquo;istituzione internazionale formata da 139 stati membri. <\/p>\n<p>La situazione di violenza in Darfur &egrave; confusa, e il problema non &egrave; di semplice risoluzione. I gruppi ribelli sono irritabili e disorganizzati, e loro stessi sono responsabili di violazioni e atrocit&agrave;. Le pistole sono ovunque e i mezzi di sostentamento in nessun luogo. Nessuno sa per certo in che modo mettere fine alle violenze, n&eacute; cosa serve per ricostruire una societ&agrave; lacerata in ogni sua parte. <\/p>\n<p>Ci&ograve; che &egrave; chiaro, tuttavia, &egrave; che il cammino intrapreso dalla Lega araba durante il suo ultimo vertice &egrave; stato decisamente non-costruttivo. <\/p>\n<p>Il presidente Bashir ha diretto una contro-insorgenza sanguinosa e repressiva contro i ribelli a sud, a est e nella regione occidentale del Darfur. Prendere di mira i civili, lasciarli morire di fame come tattica di guerra, incendiare villaggi, e lo stupro di massa di donne sono tutti episodi ben documentati ovunque nel paese. Non si &egrave; fermato davanti a niente per restare al potere. <\/p>\n<p>La colpa o l&rsquo;innocenza di Bashir rispetto alle accuse contro di lui &egrave; una questione che dovr&agrave; chiarire l&rsquo;ICC, ma mostrare solidariet&agrave; nei suoi confronti non potr&agrave; nulla per risolvere i problemi di fondo della povert&agrave; e dell&rsquo;impunit&agrave;, e servir&agrave; solo a intralciare il possibile sostegno ai negoziati per un cessate il fuoco. Di certo non metter&agrave; fine alla crisi umanitaria immediata provocata dall&rsquo;espulsione delle agenzie di aiuti da parte di Bashir. <\/p>\n<p>Il Qatar, ospite del Summit della Lega araba, aveva lavorato per infondere energia al traballante processo di pace in Darfur, con un incontro tra Khartoum e il principale gruppo ribelle, il Movimento giustizia e uguaglianza (JEM). Adesso per&ograve;, ospitando il presidente incriminato appena qualche settimana dopo l&rsquo;espulsione delle organizzazioni umanitarie e dichiarando apertamente il proprio sostegno a Bashir, la credibilit&agrave; del Qatar come ospite e coordinatore dei colloqui di pace deve essere rimesso in questione. Il JEM ha gi&agrave; lasciato i colloqui, per protestare contro la situazione umanitaria. <\/p>\n<p>Invece di preferire la politica all&rsquo;umanit&agrave;, e di privilegiare le apparenze dell&rsquo;unit&agrave; araba rispetto alle preoccupazioni per il popolo del Darfur, la Lega araba avrebbe dovuto condannare l&rsquo;espulsione delle agenzie e la persecuzione dei sostenitori dei diritti umani per mano di Bashir. Una dichiarazione dei leader arabi in cui si fossero riconosciute le atrocit&agrave; e le violenze commesse dalle forze governative avrebbe avuto un profondo impatto su Khartoum. O meglio ancora, una dichiarazione in cui si sollecitavano tutti gli amici e i vicini del Sudan a lasciare che la Corte facesse il proprio lavoro. Tutte le nazioni dovrebbero fare il possibile per convincere tutte le parti a sedersi intorno a un tavolo, includendo anche le donne nei colloqui di pace, e per assicurare giustizia e riconciliazione per il popolo del Sudan. <\/p>\n<p>Il mondo arabo ha a lungo criticato l&#039;apparente cecit&agrave; dell&rsquo;America di fronte alla questione israelo-palestinese. Rispondere per le rime quando si tratta del presidente Bashir non serve per mettere fine alle sofferenze dei palestinesi, n&eacute; a quelle della gente del Darfur. Cos&igrave; come l&rsquo;amministrazione Usa utilizza due pesi e due misure per israeliani e palestinesi, la Lega araba utilizza due pesi e due misure per Khartoum e il Darfur. Le legittime critiche alla politica israeliana dovrebbero essere prese in considerazione pi&ugrave; seriamente e cos&igrave; la loro rigorosa applicazione, e bisognerebbe avere le stesse preoccupazioni per il popolo del Darfur di quelle che si hanno per il popolo palestinese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FREDERICKSBERG, VIRGINIA, 27 aprile 2009 (IPS) &#8211; Dall&rsquo;inizio del conflitto nella regione del Darfur, Sudan, sei anni fa, la violenza di basso livello si &egrave; trasformata progressivamente in una serie incessante e sistematica di &ldquo;atrocit&agrave; di massa&rdquo; contro i civili,&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2009\/04\/27\/editoriale-i-governi-arabi-assolvono-in-darfur-ci-che-condannano-in-palestina\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":368,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,15,1,28,25,32,33],"tags":[],"class_list":["post-1120","post","type-post","status-publish","format-standard","hentry","category-africa","category-diritti-umani","category-headlines","category-medioriente","category-obiettivi-di-sviluppo-sostenibile","category-politica","category-popolazione"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/368"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1120"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1120\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1120"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}