{"id":1111,"date":"2009-04-07T15:27:05","date_gmt":"2009-04-07T15:27:05","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/04\/07\/economia-democratizzare-la-finanza\/"},"modified":"2009-04-07T15:27:05","modified_gmt":"2009-04-07T15:27:05","slug":"economia-democratizzare-la-finanza","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2009\/04\/07\/economia-democratizzare-la-finanza\/","title":{"rendered":"ECONOMIA: &quot;Democratizzare la finanza&quot;"},"content":{"rendered":"<p>ST.AUGUSTINE, Florida, 7 aprile 2009 (IPS) &#8211; La crisi finanziaria generata a Wall Street e dalla cultura del &ldquo;too<br \/>\nbig to fail&rdquo;, troppo grandi per fallire, di finanzieri e banche<br \/>\ncentrali globali, sta portando alla nascita di iniziative locali e a<br \/>\nnuove esigenze di decentralizzare e democratizzare la finanza.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1419\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1419\" class=\"size-full wp-image-1419\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/HazelHenderson.jpg\" alt=\"Hazel Henderson, presidente di Ethical Markets Media e autrice di \"Ethical Markets: Growing the Green Economy\" (2006) IPS\/Ethical Markets Media\" width=\"200\"\/><p id=\"caption-attachment-1419\" class=\"wp-caption-text\">Hazel Henderson, presidente di Ethical Markets Media e autrice di &#8220;Ethical Markets: Growing the Green Economy&#8221; (2006)<br \/>IPS\/Ethical Markets Media<\/p><\/div><\/div>\n<p>Mentre i tagli al bilancio portano al disfacimento delle reti di sicurezza nazionali, cresce la leadership locale, che offre diverse alternative creative alla comunit&agrave; per alimentare economie &ldquo;home-grown&rdquo; pi&ugrave; sane:<\/p>\n<p>&#8211; Proliferano i &ldquo;barter club&rdquo; locali, organizzazioni commerciali di baratto, come Freecycle.com, Craigslist e LETS, cos&igrave; come i sistemi monetari complementari, come sempre accade quando i banchieri centrali e il Fondo monetario internazionale falliscono o finiscono per peggiorare la situazione. Tra quelli pi&ugrave; efficaci, la moneta WIR in Svizzera, e i Berkshares negli Stati Uniti, in circolazione per un equivalente di 2 milioni di dollari Usa, e accettate da banche e imprese in Massachusetts. Analoghe forme di moneta complementare funzionano in Gran Bretagna, Canada, Australia, Argentina, Brasile e altri paesi.<\/p>\n<p>&#8211; I progetti di prestito e di microfinanza people-to-people stanno vivendo un vero e proprio boom in molti paesi: la Women&rsquo;s World Banking (WWB), o Banca mondiale delle donne, e la Grameen Bank in Bangladesh, oggi vengono emulate in diversi paesi, come Finca e Accion in America Latina, ma anche in nuove versioni on-line. Le cooperative di credito, attive da un secolo in Europa e in Nord America, oggi rispondono a nuovi bisogni locali, rivolgendosi alle persone pi&ugrave; povere e introducendo servizi di prestito e di micro-finanza per le piccole imprese.<\/p>\n<p>&#8211; Associazioni di piccole banche e imprese locali assumono un maggiore peso politico, cos&igrave; come le cooperative di credito. Negli Stati Uniti, chiedono un trattamento uguale nei fondi statali di salvataggio attualmente riversati sulle grandi banche i cui prestiti sconsiderati hanno scatenato l&rsquo;attuale caos finanziario. Il capitale a rischio e il cosiddetto &ldquo;filantrocapitalismo&rdquo;, incarnati ad esempio dalla Rudolf Steiner Foundation, Acumen, e le fondazioni dei creatori di Ebay, Pierre Omidyar e Jeffrey Skoll, stanno investendo in imprese sociali che rispondono ai bisogni sociali ricavando profitti modesti. Questo capitale sociale oggi sta creando in molte economie un nuovo settore ibrido.<\/p>\n<p>&#8211; La New Economics Foundation (NEF) in Gran Bretagna sta generando sia iniziative locali, come il movimento delle Transition Towns, le &ldquo;citt&agrave; di transizione&rdquo;, e il &ldquo;New Deal verde&rdquo; con indicatori alternativi per correggere il PIL, misurando benessere e sostenibilit&agrave; ecologica. La proposta della NEF per salvare 11.500 uffici postali in Gran Bretagna aggiungendo nuove funzioni di local banking, &egrave; appoggiata da sindacati, piccole imprese, gruppi di interesse pubblico, e pensionati.<\/p>\n<p>&#8211; La banca del tempo, nata da un&rsquo;idea di Edgar Cahn negli Usa, oggi mette in contatto le popolazioni locali per condividere servizi in Giappone, Europa e altri paesi. I vicini possono entrare in contatto attraverso un &ldquo;banchiere del tempo&rdquo; locale, per fornire pasti o un aiuto alle persone disabili costrette a rimanere in casa, o per scambiare servizi di babysitting, per sorvegliare una propriet&agrave;, falciare l&rsquo;erba, o per uno scambio di elettrodomestici in prestito. Anche l&rsquo;attivit&agrave; del car-sharing, &ldquo;l&rsquo;auto in condivisione&rdquo;, oggi ha portato alla creazione di diverse nuove imprese.<\/p>\n<p>&#8211; La Cina ospita diverse iniziative locali di questo tipo, collegando piccole imprese in reti, come Baidu.com, Alibaba.com, o Qifang.com, che offre prestiti accessibili ai 25 milioni di studenti cinesi. Circle Pleasure, un&rsquo;impresa privata che vende carte prepagate per i consumatori, ha formato una joint venture con Qifang per servizi bancari people-to-people, la prima impresa privata a ricevere una licenza bancaria dalla Banca centrale cinese. In diversi paesi dell&rsquo;Africa, sono decollati i servizi bancari tramite telefono cellulare. I cellulari sono alla base delle &ldquo;phone ladies&rdquo; nei villaggi indiani e del Bangladesh, che noleggiano i loro cellulari ad altri villaggi, cos&igrave; che agricoltori e pescatori possono consultare i prezzi dei villaggi e dei mercati vicini per ottimizzare le vendite.<\/p>\n<p>Fino a che punto la finanza people-to-people &egrave; in grado di bypassare le grandi banche ingorde, e i finanzieri di Wall Street privi di senso etico, o i loro alleati politici? In ampia misura, grazie a tutti gli strumenti della comunicazione oggi disponibili. L&rsquo;utilizzo di questi strumenti di condivisione delle informazioni oggi aiuta la gente a capire nuovamente cosa &egrave; davvero il denaro: solo una forma di informazione. Oggi &egrave; possibile commerciare utilizzando il puro scambio di informazioni. Per esempio, nella Florida rurale, esistono programmi radio call-in, interattivi, dove, ad esempio, un agricoltore pu&ograve; proporre di scambiare l&rsquo;uso del trattore con una certa quantit&agrave; di semi. Analogamente, la crescita della vendita diretta degli agricoltori permette ai consumatori locali di comprare prodotti freschi direttamente dagli agricoltori di zona.<\/p>\n<p>Perci&ograve;, come abbiamo potuto permettere alle grandi banche e alla finanza centralizzata di crescere a tal punto da diventare predatori delle economie reali che producono la ricchezza reale globale? Le popolazioni locali di tutto il mondo cominciano a capire che possono semplicemente bypassare le grandi banche e la borsa valori, e produrre gli stessi servizi a livello locale. Il vecchio settore finanziario gonfiato deve ridimensionarsi, tagliare i propri bonus e addossarsi le perdite prodotte dai giochi d&rsquo;azzardo praticati nei loro casin&ograve; globali. Un settore di servizi finanziari davvero efficace non dovrebbe rappresentare pi&ugrave; del 10 per cento del PIL nazionale. In Gran Bretagna e Stati Uniti, &egrave; cresciuto fino al 25 per cento del PIL, diffondendosi come metastasi grazie agli &ldquo;ingegneri finanziari&rdquo; che hanno saccheggiato l&rsquo;economia reale. Adesso, gli studenti cercano lavoro come ingegneri reali, insegnanti, dottori e imprenditori reali.<\/p>\n<p>In realt&agrave;, noi esseri umani non stiamo vivendo una crisi finanziaria, ma una crisi della percezione. Cominciamo a vedere il nostro mondo con occhi diversi rispetto a come i media del mainstream lo dipingono. Vediamo le nostre scelte con uno sguardo nuovo. Mentre guardiamo in TV le banche centrali stampare denaro, impariamo che la vera ricchezza non &egrave; il denaro: la vera ricchezza &egrave; generata dalla gente che produce, utilizzando le risorse della Terra in modo saggio. Il denaro &egrave; un utile mezzo di scambio, se gestito correttamente, a livello locale, nazionale, globale, o elettronico. Accaparrare denaro non &egrave; pi&ugrave; una riserva affidabile di valore. Stiamo tutti riscoprendo le tante riserve di valore all&rsquo;interno delle nostre stesse comunit&agrave;. Troviamo la ricchezza al di l&agrave; del denaro. Possiamo cambiare i nostri valori per i nuovi tempi in cui viviamo, e restituire all&rsquo;&ldquo;economia dell&rsquo;amore&rdquo; la sua centralit&agrave; nella nostra vita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ST.AUGUSTINE, Florida, 7 aprile 2009 (IPS) &#8211; La crisi finanziaria generata a Wall Street e dalla cultura del &ldquo;too big to fail&rdquo;, troppo grandi per fallire, di finanzieri e banche centrali globali, sta portando alla nascita di iniziative locali e&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2009\/04\/07\/economia-democratizzare-la-finanza\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":361,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,38,5,8,11,12,18,22,1,26,27,30,25,35,36],"tags":[],"class_list":["post-1111","post","type-post","status-publish","format-standard","hentry","category-africa","category-sviluppo","category-america-latina","category-asia-e-oceania","category-columnas","category-comunicazione-nuove-tecnologie-e-media","category-economia","category-europa","category-headlines","category-iraq-e-asia-centrale","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-nord-america","category-obiettivi-di-sviluppo-sostenibile","category-science-technologie","category-societa-civile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/361"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1111"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1111\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1111"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}