{"id":1107,"date":"2009-03-30T19:29:28","date_gmt":"2009-03-30T19:29:28","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2009\/03\/30\/diritti-cambogia-per-non-dimenticare-il-passato\/"},"modified":"2009-03-30T19:29:28","modified_gmt":"2009-03-30T19:29:28","slug":"diritti-cambogia-per-non-dimenticare-il-passato","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2009\/03\/30\/diritti-cambogia-per-non-dimenticare-il-passato\/","title":{"rendered":"DIRITTI-CAMBOGIA: Per non dimenticare il passato"},"content":{"rendered":"<p>PHNOM PENH, 30 marzo 2009 (IPS) &#8211; In questi giorni, i turisti in visita ad un vecchio liceo di questa citt&agrave; trasformato in una famigerata camera di tortura durante il brutale regime del Khmer rossi a met&agrave; degli anni &rsquo;70, hanno trovato una sorpresa: la presenza di un uomo che &egrave; sopravvissuto per raccontare la storia.<\/p>\n<p><!--more--><\/p>\n<p><div align='center'><div id=\"attachment_1413\" style=\"width: 210px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1413\" class=\"size-full wp-image-1413\" src=\"\/ipsnotizie\/\/imagenes\/images_site\/chummey3.jpg\" alt=\"Chum Mey accanto a un dipinto di Vann Nath a Tuol Slein, il vecchio carcere dei Khmer rossi Marwaan Macan-Markar\/IPS\" width=\"200\"\/><p id=\"caption-attachment-1413\" class=\"wp-caption-text\">Chum Mey accanto a un dipinto di Vann Nath a Tuol Slein, il vecchio carcere dei Khmer rossi<br \/>Marwaan Macan-Markar\/IPS<\/p><\/div><\/div>\n<p>I turisti hanno ascoltato la storia di Chum Mey, che oggi ha 78 anni, ed &egrave; una delle 11 persone uscite vive dai quattro edifici trasformati nella prigione di Tuol Sleng, o S-21. Qui, almeno 12.380 persone incarcerate, compresi i bambini, furono torturate e uccise. <\/p>\n<p>Il racconto di Chum Mey sulle sofferenze che uomini e donne hanno dovuto sopportare a Tuol Sleng ha permesso ai visitatori di ripercorrere le terribili storie vissute in queste palazzine di tre piani dalle mura grigie, le grate alle finestre ricoperte di ruggine e alcune sezioni ancora avvolte nel filo spinato.    In alcune stanze si possono vedere i letti di metallo arrugginito dove i prigionieri venivano ammanettati e torturati. In una interminabile galleria sono esposte foto in bianco e nero delle vittime &#8211; uccise con un colpo alla testa &#8211; scattate dai carcerieri di Tuol Sleng subito dopo l&rsquo;arrivo dei reclusi. Alcune lasciano trapelare il terrore nei loro occhi. <\/p>\n<p>Nelle prossime settimane, i cambogiani potranno conoscere dettagli fino ad ora sconosciuti degli orrori vissuti tra le mura del pi&ugrave; grande centro di detenzione e tortura all&rsquo;epoca in cui il paese era intrappolato nella morsa fatale dei Khmer rossi, dal 17 aprile 1975 al 16 gennaio 1979.    Alla sbarra, il capo carceriere di Tuol Sleng, Kaing Khek Eav, noto come &ldquo;Duch&rdquo;: il suo processo, cominciato luned&igrave;, &egrave; il primo di altri quattro che si terranno davanti alle Camere straordinarie dei tribunali della Cambogia (ECCC), un tribunale per i crimini di guerra che comprende una Commissione delle Nazioni Unite e istituito per giudicare i leader sopravvissuti dei Khmer rossi. <\/p>\n<p>Erano trent&rsquo;anni che si aspettava di fare giustizia. Il regime genocida dei Khmer rossi &egrave; stato responsabile della morte di circa 1,7 milioni di persone, quasi un quarto della popolazione totale del paese all&rsquo;epoca. <\/p>\n<p>Le vittime venivano giustiziate o morivano ai lavori forzati o per fame, mentre il regime estremista dei maoisti cercava di realizzare, con la forza brutale, l&rsquo;utopia agraria. <\/p>\n<p>&rdquo;Gran parte del processo a Duch sar&agrave; incentrato su Tuol Sleng&rdquo;, ha spiegato Sara Colm, ricercatrice in Cambogia per il gruppo di difesa dei diritti umani Human Rights Watch. &ldquo;Dovremmo venire a conoscenza di dettagli sul funzionamento dei crimini che venivano commessi in questa prigione&rdquo;.<\/p>\n<p>Nel programma dell&rsquo;ECCC emerge chiaramente l&rsquo;attenzione riservata a Tuol Sleng. &ldquo;I giudici della Camera di giudizio esamineranno prima il caso dell&rsquo;accusato e poi ascolteranno le parti civili, i testimoni e gli esperti, nell&rsquo;ordine che riterranno pi&ugrave; opportuno, argomento per argomento&rdquo;, si legge sul sito web dell&rsquo;ECCC.<\/p>\n<p>Tra i temi in esame, &ldquo;l&rsquo;istituzione della S-21&rdquo;, &ldquo;l&rsquo;attuazione delle politiche (dei Khmer rossi) nell&rsquo;S-21&rdquo;, e il &ldquo;funzionamento dell&rsquo;S-21&rdquo;. Tra i residenti di Phnom Pehn che sperano di assistere al processo, Chea Vannath, che vive in un&rsquo;ampia casa a pochi passi da Tuol Sleng. &ldquo;&Egrave; stata giustiziata qui&rdquo;, racconta la nota analista politica cambogiana, di 65 anni, ricordando la morte della cugina. <\/p>\n<p>&ldquo;Prima hanno ucciso il marito, che era stato il direttore di un&rsquo;altra prigione dei Khmer rossi. Non sappiamo cosa successe davvero in quel periodo&rdquo;, aggiunge. &ldquo;Grazie al processo a Duch, le generazioni pi&ugrave; giovani e quelle pi&ugrave; vecchie apprenderanno qualcosa di nuovo. Ma sar&agrave; ancora una volta un processo molto doloroso per i cambogiani&rdquo;. <\/p>\n<p>Tra i fatti gi&agrave; noti, alcune pubblicazioni portate alla luce dal Centro di documentazione della Cambogia (DC-Cam), un istituto di ricerca con sede a Phnom Penh che, dal 1995, ha identificato 20mila fosse comuni, in 198 carceri dei Khmer rossi, e ha intervistato quasi un milione di vittime per poi istituire i processi nel tribunale per i crimini di guerra. <\/p>\n<p>Una delle pubblicazioni della DC-Cam &egrave; stata distribuita nei licei del paese da met&agrave; marzo, per far conoscere agli studenti le atrocit&agrave; del regime. Oggi, quasi tutti gli studenti conoscono il funzionamento dell&rsquo;oppressivo governo della &ldquo;Kampuchea democratica&rdquo;, il nome dello stato ai tempi dei Khmer rossi, attraverso i racconti delle famiglie e dei media.<\/p>\n<p>&ldquo;[A Tuol Sleng, i prigionieri venivano] portati in piccole celle e legati a delle catene fissate ai muri o al pavimento di cemento, mentre chi veniva messo in celle pi&ugrave; grandi aveva le gambe incatenate a sbarre di ferro; i prigionieri dormivano a due a due, la testa contro i piedi dell&rsquo;altro&rdquo;, rivela il libro della DC-Cam per le scuole, &ldquo;La storia della Kampuchea democratica&rdquo;. <\/p>\n<p>&rdquo;Per far confessare i detenuti dell&rsquo;S-21 venivano utilizzate tattiche crudeli: i prigionieri venivano presi a pugni, picchiati con dei bastoni o grossi rami di alberi. Talvolta venivano collegati a dei cavi per l&rsquo;elettroshock&rdquo;, si racconta. &ldquo;Tra gli altri metodi per far confessare le vittime, strappare le unghie versando alcol sulle ferite o tenendo ferma la testa sotto l&rsquo;acqua&rdquo;. <\/p>\n<p>Le prigioniere donne venivano isolate per essere torturate con altri sistemi, denuncia il testo, di 75 pagine. &ldquo;Venivano sottoposte alla pratica del taglio dei seni&rdquo; o &ldquo;alle volte venivano stuprate dagli uomini incaricati di interrogarle, bench&eacute; la politica [dei Khmer rossi] non prevedesse l&rsquo;abuso sessuale&rdquo;. <\/p>\n<p>Alcuni di questi orrori sono stati rappresentati nei dipinti di Vann Nath, uno degli 11 sopravvissuti a Tuol Sleng. Le sue tele colorate non si risparmiano sui dettagli per trasmettere il dolore negli occhi delle vittime, mentre venivano torturate dai membri del regime. <\/p>\n<p>Questi dipinti del dolore, scaturiti dalla sua memoria negli ultimi 30 anni, sono stati fondamentali per il lavoro della DC-Cam, gettando luce sugli orrori avvenuti tra le mura dell&rsquo;S-21. Alcuni sono stati esposti oggi sulle pareti di Tuol Sleng, mentre altri sono appesi sui muri della sua galleria privata vicino a un ristorante che oggi Nath gestisce.    Ma la sua arte potrebbe avere le ore contate, adesso che l&rsquo;ECCC sta giudicando Duch per i crimini che ha commesso quando era capo torturatore di Tuol Sleng. &ldquo;Smetter&ograve; di dipingere a Tuol Sleng se il tribunale condanner&agrave; Duch&rdquo;, spiega il 62enne dalla voce dolce, in una stanza piena dei ricordi dolorosi dell&rsquo;anno che trascorse nel carcere oggi divenuto il simbolo della brutalit&agrave; del regime dei Khmer rossi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PHNOM PENH, 30 marzo 2009 (IPS) &#8211; In questi giorni, i turisti in visita ad un vecchio liceo di questa citt&agrave; trasformato in una famigerata camera di tortura durante il brutale regime del Khmer rossi a met&agrave; degli anni &rsquo;70,&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2009\/03\/30\/diritti-cambogia-per-non-dimenticare-il-passato\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[8,15,1,25,33],"tags":[],"class_list":["post-1107","post","type-post","status-publish","format-standard","hentry","category-asia-e-oceania","category-diritti-umani","category-headlines","category-obiettivi-di-sviluppo-sostenibile","category-popolazione"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1107"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1107\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1107"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}