{"id":1058,"date":"2008-12-09T17:09:04","date_gmt":"2008-12-09T17:09:04","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2008\/12\/09\/salute-nuovi-strumenti-diagnostici-potrebbero-ridurre-drasticamente-le-morti-per-malaria\/"},"modified":"2008-12-09T17:09:04","modified_gmt":"2008-12-09T17:09:04","slug":"salute-nuovi-strumenti-diagnostici-potrebbero-ridurre-drasticamente-le-morti-per-malaria","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2008\/12\/09\/salute-nuovi-strumenti-diagnostici-potrebbero-ridurre-drasticamente-le-morti-per-malaria\/","title":{"rendered":"SALUTE: Nuovi strumenti diagnostici potrebbero ridurre drasticamente le morti per malaria"},"content":{"rendered":"<p>UXBRIDGE, Canada, 9 dicembre 2008 (IPS) &#8211; La malaria uccide un bambino ogni 30 secondi, ma una nuova scoperta diagnostica potrebbe ridurre il devastante bilancio delle vittime, secondo quanto annunciato domenica scorsa da alcuni scienziati canadesi.<\/p>\n<p><!--more--><\/p>\n<p>La scoperta di &ldquo;biomarcatori&rdquo; &#8211; segnali biologici rivelatori presenti nel sangue dei bambini &#8211; utili per individuare due delle forme pi&ugrave; letali di malaria &egrave; stata annunciata la scorsa settimana al meeting annuale della American Society of Tropical Medicine and Hygiene a New Orleans, Louisiana. <\/p>\n<p>&ldquo;Un bambino con la febbre pu&ograve; essere curato in un ambulatorio con i farmaci antimalaria, che per&ograve; non sono sufficienti nel caso della malaria cerebrale&rdquo;, spiega Conrad Liles, specialista di malattia tropicale affiliato al McLaughlin-Rotman Centre for Global Health (MRC) di Toronto.<\/p>\n<p>La malaria cerebrale, che si sviluppa nei vasi sanguigni del cervello, &egrave; la forma pi&ugrave; letale di malaria. Il 2-5 per cento dei bambini con la malaria contrae la forma cerebrale, che nel 40 per cento dei casi porta alla morte, ha segnalato Liles all&rsquo;IPS.<\/p>\n<p>Liles e i suoi colleghi dell&rsquo;MRC hanno scoperto una correlazione tra la malaria cerebrale e un rapporto anomalo tra due forme di proteine che regolano l&rsquo;attivazione dei vasi sanguigni, note come angiopoietine. Quando in un campione di sangue viene individuato il rapporto anomalo, il bambino pu&ograve; ricevere un trattamento pi&ugrave; intensivo.<\/p>\n<p>Alcuni test sul campo eseguiti da due collaboratori dalla Tailandia, Noppadon Tangpukdee Srivicha Krudsood e Sornchai Looareesuwan, e dall&rsquo;Uganda, Robert Opoka e Chandy John, hanno registrato tassi di successo molti alti nell&rsquo;identificazione della malaria cerebrale &#8211; tra l&#039;80 e il 100 per cento.<\/p>\n<p>&ldquo;Limitarsi ad uccidere il parassita non &egrave; sufficiente, perch&eacute; la malattia pu&ograve; tornare a svilupparsi&rdquo;, ha spiegato Liles.<\/p>\n<p>La malaria &egrave; una malattia del sangue causata da un parassita che si trova in alcune specie di zanzare. I sintomi della malaria, come febbre, mal di testa e vomito, compaiono tra i 9 e i 14 giorni dopo il morso della zanzara infetta. Se non c&rsquo;&egrave; disponibilit&agrave; di medicine o se i parassiti sono farmaco-resistenti, l&rsquo;infezione pu&ograve; portare al coma, ad una anemia molto grave, e alla morte.<\/p>\n<p>Nel mondo, la malaria provoca ogni anno circa 350-500 milioni di malati e pi&ugrave; di un milione di morti.<\/p>\n<p>Le donne incinte che non mostrano sintomi evidenti della malaria possono per&ograve; contenere alte percentuali di parassiti nella placenta, che sono tra le principali cause di aborto spontaneo, nascite sottopeso e anemia materna. Circa 10mila donne muoiono ogni anno per malaria placentare, mentre oltre 400mila sviluppano una grave anemia. La malattia &egrave; inoltre causa di 200mila morti infantili e innumerevoli casi di neonati sottopeso &#8211; un grave fattore di rischio di morte infantile precoce.<\/p>\n<p>&ldquo;I bambini nati sottopeso per malaria placentare subiscono gravi conseguenze ancor prima di cominciare a respirare&rdquo;, osserva Kevin Kain dell&rsquo;MRC e direttore del Centre for Travel and Tropical Medicine al Toronto General Hospital.<\/p>\n<p>&ldquo;Una qualsiasi malattia contratta nella prima infanzia ha pi&ugrave; probabilit&agrave; di ucciderli&rdquo;, spiega Kain.<\/p>\n<p>I test sulle donne incinte del Kenya hanno rivelato che il sangue delle donne con malaria placentare contengono elevati livelli di un altro biomarcatore: una proteina chiamata C5a, che &egrave; una parte importante delle difese innate dell&rsquo;organismo contro le infezioni.<\/p>\n<p>&ldquo;Un test che aiuti ad individuare la malaria placentare fa s&igrave; che le donne possano essere curate prima, durante la gravidanza, riducendo il rischio di morte o anemia, e forse evitando il rischio di malformazione o aborto spontaneo dei neonati&rdquo;, ha dichiarato Kain.<\/p>\n<p>Ma questi test non sono ancora disponibili. L&rsquo;MRC e altri centri stanno sviluppando un &ldquo;test diagnostico point-of-care (decentralizzato)&rdquo;, in grado di individuare una serie di elementi, tra cui i due biomarcatori. La speranza &egrave; che questi strumenti diagnostici siano economici, semplici da usare, che non richiedano refrigerazione e siano disponibili entro tre, cinque anni&rdquo;, ha auspicato Liles.<\/p>\n<p>Queste scoperte sono state possibili grazie ad una nuova capacit&agrave; di individuare l&rsquo;origine della malattia a livello molecolare. Potendo capire i progressi della malattia, i ricercatori sperano non solo di poterla individuare al pi&ugrave; presto, ma anche di interromperne il ciclo. Questi biomarcatori possono rappresentare nuovi target per possibili nuovi farmaci, o anche per i farmaci gi&agrave; esistenti da utilizzare per altre condizioni, in grado di interrompere lo sviluppo dell&rsquo;infezione malarica, ha spiegato.<\/p>\n<p>Le angiopoietine sono state scoperte solo 10 anni fa, nel contesto dello sviluppo del tumore canceroso. Considerando che il processo della malaria cerebrale implica una sepsi (infiammazione) simile per certi versi alla crescita dei vasi sanguigni nei tumori, individuare la relazione era una &ldquo;ipotesi verificata&rdquo;, ha ricordato Liles.<\/p>\n<p>Sviluppare questi biomarcatori e strumenti diagnostici &#8211; ha osservato &#8211; pu&ograve; migliorare di molto la cura, riducendo i costi totali con un uso pi&ugrave; efficiente delle risorse limitate.<\/p>\n<p>&ldquo;Credo che questa scoperta avr&agrave; implicazioni importanti&rdquo;, ha concluso.<\/p>\n<p>Intanto il New England Journal of Medicine ha riportato luned&igrave; che il vaccino contro la malaria clinicamente pi&ugrave; avanzato al mondo ha fornito ai neonati e ai bambini una protezione significativa contro la malaria.<\/p>\n<p>&ldquo;I risultati dello studio odierno dimostrano in larga misura che i nostri investimenti nello sviluppo di vaccini anti-malarici cominciano a dare i loro frutti&rdquo;, ha detto Christian Loucq, direttore della Malaria Vaccine Initiative. &ldquo;Siamo pi&ugrave; vicini che mai allo sviluppo di un vaccino anti-malarico per i bambini in Africa&rdquo;.<\/p>\n<p>Nei bambini piccoli, il vaccino candidato pu&ograve; essere somministrato come parte dei programmi di immunizzazione nazionali africani gi&agrave; esistenti per malattie come difterite, tetano e polio. Nei piccoli tra i 5 e i 17 mesi, il candidato RTS,S\/AS01 ha ridotto del 53 per cento il rischio di malaria in un periodo di monitoraggio di otto mesi. Gli studi sono stati condotti in Kenya e Tanzania.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UXBRIDGE, Canada, 9 dicembre 2008 (IPS) &#8211; La malaria uccide un bambino ogni 30 secondi, ma una nuova scoperta diagnostica potrebbe ridurre il devastante bilancio delle vittime, secondo quanto annunciato domenica scorsa da alcuni scienziati canadesi.<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[1,30,25,33,34],"tags":[],"class_list":["post-1058","post","type-post","status-publish","format-standard","hentry","category-headlines","category-nord-america","category-obiettivi-di-sviluppo-sostenibile","category-popolazione","category-salute"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1058"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1058\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1058"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}