{"id":1040,"date":"2008-10-20T17:00:58","date_gmt":"2008-10-20T17:00:58","guid":{"rendered":"http:\/\/ipsnews.net\/ipsnotizie\/2008\/10\/20\/commercio-doha-nessun-compromesso-sullo-sviluppo\/"},"modified":"2008-10-20T17:00:58","modified_gmt":"2008-10-20T17:00:58","slug":"commercio-doha-nessun-compromesso-sullo-sviluppo","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/italiano\/2008\/10\/20\/commercio-doha-nessun-compromesso-sullo-sviluppo\/","title":{"rendered":"COMMERCIO: Doha, nessun compromesso sullo sviluppo"},"content":{"rendered":"<p>GINEVRA, 20 ottobre 2007 (IPS) &#8211; Di fronte alla crisi finanziaria globale e all&rsquo;aumento dei prezzi del cibo, i paesi africani intendono concludere entro la fine dell&rsquo;anno l&rsquo;accordo sulle modalit&agrave; nel Round di Doha sull&rsquo;agricoltura e sull&rsquo;apertura dei mercati ai prodotti industriali, che si continua a rimandare da tempo.<\/p>\n<p><!--more--><\/p>\n<p>Ma non intendono tollerare il continuo tentativo da parte di alcuni importanti componenti dell&rsquo;Organizzazione mondiale del commercio (WTO\/OMC) di indebolire &ldquo;la dimensione dello sviluppo&rdquo; nell&rsquo;accordo sulle modalit&agrave;, secondo quanto dichiarato all&rsquo;IPS da alcuni inviati commerciali africani. <\/p>\n<p>L&rsquo;accordo sulle modalit&agrave; (parametri) contiene un complesso labirinto di norme per stabilire come i membri del WTO dovranno ridurre i loro sussidi agricoli e tariffe di importazione, ma anche i dazi di importazione sui prodotti industriali.<\/p>\n<p>Per i paesi africani, le principali questioni relative allo sviluppo tra questi parametri includerebbero: una enorme riduzione dei sussidi globali al cotone; speciali flessibilit&agrave; per tutelare importanti prodotti agricoli che permettono a decine di milioni di agricoltori poveri di sopravvivere; attenuare l&rsquo;erosione delle preferenze commerciali concesse dagli ex colonizzatori; un accesso libero da quote e dazi per i paesi meno sviluppati, con regole semplici; ecc..<\/p>\n<p>&ldquo;Siamo preoccupati per la crisi finanziaria, cos&igrave; come per l&rsquo;aumento dei prezzi del cibo, perch&eacute; la maggior parte dei nostri paesi dipende dal commercio esterno, e importiamo anche molti prodotti agricoli&rdquo;, ha spiegato l&rsquo;ambasciatore Shree Baboo Chekitan Servansing, coordinatore del gruppo dei paesi di Africa, Caraibi e Pacifico (ACP)<\/p>\n<p>&ldquo;Il commercio &egrave; parte della soluzione in questa crisi finanziaria e alimentare globale, e un accordo forte per ridurre i sussidi agricoli e riequilibrare le regole degli scambi offre buone speranze per l&rsquo;economia mondiale&rdquo;, ha commentato in un&rsquo;intervista all&rsquo;IPS. &ldquo;E ogni ulteriore ritardo nel concludere questo accordo non far&agrave; altro che aggravare ancora di pi&ugrave; le crisi&rdquo;, ha sostenuto Servansing. <\/p>\n<p>Per di pi&ugrave;, la crisi finanziaria nei grandi paesi industrializzati &egrave; destinata a creare un buco nei bilanci degli aiuti pubblici allo sviluppo; e lascer&agrave; fuori gli aiuti al commercio. &ldquo;Per questo &egrave; importante che il Round di Doha sullo sviluppo (Doha Development Round, DDA) si risolva senza altri ritardi&rdquo;, ha sottolineato.<\/p>\n<p>&ldquo;Il gruppo africano ha deciso di impegnarsi per concludere i negoziati sui parametri di Doha entro la fine del 2008&rdquo;, ha affermato l&rsquo;ambasciatore Guy Alain Emmanuel Gauze, coordinatore del gruppo dei paesi africani al WTO. &ldquo;Stiamo ancora lavorando sodo perch&eacute; i lavori relativi all&rsquo;accordo sulle modalit&agrave; per agricoltura e NAMA (accesso al mercato per i prodotti non agricoli) procedano senza intoppo&rdquo;, ha detto all&rsquo;IPS. <\/p>\n<p>Un accordo tempestivo nel Round di Doha &ldquo;potrebbe sbloccare&rdquo; l&rsquo;attuale impasse nei confronti di diversi problemi globali e &ldquo;stimolare gli scambi globali in un momento in cui cresce la paura del protezionismo&rdquo;, ha osservato Anthony Mothae Maruping, inviato commerciale del Lesotho e coordinatore del gruppo dei paesi meno sviluppati (PMS) presso il WTO. <\/p>\n<p>Ma i tre coordinatori si sono detti molto preoccupati per i continui tentativi di compromettere gli aspetti legati allo sviluppo nell&rsquo;accesso al mercato dei prodotti industriali e nel libero accesso da quote e dazi per i prodotti esportati dai PMS. <\/p>\n<p>Quanto ai negoziati sui beni industriali, i paesi africani si sono opposti all&rsquo;eliminazione delle tariffe su base settoriale &#8211; che comporterebbe l&rsquo;azzeramento delle tariffe su alcuni prodotti specifici &#8211; in quanto ricadrebbe negativamente sulle loro preferenze commerciali. Per gli Stati Uniti, si tratta di un&rsquo;esigenza vitale per accontentare le proprie lobby industriali e garantirsi un sostegno nell&rsquo;accordo sulle modalit&agrave;. <\/p>\n<p>&ldquo;L&rsquo;eliminazione delle tariffe per determinati settori non &egrave; una condizione obbligatoria per i paesi africani. &Egrave; solo volontaria&rdquo;, ha precisato Gauze, suggerendo la loro presa di distanza dai negoziati su questo argomento. &ldquo;Siamo contrari a tutti i punti relativi all&rsquo;eliminazione delle tariffe su base settoriale&rdquo;, ha detto Servansing, ribadendo che questo non farebbe che minare ulteriormente le preferenze commerciali. <\/p>\n<p>Per di pi&ugrave;, un accesso al mercato libero da quote e dazi per i paesi africani non pu&ograve; essere appesantito da complicate norme d&rsquo;origine, a detta di Maruping. Secondo l&rsquo;inviato, non &egrave; stata fatta ancora chiarezza su diversi aspetti relativi all&rsquo;accesso al mercato senza dazi n&eacute; quote.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GINEVRA, 20 ottobre 2007 (IPS) &#8211; Di fronte alla crisi finanziaria globale e all&rsquo;aumento dei prezzi del cibo, i paesi africani intendono concludere entro la fine dell&rsquo;anno l&rsquo;accordo sulle modalit&agrave; nel Round di Doha sull&rsquo;agricoltura e sull&rsquo;apertura dei mercati ai&hellip; <a href=\"http:\/\/ipsnews.net\/italiano\/2008\/10\/20\/commercio-doha-nessun-compromesso-sullo-sviluppo\/\" class=\"more-link\"> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":216,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2,38,11,18,21,1,27,30,25],"tags":[],"class_list":["post-1040","post","type-post","status-publish","format-standard","hentry","category-africa","category-sviluppo","category-columnas","category-economia","category-epas-si-negozia-sul-futuro","category-headlines","category-le-citta-i-cittadini-e-gli-obiettivi-di-sviluppo","category-nord-america","category-obiettivi-di-sviluppo-sostenibile"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/comments?post=1040"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/posts\/1040\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/media?parent=1040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/categories?post=1040"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/italiano\/wp-json\/wp\/v2\/tags?post=1040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}